{"id":171960,"date":"2021-10-08T11:54:10","date_gmt":"2021-10-08T09:54:10","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=171960"},"modified":"2021-12-02T11:41:32","modified_gmt":"2021-12-02T10:41:32","slug":"euroleague-la-passe-de-deux-pour-monaco-et-lasvel","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/euroleague-la-passe-de-deux-pour-monaco-et-lasvel\/","title":{"rendered":"Euroleague\u00a0: La passe de deux pour Monaco et l\u2019ASVEL\u00a0?"},"content":{"rendered":"<p align=\"justify\"><em><b>EUROLEAGUE 2021-2022 &#8211; Une semaine apr\u00e8s avoir tous deux effectu\u00e9 une rentr\u00e9e r\u00e9ussie en Euroleague, respectivement face au <strong><a href=\"https:\/\/dicodusport.fr\/blog\/euroleague-as-monaco-fait-exploser-le-panathinaikos-pour-sa-premiere\/\">Panathina\u00efkos<\/a> et au <a href=\"https:\/\/dicodusport.fr\/blog\/euroleague-lasvel-maitrise-le-zalgiris-kaunas-pour-son-entree-en-lice\/\">Zalgiris Kaunas<\/a><\/strong>, l\u2019AS Monaco et l\u2019ASVEL sont de nouveau sur le pont pour disputer la deuxi\u00e8me journ\u00e9e ce vendredi. Si l\u2019ASVEL aborde sa rencontre \u00e0 Berlin avec confiance suite \u00e0 ses deux succ\u00e8s acquis en Betclic \u00c9lite, Monaco doit de son c\u00f4t\u00e9 se remobiliser sur le parquet de Kazan suite \u00e0 la claque re\u00e7ue face aux Metropolitans mercredi.<\/b><\/em><\/p>\n<p align=\"justify\">Pour d\u00e9buter la saison d\u2019<b>Euroleague<\/b>, le basket fran\u00e7ais n\u2019aurait pu r\u00eaver meilleur sc\u00e9nario. En fin de semaine derni\u00e8re, l\u2019<b>AS Monaco <\/b>a litt\u00e9ralement \u00e9cras\u00e9 le Panathina\u00efkos avant que l\u2019<b>ASVEL<\/b> n\u2019encha\u00eene le lendemain en se d\u00e9barrassant du Zalgiris Kaunas. Ambitieuses, les deux \u00e9quipes esp\u00e8rent cette saison batailler pour d\u00e9crocher un spot dans le Top 8, synonyme de playoffs. Pour cela, la r\u00e9gularit\u00e9 et la concentration seront de mise. Si les Lyonnais ont su faire preuve de s\u00e9rieux durant l\u2019interm\u00e8de <b>Betclic \u00c9lie<\/b> propos\u00e9 avant de revenir sur la sc\u00e8ne continentale, ce ne fut pas vraiment le cas pour la Roca Team.<\/p>\n<h2 style=\"text-align: justify;\" align=\"justify\"><b>Le<\/b><b> premier succ\u00e8s clinquant obscurci par <\/b><b>le<\/b><b> manque d\u2019implication en Betclic \u00c9lite<\/b><\/h2>\n<p align=\"justify\">En effet, l\u2019ASM n\u2019a absolument pas convaincu. Une situation inattendue tant le club princier s\u2019\u00e9tait montr\u00e9 s\u00e9duisant pour sa premi\u00e8re. Devant leur public de <b>Gaston-M\u00e9decin<\/b>, les hommes de <b>Zvezdan Mitrovic <\/b>ont montr\u00e9 un aper\u00e7u du potentiel exceptionnel qu\u2019ils rec\u00e8lent. De bout en bout, ils avaient alors fait preuve d\u2019une domination totale. Les duos <b>Mike James <\/b>&#8211; <b>L\u00e9o Westermann <\/b>et surtout <b>Paris Lee<\/b> &#8211; <b>Danilo Andjusic<\/b> s\u2019\u00e9taient balad\u00e9s sur le backcourt tandis que sur le frontcourt, <b>Donatas Motiejunas<\/b>, <b>Donta Hall <\/b>ou <b>Will Thomas<\/b> avaient propos\u00e9 des minutes solides.<\/p>\n<p align=\"justify\">Cependant, toute cette positivit\u00e9 a \u00e9t\u00e9 de courte dur\u00e9e, puisque les Mon\u00e9gasques n\u2019ont absolument pas assur\u00e9 la continuit\u00e9 de cette performance en championnat. Ce week-end, ils ont r\u00e9ussi \u00e0 gagner \u00e0 <b>Roanne<\/b>, mais sans montrer un visage rassurant. S\u2019ils ont men\u00e9 de 18 points en premi\u00e8re mi-temps, ils n\u2019ont pas su conserver cet avantage en raison d\u2019un jeu collectif d\u00e9li\u00e9, et d\u2019une intensit\u00e9 parfois reprochable. Certes, Mike James et Donatas Motiejunas \u00e9taient laiss\u00e9s de c\u00f4t\u00e9, mais \u00e0 l\u2019exception d\u2019un <b>Rob Gray<\/b> d\u00e9cisif, peu de choses sont \u00e0 retenir.<\/p>\n<p><span class=\"lqloRdD9MvnWXNPKpiQZS9BhA4JUAPMbcV2RC3SuYsjzmH0weKy11Jd8BZYyQGhD8OT5xc3ULu4Lgk7ojIOataiVxECb\"><iframe loading=\"lazy\" title=\"Roanne vs. Monaco (75-80) - R\u00e9sum\u00e9 - 2021\/22\" width=\"740\" height=\"416\" src=\"https:\/\/www.youtube.com\/embed\/PeY7cWqfcrI?start=1&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/span><\/p>\n<h2 style=\"text-align: justify;\" align=\"justify\"><b>Une r\u00e9action attendue pour Monaco face au Kazan de Mario Hezonja<\/b><\/h2>\n<p align=\"justify\">Sur le parquet des <b>Metropolitans<\/b> en revanche, les errements mon\u00e9gasques se sont pay\u00e9s cash. Avec leurs meilleurs joueurs, ils se sont fait corriger de A \u00e0 Z par l\u2019\u00e9quipe de Vincent Collet. Totalement battues dans l\u2019envie, dans l\u2019intensit\u00e9 et collectivement, les troupes d\u2019un <b>Zvezdan Mitrovic<\/b> expuls\u00e9 d\u00e8s le deuxi\u00e8me quart se sont effondr\u00e9es. Une prestation r\u00e9ellement inqui\u00e9tante face \u00e0 un outsider du championnat. Il faut donc esp\u00e9rer que cette gifle sera un \u00e9l\u00e9ment d\u00e9clencheur pour se remobiliser d\u00e8s ce vendredi.<\/p>\n<p align=\"justify\">En d\u00e9placement en Russie, l\u2019ASM va retrouver la salle dans laquelle elle a remport\u00e9 l\u2019Eurocup il y a moins de six mois. D\u00e9fait lors de son premier match par Saint-P\u00e9tersbourg, l\u2019<b>Unics Kazan<\/b> est une \u00e9quipe dangereuse pouvant s\u2019appuyer sur des individualit\u00e9s fortes capables de prendre feu \u00e0 tout moment. C\u2019est le cas d\u2019<b>Isaiah Canaan<\/b>, de <b>John Brown<\/b>, mais surtout de l\u2019ancien Magic, <b>Mario Hezonja<\/b>. Les Mon\u00e9gasques devront donc se montrer vigilants, et reproduire ce qui a \u00e9t\u00e9 effectu\u00e9 face au Panathina\u00efkos pour oublier la bouillie produite en <b>Betclic \u00c9lite<\/b> dans la semaine.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">161 jours plus tard, la Roca Team retrouve Kazan et la &#8211; Apr\u00e8s avoir \u00e9crit sa plus belle histoire dans cette salle, l\u2019ASM Basket veut la poursuivre en <a href=\"https:\/\/twitter.com\/EuroLeague?ref_src=twsrc%5Etfw\">@EuroLeague<\/a> &#x270a; <a href=\"https:\/\/t.co\/leqkWjeGzQ\">pic.twitter.com\/leqkWjeGzQ<\/a><\/p>\n<p>\u2014 AS Monaco Basket (@ASMonaco_Basket) <a href=\"https:\/\/twitter.com\/ASMonaco_Basket\/status\/1446399264721100846?ref_src=twsrc%5Etfw\">October 8, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\" align=\"justify\"><b>Une victoire importante \u00e0 aller chercher en Allemagne pour l\u2019ASVEL<\/b><\/h2>\n<p align=\"justify\">De son c\u00f4t\u00e9, l\u2019<b>ASVEL <\/b>aborde sa rencontre face \u00e0 l\u2019<b>Alba Berlin<\/b> avec les certitudes d\u2019une \u00e9quipe encore invaincue. L\u2019obstacle Kaunas ayant \u00e9t\u00e9 pass\u00e9 sans encombre derri\u00e8re un duo <b>Chris Jones<\/b> \u2013 <b>\u00c9lie Okobo <\/b>en jambes, le club lyonnais a encha\u00een\u00e9 en Betclic \u00c9lite. S\u2019ils s\u2019en SONT sortis gr\u00e2ce \u00e0 un buzzer beater de Chris Jones face \u00e0 un Gravelines-Dunkerque s\u00e9duisant, ils ont ensuite enclench\u00e9 le rouleau compresseur pour passer Le Portel \u00e0 la moulinette. Comme la saison derni\u00e8re, <b>TJ Parker<\/b> a beaucoup jou\u00e9 sur son large roster pour contr\u00f4ler les temps de jeu de ses joueurs. La profondeur de cet effectif en quantit\u00e9 et en qualit\u00e9 a permis aux Lyonnais d\u2019assurer l\u2019essentiel en d\u00e9veloppant par s\u00e9quence le jeu l\u00e9ch\u00e9 qu\u2019on lui connaissait la saison derni\u00e8re.<\/p>\n<p align=\"justify\">A <b>Berlin<\/b>, l\u2019<b>ASVEL<\/b> va avoir un v\u00e9ritable coup \u00e0 jouer face \u00e0 une \u00e9quipe qui reste sur une terrible claque re\u00e7ue \u00e0 Barcelone (96-64). S\u2019ils se sont l\u00e9g\u00e8rement rassur\u00e9s en surclassant Francfort en championnat, ils devront malgr\u00e9 tout composer sans leur principale arme offensive que repr\u00e9sente <b>Marcus Eriksson<\/b>. Avec <b>Luke Sikma<\/b> ou <b>Maodo Lo<\/b>, l\u2019<b>Alba<\/b> dispose malgr\u00e9 tout d\u2019autres joueurs capables d\u2019allumer l\u2019\u00e9tincelle. Durant la pr\u00e9paration, ils ont m\u00eame battu les Lyonnais \u00e0 l\u2019occasion des <b>Paris European Games<\/b>.<\/p>\n<p align=\"justify\">Toutefois, le dernier 15<sup>e<\/sup> de l\u2019<b>Euroleague <\/b>est une \u00e9quipe \u00e0 battre dans la qu\u00eate des playoffs, m\u00eame si TJ Parker devra faire sans <strong>Raymar Morgan<\/strong> (dos), <strong>David Lighty<\/strong> (raisons personnelles), <strong>Victor Wembanyama<\/strong> (maladie) et <strong>Antoine Diot<\/strong> (mollet). Les Lyonnais doivent donc \u00e0 tout prix aller chercher cette victoire qui permettrait d\u2019entamer id\u00e9alement la saison r\u00e9guli\u00e8re avec deux victoires en autant de rencontres.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"in\">GAME DAY<\/p>\n<p><a href=\"https:\/\/twitter.com\/albaberlin?ref_src=twsrc%5Etfw\">@albaberlin<\/a><br \/>\nMercedes-Benz Arena &#8211; Berlin<br \/>\n&#x23f0; 20h00<br \/>\nEuroLeague TV<a href=\"https:\/\/twitter.com\/hashtag\/LDLCASVEL?src=hash&amp;ref_src=twsrc%5Etfw\">#LDLCASVEL<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/EuroLeague?src=hash&amp;ref_src=twsrc%5Etfw\">#EuroLeague<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/EveryGameMatters?src=hash&amp;ref_src=twsrc%5Etfw\">#EveryGameMatters<\/a> <a href=\"https:\/\/t.co\/N5Yfi6XcRJ\">pic.twitter.com\/N5Yfi6XcRJ<\/a><\/p>\n<p>\u2014 LDLC ASVEL (@LDLCASVEL) <a href=\"https:\/\/twitter.com\/LDLCASVEL\/status\/1446352154416066563?ref_src=twsrc%5Etfw\">October 8, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>EUROLEAGUE 2021-2022 &#8211; Une semaine apr\u00e8s avoir tous deux effectu\u00e9 une rentr\u00e9e r\u00e9ussie en Euroleague, respectivement face au Panathina\u00efkos et au Zalgiris Kaunas, l\u2019AS Monaco et l\u2019ASVEL sont de nouveau sur le pont pour disputer la deuxi\u00e8me journ\u00e9e ce vendredi. Si l\u2019ASVEL aborde sa rencontre \u00e0 Berlin avec confiance suite \u00e0 ses deux succ\u00e8s acquis en Betclic \u00c9lite, Monaco doit de son c\u00f4t\u00e9 se remobiliser sur le parquet de Kazan suite \u00e0 la claque re\u00e7ue face aux Metropolitans mercredi.<\/p>\n","protected":false},"author":55,"featured_media":171967,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2305,47001],"tags":[1691,7864,4475],"class_list":["post-171960","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basket-ball","category-euroligue","tag-as-monaco","tag-asvel","tag-euroleague"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Euroleague\u00a0: La passe de deux pour Monaco et l\u2019ASVEL\u00a0?<\/title>\n<meta name=\"description\" content=\"\u00c0 Kazan pour Monaco et \u00e0 Berlin pour l&#039;ASVEL, les deux \u00e9quipes fran\u00e7aises visent la passe de deux victoires en Euroleague ce vendredi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/euroleague-la-passe-de-deux-pour-monaco-et-lasvel\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Euroleague\u00a0: La passe de deux pour Monaco et l\u2019ASVEL\u00a0?\" \/>\n<meta property=\"og:description\" content=\"\u00c0 Kazan pour Monaco et \u00e0 Berlin pour l&#039;ASVEL, les deux \u00e9quipes fran\u00e7aises visent la passe de deux victoires en Euroleague ce vendredi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/euroleague-la-passe-de-deux-pour-monaco-et-lasvel\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-08T09:54:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-02T10:41:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Euroleague-La-passe-de-deux-pour-Monaco-et-lASVEL-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Euroleague\u00a0: La passe de deux pour Monaco et l\u2019ASVEL\u00a0?\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroleague-la-passe-de-deux-pour-monaco-et-lasvel\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroleague-la-passe-de-deux-pour-monaco-et-lasvel\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"Euroleague\u00a0: La passe de deux pour Monaco et l\u2019ASVEL\u00a0?\",\"datePublished\":\"2021-10-08T09:54:10+00:00\",\"dateModified\":\"2021-12-02T10:41:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroleague-la-passe-de-deux-pour-monaco-et-lasvel\/\"},\"wordCount\":1025,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroleague-la-passe-de-deux-pour-monaco-et-lasvel\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Euroleague-La-passe-de-deux-pour-Monaco-et-lASVEL-.png\",\"keywords\":[\"AS Monaco\",\"ASVEL\",\"Euroleague\"],\"articleSection\":[\"Basket-ball\",\"EuroLigue\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/euroleague-la-passe-de-deux-pour-monaco-et-lasvel\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroleague-la-passe-de-deux-pour-monaco-et-lasvel\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/euroleague-la-passe-de-deux-pour-monaco-et-lasvel\/\",\"name\":\"Euroleague\u00a0: La passe de deux pour Monaco et l\u2019ASVEL\u00a0?\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroleague-la-passe-de-deux-pour-monaco-et-lasvel\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroleague-la-passe-de-deux-pour-monaco-et-lasvel\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Euroleague-La-passe-de-deux-pour-Monaco-et-lASVEL-.png\",\"datePublished\":\"2021-10-08T09:54:10+00:00\",\"dateModified\":\"2021-12-02T10:41:32+00:00\",\"description\":\"\u00c0 Kazan pour Monaco et \u00e0 Berlin pour l'ASVEL, les deux \u00e9quipes fran\u00e7aises visent la passe de deux victoires en Euroleague ce vendredi.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroleague-la-passe-de-deux-pour-monaco-et-lasvel\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/euroleague-la-passe-de-deux-pour-monaco-et-lasvel\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroleague-la-passe-de-deux-pour-monaco-et-lasvel\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Euroleague-La-passe-de-deux-pour-Monaco-et-lASVEL-.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Euroleague-La-passe-de-deux-pour-Monaco-et-lASVEL-.png\",\"width\":800,\"height\":445,\"caption\":\"Euroleague\u00a0: La passe de deux pour Monaco et l\u2019ASVEL\u00a0?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroleague-la-passe-de-deux-pour-monaco-et-lasvel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Euroleague\u00a0: La passe de deux pour Monaco et l\u2019ASVEL\u00a0?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/maximec\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Euroleague\u00a0: La passe de deux pour Monaco et l\u2019ASVEL\u00a0?","description":"\u00c0 Kazan pour Monaco et \u00e0 Berlin pour l'ASVEL, les deux \u00e9quipes fran\u00e7aises visent la passe de deux victoires en Euroleague ce vendredi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/euroleague-la-passe-de-deux-pour-monaco-et-lasvel\/","og_locale":"fr_FR","og_type":"article","og_title":"Euroleague\u00a0: La passe de deux pour Monaco et l\u2019ASVEL\u00a0?","og_description":"\u00c0 Kazan pour Monaco et \u00e0 Berlin pour l'ASVEL, les deux \u00e9quipes fran\u00e7aises visent la passe de deux victoires en Euroleague ce vendredi.","og_url":"https:\/\/dicodusport.fr\/blog\/euroleague-la-passe-de-deux-pour-monaco-et-lasvel\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2021-10-08T09:54:10+00:00","article_modified_time":"2021-12-02T10:41:32+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Euroleague-La-passe-de-deux-pour-Monaco-et-lASVEL-.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"Euroleague\u00a0: La passe de deux pour Monaco et l\u2019ASVEL\u00a0?","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/euroleague-la-passe-de-deux-pour-monaco-et-lasvel\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/euroleague-la-passe-de-deux-pour-monaco-et-lasvel\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"Euroleague\u00a0: La passe de deux pour Monaco et l\u2019ASVEL\u00a0?","datePublished":"2021-10-08T09:54:10+00:00","dateModified":"2021-12-02T10:41:32+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/euroleague-la-passe-de-deux-pour-monaco-et-lasvel\/"},"wordCount":1025,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/euroleague-la-passe-de-deux-pour-monaco-et-lasvel\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Euroleague-La-passe-de-deux-pour-Monaco-et-lASVEL-.png","keywords":["AS Monaco","ASVEL","Euroleague"],"articleSection":["Basket-ball","EuroLigue"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/euroleague-la-passe-de-deux-pour-monaco-et-lasvel\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/euroleague-la-passe-de-deux-pour-monaco-et-lasvel\/","url":"https:\/\/dicodusport.fr\/blog\/euroleague-la-passe-de-deux-pour-monaco-et-lasvel\/","name":"Euroleague\u00a0: La passe de deux pour Monaco et l\u2019ASVEL\u00a0?","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/euroleague-la-passe-de-deux-pour-monaco-et-lasvel\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/euroleague-la-passe-de-deux-pour-monaco-et-lasvel\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Euroleague-La-passe-de-deux-pour-Monaco-et-lASVEL-.png","datePublished":"2021-10-08T09:54:10+00:00","dateModified":"2021-12-02T10:41:32+00:00","description":"\u00c0 Kazan pour Monaco et \u00e0 Berlin pour l'ASVEL, les deux \u00e9quipes fran\u00e7aises visent la passe de deux victoires en Euroleague ce vendredi.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/euroleague-la-passe-de-deux-pour-monaco-et-lasvel\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/euroleague-la-passe-de-deux-pour-monaco-et-lasvel\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/euroleague-la-passe-de-deux-pour-monaco-et-lasvel\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Euroleague-La-passe-de-deux-pour-Monaco-et-lASVEL-.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Euroleague-La-passe-de-deux-pour-Monaco-et-lASVEL-.png","width":800,"height":445,"caption":"Euroleague\u00a0: La passe de deux pour Monaco et l\u2019ASVEL\u00a0?"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/euroleague-la-passe-de-deux-pour-monaco-et-lasvel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Euroleague\u00a0: La passe de deux pour Monaco et l\u2019ASVEL\u00a0?"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/171960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=171960"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/171960\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/171967"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=171960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=171960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=171960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}