{"id":174465,"date":"2021-10-18T18:34:08","date_gmt":"2021-10-18T16:34:08","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=174465&#038;preview=true&#038;preview_id=174465"},"modified":"2021-10-25T15:16:32","modified_gmt":"2021-10-25T13:16:32","slug":"xv-de-france-11-toulousains-6-bordelais-les-clubs-les-plus-impactes-apres-la-liste-de-galthie","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/xv-de-france-11-toulousains-6-bordelais-les-clubs-les-plus-impactes-apres-la-liste-de-galthie\/","title":{"rendered":"XV de France : 11 Toulousains, 6 Bordelais&#8230; les clubs les plus impact\u00e9s apr\u00e8s la liste de Galthi\u00e9"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>XV DE FRANCE &#8211; Ce lundi, Fabien Galthi\u00e9 a d\u00e9voil\u00e9 <a href=\"https:\/\/dicodusport.fr\/blog\/xv-de-france-la-liste-des-42-bleus-pour-la-tournee-dautomne\/\">la liste des 42 Bleus pour disputer la tourn\u00e9e d&rsquo;automne 2021<\/a>. Au sein de ce groupe, comme pr\u00e9vu, les Toulousains sont en force, tout comme les Bordelo-B\u00e9glais.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>10. C&rsquo;est le nombre de joueurs toulousains qui sont pr\u00e9sents dans la liste des 42 Bleus<\/strong> d\u00e9livr\u00e9e par <strong>Fabien Galthi\u00e9<\/strong> ce lundi. Si les derni\u00e8res rumeurs indiquaient que 11 ou 12 Stadistes pouvaient \u00eatre appel\u00e9s, le staff de <strong>XV de France<\/strong> a finalement d\u00e9cid\u00e9 de laisser <strong>Selevasio Tolofua<\/strong> en club. Derri\u00e8re le contingent haut-garonnais, celui girondin reste en ad\u00e9quation avec le niveau affich\u00e9 pour l&rsquo;UBB en ce d\u00e9but de saison, avec <strong>6<\/strong> <strong>joueurs appel\u00e9s<\/strong>. \u00c0 noter que <strong>5 Lyonnais<\/strong> seront \u00e9galement dans le groupe France.<\/p>\n<h2 style=\"text-align: justify;\"><strong>La r\u00e9partition des joueurs par club<\/strong><\/h2>\n<p style=\"text-align: justify;\">Toulouse &#8211; 11 joueurs<br \/>\nUBB &#8211; 6 joueurs<br \/>\nLOU &#8211; 5 joueurs<br \/>\nRacing 92 &#8211; 5 joueurs<br \/>\nStade Rochelais &#8211; 3 joueurs<br \/>\nCastres &#8211; 3 joueurs<br \/>\nMontpellier &#8211; 3 joueurs<br \/>\nASM Clermont &#8211; 2 joueurs<br \/>\nPau &#8211; 1 joueur<br \/>\nRC Toulon &#8211; 1 joueur<br \/>\nStade Fran\u00e7ais &#8211; 1 joueur<br \/>\nUSAP &#8211; 1 joueur<\/p>\n<h2 style=\"text-align: justify;\"><strong>La liste des 42 Bleus pour la tourn\u00e9e d&rsquo;automne<\/strong><\/h2>\n<p><span class=\"KzLOR3HxIBhDuWto2b6rFpPwkEdYsT\"><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"M8vHgCTNGM\"><p><a href=\"https:\/\/dicodusport.fr\/blog\/xv-de-france-la-liste-des-42-bleus-pour-la-tournee-dautomne\/\">XV de France : La liste des 42 Bleus pour la tourn\u00e9e d&rsquo;automne<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00ab\u00a0XV de France : La liste des 42 Bleus pour la tourn\u00e9e d&rsquo;automne\u00a0\u00bb &#8212; Dicodusport\" src=\"https:\/\/dicodusport.fr\/blog\/xv-de-france-la-liste-des-42-bleus-pour-la-tournee-dautomne\/embed\/#?secret=M8vHgCTNGM\" data-secret=\"M8vHgCTNGM\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>XV DE FRANCE &#8211; Ce lundi, Fabien Galthi\u00e9 a d\u00e9voil\u00e9 la liste des 42 Bleus pour disputer la tourn\u00e9e d&rsquo;automne 2021. Au sein de ce groupe, comme pr\u00e9vu, les Toulousains sont en force, tout comme les Bordelo-B\u00e9glais.<\/p>\n","protected":false},"author":4,"featured_media":174470,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[19951],"tags":[6016,1638],"class_list":["post-174465","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-xv-de-france","tag-tournee-dautomne","tag-xv-de-france"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>XV de France : 11 Toulousains, 6 Bordelais... les clubs les plus impact\u00e9s apr\u00e8s la liste de Galthi\u00e9<\/title>\n<meta name=\"description\" content=\"XV DE FRANCE - Ce lundi, Fabien Galthi\u00e9 a d\u00e9voil\u00e9 la liste des 42 Bleus pour disputer la tourn\u00e9e d&#039;automne 2021.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/xv-de-france-11-toulousains-6-bordelais-les-clubs-les-plus-impactes-apres-la-liste-de-galthie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"XV de France : 11 Toulousains, 6 Bordelais... les clubs les plus impact\u00e9s apr\u00e8s la liste de Galthi\u00e9\" \/>\n<meta property=\"og:description\" content=\"XV DE FRANCE - Ce lundi, Fabien Galthi\u00e9 a d\u00e9voil\u00e9 la liste des 42 Bleus pour disputer la tourn\u00e9e d&#039;automne 2021.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/xv-de-france-11-toulousains-6-bordelais-les-clubs-les-plus-impactes-apres-la-liste-de-galthie\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-18T16:34:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-25T13:16:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/XV-de-France-11-Toulousains-6-Bordelais...-les-clubs-les-plus-impactes-apres-la-liste-de-Galthie.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"XV de France : 11 Toulousains, 6 Bordelais... les clubs les plus impact\u00e9s apr\u00e8s la liste de Galthi\u00e9\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-11-toulousains-6-bordelais-les-clubs-les-plus-impactes-apres-la-liste-de-galthie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-11-toulousains-6-bordelais-les-clubs-les-plus-impactes-apres-la-liste-de-galthie\\\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"XV de France : 11 Toulousains, 6 Bordelais&#8230; les clubs les plus impact\u00e9s apr\u00e8s la liste de Galthi\u00e9\",\"datePublished\":\"2021-10-18T16:34:08+00:00\",\"dateModified\":\"2021-10-25T13:16:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-11-toulousains-6-bordelais-les-clubs-les-plus-impactes-apres-la-liste-de-galthie\\\/\"},\"wordCount\":213,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-11-toulousains-6-bordelais-les-clubs-les-plus-impactes-apres-la-liste-de-galthie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/XV-de-France-11-Toulousains-6-Bordelais...-les-clubs-les-plus-impactes-apres-la-liste-de-Galthie.png\",\"keywords\":[\"tourn\u00e9e d'automne\",\"XV de France\"],\"articleSection\":[\"XV de France\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-11-toulousains-6-bordelais-les-clubs-les-plus-impactes-apres-la-liste-de-galthie\\\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-11-toulousains-6-bordelais-les-clubs-les-plus-impactes-apres-la-liste-de-galthie\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-11-toulousains-6-bordelais-les-clubs-les-plus-impactes-apres-la-liste-de-galthie\\\/\",\"name\":\"XV de France : 11 Toulousains, 6 Bordelais... les clubs les plus impact\u00e9s apr\u00e8s la liste de Galthi\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-11-toulousains-6-bordelais-les-clubs-les-plus-impactes-apres-la-liste-de-galthie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-11-toulousains-6-bordelais-les-clubs-les-plus-impactes-apres-la-liste-de-galthie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/XV-de-France-11-Toulousains-6-Bordelais...-les-clubs-les-plus-impactes-apres-la-liste-de-Galthie.png\",\"datePublished\":\"2021-10-18T16:34:08+00:00\",\"dateModified\":\"2021-10-25T13:16:32+00:00\",\"description\":\"XV DE FRANCE - Ce lundi, Fabien Galthi\u00e9 a d\u00e9voil\u00e9 la liste des 42 Bleus pour disputer la tourn\u00e9e d'automne 2021.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-11-toulousains-6-bordelais-les-clubs-les-plus-impactes-apres-la-liste-de-galthie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-11-toulousains-6-bordelais-les-clubs-les-plus-impactes-apres-la-liste-de-galthie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-11-toulousains-6-bordelais-les-clubs-les-plus-impactes-apres-la-liste-de-galthie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/XV-de-France-11-Toulousains-6-Bordelais...-les-clubs-les-plus-impactes-apres-la-liste-de-Galthie.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/XV-de-France-11-Toulousains-6-Bordelais...-les-clubs-les-plus-impactes-apres-la-liste-de-Galthie.png\",\"width\":800,\"height\":445,\"caption\":\"XV de France : 11 Toulousains, 6 Bordelais... les clubs les plus impact\u00e9s apr\u00e8s la liste de Galthi\u00e9\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-11-toulousains-6-bordelais-les-clubs-les-plus-impactes-apres-la-liste-de-galthie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"XV de France : 11 Toulousains, 6 Bordelais&#8230; les clubs les plus impact\u00e9s apr\u00e8s la liste de Galthi\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Flo-Ostermann-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\\\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/florent.ostermann\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/FlOstermann\",\"admin\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/flo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"XV de France : 11 Toulousains, 6 Bordelais... les clubs les plus impact\u00e9s apr\u00e8s la liste de Galthi\u00e9","description":"XV DE FRANCE - Ce lundi, Fabien Galthi\u00e9 a d\u00e9voil\u00e9 la liste des 42 Bleus pour disputer la tourn\u00e9e d'automne 2021.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/xv-de-france-11-toulousains-6-bordelais-les-clubs-les-plus-impactes-apres-la-liste-de-galthie\/","og_locale":"fr_FR","og_type":"article","og_title":"XV de France : 11 Toulousains, 6 Bordelais... les clubs les plus impact\u00e9s apr\u00e8s la liste de Galthi\u00e9","og_description":"XV DE FRANCE - Ce lundi, Fabien Galthi\u00e9 a d\u00e9voil\u00e9 la liste des 42 Bleus pour disputer la tourn\u00e9e d'automne 2021.","og_url":"https:\/\/dicodusport.fr\/blog\/xv-de-france-11-toulousains-6-bordelais-les-clubs-les-plus-impactes-apres-la-liste-de-galthie\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2021-10-18T16:34:08+00:00","article_modified_time":"2021-10-25T13:16:32+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/XV-de-France-11-Toulousains-6-Bordelais...-les-clubs-les-plus-impactes-apres-la-liste-de-Galthie.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"XV de France : 11 Toulousains, 6 Bordelais... les clubs les plus impact\u00e9s apr\u00e8s la liste de Galthi\u00e9","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-11-toulousains-6-bordelais-les-clubs-les-plus-impactes-apres-la-liste-de-galthie\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-11-toulousains-6-bordelais-les-clubs-les-plus-impactes-apres-la-liste-de-galthie\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"XV de France : 11 Toulousains, 6 Bordelais&#8230; les clubs les plus impact\u00e9s apr\u00e8s la liste de Galthi\u00e9","datePublished":"2021-10-18T16:34:08+00:00","dateModified":"2021-10-25T13:16:32+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-11-toulousains-6-bordelais-les-clubs-les-plus-impactes-apres-la-liste-de-galthie\/"},"wordCount":213,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-11-toulousains-6-bordelais-les-clubs-les-plus-impactes-apres-la-liste-de-galthie\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/XV-de-France-11-Toulousains-6-Bordelais...-les-clubs-les-plus-impactes-apres-la-liste-de-Galthie.png","keywords":["tourn\u00e9e d'automne","XV de France"],"articleSection":["XV de France"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/xv-de-france-11-toulousains-6-bordelais-les-clubs-les-plus-impactes-apres-la-liste-de-galthie\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-11-toulousains-6-bordelais-les-clubs-les-plus-impactes-apres-la-liste-de-galthie\/","url":"https:\/\/dicodusport.fr\/blog\/xv-de-france-11-toulousains-6-bordelais-les-clubs-les-plus-impactes-apres-la-liste-de-galthie\/","name":"XV de France : 11 Toulousains, 6 Bordelais... les clubs les plus impact\u00e9s apr\u00e8s la liste de Galthi\u00e9","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-11-toulousains-6-bordelais-les-clubs-les-plus-impactes-apres-la-liste-de-galthie\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-11-toulousains-6-bordelais-les-clubs-les-plus-impactes-apres-la-liste-de-galthie\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/XV-de-France-11-Toulousains-6-Bordelais...-les-clubs-les-plus-impactes-apres-la-liste-de-Galthie.png","datePublished":"2021-10-18T16:34:08+00:00","dateModified":"2021-10-25T13:16:32+00:00","description":"XV DE FRANCE - Ce lundi, Fabien Galthi\u00e9 a d\u00e9voil\u00e9 la liste des 42 Bleus pour disputer la tourn\u00e9e d'automne 2021.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-11-toulousains-6-bordelais-les-clubs-les-plus-impactes-apres-la-liste-de-galthie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/xv-de-france-11-toulousains-6-bordelais-les-clubs-les-plus-impactes-apres-la-liste-de-galthie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-11-toulousains-6-bordelais-les-clubs-les-plus-impactes-apres-la-liste-de-galthie\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/XV-de-France-11-Toulousains-6-Bordelais...-les-clubs-les-plus-impactes-apres-la-liste-de-Galthie.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/XV-de-France-11-Toulousains-6-Bordelais...-les-clubs-les-plus-impactes-apres-la-liste-de-Galthie.png","width":800,"height":445,"caption":"XV de France : 11 Toulousains, 6 Bordelais... les clubs les plus impact\u00e9s apr\u00e8s la liste de Galthi\u00e9"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-11-toulousains-6-bordelais-les-clubs-les-plus-impactes-apres-la-liste-de-galthie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"XV de France : 11 Toulousains, 6 Bordelais&#8230; les clubs les plus impact\u00e9s apr\u00e8s la liste de Galthi\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/174465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=174465"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/174465\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/174470"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=174465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=174465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=174465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}