{"id":175901,"date":"2021-10-28T13:34:49","date_gmt":"2021-10-28T11:34:49","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=175901"},"modified":"2025-08-24T13:23:40","modified_gmt":"2025-08-24T11:23:40","slug":"nicolas-andre-ffc-la-france-a-une-capacite-dorganisation-tres-importante","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/nicolas-andre-ffc-la-france-a-une-capacite-dorganisation-tres-importante\/","title":{"rendered":"Nicolas Andr\u00e9 (FFC) : \u00ab\u00a0La France a une capacit\u00e9 d&rsquo;organisation tr\u00e8s importante\u00a0\u00bb"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/cyclisme\/cyclisme-sur-piste\/championnats-monde-cyclisme-sur-piste-2021\/\">Championnats du monde de cyclisme sur piste 2021<\/a> &#8211; Dimanche dernier s&rsquo;achevaient les championnats du monde de cyclisme sur piste 2021. Apr\u00e8s quasiment deux mois d&rsquo;intense travail pour l&rsquo;organisation de ces Mondiaux 2021 \u00e0 Roubaix, Nicolas Andr\u00e9 (Directeur des activit\u00e9s sportives de la F\u00e9d\u00e9ration Fran\u00e7aise de Cyclisme) a accept\u00e9 de r\u00e9pondre \u00e0 nos questions, ce dimanche, dans les trav\u00e9es du Stab V\u00e9lodrome de Roubaix.\u00a0<\/strong><\/em><\/p>\n<h3 style=\"text-align: justify;\">Bonjour Nicolas Andr\u00e9. Pouvez-vous nous raconter comment se sont d\u00e9roul\u00e9es ces derni\u00e8res semaines pour vous et la F\u00e9d\u00e9ration Fran\u00e7aise de Cyclisme (FFC) depuis la nomination de Roubaix comme ville h\u00f4te de ces championnats du monde de cyclisme sur piste 2021 ?<\/h3>\n<p style=\"text-align: justify;\">Nous avons appris cette nouvelle juste avant le 15 ao\u00fbt, une d\u00e9cision entre le pr\u00e9sident de l&rsquo;Union Cycliste Internationale (UCI), <strong>David Lappartient<\/strong>, et le pr\u00e9sident de la FFC, <strong>Michel Callot<\/strong>, suite \u00e0 la d\u00e9fection du Turkm\u00e9nistan. Nous allions donc devoir organiser les championnats du monde en France sur le Stab V\u00e9lodrome de Roubaix en un temps record. C&rsquo;est \u00e0 partir de ce moment-l\u00e0 que la course contre-la-montre s&rsquo;est lanc\u00e9e.<\/p>\n<p style=\"text-align: justify;\">En premier lieu, il a fallu apprendre la nouvelle aux institutions, aux Ministres, pour qu&rsquo;ils ne l&rsquo;apprennent pas par voie de presse et qu&rsquo;ils ne se retrouvent pas devant le fait accompli. Il a donc fallu coordonner tout cela avant l&rsquo;annonce m\u00e9diatique puisque nous avions besoin outre un soutien financier &#8211; sans lequel nous n&rsquo;aurions pu organiser cet \u00e9v\u00e9nement &#8211; d&rsquo;un soutien appuy\u00e9 sur le plan sanitaire, pour que la comp\u00e9tition soit d\u00e9clar\u00e9e sous le motif imp\u00e9rieux pour ainsi \u00e9viter aux nations de subir des quarantaines \u00e0 leur arriv\u00e9e sur le sol fran\u00e7ais.<\/p>\n<p style=\"text-align: justify;\">Les fondements de l&rsquo;organisation de ces championnats \u00e9taient de trouver un accord avec l&rsquo;UCI sur la r\u00e9partition des risques financiers, trouver des accords de subventionnement aupr\u00e8s des collectivit\u00e9s et de l&rsquo;\u00c9tat. Au regard du d\u00e9lai pour livrer cette comp\u00e9tition, la FFC a fait appel, de mani\u00e8re in\u00e9dite, \u00e0 un sous-traitant attitr\u00e9 que l&rsquo;on avait d\u00e9fini et rencontr\u00e9 \u00e0 l&rsquo;avance pour tous les \u00e9v\u00e9nements qui arrivent sur l&rsquo;Olympiade.<\/p>\n<h3 style=\"text-align: justify;\">Quel a \u00e9t\u00e9 le budget global attitr\u00e9 pour l&rsquo;organisation de ces championnats du monde ?<\/h3>\n<p style=\"text-align: justify;\">Pour cet \u00e9v\u00e9nement, nous sommes \u00e0 un million d&rsquo;euros, soit 40% de moins que la somme qui sera allou\u00e9e pour le championnat du monde de cyclisme sur piste 2022 \u00e0 St-Quentin-en-Yvelines (78), sur le v\u00e9lodrome national. Les droits UCI ont \u00e9t\u00e9 coordonn\u00e9s et r\u00e9duits suite \u00e0 ce sauvetage, entre guillemets, des championnats du monde pour qu&rsquo;ils se d\u00e9roulent dans de bonnes conditions sur le sol fran\u00e7ais.<\/p>\n<h3 style=\"text-align: justify;\">Quels moyens humains ont \u00e9t\u00e9 mobilis\u00e9s pour l&rsquo;organisation de cet \u00e9v\u00e8nement ?<\/h3>\n<p style=\"text-align: justify;\">Gr\u00e2ce au sous-traitant que j&rsquo;ai \u00e9voqu\u00e9 pr\u00e9c\u00e9demment, nous avons pu limiter le co\u00fbt humain de cette op\u00e9ration. Nous avons une coordinatrice piste en la personne d&rsquo;<strong>Aude Lefort<\/strong>, une assistante multidisciplinaire en la personne de <strong>Laetitia Monzo<\/strong>, un logisticien <strong>Lo\u00efc Pesche<\/strong> et moi-m\u00eame qui suis Directeur des \u00e9v\u00e8nements de la f\u00e9d\u00e9ration, toutes disciplines confondues. Physiquement, \u00e0 la f\u00e9d\u00e9ration, ce sont uniquement ces quatre personnes qui ont travaill\u00e9 sur le d\u00e9ploiement de ces championnats du monde. Nous avons pu g\u00e9rer le reste via la sous-traitance de l&rsquo;agence Spartner.<\/p>\n<h3 style=\"text-align: justify;\">Quels ont \u00e9t\u00e9, selon-vous, les plus grands d\u00e9fis auxquels vous avez d\u00fb faire face lors de l&rsquo;organisation de ces championnats du monde ?<\/h3>\n<p style=\"text-align: justify;\">Le plus grand d\u00e9fi et pour tous les organisateurs d\u2019\u00e9v\u00e9nements sportifs depuis 2 ans, c&rsquo;est l&rsquo;aspect sanitaire qui a pris pratiquement 50% du temps. Le protocole sanitaire impos\u00e9 par l&rsquo;Etat se substitue au protocole sanitaire de l&rsquo;UCI. Il a fallu g\u00e9rer et coordonner le bon sens sanitaire, les requis impos\u00e9s par l&rsquo;Etat et le bon sens \u00e9conomique puisque les protocoles sanitaires co\u00fbtent de l&rsquo;argent. Nous avons d\u00e9ploy\u00e9 un laboratoire de tests Covid avec lequel nous aurons effectu\u00e9 pr\u00e8s de 3000 tests de d\u00e9pistage sur le site et dans les h\u00f4tels cette semaine. \u00c0 ce jour (Dimanche ; ndlr), aucun test PCR positif signal\u00e9, ce qui est plus que remarquable. C&rsquo;est ce qui nous a pris le plus d&rsquo;\u00e9nergie au final. Il a fallu r\u00e9diger un protocole sanitaire long de 30 pages, qu&rsquo;il a fallu tenir sur place de mani\u00e8re op\u00e9rationnelle, ce qui est toujours le plus compliqu\u00e9.<\/p>\n<p style=\"text-align: justify;\">Un autre d\u00e9fi majeur qui s&rsquo;est impos\u00e9 \u00e0 nous en cours de route. Nous avons effectu\u00e9 une premi\u00e8re visite du site d\u00e9but septembre. C&rsquo;est seulement 15 jours plus tard, lors d&rsquo;une deuxi\u00e8me visite sur la piste le mercredi 21 septembre o\u00f9 l&rsquo;UCI \u00e9tait pr\u00e9sente, que cette derni\u00e8re a estim\u00e9 que la piste n&rsquo;\u00e9tait pas apte \u00e0 recevoir un championnat du monde. Cela faisait environ 9 ans (depuis la construction du STAB) que la piste n&rsquo;avait pas \u00e9t\u00e9 ponc\u00e9e. L&rsquo;hydrom\u00e9trie \u00e9tant trop faible dans le v\u00e9lodrome, le bois travaille beaucoup \u00e0 cause de cette s\u00e9cheresse. \u00c0 cause de cela, la piste \u00e9tait pleine d&rsquo;\u00e9chardes r\u00e2peuses.<\/p>\n<p style=\"text-align: justify;\">Il a donc fallu r\u00e9agir assez rapidement aupr\u00e8s de la R\u00e9gion, propri\u00e9taire de cet \u00e9quipement, mais aussi pour trouver une entreprise experte apte \u00e0 le faire dans un d\u00e9lai de 7 jours et dans un tarif acceptable. Nous avons finalis\u00e9 la r\u00e9novation de la piste seulement 10 jours avant le d\u00e9but de la comp\u00e9tition.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Un grand merci \u00e0 la <a href=\"https:\/\/twitter.com\/FFC?ref_src=twsrc%5Etfw\">@FFC<\/a> et son pr\u00e9sident Michel Callot, aux organisateurs ainsi qu\u2019\u00e0 la r\u00e9gion <a href=\"https:\/\/twitter.com\/hautsdefrance?ref_src=twsrc%5Etfw\">@hautsdefrance<\/a> pour l\u2019accueil r\u00e9serv\u00e9 aux Championnats du Monde Piste UCI Tissot 2021.<\/p>\n<p>Place au dernier jour de comp\u00e9tition ici \u00e0 <a href=\"https:\/\/twitter.com\/hashtag\/Roubaix2021?src=hash&amp;ref_src=twsrc%5Etfw\">#Roubaix2021<\/a>! <a href=\"https:\/\/t.co\/hUlkhLVClE\">pic.twitter.com\/hUlkhLVClE<\/a><\/p>\n<p>\u2014 David Lappartient (@DLappartient) <a href=\"https:\/\/twitter.com\/DLappartient\/status\/1452243451135897603?ref_src=twsrc%5Etfw\">October 24, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h3 style=\"text-align: justify;\">Nous avons pu remarquer une belle mobilisation des b\u00e9n\u00e9voles cette semaine dans l&rsquo;enceinte du V\u00e9lodrome, cela doit aussi \u00eatre une satisfaction pour vous ?<\/h3>\n<p style=\"text-align: justify;\">Oui bien s\u00fbr, c&rsquo;\u00e9tait la premi\u00e8re fois que la FFC faisait appel \u00e0 une plateforme en ligne appel\u00e9e qo.ezion qui est aussi en lien avec d&rsquo;autres plateformes. Au total, nous avons eu 249 candidatures, nous en avons retenues 170 sur les gens les plus disponibles sur la dur\u00e9e pour \u00e9viter de devoir r\u00e9attribuer des t\u00e2ches en pleine semaine. Pour cet \u00e9v\u00e9nement, je souhaitais vraiment quelque chose d&rsquo;interg\u00e9n\u00e9rationnel, ce qui est le plus dur \u00e0 faire aujourd&rsquo;hui dans le b\u00e9n\u00e9volat. G\u00e9n\u00e9ralement, ce sont surtout des tranches d&rsquo;\u00e2ges de retrait\u00e9s, qui ont du temps \u00e0 donner et ce qui est riche selon moi, ce sont les \u00e9changes interg\u00e9n\u00e9rationnels. Nous avons donc fait le choix de prendre des b\u00e9n\u00e9voles \u00e0 partir de 16 ans pour permettre aux jeunes d&rsquo;\u00e9changer avec les plus \u00e2g\u00e9s et de permettre de partager leurs exp\u00e9riences.<\/p>\n<p style=\"text-align: justify;\">D\u00e9crocher 170 b\u00e9n\u00e9voles, en si peu de temps, c&rsquo;est une tr\u00e8s grande satisfaction. Nous avons d\u00e9di\u00e9 tr\u00e8s peu de postes \u00e0 des acteurs d&rsquo;exp\u00e9rience. Seule une dizaine de postes ont \u00e9t\u00e9 fl\u00e9ch\u00e9s au centre piste, le reste \u00e9tait ouvert aux vell\u00e9it\u00e9s des b\u00e9n\u00e9voles engag\u00e9s. Je crois qu&rsquo;\u00e0 l&rsquo;avenir, nous renouvellerons ces appels sur plateforme. Nous allons essayer de noter les b\u00e9n\u00e9voles pour que ces notes entrent dans la cotation pour les volontaires <em>G\u00e9n\u00e9ration Paris 2024<\/em>. Pour moi, c&rsquo;est tr\u00e8s important que les volontaires des JO de Paris 2024 (environ 10 000 au total) ne soient pas des volontaires d&rsquo;un jour, mais de r\u00e9compenser les volontaires acteurs quotidiens des f\u00e9d\u00e9rations sportives pour les r\u00e9compenser, mais aussi les engager sur la dur\u00e9e.<\/p>\n<h3 style=\"text-align: justify;\">Quel bilan tirez-vous de cette semaine sur le plan de l&rsquo;organisation ?<\/h3>\n<p style=\"text-align: justify;\">Le bilan, c&rsquo;est que la France a une capacit\u00e9 d&rsquo;organisation tr\u00e8s importante. Un championnat du monde se programme habituellement entre 16 et 24 mois \u00e0 l&rsquo;avance pour lever des fonds et des b\u00e9n\u00e9voles, mais aussi lever des prestataires \u00e0 des co\u00fbts raisonn\u00e9s. En seulement 7 semaines, c&rsquo;est un gros d\u00e9fi que nous avons relev\u00e9. Cela montre bel et bien que la France a une puissance organisationnelle tr\u00e8s forte, m\u00eame si on le savait d\u00e9j\u00e0. Nous avons r\u00e9ussi \u00e0 le faire avec beaucoup de s\u00e9r\u00e9nit\u00e9 puisqu&rsquo;il n&rsquo;y a pas eu de grosses tensions dans l&rsquo;organisation de l&rsquo;\u00e9v\u00e8nement, c&rsquo;est une grosse satisfaction. L&rsquo;UCI nous faisait d\u00e9j\u00e0 confiance, mais je pense que cet \u00e9v\u00e8nement jouera en notre faveur \u00e0 l&rsquo;avenir pour les \u00e9v\u00e8nements mondiaux futurs.<\/p>\n<p style=\"text-align: justify;\">Le calendrier 2022 sera tr\u00e8s charg\u00e9 puisque nous accueillerons trois championnats du monde en France. Il y aura le BMX \u00e0 Nantes fin Juillet, le VTT aux Gets avec la descente et le cross-country fin ao\u00fbt, et donc du 2 au 16 octobre le retour de la piste \u00e0 St-Quentin-en-Yvelines (78) sur le site olympique. Nous avons \u00e9galement de grandes ambitions comme \u00eatre acteurs des Jeux Olympiques et Paralympiques sur les 5 disciplines olympiques du cyclisme, ce qui va \u00e9norm\u00e9ment peser sur les d\u00e9cisions aupr\u00e8s de Paris 2024, puisque l&rsquo;UCI et les autres f\u00e9d\u00e9rations parleront de cet \u00e9v\u00e8nement.<\/p>\n<p style=\"text-align: justify;\">M\u00eame apr\u00e8s les Jeux, nous aurons pour objectif de conserver cette pente ascendante derri\u00e8re pour conserver un h\u00e9ritage avec de l&#8217;empreinte humaine et mat\u00e9rielle et de l&rsquo;exp\u00e9rience. Apr\u00e8s Paris 2024, nous avons pour objectif d&rsquo;accueillir de nouveau les championnats du Monde de cyclisme sur route, d&rsquo;ici 2027-2028, ce qui n&rsquo;a plus \u00e9t\u00e9 le cas sur le sol fran\u00e7ais depuis 2000 \u00e0 Plouay.<\/p>\n<h3 style=\"text-align: justify;\">Malgr\u00e9 la taille restreinte du Stab V\u00e9lodrome de Roubaix compar\u00e9 au v\u00e9lodrome de St-Quentin-en-Yvelines, la salle s\u2019est av\u00e9r\u00e9e plut\u00f4t vide en d\u00e9but de semaine avant de se remplir petit \u00e0 petit ces derniers jours. \u00cates-vous satisfait de l\u2019ambiance pr\u00e9sente au Stab V\u00e9lodrome cette semaine ?<\/h3>\n<p style=\"text-align: justify;\">Le Stab V\u00e9lodrome poss\u00e8de environ 1200 places assises en enlevant les emplacements cam\u00e9ras et journalistes, contre 5000 au v\u00e9lodrome National de St-Quentin-en-Yvelines. Mon seul regret est que nous avons mis des tarifs<em>\u00a0<\/em>un peu trop \u00e9lev\u00e9s. Nous nous sommes dit que, avec le peu de places disponibles dans l&rsquo;enceinte, la salle allait se remplir rapidement. J&rsquo;\u00e9tais un peu contre \u00e7a au d\u00e9but, puisque le monde du cyclisme aurait pu nous le reprocher. C&rsquo;est pour cela que nous avons mis en place un tarif licenci\u00e9s largement inf\u00e9rieur pour compenser ce tarif \u00e9lev\u00e9. Mais je pense cependant que nous aurions pu descendre un petit peu et remplir un peu plus mercredi, jeudi et vendredi pour donner l&rsquo;acc\u00e8s \u00e0 ce grand \u00e9v\u00e8nement sportif \u00e0 un plus grand nombre de personnes au lieu de vouloir s\u00e9curiser les recettes, certes sur un budget global de l&rsquo;\u00e9v\u00e8nement tendu.<\/p>\n<p style=\"text-align: justify;\">Nous aurions pu \u00e9galement faire deux ann\u00e9es de suite au v\u00e9lodrome national, sauf que les collectivit\u00e9s ne nous auraient probablement pas accord\u00e9 le m\u00eame niveau de subventions pour l&rsquo;\u00e9v\u00e8nement. Par ailleurs, le v\u00e9lodrome est sous arr\u00eat\u00e9 pr\u00e9fectoral, utilis\u00e9 comme vaccinodrome en centre piste, et ce jusqu&rsquo;\u00e0 fin novembre. Nous n&rsquo;aurions pas pu d\u00e9clencher un arr\u00eat de cet arr\u00eat\u00e9 pendant 15 jours, c&rsquo;\u00e9tait impossible. Notre choix s&rsquo;est donc pos\u00e9 sur Roubaix puisque cette enceinte n&rsquo;avait pas encore re\u00e7u de grande comp\u00e9tition sportive internationale, et c&rsquo;est aussi important que la f\u00e9d\u00e9ration r\u00e9partisse g\u00e9ographiquement ses \u00e9v\u00e8nements sur le territoire pour que ce ne soit pas seulement Paris qui rayonne.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">6&#xfe0f;&#x20e3; m\u00e9dailles acquises gr\u00e2ce \u00e0 un formidable public : merci pour votre soutien ! &#x1f64f;<a href=\"https:\/\/twitter.com\/hashtag\/Roubaix2021?src=hash&amp;ref_src=twsrc%5Etfw\">#Roubaix2021<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/JeRouleAvecSKF?src=hash&amp;ref_src=twsrc%5Etfw\">#JeRouleAvecSKF<\/a> <a href=\"https:\/\/t.co\/cGFPzsTRf1\">pic.twitter.com\/cGFPzsTRf1<\/a><\/p>\n<p>\u2014 FFC (@FFCyclisme) <a href=\"https:\/\/twitter.com\/FFCyclisme\/status\/1452669750002208769?ref_src=twsrc%5Etfw\">October 25, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h3 style=\"text-align: justify;\">Sur la piste, nous avons vu de tr\u00e8s belles performances fran\u00e7aises chez les hommes comme chez les femmes. Que retenez-vous de ces Mondiaux sur le plan sportif, notamment en tant qu\u2019ancien cycliste et fan de v\u00e9lo ?<\/h3>\n<p style=\"text-align: justify;\">C\u00f4t\u00e9 Fran\u00e7ais, il faut un peu exorciser l&rsquo;\u00e9chec de Tokyo. Cette semaine, nous avons vu des m\u00e9dailles, des titres de champions du monde. On a vu notamment une belle m\u00e9daille avec Marie Le Net et Clara Copponi qui permet d&rsquo;\u00e9vacuer la d\u00e9ception des Jeux Olympiques et ainsi de repartir tout de suite sur de bonnes bases pour Paris 2024. Psychologiquement, c&rsquo;est tr\u00e8s important de se dire que l&rsquo;on est performants et pr\u00e9sents sur la sc\u00e8ne internationale. En discutant avec les staffs, c&rsquo;est le gros point positif de la semaine, d&rsquo;avoir tout de suite eu l&rsquo;opportunit\u00e9 d&rsquo;inverser la tendance et de l&rsquo;avoir saisie. Physiquement, nous savions qu&rsquo;ils allaient \u00eatre pr\u00e9sents, qu&rsquo;ils allaient \u00eatre performants, ils le sont toute l&rsquo;ann\u00e9e.<\/p>\n<h3 style=\"text-align: justify;\">Le cyclisme sur piste fran\u00e7ais voit arriver une nouvelle g\u00e9n\u00e9ration de jeunes coureurs brillants. Selon-vous, sommes-nous \u00e0 l\u2019aube d\u2019une \u00e8re prosp\u00e8re pour le cyclisme sur piste fran\u00e7ais ?<\/h3>\n<p style=\"text-align: justify;\">On se dit souvent que la transition d&rsquo;une g\u00e9n\u00e9ration \u00e0 une autre est difficile, on se dit que \u00e7a y est, on a mang\u00e9 notre pain noir. Mais je crois qu&rsquo;il faut faire confiance aux jeunes et forc\u00e9ment, lorsque l&rsquo;on a une g\u00e9n\u00e9ration en or, ils font briller les yeux des plus jeunes, ils inspirent et cr\u00e9ent des vocations, et je pense qu&rsquo;il ne faut pas \u00eatre inquiet \u00e0 partir de l\u00e0. Nous avons de tr\u00e8s bons entra\u00eeneurs qui font la transition et peuvent alors transmettre leur exp\u00e9rience aux plus jeunes qui arrivent. Je pense que le choix du pr\u00e9sident de conserver son DTN a \u00e9t\u00e9 une d\u00e9cision tr\u00e8s importante en ce sens.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Championnats du monde de cyclisme sur piste 2021 &#8211; Dimanche dernier s&rsquo;achevaient les championnats du monde de cyclisme sur piste 2021. Apr\u00e8s quasiment deux mois d&rsquo;intense travail pour l&rsquo;organisation de ces Mondiaux 2021 \u00e0 Roubaix, Nicolas Andr\u00e9 (Directeur des activit\u00e9s sportives de la f\u00e9d\u00e9ration fran\u00e7aise de cyclisme) a accept\u00e9 de r\u00e9pondre \u00e0 nos questions, ce dimanche, dans les trav\u00e9es du Stab V\u00e9lodrome de Roubaix.\u00a0<\/p>\n","protected":false},"author":46,"featured_media":176389,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[14089],"tags":[],"class_list":["post-175901","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cyclisme-sur-piste"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nicolas Andr\u00e9 (FFC) : &quot;La France a une capacit\u00e9 d&#039;organisation tr\u00e8s importante&quot;<\/title>\n<meta name=\"description\" content=\"Nicolas Andr\u00e9 (FFC) a accept\u00e9 de r\u00e9pondre \u00e0 nos questions, ce dimanche, dans les trav\u00e9es du Stab V\u00e9lodrome de Roubaix.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/nicolas-andre-ffc-la-france-a-une-capacite-dorganisation-tres-importante\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nicolas Andr\u00e9 (FFC) : &quot;La France a une capacit\u00e9 d&#039;organisation tr\u00e8s importante&quot;\" \/>\n<meta property=\"og:description\" content=\"Nicolas Andr\u00e9 (FFC) a accept\u00e9 de r\u00e9pondre \u00e0 nos questions, ce dimanche, dans les trav\u00e9es du Stab V\u00e9lodrome de Roubaix.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/nicolas-andre-ffc-la-france-a-une-capacite-dorganisation-tres-importante\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-28T11:34:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-24T11:23:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Nicolas-Andre-FFC-La-France-a-une-capacite-dorganisation-tres-importante.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Tanguy Le Jeune\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Nicolas Andr\u00e9 (FFC) : &quot;La France a une capacit\u00e9 d&#039;organisation tr\u00e8s importante&quot;\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/LeJeuneT_\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/nicolas-andre-ffc-la-france-a-une-capacite-dorganisation-tres-importante\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/nicolas-andre-ffc-la-france-a-une-capacite-dorganisation-tres-importante\/\"},\"author\":{\"name\":\"Tanguy Le Jeune\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37ea0f6075559930024fec7c0f79e8f2\"},\"headline\":\"Nicolas Andr\u00e9 (FFC) : \u00ab\u00a0La France a une capacit\u00e9 d&rsquo;organisation tr\u00e8s importante\u00a0\u00bb\",\"datePublished\":\"2021-10-28T11:34:49+00:00\",\"dateModified\":\"2025-08-24T11:23:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/nicolas-andre-ffc-la-france-a-une-capacite-dorganisation-tres-importante\/\"},\"wordCount\":2358,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/nicolas-andre-ffc-la-france-a-une-capacite-dorganisation-tres-importante\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Nicolas-Andre-FFC-La-France-a-une-capacite-dorganisation-tres-importante.png\",\"articleSection\":[\"Cyclisme sur piste\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/nicolas-andre-ffc-la-france-a-une-capacite-dorganisation-tres-importante\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/nicolas-andre-ffc-la-france-a-une-capacite-dorganisation-tres-importante\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/nicolas-andre-ffc-la-france-a-une-capacite-dorganisation-tres-importante\/\",\"name\":\"Nicolas Andr\u00e9 (FFC) : \\\"La France a une capacit\u00e9 d'organisation tr\u00e8s importante\\\"\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/nicolas-andre-ffc-la-france-a-une-capacite-dorganisation-tres-importante\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/nicolas-andre-ffc-la-france-a-une-capacite-dorganisation-tres-importante\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Nicolas-Andre-FFC-La-France-a-une-capacite-dorganisation-tres-importante.png\",\"datePublished\":\"2021-10-28T11:34:49+00:00\",\"dateModified\":\"2025-08-24T11:23:40+00:00\",\"description\":\"Nicolas Andr\u00e9 (FFC) a accept\u00e9 de r\u00e9pondre \u00e0 nos questions, ce dimanche, dans les trav\u00e9es du Stab V\u00e9lodrome de Roubaix.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/nicolas-andre-ffc-la-france-a-une-capacite-dorganisation-tres-importante\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/nicolas-andre-ffc-la-france-a-une-capacite-dorganisation-tres-importante\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/nicolas-andre-ffc-la-france-a-une-capacite-dorganisation-tres-importante\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Nicolas-Andre-FFC-La-France-a-une-capacite-dorganisation-tres-importante.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Nicolas-Andre-FFC-La-France-a-une-capacite-dorganisation-tres-importante.png\",\"width\":800,\"height\":445,\"caption\":\"Nicolas Andr\u00e9 (FFC) : \\\"La France a une capacit\u00e9 d'organisation tr\u00e8s importante\\\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/nicolas-andre-ffc-la-france-a-une-capacite-dorganisation-tres-importante\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nicolas Andr\u00e9 (FFC) : \u00ab\u00a0La France a une capacit\u00e9 d&rsquo;organisation tr\u00e8s importante\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37ea0f6075559930024fec7c0f79e8f2\",\"name\":\"Tanguy Le Jeune\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Tanguy-Le-Jeune-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Tanguy-Le-Jeune-150x150.jpg\",\"caption\":\"Tanguy Le Jeune\"},\"description\":\"Journaliste\/r\u00e9dacteur depuis novembre 2020 - Lionel Messi, Kobe Bryant, Lewis Hamilton. Quel rapport entre ces trois l\u00e9gendes ? Aucun, hormis leur statut de l\u00e9gende. Mais, pour moi, ces stars ont quelque chose en commun. Ce sont mes idoles, mes exemples et les grands cr\u00e9ateurs de ma passion pour le sport. Malgr\u00e9 mon cruel manque de talent pour pratiquer le sport au haut niveau, mon amour et ma passion me poussent, chaque jour, \u00e0 vous partager l\u2019actualit\u00e9 au travers de ce que je sais probablement faire le mieux : \u00e9crire.\",\"sameAs\":[\"https:\/\/www.instagram.com\/tanguyljn_\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/LeJeuneT_\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/tanguylj\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nicolas Andr\u00e9 (FFC) : \"La France a une capacit\u00e9 d'organisation tr\u00e8s importante\"","description":"Nicolas Andr\u00e9 (FFC) a accept\u00e9 de r\u00e9pondre \u00e0 nos questions, ce dimanche, dans les trav\u00e9es du Stab V\u00e9lodrome de Roubaix.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/nicolas-andre-ffc-la-france-a-une-capacite-dorganisation-tres-importante\/","og_locale":"fr_FR","og_type":"article","og_title":"Nicolas Andr\u00e9 (FFC) : \"La France a une capacit\u00e9 d'organisation tr\u00e8s importante\"","og_description":"Nicolas Andr\u00e9 (FFC) a accept\u00e9 de r\u00e9pondre \u00e0 nos questions, ce dimanche, dans les trav\u00e9es du Stab V\u00e9lodrome de Roubaix.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/nicolas-andre-ffc-la-france-a-une-capacite-dorganisation-tres-importante\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2021-10-28T11:34:49+00:00","article_modified_time":"2025-08-24T11:23:40+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Nicolas-Andre-FFC-La-France-a-une-capacite-dorganisation-tres-importante.png","type":"image\/png"}],"author":"Tanguy Le Jeune","twitter_card":"summary_large_image","twitter_title":"Nicolas Andr\u00e9 (FFC) : \"La France a une capacit\u00e9 d'organisation tr\u00e8s importante\"","twitter_creator":"@https:\/\/twitter.com\/LeJeuneT_","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/nicolas-andre-ffc-la-france-a-une-capacite-dorganisation-tres-importante\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/nicolas-andre-ffc-la-france-a-une-capacite-dorganisation-tres-importante\/"},"author":{"name":"Tanguy Le Jeune","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37ea0f6075559930024fec7c0f79e8f2"},"headline":"Nicolas Andr\u00e9 (FFC) : \u00ab\u00a0La France a une capacit\u00e9 d&rsquo;organisation tr\u00e8s importante\u00a0\u00bb","datePublished":"2021-10-28T11:34:49+00:00","dateModified":"2025-08-24T11:23:40+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/nicolas-andre-ffc-la-france-a-une-capacite-dorganisation-tres-importante\/"},"wordCount":2358,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/nicolas-andre-ffc-la-france-a-une-capacite-dorganisation-tres-importante\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Nicolas-Andre-FFC-La-France-a-une-capacite-dorganisation-tres-importante.png","articleSection":["Cyclisme sur piste"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/nicolas-andre-ffc-la-france-a-une-capacite-dorganisation-tres-importante\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/nicolas-andre-ffc-la-france-a-une-capacite-dorganisation-tres-importante\/","url":"https:\/\/dicodusport.fr\/blog\/nicolas-andre-ffc-la-france-a-une-capacite-dorganisation-tres-importante\/","name":"Nicolas Andr\u00e9 (FFC) : \"La France a une capacit\u00e9 d'organisation tr\u00e8s importante\"","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/nicolas-andre-ffc-la-france-a-une-capacite-dorganisation-tres-importante\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/nicolas-andre-ffc-la-france-a-une-capacite-dorganisation-tres-importante\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Nicolas-Andre-FFC-La-France-a-une-capacite-dorganisation-tres-importante.png","datePublished":"2021-10-28T11:34:49+00:00","dateModified":"2025-08-24T11:23:40+00:00","description":"Nicolas Andr\u00e9 (FFC) a accept\u00e9 de r\u00e9pondre \u00e0 nos questions, ce dimanche, dans les trav\u00e9es du Stab V\u00e9lodrome de Roubaix.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/nicolas-andre-ffc-la-france-a-une-capacite-dorganisation-tres-importante\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/nicolas-andre-ffc-la-france-a-une-capacite-dorganisation-tres-importante\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/nicolas-andre-ffc-la-france-a-une-capacite-dorganisation-tres-importante\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Nicolas-Andre-FFC-La-France-a-une-capacite-dorganisation-tres-importante.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Nicolas-Andre-FFC-La-France-a-une-capacite-dorganisation-tres-importante.png","width":800,"height":445,"caption":"Nicolas Andr\u00e9 (FFC) : \"La France a une capacit\u00e9 d'organisation tr\u00e8s importante\""},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/nicolas-andre-ffc-la-france-a-une-capacite-dorganisation-tres-importante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Nicolas Andr\u00e9 (FFC) : \u00ab\u00a0La France a une capacit\u00e9 d&rsquo;organisation tr\u00e8s importante\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37ea0f6075559930024fec7c0f79e8f2","name":"Tanguy Le Jeune","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Tanguy-Le-Jeune-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Tanguy-Le-Jeune-150x150.jpg","caption":"Tanguy Le Jeune"},"description":"Journaliste\/r\u00e9dacteur depuis novembre 2020 - Lionel Messi, Kobe Bryant, Lewis Hamilton. Quel rapport entre ces trois l\u00e9gendes ? Aucun, hormis leur statut de l\u00e9gende. Mais, pour moi, ces stars ont quelque chose en commun. Ce sont mes idoles, mes exemples et les grands cr\u00e9ateurs de ma passion pour le sport. Malgr\u00e9 mon cruel manque de talent pour pratiquer le sport au haut niveau, mon amour et ma passion me poussent, chaque jour, \u00e0 vous partager l\u2019actualit\u00e9 au travers de ce que je sais probablement faire le mieux : \u00e9crire.","sameAs":["https:\/\/www.instagram.com\/tanguyljn_\/","https:\/\/x.com\/https:\/\/twitter.com\/LeJeuneT_"],"url":"https:\/\/dicodusport.fr\/blog\/author\/tanguylj\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/175901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=175901"}],"version-history":[{"count":1,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/175901\/revisions"}],"predecessor-version":[{"id":605073,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/175901\/revisions\/605073"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/176389"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=175901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=175901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=175901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}