{"id":175925,"date":"2021-10-25T15:56:52","date_gmt":"2021-10-25T13:56:52","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=175925"},"modified":"2025-08-24T13:23:42","modified_gmt":"2025-08-24T11:23:42","slug":"championnats-du-monde-de-cyclisme-sur-piste-bilan-equipe-de-france","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-de-cyclisme-sur-piste-bilan-equipe-de-france\/","title":{"rendered":"Championnats du monde de cyclisme sur piste : Le bilan de l&rsquo;\u00e9quipe de France"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em><a href=\"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-de-cyclisme-sur-piste-2021-calendrier-et-resultats\/\">CHAMPIONNATS DU MONDE DE CYCLISME SUR PISTE 2021<\/a> &#8211; Hier se sont achev\u00e9s les 111\u00e8me championnats du monde de cyclisme sur piste \u00e0 Roubaix. Entre surprises, d\u00e9ceptions et confirmations, retour sur les performances des pistards tricolores lors de ces 5 jours de comp\u00e9tition \u00e0 domicile.<\/em><\/strong><\/p>\n<h2 style=\"text-align: justify;\">Les surprises<\/h2>\n<p style=\"text-align: justify;\">Ils n&rsquo;\u00e9taient qu&rsquo;outsiders, mais les Bleus de l&rsquo;\u00e9quipe de France masculine de poursuite ont fait bien plus que jouer les trouble-f\u00eates. Apr\u00e8s avoir sign\u00e9 le deuxi\u00e8me temps des qualifications, <strong>Thomas Boudat<\/strong>, <strong>Thomas Denis<\/strong>, <strong>Valentin Tabellion<\/strong> et <strong>Benjamin Thomas\u00a0<\/strong>ont sorti au tour suivant les champions du monde en titre danois pour s&rsquo;offrir une place en grande finale. Oppos\u00e9s aux Italiens, les Bleus auront bien r\u00e9sist\u00e9, mais ce sont bien les Transalpins qui l&#8217;emportent. C&rsquo;est la premi\u00e8re fois depuis 2003 que la France remporte une m\u00e9daille dans cette \u00e9preuve.<\/p>\n<p style=\"text-align: justify;\">M\u00e9daill\u00e9 de bronze de l&rsquo;Am\u00e9ricaine aux Jeux Olympiques de Tokyo, on connaissait le potentiel de <strong>Donavan Grondin<\/strong>. Cette fois, il a montr\u00e9 au monde entier qu&rsquo;il fallait maintenant compter sur lui pour les ann\u00e9es \u00e0 venir. Dans une \u00e9preuve du Scratch qu&rsquo;il aura parfaitement ma\u00eetris\u00e9e en menant les trois derniers tours en t\u00eate du peloton, <a href=\"https:\/\/dicodusport.fr\/blog\/mondiaux-de-cyclisme-donavan-grondin-champion-du-monde-scratch\/\">le R\u00e9unionnais s&rsquo;est offert la m\u00e9daille d&rsquo;or<\/a> en r\u00e9sistant au retour de ses concurrents. \u00c0 seulement 21 ans, il remporte son premier maillot arc-en-ciel, \u00e0 domicile, et s\u00fbrement pas le dernier.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">&#x1f1eb;&#x1f1f7; CHAMPION DU MONDE ! DONAVAN GRONDIN EN OR SUR LE SCRATCH ! &#x1f60d; <a href=\"https:\/\/twitter.com\/hashtag\/Roubaix2021?src=hash&amp;ref_src=twsrc%5Etfw\">#Roubaix2021<\/a><\/p>\n<p>Bravo champion ! &#x1f947;<a href=\"https:\/\/t.co\/dfOxwYgMyA\">https:\/\/t.co\/dfOxwYgMyA<\/a><\/p>\n<p>\u2014 Dicodusport &#x2b50;&#x2b50; (@dicodusport) <a href=\"https:\/\/twitter.com\/dicodusport\/status\/1451256006508519434?ref_src=twsrc%5Etfw\">October 21, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Les confirmations<\/h2>\n<p style=\"text-align: justify;\">Champion du monde en titre de l&rsquo;Omnium, <strong>Benjamin Thomas<\/strong> avait pour objectif de courir sur d&rsquo;autres courses. D\u00e9j\u00e0 m\u00e9daill\u00e9 d&rsquo;argent avec la poursuite par \u00e9quipes, le coureur de la Groupama-FDJ s&rsquo;alignait \u00e9galement sur la course aux points. Champion d&rsquo;Europe de l&rsquo;\u00e9preuve quelques semaines plus t\u00f4t, c&rsquo;est tout naturellement qu&rsquo;il faisait office de favori au titre mondial. Au terme des 40 km et d&rsquo;une course g\u00e9r\u00e9e d&rsquo;une main de ma\u00eetre, c&rsquo;est bien le Fran\u00e7ais qui l&#8217;emporte avec 94 points, 10 de plus que le Belge <strong>Kenny De<\/strong> <strong>Ketele<\/strong>. C&rsquo;est le 4\u00e8me titre mondial de Benjamin Thomas en \u00e9lites, dans 3 \u00e9preuves diff\u00e9rentes (Omnium (2), Am\u00e9ricaine et Course aux points), et devient le premier pistard fran\u00e7ais titr\u00e9 dans cette \u00e9preuve depuis <strong>Franck Perque<\/strong> en 2004.<\/p>\n<p style=\"text-align: justify;\">Seule nation ayant \u00e9t\u00e9 m\u00e9daill\u00e9e dans toutes les \u00e9preuves de vitesse par \u00e9quipes masculine aux Jeux Olympiques, la France n&rsquo;a pas perdu ses bonnes habitudes. M\u00e9daill\u00e9s d&rsquo;argent derri\u00e8re les N\u00e9erlandais aux championnats d&rsquo;Europe d\u00e9but octobre, ils ont remis \u00e7a aux championnats du monde cette semaine, en s&rsquo;inclinant contre les m\u00eames adversaires. C&rsquo;est le m\u00eame trio qu&rsquo;\u00e0 Tokyo, \u00e0 savoir <strong>Florian Grengbo<\/strong>, <strong>S\u00e9bastien Vigier<\/strong> et <strong>Rayan Helal<\/strong>, qui monte sur le podium.<\/p>\n<p style=\"text-align: justify;\">Lui aussi confirme qu&rsquo;il est bien parmi les meilleurs mondiaux. Vice-champion d&rsquo;Europe et du monde de vitesse par \u00e9quipes, quatri\u00e8me de la vitesse individuelle aux Europe, <strong>S\u00e9bastien Vigier<\/strong> est all\u00e9 chercher la m\u00e9daille de bronze aux Mondiaux. Deuxi\u00e8me m\u00e9daille dans ces championnats pour lui, mais aussi la 6\u00e8me aux Mondiaux, dont deux individuelles, le tout \u00e0 24 ans.<\/p>\n<p style=\"text-align: justify;\">Elles \u00e9taient vice-championnes du monde de l&rsquo;Am\u00e9ricaine en 2020, elles le sont aussi en 2021. <strong>Marie Le Net<\/strong> et <strong>Clara Copponi\u00a0<\/strong>ont une nouvelle fois remport\u00e9 la m\u00e9daille d&rsquo;argent derri\u00e8re le duo de N\u00e9erlandaises <strong>Amy Pieters<\/strong> et <strong>Kirsten Wild <\/strong>pour 5 unit\u00e9s. \u00c0 seulement 20 et 21 ans, elles apparaissent comme les futures reines de la disciplines.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"it\">&#x1f1eb;&#x1f1f7; BRAVO CLARA COPPONI ET MARIE LE NET ! &#x1f948; <a href=\"https:\/\/twitter.com\/hashtag\/Roubaix2021?src=hash&amp;ref_src=twsrc%5Etfw\">#Roubaix2021<\/a><a href=\"https:\/\/t.co\/AJMK4xDYJo\">https:\/\/t.co\/AJMK4xDYJo<\/a><\/p>\n<p>\u2014 Dicodusport &#x2b50;&#x2b50; (@dicodusport) <a href=\"https:\/\/twitter.com\/dicodusport\/status\/1451960104291557376?ref_src=twsrc%5Etfw\">October 23, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Les d\u00e9ceptions<\/h2>\n<p style=\"text-align: justify;\">En bronze en vitesse individuelle aux championnats d&rsquo;Europe, <strong>Mathilde Gros<\/strong> peine \u00e0 s&rsquo;imposer au niveau mondial. Elimin\u00e9e en quarts de finale de cette m\u00eame \u00e9preuve, elle n&rsquo;a disput\u00e9e que la petite finale du Keirin pour prendre la 3\u00e8me place, 9\u00e8me au classement final. \u00c2g\u00e9 de 22 ans, elle ne compte qu&rsquo;une m\u00e9daille mondiale en 5 participations aux Mondiaux. Si elle est encore jeune, il est frustrant, compte tenu de son talent, de ne pas la voir jouer plus souvent avec les meilleures.<\/p>\n<p style=\"text-align: justify;\">Championne d&rsquo;Europe en titre \u00e0 Granges (Suisse), on pouvait l\u00e9gitimement esp\u00e9rer mieux de la part de <strong>Valentine Fortin<\/strong> sur l&rsquo;\u00c9limination. Moins a\u00e9rienne sur la piste que lors de son titre europ\u00e9en, elle n&rsquo;a pris que la 7\u00e8me place lors des championnats du monde. Une d\u00e9ception toute relative, puisqu&rsquo;elle \u00e9tait encore espoirs il n&rsquo;y a pas si longtemps.<\/p>\n<h2 style=\"text-align: justify;\">En bref<\/h2>\n<p style=\"text-align: justify;\">L&rsquo;\u00e9quipe de France de cyclisme sur piste aura r\u00e9colt\u00e9 6 m\u00e9dailles lors de \u00ab\u00a0ses\u00a0\u00bb championnats du monde \u00e0 Roubaix. Six m\u00e9dailles dont deux en or et une 4\u00e8me place au classement des nations : c&rsquo;est le meilleur bilan fran\u00e7ais de la comp\u00e9tition depuis 2017. A noter que les Bleus n&rsquo;\u00e9taient pas loin d&rsquo;atteindre la dizaine de podiums, puisque trois 4\u00e8me places sont \u00e0 prendre en compte : <strong>Donavan Grondin<\/strong> (Elimination), <strong>Marion Borras<\/strong> (Course aux points), <strong>Clara Copponi<\/strong> (Omnium).<\/p>\n<p style=\"text-align: justify;\"><strong>Les m\u00e9daill\u00e9s<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>Donavan Grondin<\/strong> (Scratch) OR<\/li>\n<li style=\"text-align: justify;\"><strong>Benjamin Thomas<\/strong> (Course aux points) OR<\/li>\n<li style=\"text-align: justify;\"><strong>Florian Grengbo<\/strong>, <strong>S\u00e9bastien Vigier<\/strong>, <strong>Rayan Helal<\/strong> (Vitesse par \u00e9quipes) ARGENT<\/li>\n<li style=\"text-align: justify;\"><strong>Thomas Boudat<\/strong>, <strong>Thomas Denis<\/strong>, <strong>Valentin Tabellion<\/strong>, <strong>Benjamin Thomas<\/strong> (Poursuite par \u00e9quipes) ARGENT<\/li>\n<li style=\"text-align: justify;\"><strong>Clara Copponi<\/strong>, <strong>Marie Le Net<\/strong> (Am\u00e9ricaine) ARGENT<\/li>\n<li style=\"text-align: justify;\"><strong>S\u00e9bastien Vigier<\/strong> (Vitesse individuelle) BRONZE<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CHAMPIONNATS DU MONDE DE CYCLISME SUR PISTE 2021 &#8211; Hier se sont achev\u00e9s les 111\u00e8me championnats du monde de cyclisme sur piste \u00e0 Roubaix. Entre surprises, d\u00e9ceptions et confirmations, retour sur les performances des pistards tricolores lors de ces 5 jours de comp\u00e9tition \u00e0 domicile.<\/p>\n","protected":false},"author":43,"featured_media":175984,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[14089],"tags":[1664],"class_list":["post-175925","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cyclisme-sur-piste","tag-cyclisme-sur-piste"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Championnats du monde de cyclisme sur piste : Le bilan de l&#039;\u00e9quipe de France<\/title>\n<meta name=\"description\" content=\"CHAMPIONNATS DU MONDE DE CYCLISME SUR PISTE 2021 - On fait le bilan de l&#039;\u00e9quipe de France \u00e0 l&#039;issue des Mondiaux de Roubaix.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-de-cyclisme-sur-piste-bilan-equipe-de-france\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Championnats du monde de cyclisme sur piste : Le bilan de l&#039;\u00e9quipe de France\" \/>\n<meta property=\"og:description\" content=\"CHAMPIONNATS DU MONDE DE CYCLISME SUR PISTE 2021 - On fait le bilan de l&#039;\u00e9quipe de France \u00e0 l&#039;issue des Mondiaux de Roubaix.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-de-cyclisme-sur-piste-bilan-equipe-de-france\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Max.Bld2\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-25T13:56:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-24T11:23:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Championnats-du-monde-de-cyclisme-sur-piste-Le-bilan-de-lequipe-de-France.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Boulard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Championnats du monde de cyclisme sur piste : Le bilan de l&#039;\u00e9quipe de France\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/MaximeB_2\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-de-cyclisme-sur-piste-bilan-equipe-de-france\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-de-cyclisme-sur-piste-bilan-equipe-de-france\/\"},\"author\":{\"name\":\"Maxime Boulard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/5aab10ee856e86ac63e9819a9da34784\"},\"headline\":\"Championnats du monde de cyclisme sur piste : Le bilan de l&rsquo;\u00e9quipe de France\",\"datePublished\":\"2021-10-25T13:56:52+00:00\",\"dateModified\":\"2025-08-24T11:23:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-de-cyclisme-sur-piste-bilan-equipe-de-france\/\"},\"wordCount\":959,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-de-cyclisme-sur-piste-bilan-equipe-de-france\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Championnats-du-monde-de-cyclisme-sur-piste-Le-bilan-de-lequipe-de-France.png\",\"keywords\":[\"cyclisme sur piste\"],\"articleSection\":[\"Cyclisme sur piste\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-de-cyclisme-sur-piste-bilan-equipe-de-france\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-de-cyclisme-sur-piste-bilan-equipe-de-france\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-de-cyclisme-sur-piste-bilan-equipe-de-france\/\",\"name\":\"Championnats du monde de cyclisme sur piste : Le bilan de l'\u00e9quipe de France\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-de-cyclisme-sur-piste-bilan-equipe-de-france\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-de-cyclisme-sur-piste-bilan-equipe-de-france\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Championnats-du-monde-de-cyclisme-sur-piste-Le-bilan-de-lequipe-de-France.png\",\"datePublished\":\"2021-10-25T13:56:52+00:00\",\"dateModified\":\"2025-08-24T11:23:42+00:00\",\"description\":\"CHAMPIONNATS DU MONDE DE CYCLISME SUR PISTE 2021 - On fait le bilan de l'\u00e9quipe de France \u00e0 l'issue des Mondiaux de Roubaix.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-de-cyclisme-sur-piste-bilan-equipe-de-france\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-de-cyclisme-sur-piste-bilan-equipe-de-france\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-de-cyclisme-sur-piste-bilan-equipe-de-france\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Championnats-du-monde-de-cyclisme-sur-piste-Le-bilan-de-lequipe-de-France.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Championnats-du-monde-de-cyclisme-sur-piste-Le-bilan-de-lequipe-de-France.png\",\"width\":800,\"height\":445,\"caption\":\"Championnats du monde de cyclisme sur piste Le bilan de l'\u00e9quipe de France\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-de-cyclisme-sur-piste-bilan-equipe-de-france\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Championnats du monde de cyclisme sur piste : Le bilan de l&rsquo;\u00e9quipe de France\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/5aab10ee856e86ac63e9819a9da34784\",\"name\":\"Maxime Boulard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Boulard-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Boulard-150x150.jpg\",\"caption\":\"Maxime Boulard\"},\"description\":\"Journaliste\/r\u00e9dacteur depuis octobre 2020 - Si mon plus vieux souvenir de sport aurait pu m'en d\u00e9go\u00fbter, la finale de la Coupe du monde 2006 a \u00e9t\u00e9 tout le contraire. V\u00e9ritable d\u00e9clencheur d'une passion qui aujourd'hui ne fait que grandir avec le temps, mon leitmotiv est la France qui brille ! Je relate les exploits pass\u00e9s et pr\u00e9sents du sport bleu-blanc-rouge sans m\u00e9nagement depuis octobre 2020. Sport valide ou handisport, aucune diff\u00e9rence, il n'y a que du sport et plusieurs fa\u00e7ons de le pratiquer.\",\"sameAs\":[\"https:\/\/www.facebook.com\/Max.Bld2\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/MaximeB_2\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/maxime-b\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Championnats du monde de cyclisme sur piste : Le bilan de l'\u00e9quipe de France","description":"CHAMPIONNATS DU MONDE DE CYCLISME SUR PISTE 2021 - On fait le bilan de l'\u00e9quipe de France \u00e0 l'issue des Mondiaux de Roubaix.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-de-cyclisme-sur-piste-bilan-equipe-de-france\/","og_locale":"fr_FR","og_type":"article","og_title":"Championnats du monde de cyclisme sur piste : Le bilan de l'\u00e9quipe de France","og_description":"CHAMPIONNATS DU MONDE DE CYCLISME SUR PISTE 2021 - On fait le bilan de l'\u00e9quipe de France \u00e0 l'issue des Mondiaux de Roubaix.","og_url":"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-de-cyclisme-sur-piste-bilan-equipe-de-france\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/Max.Bld2\/","article_published_time":"2021-10-25T13:56:52+00:00","article_modified_time":"2025-08-24T11:23:42+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Championnats-du-monde-de-cyclisme-sur-piste-Le-bilan-de-lequipe-de-France.png","type":"image\/png"}],"author":"Maxime Boulard","twitter_card":"summary_large_image","twitter_title":"Championnats du monde de cyclisme sur piste : Le bilan de l'\u00e9quipe de France","twitter_creator":"@https:\/\/twitter.com\/MaximeB_2","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-de-cyclisme-sur-piste-bilan-equipe-de-france\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-de-cyclisme-sur-piste-bilan-equipe-de-france\/"},"author":{"name":"Maxime Boulard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/5aab10ee856e86ac63e9819a9da34784"},"headline":"Championnats du monde de cyclisme sur piste : Le bilan de l&rsquo;\u00e9quipe de France","datePublished":"2021-10-25T13:56:52+00:00","dateModified":"2025-08-24T11:23:42+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-de-cyclisme-sur-piste-bilan-equipe-de-france\/"},"wordCount":959,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-de-cyclisme-sur-piste-bilan-equipe-de-france\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Championnats-du-monde-de-cyclisme-sur-piste-Le-bilan-de-lequipe-de-France.png","keywords":["cyclisme sur piste"],"articleSection":["Cyclisme sur piste"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/championnats-du-monde-de-cyclisme-sur-piste-bilan-equipe-de-france\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-de-cyclisme-sur-piste-bilan-equipe-de-france\/","url":"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-de-cyclisme-sur-piste-bilan-equipe-de-france\/","name":"Championnats du monde de cyclisme sur piste : Le bilan de l'\u00e9quipe de France","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-de-cyclisme-sur-piste-bilan-equipe-de-france\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-de-cyclisme-sur-piste-bilan-equipe-de-france\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Championnats-du-monde-de-cyclisme-sur-piste-Le-bilan-de-lequipe-de-France.png","datePublished":"2021-10-25T13:56:52+00:00","dateModified":"2025-08-24T11:23:42+00:00","description":"CHAMPIONNATS DU MONDE DE CYCLISME SUR PISTE 2021 - On fait le bilan de l'\u00e9quipe de France \u00e0 l'issue des Mondiaux de Roubaix.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-de-cyclisme-sur-piste-bilan-equipe-de-france\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/championnats-du-monde-de-cyclisme-sur-piste-bilan-equipe-de-france\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-de-cyclisme-sur-piste-bilan-equipe-de-france\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Championnats-du-monde-de-cyclisme-sur-piste-Le-bilan-de-lequipe-de-France.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/10\/Championnats-du-monde-de-cyclisme-sur-piste-Le-bilan-de-lequipe-de-France.png","width":800,"height":445,"caption":"Championnats du monde de cyclisme sur piste Le bilan de l'\u00e9quipe de France"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/championnats-du-monde-de-cyclisme-sur-piste-bilan-equipe-de-france\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Championnats du monde de cyclisme sur piste : Le bilan de l&rsquo;\u00e9quipe de France"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/5aab10ee856e86ac63e9819a9da34784","name":"Maxime Boulard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Boulard-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Boulard-150x150.jpg","caption":"Maxime Boulard"},"description":"Journaliste\/r\u00e9dacteur depuis octobre 2020 - Si mon plus vieux souvenir de sport aurait pu m'en d\u00e9go\u00fbter, la finale de la Coupe du monde 2006 a \u00e9t\u00e9 tout le contraire. V\u00e9ritable d\u00e9clencheur d'une passion qui aujourd'hui ne fait que grandir avec le temps, mon leitmotiv est la France qui brille ! Je relate les exploits pass\u00e9s et pr\u00e9sents du sport bleu-blanc-rouge sans m\u00e9nagement depuis octobre 2020. Sport valide ou handisport, aucune diff\u00e9rence, il n'y a que du sport et plusieurs fa\u00e7ons de le pratiquer.","sameAs":["https:\/\/www.facebook.com\/Max.Bld2\/","https:\/\/x.com\/https:\/\/twitter.com\/MaximeB_2"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maxime-b\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/175925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=175925"}],"version-history":[{"count":1,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/175925\/revisions"}],"predecessor-version":[{"id":605074,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/175925\/revisions\/605074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/175984"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=175925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=175925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=175925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}