{"id":177044,"date":"2021-11-01T16:24:34","date_gmt":"2021-11-01T15:24:34","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=177044&#038;preview=true&#038;preview_id=177044"},"modified":"2021-11-01T20:32:17","modified_gmt":"2021-11-01T19:32:17","slug":"martin-bakole-devrait-etre-le-prochain-adversaire-de-tony-yoka","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/martin-bakole-devrait-etre-le-prochain-adversaire-de-tony-yoka\/","title":{"rendered":"Martin Bakole devrait \u00eatre le prochain adversaire de Tony Yoka"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><b>BOXE &#8211; Selon son entra\u00eeneur, Martin Bakole devrait \u00eatre le prochain adversaire de Tony Yoka pour un combat le 10 d\u00e9cembre prochain.\u00a0<\/b><\/em><\/p>\n<p style=\"text-align: justify;\">Pour le moment, pas de confirmation du c\u00f4t\u00e9 de <strong>Tony Yoka<\/strong>, mais <strong>Martin Bakole<\/strong>, boxeur congolais de 28 ans, pourrait en d\u00e9coudre avec le poids lourd fran\u00e7ais d&rsquo;ici un gros mois. 17 victoires dont 14 avant la limite pour Martin Bakole qui navigue autour du 15\u00e8me rang mondial et qui a combattu pour la derni\u00e8re fois en septembre \u00e0 Duba\u00ef avec une victoire face \u00e0 Haruna Osumanu. <strong>Tony Yoka<\/strong>, 11 victoires en autant de combats, reste sur <a href=\"https:\/\/dicodusport.fr\/blog\/boxe-poids-lourds-tony-yoka-simpose-par-ko-face-a-petar-milas\/\">une victoire face \u00e0 Peter Milas \u00e0 Roland-Garros<\/a>.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">On va finir l\u2019ann\u00e9e fort &#x1f440;&#x1f624; <a href=\"https:\/\/t.co\/22PGLC3cA5\">pic.twitter.com\/22PGLC3cA5<\/a><\/p>\n<p>\u2014 Tony YOKA (@TonyYoka) <a href=\"https:\/\/twitter.com\/TonyYoka\/status\/1447962267488825349?ref_src=twsrc%5Etfw\">October 12, 2021<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>BOXE &#8211; Selon son entra\u00eeneur, Martin Bakole devrait \u00eatre le prochain adversaire de Tony Yoka pour un combat le 10 d\u00e9cembre prochain.<\/p>\n","protected":false},"author":1,"featured_media":177045,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8672],"tags":[622,4268],"class_list":["post-177044","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boxe","tag-boxe","tag-tony-yoka"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Martin Bakole devrait \u00eatre le prochain adversaire de Tony Yoka<\/title>\n<meta name=\"description\" content=\"BOXE - Selon son entra\u00eeneur, Martin Bakole devrait \u00eatre le prochain adversaire de Tony Yoka pour un combat le 10 d\u00e9cembre prochain.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/martin-bakole-devrait-etre-le-prochain-adversaire-de-tony-yoka\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Martin Bakole devrait \u00eatre le prochain adversaire de Tony Yoka\" \/>\n<meta property=\"og:description\" content=\"BOXE - Selon son entra\u00eeneur, Martin Bakole devrait \u00eatre le prochain adversaire de Tony Yoka pour un combat le 10 d\u00e9cembre prochain.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/martin-bakole-devrait-etre-le-prochain-adversaire-de-tony-yoka\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-01T15:24:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-01T19:32:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/11\/Martin-Bakole-devrait-e\u0302tre-le-prochain-adversaire-de-Tony-Yoka.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Martin Bakole devrait \u00eatre le prochain adversaire de Tony Yoka\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/martin-bakole-devrait-etre-le-prochain-adversaire-de-tony-yoka\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/martin-bakole-devrait-etre-le-prochain-adversaire-de-tony-yoka\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Martin Bakole devrait \u00eatre le prochain adversaire de Tony Yoka\",\"datePublished\":\"2021-11-01T15:24:34+00:00\",\"dateModified\":\"2021-11-01T19:32:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/martin-bakole-devrait-etre-le-prochain-adversaire-de-tony-yoka\\\/\"},\"wordCount\":135,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/martin-bakole-devrait-etre-le-prochain-adversaire-de-tony-yoka\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Martin-Bakole-devrait-e\u0302tre-le-prochain-adversaire-de-Tony-Yoka.png\",\"keywords\":[\"boxe\",\"Tony Yoka\"],\"articleSection\":[\"Boxe\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/martin-bakole-devrait-etre-le-prochain-adversaire-de-tony-yoka\\\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/martin-bakole-devrait-etre-le-prochain-adversaire-de-tony-yoka\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/martin-bakole-devrait-etre-le-prochain-adversaire-de-tony-yoka\\\/\",\"name\":\"Martin Bakole devrait \u00eatre le prochain adversaire de Tony Yoka\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/martin-bakole-devrait-etre-le-prochain-adversaire-de-tony-yoka\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/martin-bakole-devrait-etre-le-prochain-adversaire-de-tony-yoka\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Martin-Bakole-devrait-e\u0302tre-le-prochain-adversaire-de-Tony-Yoka.png\",\"datePublished\":\"2021-11-01T15:24:34+00:00\",\"dateModified\":\"2021-11-01T19:32:17+00:00\",\"description\":\"BOXE - Selon son entra\u00eeneur, Martin Bakole devrait \u00eatre le prochain adversaire de Tony Yoka pour un combat le 10 d\u00e9cembre prochain.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/martin-bakole-devrait-etre-le-prochain-adversaire-de-tony-yoka\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/martin-bakole-devrait-etre-le-prochain-adversaire-de-tony-yoka\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/martin-bakole-devrait-etre-le-prochain-adversaire-de-tony-yoka\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Martin-Bakole-devrait-e\u0302tre-le-prochain-adversaire-de-Tony-Yoka.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Martin-Bakole-devrait-e\u0302tre-le-prochain-adversaire-de-Tony-Yoka.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/martin-bakole-devrait-etre-le-prochain-adversaire-de-tony-yoka\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Martin Bakole devrait \u00eatre le prochain adversaire de Tony Yoka\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Martin Bakole devrait \u00eatre le prochain adversaire de Tony Yoka","description":"BOXE - Selon son entra\u00eeneur, Martin Bakole devrait \u00eatre le prochain adversaire de Tony Yoka pour un combat le 10 d\u00e9cembre prochain.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/martin-bakole-devrait-etre-le-prochain-adversaire-de-tony-yoka\/","og_locale":"fr_FR","og_type":"article","og_title":"Martin Bakole devrait \u00eatre le prochain adversaire de Tony Yoka","og_description":"BOXE - Selon son entra\u00eeneur, Martin Bakole devrait \u00eatre le prochain adversaire de Tony Yoka pour un combat le 10 d\u00e9cembre prochain.","og_url":"https:\/\/dicodusport.fr\/blog\/martin-bakole-devrait-etre-le-prochain-adversaire-de-tony-yoka\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2021-11-01T15:24:34+00:00","article_modified_time":"2021-11-01T19:32:17+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/11\/Martin-Bakole-devrait-e\u0302tre-le-prochain-adversaire-de-Tony-Yoka.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Martin Bakole devrait \u00eatre le prochain adversaire de Tony Yoka","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/martin-bakole-devrait-etre-le-prochain-adversaire-de-tony-yoka\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/martin-bakole-devrait-etre-le-prochain-adversaire-de-tony-yoka\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Martin Bakole devrait \u00eatre le prochain adversaire de Tony Yoka","datePublished":"2021-11-01T15:24:34+00:00","dateModified":"2021-11-01T19:32:17+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/martin-bakole-devrait-etre-le-prochain-adversaire-de-tony-yoka\/"},"wordCount":135,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/martin-bakole-devrait-etre-le-prochain-adversaire-de-tony-yoka\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/11\/Martin-Bakole-devrait-e\u0302tre-le-prochain-adversaire-de-Tony-Yoka.png","keywords":["boxe","Tony Yoka"],"articleSection":["Boxe"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/martin-bakole-devrait-etre-le-prochain-adversaire-de-tony-yoka\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/martin-bakole-devrait-etre-le-prochain-adversaire-de-tony-yoka\/","url":"https:\/\/dicodusport.fr\/blog\/martin-bakole-devrait-etre-le-prochain-adversaire-de-tony-yoka\/","name":"Martin Bakole devrait \u00eatre le prochain adversaire de Tony Yoka","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/martin-bakole-devrait-etre-le-prochain-adversaire-de-tony-yoka\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/martin-bakole-devrait-etre-le-prochain-adversaire-de-tony-yoka\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/11\/Martin-Bakole-devrait-e\u0302tre-le-prochain-adversaire-de-Tony-Yoka.png","datePublished":"2021-11-01T15:24:34+00:00","dateModified":"2021-11-01T19:32:17+00:00","description":"BOXE - Selon son entra\u00eeneur, Martin Bakole devrait \u00eatre le prochain adversaire de Tony Yoka pour un combat le 10 d\u00e9cembre prochain.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/martin-bakole-devrait-etre-le-prochain-adversaire-de-tony-yoka\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/martin-bakole-devrait-etre-le-prochain-adversaire-de-tony-yoka\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/martin-bakole-devrait-etre-le-prochain-adversaire-de-tony-yoka\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/11\/Martin-Bakole-devrait-e\u0302tre-le-prochain-adversaire-de-Tony-Yoka.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/11\/Martin-Bakole-devrait-e\u0302tre-le-prochain-adversaire-de-Tony-Yoka.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/martin-bakole-devrait-etre-le-prochain-adversaire-de-tony-yoka\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Martin Bakole devrait \u00eatre le prochain adversaire de Tony Yoka"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/177044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=177044"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/177044\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/177045"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=177044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=177044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=177044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}