{"id":177784,"date":"2021-11-05T22:00:44","date_gmt":"2021-11-05T21:00:44","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=177784&#038;preview=true&#038;preview_id=177784"},"modified":"2021-11-05T22:00:35","modified_gmt":"2021-11-05T21:00:35","slug":"pronostic-rb-leipzig-dortmund-11eme-journee-de-bundesliga","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-dortmund-11eme-journee-de-bundesliga\/","title":{"rendered":"Pronostic RB Leipzig &#8211; Dortmund, 11\u00e8me journ\u00e9e de Bundesliga"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><b>BUNDESLIGA &#8211; Le RB Leipzig re\u00e7oit Dortmund dans le cadre de la 11\u00e8me journ\u00e9e du championnat allemand. Notre pronostic.<\/b><br \/>\n<\/em><\/p>\n<h2 style=\"text-align: justify;\">Pronostic RB Leipzig &#8211; Dortmund : Samedi 6 novembre, 18h30<\/h2>\n<p style=\"text-align: justify;\"><strong>Leipzig<\/strong> reste sur un nul face au PSG mais r\u00e9alise un d\u00e9but de saison d\u00e9cevant, seulement huiti\u00e8me en Bundesliga et avec un seul point en quatre rencontres en Ligue des champions. <strong>Dortmund<\/strong> est de son c\u00f4t\u00e9 dauphin du Bayern mais a eu beaucoup de mal en Ligue des champions et reste sur deux d\u00e9faites de rang face \u00e0 l&rsquo;Ajax. Leipzig a montr\u00e9 du mieux face au PSG et Haaland est toujours absent donc on \u00e9vite le r\u00e9sultat et on donne les <strong>deux \u00e9quipes qui marquent<\/strong>.<\/p>\n<table style=\"width: 100%;\">\n<tbody>\n<tr style=\"height: 16px;\">\n<td style=\"background-color: #404040; text-align: left; border-color: #ededed; width: 500px;\"><span style=\"font-size: 12px; color: #ffffff;\">Samedi 6 novembre, 18h30<\/span><\/td>\n<td style=\"background-color: #525252; border-color: #ededed; width: 300px; text-align: center;\" colspan=\"2\"><span style=\"font-size: 12px; color: #ffffff;\">Les deux \u00e9quipes vont-elles marquer ?<\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"background-color: #ffffff; text-align: justify; border-color: #ededed; vertical-align: middle; width: 500px;\"><strong>RB Leipzig &#8211; Dortmund<\/strong><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 150px;\"><span style=\"font-size: 10px;\"><strong><span style=\"font-size: 12px;\">Oui<\/span><\/strong><br \/>\n<a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/27883270?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#ffffff;background-color:#C80A00;border-color:#a00800;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#ffffff;padding:0px 16px;font-size:13px;line-height:26px;border-color:#d9544d;border-radius:5px;text-shadow:none\"> 1.44<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 150px;\"><span style=\"font-size: 10px;\"><strong><span style=\"font-size: 12px;\">Non<\/span><\/strong><br \/>\n<a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/27883270?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#ffffff;background-color:#000000;border-color:#000000;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#ffffff;padding:0px 16px;font-size:13px;line-height:26px;border-color:#4d4d4d;border-radius:5px;text-shadow:none\"> 2.20<\/span><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\">Tentez votre chance en misant jusqu\u2019\u00e0 100\u20ac gr\u00e2ce \u00e0 votre <a href=\"https:\/\/www.winamax.fr\/landing\/landing_leads.php?ldg=1er-pari-rembourse&amp;banid=33423\" target=\"_blank\" rel=\"noopener noreferrer\">premier pari rembours\u00e9<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BUNDESLIGA &#8211; Le RB Leipzig re\u00e7oit Dortmund dans le cadre de la 11\u00e8me journ\u00e9e du championnat allemand. Notre pronostic.<\/p>\n","protected":false},"author":1,"featured_media":177787,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2301],"tags":[7173,4085,75,9327,4949],"class_list":["post-177784","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","tag-bundesliga","tag-dortmund","tag-football","tag-leipzig","tag-pronostics"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pronostic RB Leipzig - Dortmund, 11\u00e8me journ\u00e9e de Bundesliga - Dicodusport<\/title>\n<meta name=\"description\" content=\"BUNDESLIGA - Le RB Leipzig re\u00e7oit Dortmund dans le cadre de la 11\u00e8me journ\u00e9e du championnat allemand. Notre pronostic.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-dortmund-11eme-journee-de-bundesliga\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pronostic RB Leipzig - Dortmund, 11\u00e8me journ\u00e9e de Bundesliga\" \/>\n<meta property=\"og:description\" content=\"BUNDESLIGA - Le RB Leipzig re\u00e7oit Dortmund dans le cadre de la 11\u00e8me journ\u00e9e du championnat allemand. Notre pronostic.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-dortmund-11eme-journee-de-bundesliga\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-05T21:00:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/11\/Pronostic-RB-Leipzig-Dortmund-11eme-journee-de-Bundesliga.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Pronostic RB Leipzig - Dortmund, 11\u00e8me journ\u00e9e de Bundesliga\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-dortmund-11eme-journee-de-bundesliga\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-dortmund-11eme-journee-de-bundesliga\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Pronostic RB Leipzig &#8211; Dortmund, 11\u00e8me journ\u00e9e de Bundesliga\",\"datePublished\":\"2021-11-05T21:00:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-dortmund-11eme-journee-de-bundesliga\/\"},\"wordCount\":203,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-dortmund-11eme-journee-de-bundesliga\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/11\/Pronostic-RB-Leipzig-Dortmund-11eme-journee-de-Bundesliga.png\",\"keywords\":[\"Bundesliga\",\"Dortmund\",\"Football\",\"Leipzig\",\"Pronostics\"],\"articleSection\":[\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-dortmund-11eme-journee-de-bundesliga\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-dortmund-11eme-journee-de-bundesliga\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-dortmund-11eme-journee-de-bundesliga\/\",\"name\":\"Pronostic RB Leipzig - Dortmund, 11\u00e8me journ\u00e9e de Bundesliga - Dicodusport\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-dortmund-11eme-journee-de-bundesliga\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-dortmund-11eme-journee-de-bundesliga\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/11\/Pronostic-RB-Leipzig-Dortmund-11eme-journee-de-Bundesliga.png\",\"datePublished\":\"2021-11-05T21:00:44+00:00\",\"description\":\"BUNDESLIGA - Le RB Leipzig re\u00e7oit Dortmund dans le cadre de la 11\u00e8me journ\u00e9e du championnat allemand. Notre pronostic.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-dortmund-11eme-journee-de-bundesliga\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-dortmund-11eme-journee-de-bundesliga\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-dortmund-11eme-journee-de-bundesliga\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/11\/Pronostic-RB-Leipzig-Dortmund-11eme-journee-de-Bundesliga.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/11\/Pronostic-RB-Leipzig-Dortmund-11eme-journee-de-Bundesliga.png\",\"width\":1200,\"height\":670,\"caption\":\"Pronostic RB Leipzig - Dortmund, 11\u00e8me journ\u00e9e de Bundesliga\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-dortmund-11eme-journee-de-bundesliga\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pronostic RB Leipzig &#8211; Dortmund, 11\u00e8me journ\u00e9e de Bundesliga\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pronostic RB Leipzig - Dortmund, 11\u00e8me journ\u00e9e de Bundesliga - Dicodusport","description":"BUNDESLIGA - Le RB Leipzig re\u00e7oit Dortmund dans le cadre de la 11\u00e8me journ\u00e9e du championnat allemand. Notre pronostic.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-dortmund-11eme-journee-de-bundesliga\/","og_locale":"fr_FR","og_type":"article","og_title":"Pronostic RB Leipzig - Dortmund, 11\u00e8me journ\u00e9e de Bundesliga","og_description":"BUNDESLIGA - Le RB Leipzig re\u00e7oit Dortmund dans le cadre de la 11\u00e8me journ\u00e9e du championnat allemand. Notre pronostic.","og_url":"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-dortmund-11eme-journee-de-bundesliga\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2021-11-05T21:00:44+00:00","og_image":[{"width":1200,"height":670,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/11\/Pronostic-RB-Leipzig-Dortmund-11eme-journee-de-Bundesliga.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Pronostic RB Leipzig - Dortmund, 11\u00e8me journ\u00e9e de Bundesliga","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-dortmund-11eme-journee-de-bundesliga\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-dortmund-11eme-journee-de-bundesliga\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Pronostic RB Leipzig &#8211; Dortmund, 11\u00e8me journ\u00e9e de Bundesliga","datePublished":"2021-11-05T21:00:44+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-dortmund-11eme-journee-de-bundesliga\/"},"wordCount":203,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-dortmund-11eme-journee-de-bundesliga\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/11\/Pronostic-RB-Leipzig-Dortmund-11eme-journee-de-Bundesliga.png","keywords":["Bundesliga","Dortmund","Football","Leipzig","Pronostics"],"articleSection":["Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-dortmund-11eme-journee-de-bundesliga\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-dortmund-11eme-journee-de-bundesliga\/","url":"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-dortmund-11eme-journee-de-bundesliga\/","name":"Pronostic RB Leipzig - Dortmund, 11\u00e8me journ\u00e9e de Bundesliga - Dicodusport","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-dortmund-11eme-journee-de-bundesliga\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-dortmund-11eme-journee-de-bundesliga\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/11\/Pronostic-RB-Leipzig-Dortmund-11eme-journee-de-Bundesliga.png","datePublished":"2021-11-05T21:00:44+00:00","description":"BUNDESLIGA - Le RB Leipzig re\u00e7oit Dortmund dans le cadre de la 11\u00e8me journ\u00e9e du championnat allemand. Notre pronostic.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-dortmund-11eme-journee-de-bundesliga\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-dortmund-11eme-journee-de-bundesliga\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-dortmund-11eme-journee-de-bundesliga\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/11\/Pronostic-RB-Leipzig-Dortmund-11eme-journee-de-Bundesliga.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/11\/Pronostic-RB-Leipzig-Dortmund-11eme-journee-de-Bundesliga.png","width":1200,"height":670,"caption":"Pronostic RB Leipzig - Dortmund, 11\u00e8me journ\u00e9e de Bundesliga"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/pronostic-rb-leipzig-dortmund-11eme-journee-de-bundesliga\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Pronostic RB Leipzig &#8211; Dortmund, 11\u00e8me journ\u00e9e de Bundesliga"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/177784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=177784"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/177784\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/177787"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=177784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=177784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=177784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}