{"id":178256,"date":"2021-11-07T23:47:14","date_gmt":"2021-11-07T22:47:14","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=178256&#038;preview=true&#038;preview_id=178256"},"modified":"2021-11-07T23:52:51","modified_gmt":"2021-11-07T22:52:51","slug":"nba-cinquieme-victoire-daffilee-pour-des-brooklyn-nets-qui-montent-en-puissance","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/nba-cinquieme-victoire-daffilee-pour-des-brooklyn-nets-qui-montent-en-puissance\/","title":{"rendered":"NBA : Cinqui\u00e8me victoire d&rsquo;affil\u00e9e pour des Brooklyn Nets qui montent en puissance"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>NBA 2021-2022 &#8211; L&rsquo;affiche de ce dimanche soir opposait les Nets, candidats au titre NBA, \u00e0 des Raptors qui cherchaient \u00e0 confirmer leur bon d\u00e9but de saison. Malheureusement pour ces derniers, ils sont tomb\u00e9s sur un Kevin Durant intenable (31 points), grand artisan du succ\u00e8s 116-103 de son \u00e9quipe, d\u00e9sormais lanc\u00e9e dans cette saison o\u00f9 ils sont attendus.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">De fa\u00e7on surprenante, les <strong>Raptors<\/strong> avan\u00e7aient vers ce match avec un bilan quasiment \u00e9quivalent \u00e0 celui de leurs adversaires (6-4 contre 6-3). L&rsquo;occasion \u00e9tait donc belle pour le club canadien de confronter son niveau avec celui d&rsquo;un poids lourd de la conf\u00e9rence Est, apr\u00e8s avoir notamment battu des outsiders tels que les Celtics ou les Knicks depuis le d\u00e9but de la saison NBA. Les <strong>Net<\/strong>s, eux, \u00e9taient \u00e0 la recherche de leur cinqui\u00e8me succ\u00e8s cons\u00e9cutif apr\u00e8s un d\u00e9but de saison h\u00e9sitant, mais ces matchs en d\u00e9but d&rsquo;apr\u00e8s-midi pour eux sont par essence pi\u00e9geux.<\/p>\n<h2 style=\"text-align: justify;\">De surprenants Raptors mettent \u00e0 mal les Nets<\/h2>\n<p style=\"text-align: justify;\">Et cet \u00e9tat de fait se confirme d&rsquo;entr\u00e9e de jeu. Boost\u00e9s par le retour de <strong>Pascal Siakam,\u00a0<\/strong>absent depuis le d\u00e9but de saison NBA, dans le cinq de d\u00e9part, les Raptors d\u00e9marrent pied au plancher, avec le rookie <strong>Scottie Barnes<\/strong> en t\u00eate de gondole. Heureusement, <strong>Kevin Durant<\/strong> (12 points dans le premier quart) est l\u00e0 pour maintenir son \u00e9quipe dans le rythme, malgr\u00e9 un d\u00e9but de match indigent de<strong> James Harden<\/strong>. Brooklyn est dans le coup malgr\u00e9 une d\u00e9fense suspecte et m\u00e8ne<strong> 29-26<\/strong> \u00e0 l&rsquo;issue du premier quart.<\/p>\n<p style=\"text-align: justify;\">Brooklyn est bien d\u00e9cid\u00e9 \u00e0 se rendre le match facile et acc\u00e9l\u00e8re en d\u00e9but de deuxi\u00e8me quart, prenant six points d&rsquo;avance gr\u00e2ce \u00e0 un <strong>Joe Harris<\/strong> qui semble retrouv\u00e9. Mais comme depuis le d\u00e9but de la saison, Toronto est accrocheur et revient au score, dans la foul\u00e9e d&rsquo;un <strong>Siakam<\/strong> entreprenant, \u00e0 l&rsquo;instar de <strong>Fred VanVleet <\/strong>en r\u00e9ussite au shoot. Le jeu des Nets est unidimensionnel et repose principalement sur <strong>Kevin Durant<\/strong>, alors que Toronto varie beaucoup, et chaque joueur apporte sa pierre \u00e0 l&rsquo;\u00e9difice. Hormis <strong>Durant<\/strong> et <strong>Harris<\/strong>, les Nets sont peu en r\u00e9ussite et c\u00e8dent dans les deux derni\u00e8res minutes, ce qui permet \u00e0 Toronto de rentrer au vestiaire avec sept points d&rsquo;avance suite \u00e0 une interception de <strong>Barnes<\/strong> conclue par un dunk arri\u00e8re, puis un dernier panier de <strong>VanVleet (60-53)<\/strong>.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Jheeez&#8230; Scottie really said &lsquo;GIMMIE DAT&rsquo; <a href=\"https:\/\/t.co\/MkrnYDFYzr\">pic.twitter.com\/MkrnYDFYzr<\/a><\/p>\n<p>\u2014 Toronto Raptors (@Raptors) <a href=\"https:\/\/twitter.com\/Raptors\/status\/1457462910008143878?ref_src=twsrc%5Etfw\">November 7, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Brooklyn se met en place et \u00e9touffe Toronto<\/h2>\n<p style=\"text-align: justify;\"><strong>Steve Nash<\/strong> a d\u00fb souffler dans les bronches de ses joueurs, puisque ceux-ci entament le troisi\u00e8me quart-temps en collant en 9-0 \u00e0 leur adversaire, sous la houlette d&rsquo;un <strong>Bruce Brown<\/strong> combatif en d\u00e9fense. <strong>Joe Harris<\/strong> retrouve de l&rsquo;allant, et c&rsquo;est toute la machine Nets qui se remet en marche. Brooklyn creuse un \u00e9cart de 10 points (77-67), et semble nettement sup\u00e9rieur quand son jeu est en place. Les Raptors continuent de s&rsquo;accrocher, bien aid\u00e9s par 8 points d&rsquo;affil\u00e9e de <strong>Gary Trent Jr<\/strong>, mais <strong>Kevin Durant<\/strong> est inarr\u00eatable (13 points dans ce quart). Les Nets infligent un implacable <strong>35-17<\/strong> dans le troisi\u00e8me quart \u00e0 des Raptors d\u00e9pass\u00e9s et m\u00e8nent<strong> 88-77<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>Nick Nurse<\/strong> remet <strong>VanVleet, Siakam<\/strong> et <strong>Barnes<\/strong> sur le parquet en d\u00e9but de quatri\u00e8me quart pour tenter de boucher rapidement le trou. Mais c&rsquo;est peine perdue car les Nets g\u00e8rent bien leur affaire. Malgr\u00e9 un <strong>Precious Achiuwa<\/strong> incisif (13 points au total), Toronto ne revient pas \u00e0 moins de sept points. <strong>James Harden<\/strong> est pourtant toujours en gal\u00e8re avec son shoot (2\/9 \u00e0 trois points), mais mettra tout de m\u00eame 13 points dans le dernier quart, alors que <strong>Bruce Brown<\/strong> et <strong>Patty Mills<\/strong> font le travail pour maintenir les Raptors \u00e0 distance. Malgr\u00e9 les 21 points de <strong>Fred Vanvleet<\/strong>, et une derni\u00e8re tentative de comeback des Raptors, Brooklyn cl\u00f4t l&rsquo;affaire proprement et s&rsquo;impose <strong>116-103.<\/strong><\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Stepback three from the top of the key &#x1f44c;<\/p>\n<p>James Harden (25 PTS, 10 REB, 8 AST) extends the <a href=\"https:\/\/twitter.com\/BrooklynNets?ref_src=twsrc%5Etfw\">@BrooklynNets<\/a> lead late on NBA League Pass: <a href=\"https:\/\/t.co\/V0kkYEEIkG\">https:\/\/t.co\/V0kkYEEIkG<\/a> <a href=\"https:\/\/t.co\/9jLR7XxWCt\">pic.twitter.com\/9jLR7XxWCt<\/a><\/p>\n<p>\u2014 NBA (@NBA) <a href=\"https:\/\/twitter.com\/NBA\/status\/1457478522616827911?ref_src=twsrc%5Etfw\">November 7, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Septi\u00e8me victoire de la saison donc pour les Nets, la cinqui\u00e8me cons\u00e9cutive. Brooklyn grimpe sur le podium de la conf\u00e9rence Est, avant un d\u00e9placement int\u00e9ressant \u00e0 Chicago, le tout toujours sans <strong>Kyrie Irving<\/strong>. La machine Nets semble lanc\u00e9e, et l&rsquo;on ignore encore les limites de la bande \u00e0 <strong>Kevin Durant<\/strong>, qui ne vise rien d&rsquo;autre que le titre cette saison.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>NBA 2021-2022 &#8211; L&rsquo;affiche de ce dimanche soir opposait les Nets, candidats au titre NBA, \u00e0 des Raptors qui cherchaient \u00e0 confirmer leur bon d\u00e9but de saison. Malheureusement pour ces derniers, ils sont tomb\u00e9s sur un Kevin Durant intenable (31 points), grand artisan du succ\u00e8s 116-103 de son \u00e9quipe, d\u00e9sormais lanc\u00e9e dans cette saison o\u00f9 ils sont attendus.<\/p>\n","protected":false},"author":59,"featured_media":178307,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[10533],"tags":[1825,1822],"class_list":["post-178256","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nba","tag-brooklyn-nets","tag-toronto-raptors"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>NBA : Cinqui\u00e8me victoire d&#039;affil\u00e9e pour des Brooklyn Nets qui montent en puissance<\/title>\n<meta name=\"description\" content=\"NBA 2021-2022 - Les Brooklyn Nets encha\u00eenent avec un cinqui\u00e8me succ\u00e8s de rang en s&#039;imposant face aux Toronto Raptors (116-103).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/nba-cinquieme-victoire-daffilee-pour-des-brooklyn-nets-qui-montent-en-puissance\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NBA : Cinqui\u00e8me victoire d&#039;affil\u00e9e pour des Brooklyn Nets qui montent en puissance\" \/>\n<meta property=\"og:description\" content=\"NBA 2021-2022 - Les Brooklyn Nets encha\u00eenent avec un cinqui\u00e8me succ\u00e8s de rang en s&#039;imposant face aux Toronto Raptors (116-103).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/nba-cinquieme-victoire-daffilee-pour-des-brooklyn-nets-qui-montent-en-puissance\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-07T22:47:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-07T22:52:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/11\/NBA-Cinquieme-victoire-daffilee-pour-des-Brooklyn-Nets-qui-montent-en-puissance.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"NBA : Cinqui\u00e8me victoire d&#039;affil\u00e9e pour des Brooklyn Nets qui montent en puissance\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nba-cinquieme-victoire-daffilee-pour-des-brooklyn-nets-qui-montent-en-puissance\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nba-cinquieme-victoire-daffilee-pour-des-brooklyn-nets-qui-montent-en-puissance\\\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"NBA : Cinqui\u00e8me victoire d&rsquo;affil\u00e9e pour des Brooklyn Nets qui montent en puissance\",\"datePublished\":\"2021-11-07T22:47:14+00:00\",\"dateModified\":\"2021-11-07T22:52:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nba-cinquieme-victoire-daffilee-pour-des-brooklyn-nets-qui-montent-en-puissance\\\/\"},\"wordCount\":795,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nba-cinquieme-victoire-daffilee-pour-des-brooklyn-nets-qui-montent-en-puissance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/NBA-Cinquieme-victoire-daffilee-pour-des-Brooklyn-Nets-qui-montent-en-puissance.png\",\"keywords\":[\"Brooklyn Nets\",\"Toronto Raptors\"],\"articleSection\":[\"NBA\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nba-cinquieme-victoire-daffilee-pour-des-brooklyn-nets-qui-montent-en-puissance\\\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nba-cinquieme-victoire-daffilee-pour-des-brooklyn-nets-qui-montent-en-puissance\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nba-cinquieme-victoire-daffilee-pour-des-brooklyn-nets-qui-montent-en-puissance\\\/\",\"name\":\"NBA : Cinqui\u00e8me victoire d'affil\u00e9e pour des Brooklyn Nets qui montent en puissance\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nba-cinquieme-victoire-daffilee-pour-des-brooklyn-nets-qui-montent-en-puissance\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nba-cinquieme-victoire-daffilee-pour-des-brooklyn-nets-qui-montent-en-puissance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/NBA-Cinquieme-victoire-daffilee-pour-des-Brooklyn-Nets-qui-montent-en-puissance.png\",\"datePublished\":\"2021-11-07T22:47:14+00:00\",\"dateModified\":\"2021-11-07T22:52:51+00:00\",\"description\":\"NBA 2021-2022 - Les Brooklyn Nets encha\u00eenent avec un cinqui\u00e8me succ\u00e8s de rang en s'imposant face aux Toronto Raptors (116-103).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nba-cinquieme-victoire-daffilee-pour-des-brooklyn-nets-qui-montent-en-puissance\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nba-cinquieme-victoire-daffilee-pour-des-brooklyn-nets-qui-montent-en-puissance\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nba-cinquieme-victoire-daffilee-pour-des-brooklyn-nets-qui-montent-en-puissance\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/NBA-Cinquieme-victoire-daffilee-pour-des-Brooklyn-Nets-qui-montent-en-puissance.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/NBA-Cinquieme-victoire-daffilee-pour-des-Brooklyn-Nets-qui-montent-en-puissance.png\",\"width\":800,\"height\":445,\"caption\":\"NBA Cinqui\u00e8me victoire d\u2019affil\u00e9e pour des Brooklyn Nets qui montent en puissance\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nba-cinquieme-victoire-daffilee-pour-des-brooklyn-nets-qui-montent-en-puissance\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NBA : Cinqui\u00e8me victoire d&rsquo;affil\u00e9e pour des Brooklyn Nets qui montent en puissance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sebastien.gente\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sebgente\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/sbastien-gente-a29583169\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sebastiengente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"NBA : Cinqui\u00e8me victoire d'affil\u00e9e pour des Brooklyn Nets qui montent en puissance","description":"NBA 2021-2022 - Les Brooklyn Nets encha\u00eenent avec un cinqui\u00e8me succ\u00e8s de rang en s'imposant face aux Toronto Raptors (116-103).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/nba-cinquieme-victoire-daffilee-pour-des-brooklyn-nets-qui-montent-en-puissance\/","og_locale":"fr_FR","og_type":"article","og_title":"NBA : Cinqui\u00e8me victoire d'affil\u00e9e pour des Brooklyn Nets qui montent en puissance","og_description":"NBA 2021-2022 - Les Brooklyn Nets encha\u00eenent avec un cinqui\u00e8me succ\u00e8s de rang en s'imposant face aux Toronto Raptors (116-103).","og_url":"https:\/\/dicodusport.fr\/blog\/nba-cinquieme-victoire-daffilee-pour-des-brooklyn-nets-qui-montent-en-puissance\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2021-11-07T22:47:14+00:00","article_modified_time":"2021-11-07T22:52:51+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/11\/NBA-Cinquieme-victoire-daffilee-pour-des-Brooklyn-Nets-qui-montent-en-puissance.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"NBA : Cinqui\u00e8me victoire d'affil\u00e9e pour des Brooklyn Nets qui montent en puissance","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/nba-cinquieme-victoire-daffilee-pour-des-brooklyn-nets-qui-montent-en-puissance\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/nba-cinquieme-victoire-daffilee-pour-des-brooklyn-nets-qui-montent-en-puissance\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"NBA : Cinqui\u00e8me victoire d&rsquo;affil\u00e9e pour des Brooklyn Nets qui montent en puissance","datePublished":"2021-11-07T22:47:14+00:00","dateModified":"2021-11-07T22:52:51+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/nba-cinquieme-victoire-daffilee-pour-des-brooklyn-nets-qui-montent-en-puissance\/"},"wordCount":795,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/nba-cinquieme-victoire-daffilee-pour-des-brooklyn-nets-qui-montent-en-puissance\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/11\/NBA-Cinquieme-victoire-daffilee-pour-des-Brooklyn-Nets-qui-montent-en-puissance.png","keywords":["Brooklyn Nets","Toronto Raptors"],"articleSection":["NBA"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/nba-cinquieme-victoire-daffilee-pour-des-brooklyn-nets-qui-montent-en-puissance\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/nba-cinquieme-victoire-daffilee-pour-des-brooklyn-nets-qui-montent-en-puissance\/","url":"https:\/\/dicodusport.fr\/blog\/nba-cinquieme-victoire-daffilee-pour-des-brooklyn-nets-qui-montent-en-puissance\/","name":"NBA : Cinqui\u00e8me victoire d'affil\u00e9e pour des Brooklyn Nets qui montent en puissance","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/nba-cinquieme-victoire-daffilee-pour-des-brooklyn-nets-qui-montent-en-puissance\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/nba-cinquieme-victoire-daffilee-pour-des-brooklyn-nets-qui-montent-en-puissance\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/11\/NBA-Cinquieme-victoire-daffilee-pour-des-Brooklyn-Nets-qui-montent-en-puissance.png","datePublished":"2021-11-07T22:47:14+00:00","dateModified":"2021-11-07T22:52:51+00:00","description":"NBA 2021-2022 - Les Brooklyn Nets encha\u00eenent avec un cinqui\u00e8me succ\u00e8s de rang en s'imposant face aux Toronto Raptors (116-103).","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/nba-cinquieme-victoire-daffilee-pour-des-brooklyn-nets-qui-montent-en-puissance\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/nba-cinquieme-victoire-daffilee-pour-des-brooklyn-nets-qui-montent-en-puissance\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/nba-cinquieme-victoire-daffilee-pour-des-brooklyn-nets-qui-montent-en-puissance\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/11\/NBA-Cinquieme-victoire-daffilee-pour-des-Brooklyn-Nets-qui-montent-en-puissance.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/11\/NBA-Cinquieme-victoire-daffilee-pour-des-Brooklyn-Nets-qui-montent-en-puissance.png","width":800,"height":445,"caption":"NBA Cinqui\u00e8me victoire d\u2019affil\u00e9e pour des Brooklyn Nets qui montent en puissance"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/nba-cinquieme-victoire-daffilee-pour-des-brooklyn-nets-qui-montent-en-puissance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"NBA : Cinqui\u00e8me victoire d&rsquo;affil\u00e9e pour des Brooklyn Nets qui montent en puissance"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/178256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=178256"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/178256\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/178307"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=178256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=178256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=178256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}