{"id":178711,"date":"2021-11-11T16:04:22","date_gmt":"2021-11-11T15:04:22","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=178711&#038;preview=true&#038;preview_id=178711"},"modified":"2021-11-11T20:32:17","modified_gmt":"2021-11-11T19:32:17","slug":"frank-lampard-devrait-etre-le-prochain-entraineur-de-norwich","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/frank-lampard-devrait-etre-le-prochain-entraineur-de-norwich\/","title":{"rendered":"Frank Lampard devrait \u00eatre le prochain entra\u00eeneur de Norwich"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>PREMIER LEAGUE &#8211; Apr\u00e8s avoir licenci\u00e9 son entraineur Daniel Farke apr\u00e8s le succ\u00e8s \u00e0 Brendtord (1-2), le board de Norwich City, dernier de Premier League, a d\u00e9cid\u00e9 de se s\u00e9parer de son entraineur. D&rsquo;apr\u00e8s talkSPORT, Frank Lampard tiendrait la corde pour reprendre le flambeau et tenter de maintenir l&rsquo;\u00e9quipe en premi\u00e8re division.\u00a0<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s son \u00e9chec \u00e0 Chelsea, <strong>Frank Lampard<\/strong> pourrait revenir sur un banc de Premier League.\u00a0<b>Entra\u00eeneur des Blues entre l&rsquo;\u00e9t\u00e9 2019 et janvier 2021<\/b>, l&rsquo;ancien meneur de jeu de Chelsea pourrait reprendre en main <strong>Norwich City<\/strong>, qui cherche un entra\u00eeneur suite au limogeage de <strong>Daniel Farke<\/strong>. D&rsquo;apr\u00e8s <em>talkSPORT<\/em>, il sera nomm\u00e9 dans les prochaines heures voire les prochains jours. Il aura la mission d\u00e9licate de sauver le club en Premi\u00e8re Division, apr\u00e8s sa promotion en Premier League \u00e0 l&rsquo;intersaison. Dernier du championnat anglais apr\u00e8s 11 journ\u00e9es, \u00a0\u00bbThe Canaries\u00a0\u00bb n&rsquo;ont inscrit que 5 buts depuis le d\u00e9but, trop peu pour pouvoir exister dans un championnat aussi exigeant que la Premier League.<\/p>\n<p style=\"text-align: justify;\"><strong>Frank Lampard<\/strong> est en attente d&rsquo;un nouveau projet depuis son d\u00e9part de <strong>Chelsea<\/strong> en janvier 2021, et il semblerait toujours d&rsquo;apr\u00e8s le m\u00e9dia anglais que le challenge lui irait \u00e0 merveille. Chez les Blues, il a repris les r\u00eanes du club alors que celui-ci \u00e9tait priv\u00e9 de mercato. Lors de sa premi\u00e8re saison, il a men\u00e9 Chelsea \u00e0 la quatri\u00e8me place du championnat mais sa deuxi\u00e8me saison fut plus d\u00e9licate. Apr\u00e8s voir sorti le carnet de ch\u00e8ques pour recruter des joueurs tels que Kai Havertz ou Timo Werner, il s&rsquo;est retrouv\u00e9 face \u00e0 une pression \u00e9norme en termes de r\u00e9sultats et n&rsquo;a pas su mener sa mission sur le banc des Blues \u00e0 son terme. Il a \u00e9t\u00e9 remplac\u00e9 par <strong>Thomas Tuchel<\/strong>, qui a ensuite remport\u00e9 la Ligue des Champions la m\u00eame ann\u00e9e, face \u00e0 Manchester City lors de la finale.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">BREAKING &#x1f6a8;: Frank Lampard is expected to be named as Norwich manager, talkSPORT understands <a href=\"https:\/\/twitter.com\/hashtag\/NCFC?src=hash&amp;ref_src=twsrc%5Etfw\">#NCFC<\/a><\/p>\n<p>\u2014 talkSPORT (@talkSPORT) <a href=\"https:\/\/twitter.com\/talkSPORT\/status\/1458797433769627650?ref_src=twsrc%5Etfw\">November 11, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PREMIER LEAGUE &#8211; Apr\u00e8s avoir licenci\u00e9 son entraineur Daniel Farke apr\u00e8s le succ\u00e8s \u00e0 Brendtord (1-2), le board de Norwich City, dernier de Premier League, a d\u00e9cid\u00e9 de se s\u00e9parer de son entraineur. D&rsquo;apr\u00e8s talkSPORT, Frank Lampard tiendrait la corde pour reprendre le flambeau et tenter de maintenir l&rsquo;\u00e9quipe en premi\u00e8re division.\u00a0<\/p>\n","protected":false},"author":42,"featured_media":178719,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2301],"tags":[75,50],"class_list":["post-178711","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","tag-football","tag-premier-league"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Frank Lampard devrait \u00eatre le prochain entra\u00eeneur de Norwich<\/title>\n<meta name=\"description\" content=\"Apr\u00e8s le limogeage de Daniel Farke malgr\u00e9 le succ\u00e8s \u00e0 Brendford, Frank Lampard devrait \u00eatre le prochain entraineur de Norwich.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/frank-lampard-devrait-etre-le-prochain-entraineur-de-norwich\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frank Lampard devrait \u00eatre le prochain entra\u00eeneur de Norwich\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s le limogeage de Daniel Farke malgr\u00e9 le succ\u00e8s \u00e0 Brendford, Frank Lampard devrait \u00eatre le prochain entraineur de Norwich.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/frank-lampard-devrait-etre-le-prochain-entraineur-de-norwich\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-11T15:04:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-11T19:32:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/11\/Icon_57474634.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nicolas Mezine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Frank Lampard devrait \u00eatre le prochain entra\u00eeneur de Norwich\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Lbiji13\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/frank-lampard-devrait-etre-le-prochain-entraineur-de-norwich\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/frank-lampard-devrait-etre-le-prochain-entraineur-de-norwich\/\"},\"author\":{\"name\":\"Nicolas Mezine\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/99fcf31b3ee0d51fed53ade78139bbbf\"},\"headline\":\"Frank Lampard devrait \u00eatre le prochain entra\u00eeneur de Norwich\",\"datePublished\":\"2021-11-11T15:04:22+00:00\",\"dateModified\":\"2021-11-11T19:32:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/frank-lampard-devrait-etre-le-prochain-entraineur-de-norwich\/\"},\"wordCount\":361,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/frank-lampard-devrait-etre-le-prochain-entraineur-de-norwich\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/11\/Icon_57474634.jpg\",\"keywords\":[\"Football\",\"Premier League\"],\"articleSection\":[\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/frank-lampard-devrait-etre-le-prochain-entraineur-de-norwich\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/frank-lampard-devrait-etre-le-prochain-entraineur-de-norwich\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/frank-lampard-devrait-etre-le-prochain-entraineur-de-norwich\/\",\"name\":\"Frank Lampard devrait \u00eatre le prochain entra\u00eeneur de Norwich\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/frank-lampard-devrait-etre-le-prochain-entraineur-de-norwich\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/frank-lampard-devrait-etre-le-prochain-entraineur-de-norwich\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/11\/Icon_57474634.jpg\",\"datePublished\":\"2021-11-11T15:04:22+00:00\",\"dateModified\":\"2021-11-11T19:32:17+00:00\",\"description\":\"Apr\u00e8s le limogeage de Daniel Farke malgr\u00e9 le succ\u00e8s \u00e0 Brendford, Frank Lampard devrait \u00eatre le prochain entraineur de Norwich.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/frank-lampard-devrait-etre-le-prochain-entraineur-de-norwich\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/frank-lampard-devrait-etre-le-prochain-entraineur-de-norwich\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/frank-lampard-devrait-etre-le-prochain-entraineur-de-norwich\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/11\/Icon_57474634.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/11\/Icon_57474634.jpg\",\"width\":800,\"height\":445,\"caption\":\"Frank Lampard devrait \u00eatre le prochain entra\u00eeneur de Norwich\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/frank-lampard-devrait-etre-le-prochain-entraineur-de-norwich\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frank Lampard devrait \u00eatre le prochain entra\u00eeneur de Norwich\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/99fcf31b3ee0d51fed53ade78139bbbf\",\"name\":\"Nicolas Mezine\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/IMG_4655-e1631787111223-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/IMG_4655-e1631787111223-150x150.jpg\",\"caption\":\"Nicolas Mezine\"},\"description\":\"Passionn\u00e9 de sport, notamment de rugby dans toutes ses variantes (XV, XIII et VII). Fan du RC Toulon et de l'Olympique de Marseille.\",\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/nicolas-mezine-521380160\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/Lbiji13\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/nicolas-m\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Frank Lampard devrait \u00eatre le prochain entra\u00eeneur de Norwich","description":"Apr\u00e8s le limogeage de Daniel Farke malgr\u00e9 le succ\u00e8s \u00e0 Brendford, Frank Lampard devrait \u00eatre le prochain entraineur de Norwich.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/frank-lampard-devrait-etre-le-prochain-entraineur-de-norwich\/","og_locale":"fr_FR","og_type":"article","og_title":"Frank Lampard devrait \u00eatre le prochain entra\u00eeneur de Norwich","og_description":"Apr\u00e8s le limogeage de Daniel Farke malgr\u00e9 le succ\u00e8s \u00e0 Brendford, Frank Lampard devrait \u00eatre le prochain entraineur de Norwich.","og_url":"https:\/\/dicodusport.fr\/blog\/frank-lampard-devrait-etre-le-prochain-entraineur-de-norwich\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2021-11-11T15:04:22+00:00","article_modified_time":"2021-11-11T19:32:17+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/11\/Icon_57474634.jpg","type":"image\/jpeg"}],"author":"Nicolas Mezine","twitter_card":"summary_large_image","twitter_title":"Frank Lampard devrait \u00eatre le prochain entra\u00eeneur de Norwich","twitter_creator":"@https:\/\/twitter.com\/Lbiji13","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/frank-lampard-devrait-etre-le-prochain-entraineur-de-norwich\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/frank-lampard-devrait-etre-le-prochain-entraineur-de-norwich\/"},"author":{"name":"Nicolas Mezine","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/99fcf31b3ee0d51fed53ade78139bbbf"},"headline":"Frank Lampard devrait \u00eatre le prochain entra\u00eeneur de Norwich","datePublished":"2021-11-11T15:04:22+00:00","dateModified":"2021-11-11T19:32:17+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/frank-lampard-devrait-etre-le-prochain-entraineur-de-norwich\/"},"wordCount":361,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/frank-lampard-devrait-etre-le-prochain-entraineur-de-norwich\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/11\/Icon_57474634.jpg","keywords":["Football","Premier League"],"articleSection":["Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/frank-lampard-devrait-etre-le-prochain-entraineur-de-norwich\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/frank-lampard-devrait-etre-le-prochain-entraineur-de-norwich\/","url":"https:\/\/dicodusport.fr\/blog\/frank-lampard-devrait-etre-le-prochain-entraineur-de-norwich\/","name":"Frank Lampard devrait \u00eatre le prochain entra\u00eeneur de Norwich","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/frank-lampard-devrait-etre-le-prochain-entraineur-de-norwich\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/frank-lampard-devrait-etre-le-prochain-entraineur-de-norwich\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/11\/Icon_57474634.jpg","datePublished":"2021-11-11T15:04:22+00:00","dateModified":"2021-11-11T19:32:17+00:00","description":"Apr\u00e8s le limogeage de Daniel Farke malgr\u00e9 le succ\u00e8s \u00e0 Brendford, Frank Lampard devrait \u00eatre le prochain entraineur de Norwich.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/frank-lampard-devrait-etre-le-prochain-entraineur-de-norwich\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/frank-lampard-devrait-etre-le-prochain-entraineur-de-norwich\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/frank-lampard-devrait-etre-le-prochain-entraineur-de-norwich\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/11\/Icon_57474634.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/11\/Icon_57474634.jpg","width":800,"height":445,"caption":"Frank Lampard devrait \u00eatre le prochain entra\u00eeneur de Norwich"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/frank-lampard-devrait-etre-le-prochain-entraineur-de-norwich\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Frank Lampard devrait \u00eatre le prochain entra\u00eeneur de Norwich"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/99fcf31b3ee0d51fed53ade78139bbbf","name":"Nicolas Mezine","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/IMG_4655-e1631787111223-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/IMG_4655-e1631787111223-150x150.jpg","caption":"Nicolas Mezine"},"description":"Passionn\u00e9 de sport, notamment de rugby dans toutes ses variantes (XV, XIII et VII). Fan du RC Toulon et de l'Olympique de Marseille.","sameAs":["https:\/\/www.linkedin.com\/in\/nicolas-mezine-521380160\/","https:\/\/x.com\/https:\/\/twitter.com\/Lbiji13"],"url":"https:\/\/dicodusport.fr\/blog\/author\/nicolas-m\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/178711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=178711"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/178711\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/178719"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=178711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=178711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=178711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}