{"id":182698,"date":"2021-12-01T09:34:36","date_gmt":"2021-12-01T08:34:36","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=182698&#038;preview=true&#038;preview_id=182698"},"modified":"2021-12-01T09:40:25","modified_gmt":"2021-12-01T08:40:25","slug":"pronostic-psg-nice-16eme-journee-de-ligue-1","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/pronostic-psg-nice-16eme-journee-de-ligue-1\/","title":{"rendered":"Pronostic PSG &#8211; Nice, 16\u00e8me journ\u00e9e de Ligue 1"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><a href=\"https:\/\/dicodusport.fr\/blog\/calendrier-ligue-1-2021-2022-16eme-journee-programme-tv-et-resultats\/\"><strong>LIGUE 1 &#8211; 16\u00c8ME JOURN\u00c9E<\/strong><\/a><b> &#8211; Le PSG accueille Nice lors de la 16\u00e8me journ\u00e9e du championnat fran\u00e7ais. Notre pronostic pour la rencontre.<\/b><\/em><\/p>\n<h2 style=\"text-align: justify;\">Pronostic PSG &#8211; Nice : Mercredi 1er d\u00e9cembre, 21h00<\/h2>\n<p style=\"text-align: justify;\">Le <strong>PSG<\/strong>, qui reste sur un succ\u00e8s compliqu\u00e9 face \u00e0 l&rsquo;ASSE, se pr\u00e9sente diminu\u00e9 pour ce choc face \u00e0 Nice. Neymar est forfait comme Wijnaldum et Ramos. Messi devrait \u00eatre l\u00e0 mais il ne s&rsquo;est pas entrain\u00e9 mardi. <strong>Nice<\/strong> reste de son c\u00f4t\u00e9 sur une contre-performance face \u00e0 Metz mais les Aiglons voyagent bien cette saison. On voit une rencontre ouverte donc on part sur <strong>les deux \u00e9quipes qui marquent<\/strong>.<\/p>\n<table style=\"width: 100%;\">\n<tbody>\n<tr style=\"height: 16px;\">\n<td style=\"background-color: #404040; text-align: left; border-color: #ededed; width: 500px;\"><span style=\"font-size: 12px; color: #ffffff;\">Mercredi 1er d\u00e9cembre, 21h00<\/span><\/td>\n<td style=\"background-color: #525252; border-color: #ededed; width: 300px; text-align: center;\" colspan=\"2\"><span style=\"font-size: 12px; color: #ffffff;\">Les deux \u00e9quipes vont-elles marquer ?<\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"background-color: #ffffff; text-align: justify; border-color: #ededed; vertical-align: middle; width: 500px;\"><strong>PSG &#8211; Nice<\/strong><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 150px;\"><span style=\"font-size: 10px;\"><strong><span style=\"font-size: 12px;\">Oui<\/span><\/strong><br \/>\n<a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/27884998?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#091C3E;background-color:#CDFB0A;border-color:#a4c908;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#091C3E;padding:0px 16px;font-size:13px;line-height:26px;border-color:#dcfd54;border-radius:5px;text-shadow:none\"> 1.62<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 150px;\"><span style=\"font-size: 10px;\"><strong><span style=\"font-size: 12px;\">Non<\/span><\/strong><br \/>\n<a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/27884998?banid=33423\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#091C3E;border-color:#081732;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#536178;border-radius:5px;text-shadow:none\"> 2.10<\/span><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\">Tentez votre chance en misant jusqu\u2019\u00e0 100\u20ac gr\u00e2ce \u00e0 votre <a href=\"https:\/\/www.winamax.fr\/landing\/landing_leads.php?ldg=1er-pari-rembourse&amp;banid=33423\" target=\"_blank\" rel=\"nofollow noopener\">premier pari rembours\u00e9<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LIGUE 1 &#8211; 16\u00c8ME JOURN\u00c9E &#8211; Le PSG accueille Nice lors de la 16\u00e8me journ\u00e9e du championnat fran\u00e7ais. Notre pronostic pour la rencontre.<\/p>\n","protected":false},"author":1,"featured_media":182701,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[47045],"tags":[1554,460,4949,910],"class_list":["post-182698","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ligue-1","tag-ligue-1","tag-nice","tag-pronostics","tag-psg"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pronostic PSG - Nice, 16\u00e8me journ\u00e9e de Ligue 1 - Dicodusport<\/title>\n<meta name=\"description\" content=\"LIGUE 1 - 16\u00c8ME JOURN\u00c9E - Le PSG accueille Nice lors de la 16\u00e8me journ\u00e9e du championnat fran\u00e7ais. Notre pronostic pour la rencontre.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/pronostic-psg-nice-16eme-journee-de-ligue-1\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pronostic PSG - Nice, 16\u00e8me journ\u00e9e de Ligue 1\" \/>\n<meta property=\"og:description\" content=\"LIGUE 1 - 16\u00c8ME JOURN\u00c9E - Le PSG accueille Nice lors de la 16\u00e8me journ\u00e9e du championnat fran\u00e7ais. Notre pronostic pour la rencontre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/pronostic-psg-nice-16eme-journee-de-ligue-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-01T08:34:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-01T08:40:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/Pronostic-PSG-Nice-16eme-journee-de-Ligue-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Pronostic PSG - Nice, 16\u00e8me journ\u00e9e de Ligue 1\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pronostic-psg-nice-16eme-journee-de-ligue-1\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pronostic-psg-nice-16eme-journee-de-ligue-1\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Pronostic PSG &#8211; Nice, 16\u00e8me journ\u00e9e de Ligue 1\",\"datePublished\":\"2021-12-01T08:34:36+00:00\",\"dateModified\":\"2021-12-01T08:40:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pronostic-psg-nice-16eme-journee-de-ligue-1\\\/\"},\"wordCount\":189,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pronostic-psg-nice-16eme-journee-de-ligue-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Pronostic-PSG-Nice-16eme-journee-de-Ligue-1.png\",\"keywords\":[\"Ligue 1\",\"Nice\",\"Pronostics\",\"PSG\"],\"articleSection\":[\"Ligue 1\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pronostic-psg-nice-16eme-journee-de-ligue-1\\\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pronostic-psg-nice-16eme-journee-de-ligue-1\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pronostic-psg-nice-16eme-journee-de-ligue-1\\\/\",\"name\":\"Pronostic PSG - Nice, 16\u00e8me journ\u00e9e de Ligue 1 - Dicodusport\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pronostic-psg-nice-16eme-journee-de-ligue-1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pronostic-psg-nice-16eme-journee-de-ligue-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Pronostic-PSG-Nice-16eme-journee-de-Ligue-1.png\",\"datePublished\":\"2021-12-01T08:34:36+00:00\",\"dateModified\":\"2021-12-01T08:40:25+00:00\",\"description\":\"LIGUE 1 - 16\u00c8ME JOURN\u00c9E - Le PSG accueille Nice lors de la 16\u00e8me journ\u00e9e du championnat fran\u00e7ais. Notre pronostic pour la rencontre.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pronostic-psg-nice-16eme-journee-de-ligue-1\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pronostic-psg-nice-16eme-journee-de-ligue-1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pronostic-psg-nice-16eme-journee-de-ligue-1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Pronostic-PSG-Nice-16eme-journee-de-Ligue-1.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Pronostic-PSG-Nice-16eme-journee-de-Ligue-1.png\",\"width\":1200,\"height\":670,\"caption\":\"Pronostic PSG - Nice, 16\u00e8me journ\u00e9e de Ligue 1\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pronostic-psg-nice-16eme-journee-de-ligue-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pronostic PSG &#8211; Nice, 16\u00e8me journ\u00e9e de Ligue 1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pronostic PSG - Nice, 16\u00e8me journ\u00e9e de Ligue 1 - Dicodusport","description":"LIGUE 1 - 16\u00c8ME JOURN\u00c9E - Le PSG accueille Nice lors de la 16\u00e8me journ\u00e9e du championnat fran\u00e7ais. Notre pronostic pour la rencontre.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/pronostic-psg-nice-16eme-journee-de-ligue-1\/","og_locale":"fr_FR","og_type":"article","og_title":"Pronostic PSG - Nice, 16\u00e8me journ\u00e9e de Ligue 1","og_description":"LIGUE 1 - 16\u00c8ME JOURN\u00c9E - Le PSG accueille Nice lors de la 16\u00e8me journ\u00e9e du championnat fran\u00e7ais. Notre pronostic pour la rencontre.","og_url":"https:\/\/dicodusport.fr\/blog\/pronostic-psg-nice-16eme-journee-de-ligue-1\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2021-12-01T08:34:36+00:00","article_modified_time":"2021-12-01T08:40:25+00:00","og_image":[{"width":1200,"height":670,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/Pronostic-PSG-Nice-16eme-journee-de-Ligue-1.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Pronostic PSG - Nice, 16\u00e8me journ\u00e9e de Ligue 1","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/pronostic-psg-nice-16eme-journee-de-ligue-1\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-psg-nice-16eme-journee-de-ligue-1\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Pronostic PSG &#8211; Nice, 16\u00e8me journ\u00e9e de Ligue 1","datePublished":"2021-12-01T08:34:36+00:00","dateModified":"2021-12-01T08:40:25+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-psg-nice-16eme-journee-de-ligue-1\/"},"wordCount":189,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-psg-nice-16eme-journee-de-ligue-1\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/Pronostic-PSG-Nice-16eme-journee-de-Ligue-1.png","keywords":["Ligue 1","Nice","Pronostics","PSG"],"articleSection":["Ligue 1"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/pronostic-psg-nice-16eme-journee-de-ligue-1\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/pronostic-psg-nice-16eme-journee-de-ligue-1\/","url":"https:\/\/dicodusport.fr\/blog\/pronostic-psg-nice-16eme-journee-de-ligue-1\/","name":"Pronostic PSG - Nice, 16\u00e8me journ\u00e9e de Ligue 1 - Dicodusport","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-psg-nice-16eme-journee-de-ligue-1\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-psg-nice-16eme-journee-de-ligue-1\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/Pronostic-PSG-Nice-16eme-journee-de-Ligue-1.png","datePublished":"2021-12-01T08:34:36+00:00","dateModified":"2021-12-01T08:40:25+00:00","description":"LIGUE 1 - 16\u00c8ME JOURN\u00c9E - Le PSG accueille Nice lors de la 16\u00e8me journ\u00e9e du championnat fran\u00e7ais. Notre pronostic pour la rencontre.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/pronostic-psg-nice-16eme-journee-de-ligue-1\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/pronostic-psg-nice-16eme-journee-de-ligue-1\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/pronostic-psg-nice-16eme-journee-de-ligue-1\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/Pronostic-PSG-Nice-16eme-journee-de-Ligue-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/Pronostic-PSG-Nice-16eme-journee-de-Ligue-1.png","width":1200,"height":670,"caption":"Pronostic PSG - Nice, 16\u00e8me journ\u00e9e de Ligue 1"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/pronostic-psg-nice-16eme-journee-de-ligue-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Pronostic PSG &#8211; Nice, 16\u00e8me journ\u00e9e de Ligue 1"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/182698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=182698"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/182698\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/182701"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=182698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=182698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=182698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}