{"id":183423,"date":"2021-12-06T09:47:56","date_gmt":"2021-12-06T08:47:56","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=183423&#038;preview=true&#038;preview_id=183423"},"modified":"2021-12-06T09:47:56","modified_gmt":"2021-12-06T08:47:56","slug":"top-14-immanquable-de-la-12eme-journee","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/top-14-immanquable-de-la-12eme-journee\/","title":{"rendered":"Top 14 : L&rsquo;immanquable de la 12\u00e8me journ\u00e9e"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><b>TOP 14 2021-2022 &#8211;\u00a0 Le choc au sommet a tourn\u00e9 \u00e0 l&rsquo;avantage de l&rsquo;Union Bordeaux-B\u00e8gles, qui reprend la t\u00eate du classement. Montpellier et Lyon tiennent le rythme, alors que le nul entre Pau et Toulon n&rsquo;arrange personne. L&rsquo;immanquable de la 12\u00e8me journ\u00e9e.<\/b><\/em><\/p>\n<h2 class=\"western\" style=\"text-align: justify;\">Le match de la journ\u00e9e : Union Bordeaux-B\u00e8gles 17-7 Stade Toulousain<\/h2>\n<p style=\"text-align: justify;\">Certains diront que la montagne a accouch\u00e9 d&rsquo;une souris. Mais dans ce sommet attendu entre les deux meilleures \u00e9quipes du Top 14, on a pu v\u00e9rifier un vieil adage rugbystique : <em>les avants d\u00e9cident de qui gagne le match, les arri\u00e8res d\u00e9cident de combien<\/em>. Car c&rsquo;est bien devant que l&rsquo;UBB est all\u00e9e chercher de haute lutte sa victoire. Les hommes de <strong>Christophe Urios<\/strong> ont constamment mis leurs adversaires sous l&rsquo;\u00e9teignoir dans les rucks, grattant plusieurs p\u00e9nalit\u00e9s dont deux furent converties par <strong>Matthieu Jalibert,<\/strong> scrut\u00e9 de pr\u00e8s dans son duel avec <strong>Romain Ntamack.<\/strong> L&rsquo;affrontement a tourn\u00e9 court, puisque le 10 Girondin est sorti \u00e0 la pause sur blessure <strong>(mi-temps: 6-0)<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Ragaillardis, les Toulousains d\u00e9marrent la seconde mi-temps pied au plancher et inscrivent rapidement un essai par le troisi\u00e8me ligne international <strong>Fran\u00e7ois Cros,<\/strong> apr\u00e8s une succession de pick&rsquo;n&rsquo;go, preuve que Toulouse sait aussi jouer avec ses gros. Les Haut-Garonnais passent en t\u00eate pour la premi\u00e8re et unique fois du match (6-7). Car l&rsquo;UBB remet la main sur le match avec une p\u00e9nalit\u00e9 de <strong>Maxime Lucu,<\/strong> avant d&rsquo;inscrire un essai de filou par <strong>Bastien Vergnes-Taillefer,<\/strong> sur une combinaison astucieuse en touche entre <strong>Lamothe<\/strong> et <strong>Lucu<\/strong>, essai non transform\u00e9 <strong>(14-7, 58\u00e8me).<\/strong><\/p>\n<p style=\"text-align: justify;\">D\u00e8s lors, l&rsquo;intensit\u00e9 monte d&rsquo;un cran, les Toulousains ne voulant pas rentrer bredouilles de leur d\u00e9placement. Mais malgr\u00e9 les efforts de la charni\u00e8re <strong>Dupont &#8211; Ntamack,<\/strong> les offensives toulousaines sont d\u00e9sordonn\u00e9es et la d\u00e9fense b\u00e9glaise est bien en place. C&rsquo;est finalement \u00e0 la 70\u00e8me minute que <strong>Maxime Lucu<\/strong> scelle le sort du match sur une nouvelle p\u00e9nalit\u00e9, sanctionnant une \u00e9ni\u00e8me faute au sol des Stadistes. Malgr\u00e9 un ultime effort toulousain pour aller accrocher le point de bonus d\u00e9fensif, le score en restera l\u00e0. L&rsquo;UBB remonte sur le tr\u00f4ne du Top 14 gr\u00e2ce \u00e0 ce succ\u00e8s, et si ce match n&rsquo;aura pas fourni les grandes envol\u00e9es esp\u00e9r\u00e9es, il aura permis aux deux \u00e9quipes de se jauger avant le d\u00e9but de la Coupe d&rsquo;Europe.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">&#x1f3c9;&#x1f399; retrouvez la r\u00e9action de Christophe Urios, apr\u00e8s le match contre le <a href=\"https:\/\/twitter.com\/StadeToulousain?ref_src=twsrc%5Etfw\">@StadeToulousain<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/UBBST?src=hash&amp;ref_src=twsrc%5Etfw\">#UBBST<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/UBB?src=hash&amp;ref_src=twsrc%5Etfw\">#UBB<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/arlfm?src=hash&amp;ref_src=twsrc%5Etfw\">#arlfm<\/a> <a href=\"https:\/\/t.co\/IHv0H7kuX2\">pic.twitter.com\/IHv0H7kuX2<\/a><\/p>\n<p>\u2014 Dorian Malvesin (@MalvesinDorian) <a href=\"https:\/\/twitter.com\/MalvesinDorian\/status\/1467277557007536129?ref_src=twsrc%5Etfw\">December 4, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 class=\"western\" style=\"text-align: justify;\">Le club en forme : le Montpellier HR<\/h2>\n<p style=\"text-align: justify;\">La victoire des H\u00e9raultais \u00e9tait attendue pour ce derby face \u00e0 Perpignan, mais ce qui l&rsquo;\u00e9tait moins, c&rsquo;est le sentiment de ma\u00eetrise des hommes de <strong>Philippe Saint-Andr\u00e9<\/strong> tout au long du match. Rarement inqui\u00e9t\u00e9s, les Montpelli\u00e9rains ont mis une mi-temps \u00e0 prendre la mesure de leur adversaire <strong>(6-6 \u00e0 la pause)<\/strong> avant d&rsquo;acc\u00e9l\u00e9rer brutalement au retour des vestiaires, inscrivant deux essais en cinq minutes pour prendre le large. Sans paniquer, les H\u00e9raultais ont maintenu l&rsquo;\u00e9tau autour de leurs opposants, patientant jusqu&rsquo;\u00e0 la 77\u00e8me minute pour d\u00e9crocher le bonus offensif gr\u00e2ce \u00e0 un essai opportuniste d&rsquo;<strong>Aubin Eymeri<\/strong>, pour sa premi\u00e8re titularisation en \u00e9quipe une. Cinqui\u00e8me succ\u00e8s de rang pour le MHR<strong> (30-6),<\/strong> qui consolide sa troisi\u00e8me place.<\/p>\n<p>&nbsp;<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\"><a href=\"https:\/\/twitter.com\/MHR_officiel?ref_src=twsrc%5Etfw\">@MHR_officiel<\/a> essai de Eymerie pour son premier match! Ici c\u2019est montpellier <a href=\"https:\/\/twitter.com\/hashtag\/MHRUSAP?src=hash&amp;ref_src=twsrc%5Etfw\">#MHRUSAP<\/a> <a href=\"https:\/\/t.co\/PvsXBHeTVJ\">pic.twitter.com\/PvsXBHeTVJ<\/a><\/p>\n<p>\u2014 J\u00e9r\u00f4me MOYNIER (@MoynierJ) <a href=\"https:\/\/twitter.com\/MoynierJ\/status\/1467162085733945344?ref_src=twsrc%5Etfw\">December 4, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 class=\"western\" style=\"text-align: justify;\">Le club qui d\u00e9\u00e7oit : le Racing 92<\/h2>\n<p style=\"text-align: justify;\">Troisi\u00e8me d\u00e9faite d&rsquo;affil\u00e9e pour les hommes de <strong>Laurent Travers.<\/strong> Ils viennent d&rsquo;inscrire seulement trois points lors de leurs trois derni\u00e8res mi-temps disput\u00e9es. Chez des Castrais intraitables \u00e0 domicile, les Racingmen n&rsquo;ont pas exist\u00e9, m\u00eame quand leurs adversaires ont pris un carton jaune en d\u00e9but de deuxi\u00e8me mi-temps. Les Franciliens ont alors fait le si\u00e8ge de la ligne castraise pendant les dix minutes de leur sup\u00e9riorit\u00e9 num\u00e9rique, sans aucun r\u00e9sultat. Buvant le calice jusqu&rsquo;\u00e0 la lie, ils ont encaiss\u00e9 un dernier essai splendide dans les arr\u00eats de jeu qui a offert le point de bonus offensif \u00e0 Castres. Voil\u00e0 le Racing 92 bout\u00e9 hors du top 6, et le club esp\u00e8re que la tr\u00eave europ\u00e9enne permettra de relancer la machine.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">&#x1f570; Fin de match et d\u00e9faite des Ciel &amp; Blanc<br \/>\nBravo \u00e0 <a href=\"https:\/\/twitter.com\/CastresRugby?ref_src=twsrc%5Etfw\">@CastresRugby<\/a> pour sa victoire !<\/p>\n<p>&#x1f535;&#x26aa;&#xfe0f; 25 &#8211; 3 &#x1f499;&#x1f90d;<br \/>\n\u00ab\u00a0Je suis convaincu que l&rsquo;\u00e9quipe est l\u00e0 sauf qu&rsquo;il faut continuer \u00e0 travailler pour sortir de ce moment difficile\u00a0\u00bb &#8211; Juan Imhoff<br \/>\n<a href=\"https:\/\/twitter.com\/hashtag\/RacingFamily?src=hash&amp;ref_src=twsrc%5Etfw\">#RacingFamily<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/COR92?src=hash&amp;ref_src=twsrc%5Etfw\">#COR92<\/a> <a href=\"https:\/\/t.co\/ERIu3YUJQy\">pic.twitter.com\/ERIu3YUJQy<\/a><\/p>\n<p>\u2014 Racing 92 (@racing92) <a href=\"https:\/\/twitter.com\/racing92\/status\/1467161269958549509?ref_src=twsrc%5Etfw\">December 4, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 class=\"western\" style=\"text-align: justify;\">Le joueur : Yohan Beheregaray (AS Clermont-Auvergne)<\/h2>\n<p style=\"text-align: justify;\">Rarement titulaire au sein du pl\u00e9thorique effectif clermontois, le talonneur a profit\u00e9 des blessures pour connaitre son moment de gloire. Titulaire pour la premi\u00e8re fois de saison, le talonneur basque a inscrit la bagatelle de trois essais ! Trois r\u00e9alisations identiques, puisqu&rsquo;apr\u00e8s une touche assur\u00e9e, il a parfaitement conduit le camion clermontois pour aplatir en force. Au club depuis 2013, <strong>Yohan Beheregaray<\/strong> est l&rsquo;un des plus anciens joueurs de l&rsquo;effectif. Empreint d&rsquo;humilit\u00e9, il d\u00e9\u00e7oit rarement quand son entra\u00eeneur fait appel \u00e0 lui. Il a grandement contribu\u00e9 au large succ\u00e8s auvergnat face au Biarritz Olympique <strong>(39-11)<\/strong> qui replace Clermont dans le top 6.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Yohan Beheregaray : \u00ab le coup du chapeau c\u2019est anecdotique. Ce sont les gars qui font le travail. Ce soir il y a des satisfactions dans le contenu \u00bb \u2066<a href=\"https:\/\/twitter.com\/ASMOfficiel?ref_src=twsrc%5Etfw\">@ASMOfficiel<\/a>\u2069 \u2066<a href=\"https:\/\/twitter.com\/top14rugby?ref_src=twsrc%5Etfw\">@top14rugby<\/a>\u2069 <a href=\"https:\/\/twitter.com\/hashtag\/ASMBO?src=hash&amp;ref_src=twsrc%5Etfw\">#ASMBO<\/a> <a href=\"https:\/\/t.co\/Hv7SHXzTqH\">pic.twitter.com\/Hv7SHXzTqH<\/a><\/p>\n<p>\u2014 France Bleu Pays d&rsquo;Auvergne (@FBAuvergne) <a href=\"https:\/\/twitter.com\/FBAuvergne\/status\/1467167843259195394?ref_src=twsrc%5Etfw\">December 4, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 class=\"western\" style=\"text-align: justify;\">L&rsquo;essai : Charlie Ngatai (Lyon OU)<\/h2>\n<p style=\"text-align: justify;\">Lyon n&rsquo;a fait qu&rsquo;une bouch\u00e9e de Brive <strong>(41-0)<\/strong> et cet essai est le symbole de la domination totale des Rhodaniens dans ce match. Tout part d&rsquo;une touche vol\u00e9e aux Brivistes dans leurs propres 40 m\u00e8tres. <strong>Jean-Marc Doussain<\/strong> sert le surpuissant <strong>Josua Tuisova<\/strong> qui met sur les fesses son adversaire direct avant d&rsquo;\u00e9carter vers <strong>Taufua<\/strong> qui trouve <strong>L\u00e9o Berdeu<\/strong>. L&rsquo;ouvreur lyonnais fait vivre le cuir en passant \u00e0 <strong>Barassi<\/strong> qui trouve \u00e0 hauteur son ailier <strong>Veredamu<\/strong>. Ce dernier reprend int\u00e9rieur, \u00e9limine deux adversaires avant de trouver <strong>Charlie Ngatai,<\/strong> qui renverse deux Brivistes avant d&rsquo;aplatir. Un essai symbole des intentions de jeu et des ambitions lyonnaises, qui permettent aux hommes de <strong>Pierre Mignoni<\/strong> de garder leur place dans le top 6.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\"><a href=\"https:\/\/twitter.com\/hashtag\/TOP14?src=hash&amp;ref_src=twsrc%5Etfw\">#TOP14<\/a> \u2013 L\u2019image de la J12 : Comme au bowling<\/p>\n<p>Un spare pour Tuisova et un strike pour Ngatai ! &#x1f3b3; Les deux surpuissants trois-quarts du <a href=\"https:\/\/twitter.com\/LeLOURugby?ref_src=twsrc%5Etfw\">@LeLOURugby<\/a> ont renvers\u00e9 la d\u00e9fense adverse lors de cette magnifique action alliant finesse et percussion ! &#x1f92f;&#x1f43a; <a href=\"https:\/\/t.co\/gF2CnLwrUT\">pic.twitter.com\/gF2CnLwrUT<\/a><\/p>\n<p>\u2014 TOP 14 Rugby (@top14rugby) <a href=\"https:\/\/twitter.com\/top14rugby\/status\/1467457718386671621?ref_src=twsrc%5Etfw\">December 5, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 class=\"western\" style=\"text-align: justify;\">La d\u00e9claration du week-end :<\/h2>\n<blockquote>\n<p style=\"text-align: justify;\">J\u2019ai trois probl\u00e8mes avec Laurent Travers : d\u2019abord, c\u2019est un immense entra\u00eeneur, peut-\u00eatre le meilleur en France ; ensuite, c\u2019est un ami ; enfin, il est un grand dirigeant et prendra ma suite, probablement en 2023.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\"><strong>Jacky Lorenzetti<\/strong>, pr\u00e9sident du Racing 92, balayant d&rsquo;un revers de la main un possible renvoi de son entra\u00eeneur <strong>Laurent Travers<\/strong>.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Jacky Lorenzetti : \u00ab\u00a0J&rsquo;ai trois probl\u00e8mes avec Laurent Travers\u00a0\u00bb <a href=\"https:\/\/t.co\/wjZ2D29Chs\">https:\/\/t.co\/wjZ2D29Chs<\/a><\/p>\n<p>\u2014 blog-rct.com (@Blog_RCT) <a href=\"https:\/\/twitter.com\/Blog_RCT\/status\/1467488440266772488?ref_src=twsrc%5Etfw\">December 5, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 class=\"western\" style=\"text-align: justify;\">La stat<\/h2>\n<p style=\"text-align: justify;\">Apr\u00e8s le match nul de samedi <strong>(16-16),<\/strong> la Section Paloise n&rsquo;a pas battu Toulon en Top 14 lors de leurs cinq derniers affrontements.<\/p>\n<h2 class=\"western\" style=\"text-align: justify;\">R\u00e9sultats et classement<\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/calendrier-top-14-2021-2022-12eme-journee-programme-tv-et-resultats\/\"><strong>Les r\u00e9sultats de la 12\u00e8me journ\u00e9e de Top 14<\/strong><\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/top-14-2021-2022-le-classement-complet\/\"><strong>Le classement du Top 14<\/strong><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>TOP 14 2021-2022 &#8211;\u00a0 Le choc au sommet a tourn\u00e9 \u00e0 l&rsquo;avantage de l&rsquo;Union Bordeaux-B\u00e8gles, qui reprend la t\u00eate du classement. Montpellier et Lyon tiennent le rythme, alors que le nul entre Pau et Toulon n&rsquo;arrange personne. L&rsquo;immanquable de la 12\u00e8me journ\u00e9e.<\/p>\n","protected":false},"author":59,"featured_media":183923,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[47050],"tags":[111],"class_list":["post-183423","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-top-14","tag-top-14"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Top 14 : L&#039;immanquable de la 12\u00e8me journ\u00e9e<\/title>\n<meta name=\"description\" content=\"TOP 14 2021-2022 -\u00a0 Le choc au sommet a tourn\u00e9 \u00e0 l&#039;avantage de l&#039;Union Bordeaux-B\u00e8gles. L&#039;immanquable de la 12\u00e8me journ\u00e9e.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/top-14-immanquable-de-la-12eme-journee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Top 14 : L&#039;immanquable de la 12\u00e8me journ\u00e9e\" \/>\n<meta property=\"og:description\" content=\"TOP 14 2021-2022 -\u00a0 Le choc au sommet a tourn\u00e9 \u00e0 l&#039;avantage de l&#039;Union Bordeaux-B\u00e8gles. L&#039;immanquable de la 12\u00e8me journ\u00e9e.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/top-14-immanquable-de-la-12eme-journee\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-06T08:47:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/Top-14-Limmanquable-de-la-12eme-journee.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Top 14 : L&#039;immanquable de la 12\u00e8me journ\u00e9e\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-immanquable-de-la-12eme-journee\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-immanquable-de-la-12eme-journee\\\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Top 14 : L&rsquo;immanquable de la 12\u00e8me journ\u00e9e\",\"datePublished\":\"2021-12-06T08:47:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-immanquable-de-la-12eme-journee\\\/\"},\"wordCount\":1304,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-immanquable-de-la-12eme-journee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Top-14-Limmanquable-de-la-12eme-journee.png\",\"keywords\":[\"Top 14\"],\"articleSection\":[\"Top 14\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-immanquable-de-la-12eme-journee\\\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-immanquable-de-la-12eme-journee\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-immanquable-de-la-12eme-journee\\\/\",\"name\":\"Top 14 : L'immanquable de la 12\u00e8me journ\u00e9e\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-immanquable-de-la-12eme-journee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-immanquable-de-la-12eme-journee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Top-14-Limmanquable-de-la-12eme-journee.png\",\"datePublished\":\"2021-12-06T08:47:56+00:00\",\"description\":\"TOP 14 2021-2022 -\u00a0 Le choc au sommet a tourn\u00e9 \u00e0 l'avantage de l'Union Bordeaux-B\u00e8gles. L'immanquable de la 12\u00e8me journ\u00e9e.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-immanquable-de-la-12eme-journee\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-immanquable-de-la-12eme-journee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-immanquable-de-la-12eme-journee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Top-14-Limmanquable-de-la-12eme-journee.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Top-14-Limmanquable-de-la-12eme-journee.png\",\"width\":800,\"height\":445,\"caption\":\"Top 14 L'immanquable de la 12\u00e8me journ\u00e9e\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-immanquable-de-la-12eme-journee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Top 14 : L&rsquo;immanquable de la 12\u00e8me journ\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sebastien.gente\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sebgente\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/sbastien-gente-a29583169\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sebastiengente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Top 14 : L'immanquable de la 12\u00e8me journ\u00e9e","description":"TOP 14 2021-2022 -\u00a0 Le choc au sommet a tourn\u00e9 \u00e0 l'avantage de l'Union Bordeaux-B\u00e8gles. L'immanquable de la 12\u00e8me journ\u00e9e.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/top-14-immanquable-de-la-12eme-journee\/","og_locale":"fr_FR","og_type":"article","og_title":"Top 14 : L'immanquable de la 12\u00e8me journ\u00e9e","og_description":"TOP 14 2021-2022 -\u00a0 Le choc au sommet a tourn\u00e9 \u00e0 l'avantage de l'Union Bordeaux-B\u00e8gles. L'immanquable de la 12\u00e8me journ\u00e9e.","og_url":"https:\/\/dicodusport.fr\/blog\/top-14-immanquable-de-la-12eme-journee\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2021-12-06T08:47:56+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/Top-14-Limmanquable-de-la-12eme-journee.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Top 14 : L'immanquable de la 12\u00e8me journ\u00e9e","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/top-14-immanquable-de-la-12eme-journee\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-immanquable-de-la-12eme-journee\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Top 14 : L&rsquo;immanquable de la 12\u00e8me journ\u00e9e","datePublished":"2021-12-06T08:47:56+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-immanquable-de-la-12eme-journee\/"},"wordCount":1304,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-immanquable-de-la-12eme-journee\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/Top-14-Limmanquable-de-la-12eme-journee.png","keywords":["Top 14"],"articleSection":["Top 14"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/top-14-immanquable-de-la-12eme-journee\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/top-14-immanquable-de-la-12eme-journee\/","url":"https:\/\/dicodusport.fr\/blog\/top-14-immanquable-de-la-12eme-journee\/","name":"Top 14 : L'immanquable de la 12\u00e8me journ\u00e9e","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-immanquable-de-la-12eme-journee\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-immanquable-de-la-12eme-journee\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/Top-14-Limmanquable-de-la-12eme-journee.png","datePublished":"2021-12-06T08:47:56+00:00","description":"TOP 14 2021-2022 -\u00a0 Le choc au sommet a tourn\u00e9 \u00e0 l'avantage de l'Union Bordeaux-B\u00e8gles. L'immanquable de la 12\u00e8me journ\u00e9e.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-immanquable-de-la-12eme-journee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/top-14-immanquable-de-la-12eme-journee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/top-14-immanquable-de-la-12eme-journee\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/Top-14-Limmanquable-de-la-12eme-journee.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/Top-14-Limmanquable-de-la-12eme-journee.png","width":800,"height":445,"caption":"Top 14 L'immanquable de la 12\u00e8me journ\u00e9e"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/top-14-immanquable-de-la-12eme-journee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Top 14 : L&rsquo;immanquable de la 12\u00e8me journ\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/183423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=183423"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/183423\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/183923"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=183423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=183423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=183423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}