{"id":184370,"date":"2021-12-09T08:05:10","date_gmt":"2021-12-09T07:05:10","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=184370"},"modified":"2021-12-09T08:04:20","modified_gmt":"2021-12-09T07:04:20","slug":"9-decembre-2001-yamna-belkacem-championne-d-europe","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/9-decembre-2001-yamna-belkacem-championne-d-europe\/","title":{"rendered":"9 d\u00e9cembre 2001 : Yamna Belkacem, championne d\u2019Europe"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong><a href=\"https:\/\/dicodusport.fr\/definition-sport\/athletisme\/\">ATHLETISME<\/a> &#8211; Avant ce jour de d\u00e9cembre 2001, Yamna Belkacem -maintenant Oubouhou- est mont\u00e9e \u00e0 trois reprises sur le podium des Championnats d\u2019Europe de cross. Seulement \u00e0 chaque fois, c\u2019\u00e9tait par \u00e9quipe. Maintenant, c\u2019est en individuel \u00e9galement.<\/strong> <\/em><\/p>\n<h2>\u00c7a s&rsquo;est pass\u00e9 le 9 d\u00e9cembre 2001<\/h2>\n<p style=\"text-align: justify;\">Elle est all\u00e9e la chercher celle-l\u00e0\u00a0! Pour son premier podium europ\u00e9en en individuel, <strong>Yamna Belkacem<\/strong> a grimp\u00e9 directement sur la plus haute marche. Septi\u00e8me de la comp\u00e9tition en 1997, sixi\u00e8me l\u2019ann\u00e9e suivante, c\u2019est maintenant la premi\u00e8re place pour l\u2019athl\u00e8te tricolore. Parfaitement plac\u00e9e lors des deux premiers tours, elle a fait la diff\u00e9rence sur le troisi\u00e8me -et dernier-. Accompagn\u00e9e par <strong>Olga Romanova<\/strong>, suivie de pr\u00e8s par <strong>Justyna Bak<\/strong>, la Meldoise se d\u00e9fait d\u2019abord de cette derni\u00e8re. Reste la Russe. <strong>Yamna Belkacem<\/strong> fournit alors son effort pour un sprint avec <strong>Romanova<\/strong>. Et pour une petite seconde, c\u2019est bien la Fran\u00e7aise qui s\u2019impose. En 15 min 48, elle a boucl\u00e9 les quelques 4\u00a0600 m\u00e8tres, comptez 15 min 49 donc pour la Russe. La Polonaise <strong>Justyna Bak<\/strong> prend le bronze en 15 min 51. Quatre ans apr\u00e8s <strong>Joalsiae Llado<\/strong>, <strong>Yamna Belkacem<\/strong> devient quant \u00e0 elle la seconde Fran\u00e7aise championne d\u2019Europe de cross.<\/p>\n<p style=\"text-align: justify;\"><strong>Info\u00a0<\/strong>: Avec ce titre continental, <strong>Yamna Belkacem<\/strong> est repartie de Suisse avec une m\u00e9daille de bronze, acquise en \u00e9quipe.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 9 d\u00e9cembre 2001, Yamna Belkacem devenait la seconde Fran\u00e7aise championne d&rsquo;Europe de cross apr\u00e8s un sprint victorieux en Suisse.<\/p>\n","protected":false},"author":18,"featured_media":184373,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2308,8],"tags":[143,8481],"class_list":["post-184370","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-athletisme","category-histoire","tag-athletisme","tag-histoire"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>9 d\u00e9cembre 2001 : Yamna Belkacem, championne d\u2019Europe<\/title>\n<meta name=\"description\" content=\"Le 9 d\u00e9cembre 2001, Yamna Belkacem devenait la seconde Fran\u00e7aise championne d&#039;Europe de cross apr\u00e8s un sprint victorieux en Suisse.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/9-decembre-2001-yamna-belkacem-championne-d-europe\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"9 d\u00e9cembre 2001 : Yamna Belkacem, championne d\u2019Europe\" \/>\n<meta property=\"og:description\" content=\"Le 9 d\u00e9cembre 2001, Yamna Belkacem devenait la seconde Fran\u00e7aise championne d&#039;Europe de cross apr\u00e8s un sprint victorieux en Suisse.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/9-decembre-2001-yamna-belkacem-championne-d-europe\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/soocube\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-09T07:05:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/9-decembre-2001-Yamna-Belkacem-championne-dEurope.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sophie Clapier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"9 d\u00e9cembre 2001 : Yamna Belkacem, championne d\u2019Europe\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/soocube\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/9-decembre-2001-yamna-belkacem-championne-d-europe\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/9-decembre-2001-yamna-belkacem-championne-d-europe\/\"},\"author\":{\"name\":\"Sophie Clapier\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9\"},\"headline\":\"9 d\u00e9cembre 2001 : Yamna Belkacem, championne d\u2019Europe\",\"datePublished\":\"2021-12-09T07:05:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/9-decembre-2001-yamna-belkacem-championne-d-europe\/\"},\"wordCount\":238,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/9-decembre-2001-yamna-belkacem-championne-d-europe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/9-decembre-2001-Yamna-Belkacem-championne-dEurope.png\",\"keywords\":[\"Athl\u00e9tisme\",\"histoire\"],\"articleSection\":[\"Athl\u00e9tisme\",\"Histoire\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/9-decembre-2001-yamna-belkacem-championne-d-europe\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/9-decembre-2001-yamna-belkacem-championne-d-europe\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/9-decembre-2001-yamna-belkacem-championne-d-europe\/\",\"name\":\"9 d\u00e9cembre 2001 : Yamna Belkacem, championne d\u2019Europe\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/9-decembre-2001-yamna-belkacem-championne-d-europe\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/9-decembre-2001-yamna-belkacem-championne-d-europe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/9-decembre-2001-Yamna-Belkacem-championne-dEurope.png\",\"datePublished\":\"2021-12-09T07:05:10+00:00\",\"description\":\"Le 9 d\u00e9cembre 2001, Yamna Belkacem devenait la seconde Fran\u00e7aise championne d'Europe de cross apr\u00e8s un sprint victorieux en Suisse.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/9-decembre-2001-yamna-belkacem-championne-d-europe\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/9-decembre-2001-yamna-belkacem-championne-d-europe\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/9-decembre-2001-yamna-belkacem-championne-d-europe\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/9-decembre-2001-Yamna-Belkacem-championne-dEurope.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/9-decembre-2001-Yamna-Belkacem-championne-dEurope.png\",\"width\":800,\"height\":445,\"caption\":\"9 d\u00e9cembre 2001 Yamna Belkacem, championne d\u2019Europe\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/9-decembre-2001-yamna-belkacem-championne-d-europe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"9 d\u00e9cembre 2001 : Yamna Belkacem, championne d\u2019Europe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9\",\"name\":\"Sophie Clapier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg\",\"caption\":\"Sophie Clapier\"},\"description\":\"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.\",\"sameAs\":[\"https:\/\/www.facebook.com\/soocube\",\"https:\/\/x.com\/https:\/\/twitter.com\/soocube\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sophie\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"9 d\u00e9cembre 2001 : Yamna Belkacem, championne d\u2019Europe","description":"Le 9 d\u00e9cembre 2001, Yamna Belkacem devenait la seconde Fran\u00e7aise championne d'Europe de cross apr\u00e8s un sprint victorieux en Suisse.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/9-decembre-2001-yamna-belkacem-championne-d-europe\/","og_locale":"fr_FR","og_type":"article","og_title":"9 d\u00e9cembre 2001 : Yamna Belkacem, championne d\u2019Europe","og_description":"Le 9 d\u00e9cembre 2001, Yamna Belkacem devenait la seconde Fran\u00e7aise championne d'Europe de cross apr\u00e8s un sprint victorieux en Suisse.","og_url":"https:\/\/dicodusport.fr\/blog\/9-decembre-2001-yamna-belkacem-championne-d-europe\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/soocube","article_published_time":"2021-12-09T07:05:10+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/9-decembre-2001-Yamna-Belkacem-championne-dEurope.png","type":"image\/png"}],"author":"Sophie Clapier","twitter_card":"summary_large_image","twitter_title":"9 d\u00e9cembre 2001 : Yamna Belkacem, championne d\u2019Europe","twitter_creator":"@https:\/\/twitter.com\/soocube","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/9-decembre-2001-yamna-belkacem-championne-d-europe\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/9-decembre-2001-yamna-belkacem-championne-d-europe\/"},"author":{"name":"Sophie Clapier","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9"},"headline":"9 d\u00e9cembre 2001 : Yamna Belkacem, championne d\u2019Europe","datePublished":"2021-12-09T07:05:10+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/9-decembre-2001-yamna-belkacem-championne-d-europe\/"},"wordCount":238,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/9-decembre-2001-yamna-belkacem-championne-d-europe\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/9-decembre-2001-Yamna-Belkacem-championne-dEurope.png","keywords":["Athl\u00e9tisme","histoire"],"articleSection":["Athl\u00e9tisme","Histoire"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/9-decembre-2001-yamna-belkacem-championne-d-europe\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/9-decembre-2001-yamna-belkacem-championne-d-europe\/","url":"https:\/\/dicodusport.fr\/blog\/9-decembre-2001-yamna-belkacem-championne-d-europe\/","name":"9 d\u00e9cembre 2001 : Yamna Belkacem, championne d\u2019Europe","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/9-decembre-2001-yamna-belkacem-championne-d-europe\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/9-decembre-2001-yamna-belkacem-championne-d-europe\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/9-decembre-2001-Yamna-Belkacem-championne-dEurope.png","datePublished":"2021-12-09T07:05:10+00:00","description":"Le 9 d\u00e9cembre 2001, Yamna Belkacem devenait la seconde Fran\u00e7aise championne d'Europe de cross apr\u00e8s un sprint victorieux en Suisse.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/9-decembre-2001-yamna-belkacem-championne-d-europe\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/9-decembre-2001-yamna-belkacem-championne-d-europe\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/9-decembre-2001-yamna-belkacem-championne-d-europe\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/9-decembre-2001-Yamna-Belkacem-championne-dEurope.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/9-decembre-2001-Yamna-Belkacem-championne-dEurope.png","width":800,"height":445,"caption":"9 d\u00e9cembre 2001 Yamna Belkacem, championne d\u2019Europe"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/9-decembre-2001-yamna-belkacem-championne-d-europe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"9 d\u00e9cembre 2001 : Yamna Belkacem, championne d\u2019Europe"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9","name":"Sophie Clapier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","caption":"Sophie Clapier"},"description":"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.","sameAs":["https:\/\/www.facebook.com\/soocube","https:\/\/x.com\/https:\/\/twitter.com\/soocube","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/sophie\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/184370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=184370"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/184370\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/184373"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=184370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=184370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=184370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}