{"id":186179,"date":"2021-12-17T14:26:23","date_gmt":"2021-12-17T13:26:23","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=186179&#038;preview=true&#038;preview_id=186179"},"modified":"2021-12-17T15:08:00","modified_gmt":"2021-12-17T14:08:00","slug":"champions-cup-les-clubs-francais-n-affronteront-pas-les-equipe-britanniques-ce-week-end","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/champions-cup-les-clubs-francais-n-affronteront-pas-les-equipe-britanniques-ce-week-end\/","title":{"rendered":"Champions Cup : Les clubs fran\u00e7ais n&rsquo;affronteront pas les \u00e9quipes britanniques ce week-end"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em><a href=\"https:\/\/dicodusport.fr\/blog\/champions-cup-2021-2022-calendrier-resultats-et-classements\/\">CHAMPIONS CUP 2021-2022<\/a> &#8211; C&rsquo;est d\u00e9sormais une certitude : les rencontres de Coupe d&rsquo;Europe entre clubs fran\u00e7ais et britanniques n&rsquo;auront pas lieu ce week-end. Les 2\u00e8mes journ\u00e9es de Challenge Cup et Champions Cup seront donc largement tronqu\u00e9es.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">L&rsquo;EPCR vient de le confirmer. Les rencontres de Coupe d&rsquo;Europe entre club fran\u00e7ais et britanniques n&rsquo;auront pas lieu ce week-end. Cela vaut donc pour les deuxi\u00e8mes journ\u00e9es des deux comp\u00e9titions europ\u00e9ennes, la <strong>Champions Cup<\/strong> et la<strong> Challenge Cup<\/strong>. L&rsquo;organisme europ\u00e9en annonce \u00e9galement vouloir reporter ces rencontres \u00e0 une date ult\u00e9rieure. Reste \u00e0 savoir quand, car les troisi\u00e8me et quatri\u00e8me journ\u00e9es des comp\u00e9titions europ\u00e9ennes sont pr\u00e9vues en janvier, avant le 6 Nations.<\/p>\n<h2 style=\"text-align: justify;\">Le communiqu\u00e9 de l&rsquo;EPCR<\/h2>\n<blockquote><p>Il s\u2019agit d\u2019une cons\u00e9quence des nouvelles restrictions de d\u00e9placement entre le Royaume-Uni et la France qui ont \u00e9t\u00e9 mises en place par le gouvernement fran\u00e7ais.<\/p><\/blockquote>\n<blockquote><p>Le Conseil d\u2019administration a re\u00e7u des briefings des trois ligues professionnelles contenant des informations de la part des gouvernements respectifs. Cependant, il n\u2019y avait pas suffisamment de garanties que ces matchs ne pr\u00e9senteraient pas de risque.<\/p><\/blockquote>\n<h2 style=\"text-align: justify;\"><strong>Les matchs annul\u00e9s<\/strong><\/h2>\n<p><strong>CHAMPIONS CUP<\/strong><\/p>\n<p>Bath \u2013 Stade Rochelais<br \/>\nSale Sharks \u2013 ASM Clermont<br \/>\nScarlets \u2013 Union Bordeaux-B\u00e8gles<br \/>\nStade Toulousain \u2013 Wasps<br \/>\nStade Fran\u00e7ais \u2013 Bristol Bears<\/p>\n<p><strong>CHALLENGE CUP<\/strong><\/p>\n<p>Worcester Warriors \u2013 Biarritz Olympique<br \/>\nLondon Irish \u2013 Brive<\/p>\n<p style=\"text-align: justify;\">Par cons\u00e9quent, seul le <strong>LOU<\/strong> \u00e0 Newport et <strong>Toulon<\/strong> face au Z\u00e8bre joueront ce vendredi soir en Challenge Cup. <strong>Castres<\/strong> sera le seul club fran\u00e7ais sur le terrain en Champions Cup, les Tarnais se d\u00e9pla\u00e7ant au Munster samedi soir.<\/p>\n<p><span class=\"TX93Lj\"><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"6KloYco5NP\"><p><a href=\"https:\/\/www.epcrugby.com\/2021\/12\/17\/communique-de-lepcr-matchs-de-la-journee-2\/\">Communiqu\u00e9 de l\u2019EPCR \u2013 matchs de la Journ\u00e9e 2<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;Communiqu\u00e9 de l\u2019EPCR \u2013 matchs de la Journ\u00e9e 2&#8221; &#8212; European Professional Club Rugby\" src=\"https:\/\/www.epcrugby.com\/2021\/12\/17\/communique-de-lepcr-matchs-de-la-journee-2\/embed\/#?secret=6KloYco5NP\" data-secret=\"6KloYco5NP\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CHAMPIONS CUP 2021-2022 &#8211; C&rsquo;est d\u00e9sormais une certitude : les rencontres de Coupe d&rsquo;Europe entre clubs fran\u00e7ais et britanniques n&rsquo;auront pas lieu ce week-end. Les 2\u00e8mes journ\u00e9es de Challenge Cup et Champions Cup seront donc largement tronqu\u00e9es.<\/p>\n","protected":false},"author":4,"featured_media":185115,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[47051],"tags":[2823],"class_list":["post-186179","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-champions-cup","tag-champions-cup"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Champions Cup : Les clubs fran\u00e7ais n&#039;affronteront pas les \u00e9quipes britanniques ce week-end<\/title>\n<meta name=\"description\" content=\"CHAMPIONS CUP 2021-2022 - Les rencontres de Coupe d&#039;Europe entre clubs fran\u00e7ais et britanniques n&#039;auront pas lieu ce week-end.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/champions-cup-les-clubs-francais-n-affronteront-pas-les-equipe-britanniques-ce-week-end\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Champions Cup : Les clubs fran\u00e7ais n&#039;affronteront pas les \u00e9quipes britanniques ce week-end\" \/>\n<meta property=\"og:description\" content=\"CHAMPIONS CUP 2021-2022 - Les rencontres de Coupe d&#039;Europe entre clubs fran\u00e7ais et britanniques n&#039;auront pas lieu ce week-end.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/champions-cup-les-clubs-francais-n-affronteront-pas-les-equipe-britanniques-ce-week-end\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-17T13:26:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-17T14:08:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/Champions-Cup-LUnion-Bordeaux-Begles-chute-dentree-face-a-Leicester.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Champions Cup : Les clubs fran\u00e7ais n&#039;affronteront pas les \u00e9quipes britanniques ce week-end\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/champions-cup-les-clubs-francais-n-affronteront-pas-les-equipe-britanniques-ce-week-end\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/champions-cup-les-clubs-francais-n-affronteront-pas-les-equipe-britanniques-ce-week-end\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Champions Cup : Les clubs fran\u00e7ais n&rsquo;affronteront pas les \u00e9quipes britanniques ce week-end\",\"datePublished\":\"2021-12-17T13:26:23+00:00\",\"dateModified\":\"2021-12-17T14:08:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/champions-cup-les-clubs-francais-n-affronteront-pas-les-equipe-britanniques-ce-week-end\/\"},\"wordCount\":301,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/champions-cup-les-clubs-francais-n-affronteront-pas-les-equipe-britanniques-ce-week-end\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/Champions-Cup-LUnion-Bordeaux-Begles-chute-dentree-face-a-Leicester.png\",\"keywords\":[\"Champions Cup\"],\"articleSection\":[\"Champions Cup\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/champions-cup-les-clubs-francais-n-affronteront-pas-les-equipe-britanniques-ce-week-end\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/champions-cup-les-clubs-francais-n-affronteront-pas-les-equipe-britanniques-ce-week-end\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/champions-cup-les-clubs-francais-n-affronteront-pas-les-equipe-britanniques-ce-week-end\/\",\"name\":\"Champions Cup : Les clubs fran\u00e7ais n'affronteront pas les \u00e9quipes britanniques ce week-end\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/champions-cup-les-clubs-francais-n-affronteront-pas-les-equipe-britanniques-ce-week-end\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/champions-cup-les-clubs-francais-n-affronteront-pas-les-equipe-britanniques-ce-week-end\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/Champions-Cup-LUnion-Bordeaux-Begles-chute-dentree-face-a-Leicester.png\",\"datePublished\":\"2021-12-17T13:26:23+00:00\",\"dateModified\":\"2021-12-17T14:08:00+00:00\",\"description\":\"CHAMPIONS CUP 2021-2022 - Les rencontres de Coupe d'Europe entre clubs fran\u00e7ais et britanniques n'auront pas lieu ce week-end.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/champions-cup-les-clubs-francais-n-affronteront-pas-les-equipe-britanniques-ce-week-end\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/champions-cup-les-clubs-francais-n-affronteront-pas-les-equipe-britanniques-ce-week-end\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/champions-cup-les-clubs-francais-n-affronteront-pas-les-equipe-britanniques-ce-week-end\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/Champions-Cup-LUnion-Bordeaux-Begles-chute-dentree-face-a-Leicester.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/Champions-Cup-LUnion-Bordeaux-Begles-chute-dentree-face-a-Leicester.png\",\"width\":800,\"height\":445,\"caption\":\"Champions Cup L'Union Bordeaux-B\u00e8gles chute d'entr\u00e9e face \u00e0 Leicester\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/champions-cup-les-clubs-francais-n-affronteront-pas-les-equipe-britanniques-ce-week-end\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Champions Cup : Les clubs fran\u00e7ais n&rsquo;affronteront pas les \u00e9quipes britanniques ce week-end\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Champions Cup : Les clubs fran\u00e7ais n'affronteront pas les \u00e9quipes britanniques ce week-end","description":"CHAMPIONS CUP 2021-2022 - Les rencontres de Coupe d'Europe entre clubs fran\u00e7ais et britanniques n'auront pas lieu ce week-end.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/champions-cup-les-clubs-francais-n-affronteront-pas-les-equipe-britanniques-ce-week-end\/","og_locale":"fr_FR","og_type":"article","og_title":"Champions Cup : Les clubs fran\u00e7ais n'affronteront pas les \u00e9quipes britanniques ce week-end","og_description":"CHAMPIONS CUP 2021-2022 - Les rencontres de Coupe d'Europe entre clubs fran\u00e7ais et britanniques n'auront pas lieu ce week-end.","og_url":"https:\/\/dicodusport.fr\/blog\/champions-cup-les-clubs-francais-n-affronteront-pas-les-equipe-britanniques-ce-week-end\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2021-12-17T13:26:23+00:00","article_modified_time":"2021-12-17T14:08:00+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/Champions-Cup-LUnion-Bordeaux-Begles-chute-dentree-face-a-Leicester.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Champions Cup : Les clubs fran\u00e7ais n'affronteront pas les \u00e9quipes britanniques ce week-end","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/champions-cup-les-clubs-francais-n-affronteront-pas-les-equipe-britanniques-ce-week-end\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/champions-cup-les-clubs-francais-n-affronteront-pas-les-equipe-britanniques-ce-week-end\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Champions Cup : Les clubs fran\u00e7ais n&rsquo;affronteront pas les \u00e9quipes britanniques ce week-end","datePublished":"2021-12-17T13:26:23+00:00","dateModified":"2021-12-17T14:08:00+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/champions-cup-les-clubs-francais-n-affronteront-pas-les-equipe-britanniques-ce-week-end\/"},"wordCount":301,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/champions-cup-les-clubs-francais-n-affronteront-pas-les-equipe-britanniques-ce-week-end\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/Champions-Cup-LUnion-Bordeaux-Begles-chute-dentree-face-a-Leicester.png","keywords":["Champions Cup"],"articleSection":["Champions Cup"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/champions-cup-les-clubs-francais-n-affronteront-pas-les-equipe-britanniques-ce-week-end\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/champions-cup-les-clubs-francais-n-affronteront-pas-les-equipe-britanniques-ce-week-end\/","url":"https:\/\/dicodusport.fr\/blog\/champions-cup-les-clubs-francais-n-affronteront-pas-les-equipe-britanniques-ce-week-end\/","name":"Champions Cup : Les clubs fran\u00e7ais n'affronteront pas les \u00e9quipes britanniques ce week-end","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/champions-cup-les-clubs-francais-n-affronteront-pas-les-equipe-britanniques-ce-week-end\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/champions-cup-les-clubs-francais-n-affronteront-pas-les-equipe-britanniques-ce-week-end\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/Champions-Cup-LUnion-Bordeaux-Begles-chute-dentree-face-a-Leicester.png","datePublished":"2021-12-17T13:26:23+00:00","dateModified":"2021-12-17T14:08:00+00:00","description":"CHAMPIONS CUP 2021-2022 - Les rencontres de Coupe d'Europe entre clubs fran\u00e7ais et britanniques n'auront pas lieu ce week-end.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/champions-cup-les-clubs-francais-n-affronteront-pas-les-equipe-britanniques-ce-week-end\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/champions-cup-les-clubs-francais-n-affronteront-pas-les-equipe-britanniques-ce-week-end\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/champions-cup-les-clubs-francais-n-affronteront-pas-les-equipe-britanniques-ce-week-end\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/Champions-Cup-LUnion-Bordeaux-Begles-chute-dentree-face-a-Leicester.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/Champions-Cup-LUnion-Bordeaux-Begles-chute-dentree-face-a-Leicester.png","width":800,"height":445,"caption":"Champions Cup L'Union Bordeaux-B\u00e8gles chute d'entr\u00e9e face \u00e0 Leicester"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/champions-cup-les-clubs-francais-n-affronteront-pas-les-equipe-britanniques-ce-week-end\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Champions Cup : Les clubs fran\u00e7ais n&rsquo;affronteront pas les \u00e9quipes britanniques ce week-end"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/186179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=186179"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/186179\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/185115"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=186179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=186179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=186179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}