{"id":187189,"date":"2021-12-22T08:00:37","date_gmt":"2021-12-22T07:00:37","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=187189"},"modified":"2021-12-22T07:19:55","modified_gmt":"2021-12-22T06:19:55","slug":"22-decembre-2001-deuxieme-ceinture-pour-bruno-girard","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/22-decembre-2001-deuxieme-ceinture-pour-bruno-girard\/","title":{"rendered":"22 d\u00e9cembre 2001 : Deuxi\u00e8me ceinture pour Bruno Girard"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong><a href=\"https:\/\/dicodusport.fr\/definition-sport\/boxe\/\">BOXE<\/a> &#8211; Champion du monde WBA des super-moyens l\u2019ann\u00e9e pr\u00e9c\u00e9dente, Bruno Girard a rendez-vous en ce 22 d\u00e9cembre 2001 pour un nouveau titre, chez les mi-lourds cette fois. Un combat en sens unique pour le Fran\u00e7ais.<\/strong><\/em><\/p>\n<h2 style=\"text-align: justify;\">\u00c7a s&rsquo;est pass\u00e9 le 22 d\u00e9cembre 2001<\/h2>\n<p style=\"text-align: justify;\">Aout 2000, le combat pour le titre mondial des mi-lourds entre <strong>Bruno Girard<\/strong> et <strong>Lou Del Valle<\/strong> ne trouve pas son vainqueur. Qu\u2019\u00e0 cela ne tienne, une nouvelle rencontre est organis\u00e9e \u00e0 Orl\u00e9ans entre les deux boxeurs un an plus tard. Cependant, <strong>Del Valle<\/strong> d\u00e9clare forfait, c\u2019est un autre Am\u00e9ricain, <strong>Robert Koon<\/strong>, qui se pr\u00e9sente contre le Fran\u00e7ais. Mais <strong>Koon<\/strong> ne vaut pas <strong>Del Valle<\/strong>, il n\u2019y a pas vraiment match. La vitesse de <strong>Bruno Girard<\/strong> lui permet d\u2019encha\u00eener les coups. Son adversaire, lui, a bien du mal \u00e0 faire mouche. C\u2019est simple, toutes les reprises sont donn\u00e9es au Bl\u00e9sois. Avant le 10<sup>\u00e8me<\/sup> round, l\u2019Am\u00e9ricain a le nez en sang. A la onzi\u00e8me, l\u2019arbitre arr\u00eate le combat apr\u00e8s un encha\u00eenement de <strong>Bruno Girard<\/strong> sur <strong>Del Valle<\/strong>. Avec cette seconde ceinture mondiale, <strong>Bruno Girard<\/strong> rejoint <strong>Fabrice Tiozzo<\/strong> et devient le deuxi\u00e8me boxeur tricolore \u00e0 s&rsquo;imposer dans deux cat\u00e9gories diff\u00e9rentes.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Info\u00a0: <strong>Bruno Girard<\/strong> perd cette ceinture des mi-lourds en mars 2003, au profit de Medhi Sahnoune.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BOXE &#8211; Champion du monde WBA des super-moyens l\u2019ann\u00e9e pr\u00e9c\u00e9dente, Bruno Girard a rendez-vous en ce 22 d\u00e9cembre 2001 pour un nouveau titre, chez les mi-lourds cette fois. Un combat en sens unique pour le Fran\u00e7ais.<\/p>\n","protected":false},"author":18,"featured_media":187194,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8672,8],"tags":[622,8481,4291],"class_list":["post-187189","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boxe","category-histoire","tag-boxe","tag-histoire","tag-wba"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>22 d\u00e9cembre 2001 : Deuxi\u00e8me ceinture pour Bruno Girard<\/title>\n<meta name=\"description\" content=\"Le 22 d\u00e9cembre 2001, Bruno Girard d\u00e9crochait la ceinture WBA des mi-lourds, un an apr\u00e8s son sacre dans la cat\u00e9gorie des super-moyens.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/22-decembre-2001-deuxieme-ceinture-pour-bruno-girard\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"22 d\u00e9cembre 2001 : Deuxi\u00e8me ceinture pour Bruno Girard\" \/>\n<meta property=\"og:description\" content=\"Le 22 d\u00e9cembre 2001, Bruno Girard d\u00e9crochait la ceinture WBA des mi-lourds, un an apr\u00e8s son sacre dans la cat\u00e9gorie des super-moyens.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/22-decembre-2001-deuxieme-ceinture-pour-bruno-girard\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/soocube\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-22T07:00:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/22-decembre-2001-Deuxieme-ceinture-pour-Bruno-Girard.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sophie Clapier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"22 d\u00e9cembre 2001 : Deuxi\u00e8me ceinture pour Bruno Girard\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/soocube\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/22-decembre-2001-deuxieme-ceinture-pour-bruno-girard\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/22-decembre-2001-deuxieme-ceinture-pour-bruno-girard\\\/\"},\"author\":{\"name\":\"Sophie Clapier\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/416c975648aca9da8839bdfe333a21c9\"},\"headline\":\"22 d\u00e9cembre 2001 : Deuxi\u00e8me ceinture pour Bruno Girard\",\"datePublished\":\"2021-12-22T07:00:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/22-decembre-2001-deuxieme-ceinture-pour-bruno-girard\\\/\"},\"wordCount\":239,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/22-decembre-2001-deuxieme-ceinture-pour-bruno-girard\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/22-decembre-2001-Deuxieme-ceinture-pour-Bruno-Girard.png\",\"keywords\":[\"boxe\",\"histoire\",\"WBA\"],\"articleSection\":[\"Boxe\",\"Histoire\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/22-decembre-2001-deuxieme-ceinture-pour-bruno-girard\\\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/22-decembre-2001-deuxieme-ceinture-pour-bruno-girard\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/22-decembre-2001-deuxieme-ceinture-pour-bruno-girard\\\/\",\"name\":\"22 d\u00e9cembre 2001 : Deuxi\u00e8me ceinture pour Bruno Girard\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/22-decembre-2001-deuxieme-ceinture-pour-bruno-girard\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/22-decembre-2001-deuxieme-ceinture-pour-bruno-girard\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/22-decembre-2001-Deuxieme-ceinture-pour-Bruno-Girard.png\",\"datePublished\":\"2021-12-22T07:00:37+00:00\",\"description\":\"Le 22 d\u00e9cembre 2001, Bruno Girard d\u00e9crochait la ceinture WBA des mi-lourds, un an apr\u00e8s son sacre dans la cat\u00e9gorie des super-moyens.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/22-decembre-2001-deuxieme-ceinture-pour-bruno-girard\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/22-decembre-2001-deuxieme-ceinture-pour-bruno-girard\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/22-decembre-2001-deuxieme-ceinture-pour-bruno-girard\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/22-decembre-2001-Deuxieme-ceinture-pour-Bruno-Girard.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/22-decembre-2001-Deuxieme-ceinture-pour-Bruno-Girard.png\",\"width\":800,\"height\":445,\"caption\":\"22 d\u00e9cembre 2001 Deuxi\u00e8me ceinture pour Bruno Girard\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/22-decembre-2001-deuxieme-ceinture-pour-bruno-girard\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"22 d\u00e9cembre 2001 : Deuxi\u00e8me ceinture pour Bruno Girard\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/416c975648aca9da8839bdfe333a21c9\",\"name\":\"Sophie Clapier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"caption\":\"Sophie Clapier\"},\"description\":\"Journaliste\\\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\\\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/soocube\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/soocube\",\"admin\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sophie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"22 d\u00e9cembre 2001 : Deuxi\u00e8me ceinture pour Bruno Girard","description":"Le 22 d\u00e9cembre 2001, Bruno Girard d\u00e9crochait la ceinture WBA des mi-lourds, un an apr\u00e8s son sacre dans la cat\u00e9gorie des super-moyens.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/22-decembre-2001-deuxieme-ceinture-pour-bruno-girard\/","og_locale":"fr_FR","og_type":"article","og_title":"22 d\u00e9cembre 2001 : Deuxi\u00e8me ceinture pour Bruno Girard","og_description":"Le 22 d\u00e9cembre 2001, Bruno Girard d\u00e9crochait la ceinture WBA des mi-lourds, un an apr\u00e8s son sacre dans la cat\u00e9gorie des super-moyens.","og_url":"https:\/\/dicodusport.fr\/blog\/22-decembre-2001-deuxieme-ceinture-pour-bruno-girard\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/soocube","article_published_time":"2021-12-22T07:00:37+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/22-decembre-2001-Deuxieme-ceinture-pour-Bruno-Girard.png","type":"image\/png"}],"author":"Sophie Clapier","twitter_card":"summary_large_image","twitter_title":"22 d\u00e9cembre 2001 : Deuxi\u00e8me ceinture pour Bruno Girard","twitter_creator":"@https:\/\/twitter.com\/soocube","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/22-decembre-2001-deuxieme-ceinture-pour-bruno-girard\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/22-decembre-2001-deuxieme-ceinture-pour-bruno-girard\/"},"author":{"name":"Sophie Clapier","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9"},"headline":"22 d\u00e9cembre 2001 : Deuxi\u00e8me ceinture pour Bruno Girard","datePublished":"2021-12-22T07:00:37+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/22-decembre-2001-deuxieme-ceinture-pour-bruno-girard\/"},"wordCount":239,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/22-decembre-2001-deuxieme-ceinture-pour-bruno-girard\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/22-decembre-2001-Deuxieme-ceinture-pour-Bruno-Girard.png","keywords":["boxe","histoire","WBA"],"articleSection":["Boxe","Histoire"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/22-decembre-2001-deuxieme-ceinture-pour-bruno-girard\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/22-decembre-2001-deuxieme-ceinture-pour-bruno-girard\/","url":"https:\/\/dicodusport.fr\/blog\/22-decembre-2001-deuxieme-ceinture-pour-bruno-girard\/","name":"22 d\u00e9cembre 2001 : Deuxi\u00e8me ceinture pour Bruno Girard","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/22-decembre-2001-deuxieme-ceinture-pour-bruno-girard\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/22-decembre-2001-deuxieme-ceinture-pour-bruno-girard\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/22-decembre-2001-Deuxieme-ceinture-pour-Bruno-Girard.png","datePublished":"2021-12-22T07:00:37+00:00","description":"Le 22 d\u00e9cembre 2001, Bruno Girard d\u00e9crochait la ceinture WBA des mi-lourds, un an apr\u00e8s son sacre dans la cat\u00e9gorie des super-moyens.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/22-decembre-2001-deuxieme-ceinture-pour-bruno-girard\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/22-decembre-2001-deuxieme-ceinture-pour-bruno-girard\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/22-decembre-2001-deuxieme-ceinture-pour-bruno-girard\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/22-decembre-2001-Deuxieme-ceinture-pour-Bruno-Girard.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/12\/22-decembre-2001-Deuxieme-ceinture-pour-Bruno-Girard.png","width":800,"height":445,"caption":"22 d\u00e9cembre 2001 Deuxi\u00e8me ceinture pour Bruno Girard"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/22-decembre-2001-deuxieme-ceinture-pour-bruno-girard\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"22 d\u00e9cembre 2001 : Deuxi\u00e8me ceinture pour Bruno Girard"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9","name":"Sophie Clapier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","caption":"Sophie Clapier"},"description":"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.","sameAs":["https:\/\/www.facebook.com\/soocube","https:\/\/x.com\/https:\/\/twitter.com\/soocube","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/sophie\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/187189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=187189"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/187189\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/187194"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=187189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=187189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=187189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}