{"id":188428,"date":"2022-01-02T09:30:10","date_gmt":"2022-01-02T08:30:10","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=188428&#038;preview=true&#038;preview_id=188428"},"modified":"2022-01-02T15:14:25","modified_gmt":"2022-01-02T14:14:25","slug":"dakar-2022-autos-classement-1ere-etape-b","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/dakar-2022-autos-classement-1ere-etape-b\/","title":{"rendered":"Dakar 2022 Autos : Le classement de la 1\u00e8re \u00e9tape B"},"content":{"rendered":"<p style=\"text-align: justify;\"><b><i><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/sports-mecaniques\/dakar\/\" target=\"_blank\" rel=\"noopener noreferrer\">DAKAR<\/a> \u2013 D\u00e9couvrez le classement de la 1\u00e8re \u00e9tape B du Dakar 2022 dans la cat\u00e9gorie autos, qui s&rsquo;est disput\u00e9e ce dimanche 2 janvier autour de Hail.<\/i><\/b><\/p>\n<div class=\"su-table su-table-alternate\">\n<table style=\"width: 800px;border-collapse: collapse\" border=\"1\">\n<tbody>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\">&#x1f3c6;<\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>PILOTES<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>TEMPS<br \/>\n<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">1.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>&#x1f1f6;&#x1f1e6; Nasser AL-ATTIYAH \/ &#x1f1eb;&#x1f1f7; Mathieu BAUMEL<\/strong><br \/>\nTOYOTA GAZOO RACING<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">3h19m57s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">2.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>&#x1f1eb;&#x1f1f7; S\u00e9bastien LOEB \/ &#x1f1e7;&#x1f1ea; Fabian LURQUIN<\/strong><br \/>\nBAHRAIN RAID XTREME<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 12m07s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">3.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>&#x1f1e8;&#x1f1ff; Martin PROKOP \/ &#x1f1e8;&#x1f1ff; Viktor CHYTKA<\/strong><br \/>\nBENZINA ORLEN TEAM<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 21m21s<\/span><\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">4.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>&#x1f1e6;&#x1f1f7; Lucio ALVAREZ \/ &#x1f1ea;&#x1f1f8; Armand MONLEON<\/strong><br \/>\nOVERDRIVE TOYOTA<br \/>\n<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 26m31s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">5.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>&#x1f1f7;&#x1f1fa; Vladimir VASILYEV \/ &#x1f1f1;&#x1f1fb; Uleg UPERENKO<\/strong><br \/>\nVRT TEAM<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 27m52s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">6<\/span><span style=\"font-size: 0.9em\">.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>&#x1f1e6;&#x1f1f7; Sebastian HALPERN \/ &#x1f1e6;&#x1f1f7; Bernardo GRAUE<\/strong><br \/>\nX-RAID MINI JCW TEAM<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 28m16s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">7.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>&#x1f1ff;&#x1f1e6; Giniel DE VILLIERS \/ &#x1f1ff;&#x1f1e6; Dennis MURPHY<\/strong><br \/>\nTOYOTA GAZOO RACING<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 32m43s<\/span><\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">8.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>&#x1f1eb;&#x1f1f7; Guerlain CHICHERIT \/ &#x1f1eb;&#x1f1f7; Alex WINOCQ<\/strong><br \/>\nGCK MOTORSPORT<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 37m00s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">9.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>&#x1f1f5;&#x1f1f1; Jakub PRZYGONSKI \/ &#x1f1e9;&#x1f1ea; Timo GOTTSCHALK<\/strong><br \/>\nORLEN TEAM<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 40m50s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">10.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>&#x1f1f8;&#x1f1e6; Yazeed AL RAJHI \/ &#x1f1ec;&#x1f1e7; Michael ORR<\/strong><br \/>\nOVERDRIVE TOYOTA<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 42m53s<\/span><\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<h2><strong>\u00c0 lire aussi<\/strong><\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/www.dakar.com\/fr\/classements\/etape-1\/auto\"><strong>Le classement complet de la 1\u00e8re \u00e9tape B Autos<\/strong><\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/dakar-2022-autos-le-classement-general\/\"><strong>Le classement g\u00e9n\u00e9ral du Dakar 2022 Autos<\/strong><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>DAKAR \u2013 D\u00e9couvrez le classement de la 1\u00e8re \u00e9tape B du Dakar 2022 dans la cat\u00e9gorie autos, qui s&rsquo;est disput\u00e9e ce dimanche 2 janvier autour de Hail.<\/p>\n","protected":false},"author":4,"featured_media":188429,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[9493],"tags":[2736],"class_list":["post-188428","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dakar","tag-dakar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dakar 2022 Autos : Le classement de la 1\u00e8re \u00e9tape B<\/title>\n<meta name=\"description\" content=\"DAKAR \u2013 D\u00e9couvrez le classement de la 1\u00e8re \u00e9tape B du Dakar 2022 dans la cat\u00e9gorie autos, qui s&#039;est disput\u00e9e ce dimanche 2 janvier.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/dakar-2022-autos-classement-1ere-etape-b\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dakar 2022 Autos : Le classement de la 1\u00e8re \u00e9tape B\" \/>\n<meta property=\"og:description\" content=\"DAKAR \u2013 D\u00e9couvrez le classement de la 1\u00e8re \u00e9tape B du Dakar 2022 dans la cat\u00e9gorie autos, qui s&#039;est disput\u00e9e ce dimanche 2 janvier.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/dakar-2022-autos-classement-1ere-etape-b\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-02T08:30:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-02T14:14:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Dakar-2022-Autos-Le-classement-de-la-1ere-etape-B.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Dakar 2022 Autos : Le classement de la 1\u00e8re \u00e9tape B\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/dakar-2022-autos-classement-1ere-etape-b\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dakar-2022-autos-classement-1ere-etape-b\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Dakar 2022 Autos : Le classement de la 1\u00e8re \u00e9tape B\",\"datePublished\":\"2022-01-02T08:30:10+00:00\",\"dateModified\":\"2022-01-02T14:14:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dakar-2022-autos-classement-1ere-etape-b\/\"},\"wordCount\":275,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dakar-2022-autos-classement-1ere-etape-b\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Dakar-2022-Autos-Le-classement-de-la-1ere-etape-B.png\",\"keywords\":[\"dakar\"],\"articleSection\":[\"Dakar\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/dakar-2022-autos-classement-1ere-etape-b\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/dakar-2022-autos-classement-1ere-etape-b\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/dakar-2022-autos-classement-1ere-etape-b\/\",\"name\":\"Dakar 2022 Autos : Le classement de la 1\u00e8re \u00e9tape B\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dakar-2022-autos-classement-1ere-etape-b\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dakar-2022-autos-classement-1ere-etape-b\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Dakar-2022-Autos-Le-classement-de-la-1ere-etape-B.png\",\"datePublished\":\"2022-01-02T08:30:10+00:00\",\"dateModified\":\"2022-01-02T14:14:25+00:00\",\"description\":\"DAKAR \u2013 D\u00e9couvrez le classement de la 1\u00e8re \u00e9tape B du Dakar 2022 dans la cat\u00e9gorie autos, qui s'est disput\u00e9e ce dimanche 2 janvier.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dakar-2022-autos-classement-1ere-etape-b\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/dakar-2022-autos-classement-1ere-etape-b\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/dakar-2022-autos-classement-1ere-etape-b\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Dakar-2022-Autos-Le-classement-de-la-1ere-etape-B.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Dakar-2022-Autos-Le-classement-de-la-1ere-etape-B.png\",\"width\":1200,\"height\":670,\"caption\":\"Dakar 2022 Autos Le classement de la 1\u00e8re \u00e9tape B\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/dakar-2022-autos-classement-1ere-etape-b\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dakar 2022 Autos : Le classement de la 1\u00e8re \u00e9tape B\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dakar 2022 Autos : Le classement de la 1\u00e8re \u00e9tape B","description":"DAKAR \u2013 D\u00e9couvrez le classement de la 1\u00e8re \u00e9tape B du Dakar 2022 dans la cat\u00e9gorie autos, qui s'est disput\u00e9e ce dimanche 2 janvier.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/dakar-2022-autos-classement-1ere-etape-b\/","og_locale":"fr_FR","og_type":"article","og_title":"Dakar 2022 Autos : Le classement de la 1\u00e8re \u00e9tape B","og_description":"DAKAR \u2013 D\u00e9couvrez le classement de la 1\u00e8re \u00e9tape B du Dakar 2022 dans la cat\u00e9gorie autos, qui s'est disput\u00e9e ce dimanche 2 janvier.","og_url":"https:\/\/dicodusport.fr\/blog\/dakar-2022-autos-classement-1ere-etape-b\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2022-01-02T08:30:10+00:00","article_modified_time":"2022-01-02T14:14:25+00:00","og_image":[{"width":1200,"height":670,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Dakar-2022-Autos-Le-classement-de-la-1ere-etape-B.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Dakar 2022 Autos : Le classement de la 1\u00e8re \u00e9tape B","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/dakar-2022-autos-classement-1ere-etape-b\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/dakar-2022-autos-classement-1ere-etape-b\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Dakar 2022 Autos : Le classement de la 1\u00e8re \u00e9tape B","datePublished":"2022-01-02T08:30:10+00:00","dateModified":"2022-01-02T14:14:25+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/dakar-2022-autos-classement-1ere-etape-b\/"},"wordCount":275,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/dakar-2022-autos-classement-1ere-etape-b\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Dakar-2022-Autos-Le-classement-de-la-1ere-etape-B.png","keywords":["dakar"],"articleSection":["Dakar"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/dakar-2022-autos-classement-1ere-etape-b\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/dakar-2022-autos-classement-1ere-etape-b\/","url":"https:\/\/dicodusport.fr\/blog\/dakar-2022-autos-classement-1ere-etape-b\/","name":"Dakar 2022 Autos : Le classement de la 1\u00e8re \u00e9tape B","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/dakar-2022-autos-classement-1ere-etape-b\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/dakar-2022-autos-classement-1ere-etape-b\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Dakar-2022-Autos-Le-classement-de-la-1ere-etape-B.png","datePublished":"2022-01-02T08:30:10+00:00","dateModified":"2022-01-02T14:14:25+00:00","description":"DAKAR \u2013 D\u00e9couvrez le classement de la 1\u00e8re \u00e9tape B du Dakar 2022 dans la cat\u00e9gorie autos, qui s'est disput\u00e9e ce dimanche 2 janvier.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/dakar-2022-autos-classement-1ere-etape-b\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/dakar-2022-autos-classement-1ere-etape-b\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/dakar-2022-autos-classement-1ere-etape-b\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Dakar-2022-Autos-Le-classement-de-la-1ere-etape-B.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Dakar-2022-Autos-Le-classement-de-la-1ere-etape-B.png","width":1200,"height":670,"caption":"Dakar 2022 Autos Le classement de la 1\u00e8re \u00e9tape B"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/dakar-2022-autos-classement-1ere-etape-b\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Dakar 2022 Autos : Le classement de la 1\u00e8re \u00e9tape B"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/188428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=188428"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/188428\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/188429"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=188428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=188428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=188428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}