{"id":189820,"date":"2022-01-09T18:34:15","date_gmt":"2022-01-09T17:34:15","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=189820&#038;preview=true&#038;preview_id=189820"},"modified":"2022-01-09T18:34:15","modified_gmt":"2022-01-09T17:34:15","slug":"top-14-limmanquable-de-la-15eme-journee","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/top-14-limmanquable-de-la-15eme-journee\/","title":{"rendered":"Top 14 : L&rsquo;immanquable de la 15\u00e8me journ\u00e9e"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><b>TOP 14 2021-2022 &#8211; l&rsquo;Union Bordeaux-B\u00e8gles a parfaitement profit\u00e9 du report du match du Stade Toulousain pour creuser l&rsquo;\u00e9cart en t\u00eate. En bas de classement, le duel des promus \u00e0 une nouvelle fois tourn\u00e9 en faveur de Perpignan, qui laisse Biarritz seule lanterne rouge. L&rsquo;immanquable de la 15\u00e8me journ\u00e9e de Top 14.<\/b><\/em><\/p>\n<h2 class=\"western\" style=\"text-align: justify;\">Le match de la journ\u00e9e : Biarritz Olympique 23-25 USA Perpignan<\/h2>\n<p style=\"text-align: justify;\">Traditionnellement, un match de Top 14 entre les deux promus est affubl\u00e9 du titre de match de la peur. Mais cette ann\u00e9e, Biarritz et Perpignan ne sont pas timor\u00e9s et proposent du jeu. Cependant, les deux \u00e9quipes \u00e9taient derni\u00e8res ex\u00e6quo avant cette journ\u00e9e, et le vainqueur allait forc\u00e9ment frapper un grand coup dans la course au maintien. Alors que Biarritz domine le d\u00e9but de match, Perpignan ouvre le score contre le cours du jeu gr\u00e2ce \u00e0 un essai en coin d&rsquo;<strong>Alivereti Duguivalu<\/strong>. Titulaire \u00e0 l&rsquo;ouverture,<strong> Ilian Perraux<\/strong> passera deux p\u00e9nalit\u00e9s avant que Biarritz ne parvienne enfin \u00e0 envoyer du jeu, inscrivant un essai de renard par <strong>Tomas Cubelli<\/strong>, pour mener <strong>13-8<\/strong> \u00e0 la pause.<\/p>\n<p style=\"text-align: justify;\">D\u00e9cid\u00e9s \u00e0 ne pas laisser passer leur chance, les Catalans font le dos rond en d\u00e9but de seconde mi-temps avant de frapper deux fois en quelques minutes. D&rsquo;abord gr\u00e2ce \u00e0 <strong>Duguivalu<\/strong>, qui signe un doubl\u00e9 sur une merveille de passe au pied de <strong>Tristan Tedder<\/strong>, puis par ce m\u00eame <strong>Tedder<\/strong> qui intercepte une passe mal sentie d&rsquo;<strong>Henry Sa\u00efli<\/strong>. Biarritz est KO et n&rsquo;a m\u00eame plus le bonus d\u00e9fensif <strong>(13-22, 60\u00e8me)<\/strong> . Mais pouss\u00e9s par leur public, les Basques se reprennent et <strong>Baptiste Couilloud<\/strong> inscrit un essai de filou, avant que<strong> Brett Henron<\/strong> ne passe une p\u00e9nalit\u00e9 qui permet \u00e0 Biarritz de repasser devant d&rsquo;un petit point (23-22, 74\u00e8me).<\/p>\n<p style=\"text-align: justify;\">Mais les Biarrots, tout \u00e0 leur bonheur, commettent une faute \u00e9vitable d\u00e8s le renvoi suivant. Une p\u00e9nalit\u00e9 est siffl\u00e9e en bonne position et <strong>Melvyn Jaminet,<\/strong> pourtant pas \u00e0 la f\u00eate sur ce match, ne se fait pas prier pour permettre \u00e0 l&rsquo;USAP de reprendre l&rsquo;avantage <strong>(23-25)<\/strong>. Biarritz tente alors le tout pour le tout, et obtient une ultime p\u00e9nalit\u00e9 pas \u00e9vidente aux 40 m\u00e8tres. <strong>Brett Henron<\/strong> se d\u00e9voue, mais rate de peu la cible, et la derni\u00e8re tentative de Biarritz tourne court. Apr\u00e8s trois d\u00e9faites d&rsquo;affil\u00e9e, Perpignan remporte un succ\u00e8s crucial et sort enfin de la zone de rel\u00e9gation. Biarritz r\u00e9alise une mauvaise affaire et devra aller gagner \u00e0 l&rsquo;ext\u00e9rieur pour esp\u00e9rer se maintenir.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Reine du suspense, l&rsquo;Usap s&rsquo;adjuge le match de la peur !<\/p>\n<p>Le film du match &gt; <a href=\"https:\/\/t.co\/oj8FRwZG4P\">https:\/\/t.co\/oj8FRwZG4P<\/a><a href=\"https:\/\/twitter.com\/hashtag\/BOUSAP?src=hash&amp;ref_src=twsrc%5Etfw\">#BOUSAP<\/a> <a href=\"https:\/\/t.co\/xKExsBZ2JC\">pic.twitter.com\/xKExsBZ2JC<\/a><\/p>\n<p>\u2014 RUGBYRAMA (@RugbyramaFR) <a href=\"https:\/\/twitter.com\/RugbyramaFR\/status\/1479871917704290310?ref_src=twsrc%5Etfw\">January 8, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 class=\"western\" style=\"text-align: justify;\">Le club en forme : l&rsquo;Union Bordeaux B\u00e8gles<\/h2>\n<p style=\"text-align: justify;\">Alors que son dauphin, le Stade Toulousain, \u00e9tait \u00e0 l&rsquo;arr\u00eat cette semaine pour cause de Covid dans les rangs du MHR, l&rsquo;UBB a saisi non sans mal l&rsquo;occasion de creuser l&rsquo;\u00e9cart sur la pelouse de Brive. Sous une pluie battante, les Girondins sont pass\u00e9s \u00e0 c\u00f4t\u00e9 de leur premi\u00e8re p\u00e9riode, puisque men\u00e9s 14-3 \u00e0 la pause. On imagine parfaitement que <strong>Christophe Urios<\/strong> a d\u00fb manifester sa d\u00e9ception dans les vestiaires, et les B\u00e9glais sont revenus pav\u00e9s des meilleures intentions. Patiemment, ils ont pouss\u00e9 les Brivistes \u00e0 commettre d&rsquo;innombrables fautes, sanctionn\u00e9es par le pied de <strong>Maxime Lucu<\/strong>, excellent tout au long du match. L&rsquo;autre homme fort des Grenats se nomme <strong>Cameron Woki,<\/strong> imp\u00e9rial comme \u00e0 son habitude en touche et auteur d&rsquo;un essai salvateur qui a chang\u00e9 la face du match. Quatri\u00e8me succ\u00e8s cons\u00e9cutif pour l&rsquo;UBB, qui poss\u00e8de neuf points d&rsquo;avance en t\u00eate du Top 14.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">&#x1f3c9;&#x1f399;r\u00e9action de <a href=\"https:\/\/twitter.com\/ChristopheUrios?ref_src=twsrc%5Etfw\">@ChristopheUrios<\/a> apr\u00e8s la victoire de <a href=\"https:\/\/twitter.com\/UBBrugby?ref_src=twsrc%5Etfw\">@UBBrugby<\/a> contre le <a href=\"https:\/\/twitter.com\/CABCLRUGBY?ref_src=twsrc%5Etfw\">@CABCLRUGBY<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/CABUBB?src=hash&amp;ref_src=twsrc%5Etfw\">#CABUBB<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/UBB?src=hash&amp;ref_src=twsrc%5Etfw\">#UBB<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/arlfm?src=hash&amp;ref_src=twsrc%5Etfw\">#arlfm<\/a> <a href=\"https:\/\/t.co\/FQQ4pbYToH\">pic.twitter.com\/FQQ4pbYToH<\/a><\/p>\n<p>\u2014 Dorian Malvesin (@MalvesinDorian) <a href=\"https:\/\/twitter.com\/MalvesinDorian\/status\/1479890527684341770?ref_src=twsrc%5Etfw\">January 8, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 class=\"western\" style=\"text-align: justify;\">Le club qui d\u00e9\u00e7oit : le Stade Fran\u00e7ais<\/h2>\n<p style=\"text-align: justify;\">D\u00e8s le moment o\u00f9 l&rsquo;on croit que le Stade Fran\u00e7ais s&rsquo;est remis sur les rails, les Parisiens manquent l&rsquo;occasion de valider leur progression. Nouvel exemple ce samedi \u00e0 Castres, dans un match ferm\u00e9 o\u00f9 aucun essai n&rsquo;aura \u00e9t\u00e9 inscrit. Mais dans des conditions difficiles, les Stadistes se sont sabord\u00e9s en commettant beaucoup trop de fautes, donnant l&rsquo;occasion \u00e0<strong> Benjamin Botica<\/strong> de meubler le score efficacement pour les Castrais. De plus, le carton jaune de <strong>Tolu Latu<\/strong> en d\u00e9but de seconde mi-temps (son troisi\u00e8me de la saison !) aura forc\u00e9ment co\u00fbt\u00e9 aux Parisiens dans un match exigeant physiquement. Alors qu&rsquo;une victoire aurait replac\u00e9 le Stade Fran\u00e7ais \u00e0 port\u00e9e de fusil du top 6, les hommes de <strong>Gonzalo Quesada<\/strong> rentrent bredouilles du Tarn, et leurs espoirs de qualification s&rsquo;amenuisent journ\u00e9e apr\u00e8s journ\u00e9e.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Top 14: la d\u00e9faite \u00e0 Castres reste \u00ab\u00a0en travers de la gorge\u00a0\u00bb d&rsquo;Arias (Stade fran\u00e7ais)<br \/>\n<a href=\"https:\/\/twitter.com\/hashtag\/Castres?src=hash&amp;ref_src=twsrc%5Etfw\">#Castres<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/COSFP?src=hash&amp;ref_src=twsrc%5Etfw\">#COSFP<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/Paris?src=hash&amp;ref_src=twsrc%5Etfw\">#Paris<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/SFPARIS?src=hash&amp;ref_src=twsrc%5Etfw\">#SFPARIS<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/teamco?src=hash&amp;ref_src=twsrc%5Etfw\">#teamco<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/Top14?src=hash&amp;ref_src=twsrc%5Etfw\">#Top14<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/TousEnsemble?src=hash&amp;ref_src=twsrc%5Etfw\">#TousEnsemble<\/a> <a href=\"https:\/\/twitter.com\/vibrezrugbyd2?ref_src=twsrc%5Etfw\">@vibrezrugbyd2<\/a><a href=\"https:\/\/t.co\/OT09pMKUgT\">https:\/\/t.co\/OT09pMKUgT<\/a> <a href=\"https:\/\/t.co\/chpt7tJ0vz\">pic.twitter.com\/chpt7tJ0vz<\/a><\/p>\n<p>\u2014 vibrezrugbyd2 (@vibrezrugbyd2) <a href=\"https:\/\/twitter.com\/vibrezrugbyd2\/status\/1480095342754467840?ref_src=twsrc%5Etfw\">January 9, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 class=\"western\" style=\"text-align: justify;\">Le joueur : Jordan Taufua (Lyon OU)<\/h2>\n<p style=\"text-align: justify;\">Arriv\u00e9 en tant que joker m\u00e9dical voil\u00e0 un an, <strong>Jordan Taufua<\/strong> a fait son trou \u00e0 Lyon. Face \u00e0 la Section Paloise, il s&rsquo;est montr\u00e9 royal dans tous les secteurs de jeu. De plus, il a ponctu\u00e9 sa prestation par un superbe doubl\u00e9. Le premier \u00e0 la suite d&rsquo;une p\u00e9naltouche bien n\u00e9goci\u00e9e par le paquet d&rsquo;avants lyonnais, et le second \u00e0 la suite d&rsquo;une action de grande envergure qu&rsquo;il a conclue superbement. Capitaine du LOU pour ce match, il a fait honneur \u00e0 son statut et contribue pour beaucoup \u00e0 la bonne passe des Lyonnais, d\u00e9sormais 4\u00e8mes du Top 14.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">At least 5 offloads in the build-up to this Jordan Taufua try for Lyon and none of them the same.<\/p>\n<p>When it comes to keeping the ball alive, no league in the Northern Hemisphere does it better than the Top 14.<a href=\"https:\/\/twitter.com\/hashtag\/LOUSP?src=hash&amp;ref_src=twsrc%5Etfw\">#LOUSP<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/TOP14?src=hash&amp;ref_src=twsrc%5Etfw\">#TOP14<\/a> <a href=\"https:\/\/t.co\/PS2O2vr4Yf\">pic.twitter.com\/PS2O2vr4Yf<\/a><\/p>\n<p>\u2014 EK Rugby Analysis (@ek_rugby) <a href=\"https:\/\/twitter.com\/ek_rugby\/status\/1479961282484875273?ref_src=twsrc%5Etfw\">January 8, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 class=\"western\" style=\"text-align: justify;\">L&rsquo;essai : Wenceslas Lauret (Racing 92)<\/h2>\n<p style=\"text-align: justify;\">Il restait seulement 10 minutes \u00e0 jouer et le Racing n&rsquo;avait que trois points d&rsquo;avance. Le spectre d&rsquo;une cinqui\u00e8me d\u00e9faite d&rsquo;affil\u00e9e se profilait alors, mais les Racingmen ont alors d\u00e9cid\u00e9 de profiler l&rsquo;estocade. Sur une r\u00e9cup\u00e9ration de coup de pied, <strong>Kurtley Beale<\/strong> a attaqu\u00e9 la ligne d&rsquo;avantage et cr\u00e9\u00e9 un point de fixation. <strong>Antoine Gibert<\/strong>, repositionn\u00e9 \u00e0 la m\u00eal\u00e9e, r\u00e9alise alors une valise monumentale et emporte toute la d\u00e9fense avec lui, attirant<strong> Damian Penaud<\/strong> le long de la ligne de touche avant d&rsquo;offrir l&rsquo;essai \u00e0 <strong>Wenceslas Lauret<\/strong>, toujours bien plac\u00e9 au soutien sur ce genre d&rsquo;actions. En plus d&rsquo;\u00eatre magnifique, cet essai a d\u00e9finitivement scell\u00e9 la victoire des Racingmen, et peut-\u00eatre sauv\u00e9 la t\u00eate de <strong>Laurent Travers<\/strong>.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Also very nice, the winning try.<\/p>\n<p>This Antoine Gibert dummy, break and last-second offload to Wenceslas Lauret is just all class.<a href=\"https:\/\/twitter.com\/hashtag\/R92ASM?src=hash&amp;ref_src=twsrc%5Etfw\">#R92ASM<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/Top14?src=hash&amp;ref_src=twsrc%5Etfw\">#Top14<\/a> <a href=\"https:\/\/t.co\/VWpGDzjOtX\">pic.twitter.com\/VWpGDzjOtX<\/a><\/p>\n<p>\u2014 EK Rugby Analysis (@ek_rugby) <a href=\"https:\/\/twitter.com\/ek_rugby\/status\/1479938691598540801?ref_src=twsrc%5Etfw\">January 8, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 class=\"western\" style=\"text-align: justify;\">La d\u00e9claration du week-end :<\/h2>\n<blockquote>\n<p style=\"text-align: justify;\">Je me suis fait insulter pendant 80 minutes devant ma famille alors que j&rsquo;ai port\u00e9 le maillot de ce club.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\"><strong>Mathieu Acebes<\/strong>, Basque d&rsquo;origine, qui n&rsquo;a que peu go\u00fbt\u00e9 l&rsquo;accueil du public biarrot.<\/p>\n<blockquote>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">&#x1f92c;&#x1f4ac; \u00ab\u00a0Le climat \u00e9tait hostile. Je suis d\u00e9\u00e7u, je me suis fait insulter pendant 80 minutes devant ma famille alors que j&rsquo;ai port\u00e9 le maillot de ce club, il faut \u00eatre respectueux&#8230;\u00a0\u00bb<\/p>\n<p>&#x1f399; La mise au point de Mathieu Acebes apr\u00e8s <a href=\"https:\/\/twitter.com\/hashtag\/Biarritz?src=hash&amp;ref_src=twsrc%5Etfw\">#Biarritz<\/a> &#8211; <a href=\"https:\/\/twitter.com\/hashtag\/Perpignan?src=hash&amp;ref_src=twsrc%5Etfw\">#Perpignan<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/fbsport?src=hash&amp;ref_src=twsrc%5Etfw\">#fbsport<\/a> <a href=\"https:\/\/t.co\/u9kc0wiZOK\">pic.twitter.com\/u9kc0wiZOK<\/a><\/p>\n<p>\u2014 France Bleu Pays Basque (@Bleu_Basque) <a href=\"https:\/\/twitter.com\/Bleu_Basque\/status\/1479885117007011843?ref_src=twsrc%5Etfw\">January 8, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p><\/blockquote>\n<h2 class=\"western\" style=\"text-align: justify;\">La stat :<\/h2>\n<p style=\"text-align: justify;\"><strong>4<\/strong><\/p>\n<p style=\"text-align: justify;\">Biarritz vient de conc\u00e9der sa quatri\u00e8me d\u00e9faite d&rsquo;affil\u00e9e tous niveaux confondus contre Perpignan.<\/p>\n<h2 class=\"western\" style=\"text-align: justify;\">R\u00e9sultats et classement<\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/top-14-15eme-journee-programme-tv-et-resultats\/\"><strong>Les r\u00e9sultats de la 15\u00e8me journ\u00e9e de Top 14<\/strong><\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/top-14-2021-2022-le-classement-complet\/\"><strong>Le classement du Top 14<\/strong><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>TOP 14 2021-2022 &#8211; l&rsquo;Union Bordeaux-B\u00e8gles a parfaitement profit\u00e9 du report du match du Stade Toulousain pour creuser l&rsquo;\u00e9cart en t\u00eate. En bas de classement, le duel des promus \u00e0 une nouvelle fois tourn\u00e9 en faveur de Perpignan, qui laisse Biarritz seule lanterne rouge. L&rsquo;immanquable de la 15\u00e8me journ\u00e9e de Top 14.<\/p>\n","protected":false},"author":59,"featured_media":190109,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[47050],"tags":[111],"class_list":["post-189820","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-top-14","tag-top-14"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Top 14 : L&#039;immanquable de la 15\u00e8me journ\u00e9e<\/title>\n<meta name=\"description\" content=\"TOP 14 2021-2022 - l&#039;Union Bordeaux-B\u00e8gles a parfaitement profit\u00e9 du report du match du Stade Toulousain pour creuser l&#039;\u00e9cart en t\u00eate.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/top-14-limmanquable-de-la-15eme-journee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Top 14 : L&#039;immanquable de la 15\u00e8me journ\u00e9e\" \/>\n<meta property=\"og:description\" content=\"TOP 14 2021-2022 - l&#039;Union Bordeaux-B\u00e8gles a parfaitement profit\u00e9 du report du match du Stade Toulousain pour creuser l&#039;\u00e9cart en t\u00eate.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/top-14-limmanquable-de-la-15eme-journee\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-09T17:34:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Top-14-Limmanquable-de-la-15eme-journee.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Top 14 : L&#039;immanquable de la 15\u00e8me journ\u00e9e\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-limmanquable-de-la-15eme-journee\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-limmanquable-de-la-15eme-journee\\\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Top 14 : L&rsquo;immanquable de la 15\u00e8me journ\u00e9e\",\"datePublished\":\"2022-01-09T17:34:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-limmanquable-de-la-15eme-journee\\\/\"},\"wordCount\":1352,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-limmanquable-de-la-15eme-journee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Top-14-Limmanquable-de-la-15eme-journee.png\",\"keywords\":[\"Top 14\"],\"articleSection\":[\"Top 14\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-limmanquable-de-la-15eme-journee\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-limmanquable-de-la-15eme-journee\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-limmanquable-de-la-15eme-journee\\\/\",\"name\":\"Top 14 : L'immanquable de la 15\u00e8me journ\u00e9e\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-limmanquable-de-la-15eme-journee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-limmanquable-de-la-15eme-journee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Top-14-Limmanquable-de-la-15eme-journee.png\",\"datePublished\":\"2022-01-09T17:34:15+00:00\",\"description\":\"TOP 14 2021-2022 - l'Union Bordeaux-B\u00e8gles a parfaitement profit\u00e9 du report du match du Stade Toulousain pour creuser l'\u00e9cart en t\u00eate.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-limmanquable-de-la-15eme-journee\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-limmanquable-de-la-15eme-journee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-limmanquable-de-la-15eme-journee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Top-14-Limmanquable-de-la-15eme-journee.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Top-14-Limmanquable-de-la-15eme-journee.png\",\"width\":800,\"height\":445,\"caption\":\"Top 14 L'immanquable de la 15\u00e8me journ\u00e9e\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-limmanquable-de-la-15eme-journee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Top 14 : L&rsquo;immanquable de la 15\u00e8me journ\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sebastien.gente\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sebgente\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/sbastien-gente-a29583169\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sebastiengente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Top 14 : L'immanquable de la 15\u00e8me journ\u00e9e","description":"TOP 14 2021-2022 - l'Union Bordeaux-B\u00e8gles a parfaitement profit\u00e9 du report du match du Stade Toulousain pour creuser l'\u00e9cart en t\u00eate.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/top-14-limmanquable-de-la-15eme-journee\/","og_locale":"fr_FR","og_type":"article","og_title":"Top 14 : L'immanquable de la 15\u00e8me journ\u00e9e","og_description":"TOP 14 2021-2022 - l'Union Bordeaux-B\u00e8gles a parfaitement profit\u00e9 du report du match du Stade Toulousain pour creuser l'\u00e9cart en t\u00eate.","og_url":"https:\/\/dicodusport.fr\/blog\/top-14-limmanquable-de-la-15eme-journee\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2022-01-09T17:34:15+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Top-14-Limmanquable-de-la-15eme-journee.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Top 14 : L'immanquable de la 15\u00e8me journ\u00e9e","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/top-14-limmanquable-de-la-15eme-journee\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-limmanquable-de-la-15eme-journee\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Top 14 : L&rsquo;immanquable de la 15\u00e8me journ\u00e9e","datePublished":"2022-01-09T17:34:15+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-limmanquable-de-la-15eme-journee\/"},"wordCount":1352,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-limmanquable-de-la-15eme-journee\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Top-14-Limmanquable-de-la-15eme-journee.png","keywords":["Top 14"],"articleSection":["Top 14"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/top-14-limmanquable-de-la-15eme-journee\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/top-14-limmanquable-de-la-15eme-journee\/","url":"https:\/\/dicodusport.fr\/blog\/top-14-limmanquable-de-la-15eme-journee\/","name":"Top 14 : L'immanquable de la 15\u00e8me journ\u00e9e","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-limmanquable-de-la-15eme-journee\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-limmanquable-de-la-15eme-journee\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Top-14-Limmanquable-de-la-15eme-journee.png","datePublished":"2022-01-09T17:34:15+00:00","description":"TOP 14 2021-2022 - l'Union Bordeaux-B\u00e8gles a parfaitement profit\u00e9 du report du match du Stade Toulousain pour creuser l'\u00e9cart en t\u00eate.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-limmanquable-de-la-15eme-journee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/top-14-limmanquable-de-la-15eme-journee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/top-14-limmanquable-de-la-15eme-journee\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Top-14-Limmanquable-de-la-15eme-journee.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Top-14-Limmanquable-de-la-15eme-journee.png","width":800,"height":445,"caption":"Top 14 L'immanquable de la 15\u00e8me journ\u00e9e"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/top-14-limmanquable-de-la-15eme-journee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Top 14 : L&rsquo;immanquable de la 15\u00e8me journ\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/189820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=189820"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/189820\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/190109"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=189820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=189820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=189820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}