{"id":190559,"date":"2022-01-11T19:33:28","date_gmt":"2022-01-11T18:33:28","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=190559&#038;preview=true&#038;preview_id=190559"},"modified":"2022-01-11T19:33:28","modified_gmt":"2022-01-11T18:33:28","slug":"antoine-dupont-toujours-absent-de-l-entrainement-et-incertain-pour-les-wasps","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/antoine-dupont-toujours-absent-de-l-entrainement-et-incertain-pour-les-wasps\/","title":{"rendered":"Antoine Dupont toujours absent de l&rsquo;entra\u00eenement et incertain pour les Wasps"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>CHAMPIONS CUP &#8211; Antoine Dupont n&rsquo;a toujours pas repris l&rsquo;entra\u00eenement avec le Stade Toulousain, et reste incertain pour le match face aux Wasps ce week-end, comme le confirme Rugbyrama.\u00a0<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Ugo Mola a trouv\u00e9 son capitaine fatigu\u00e9, et l&rsquo;a mis au repos depuis plusieurs jours. Le meilleur joueur du monde, <strong>Antoine Dupont<\/strong>, a notamment rat\u00e9 <a href=\"https:\/\/dicodusport.fr\/blog\/top-14-clermont-l-emporte-au-finish-face-au-stade-toulousain\/\">le match face \u00e0 l&rsquo;ASM Clermont<\/a> (perdu 16-13) et n&rsquo;aurait pas \u00e9t\u00e9 du choc face au MHR le week-end pass\u00e9, s&rsquo;il n&rsquo;avait pas \u00e9t\u00e9 report\u00e9. Pr\u00e9sent \u00e0 Ernest Wallon aujourd&rsquo;hui, <strong>Antoine Dupont<\/strong> s&rsquo;est content\u00e9 d&rsquo;exercices en salle de musculation et reste donc incertain pour le d\u00e9placement \u00e0 Coventry face aux Wasps, ce samedi \u00e0 14 heures. Quand on conna\u00eet l&rsquo;importance du demi de m\u00eal\u00e9e international au Stade Toulousain, son absence serait \u00e9videmment un coup dur.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Le demi de m\u00eal\u00e9e n&rsquo;a pas pris part \u00e0 la s\u00e9ance d&rsquo;entra\u00eenement avec l&rsquo;ensemble du groupe toulousain.<a href=\"https:\/\/t.co\/02NUt6HQ3n\">https:\/\/t.co\/02NUt6HQ3n<\/a><\/p>\n<p>\u2014 RUGBYRAMA (@RugbyramaFR) <a href=\"https:\/\/twitter.com\/RugbyramaFR\/status\/1480945898146476034?ref_src=twsrc%5Etfw\">January 11, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CHAMPIONS CUP &#8211; Antoine Dupont n&rsquo;a toujours pas repris l&rsquo;entra\u00eenement avec le Stade Toulousain, et reste incertain pour le match face aux Wasps ce week-end, comme le confirme Rugbyrama.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":190570,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[47051,9129],"tags":[2373,2823,4008],"class_list":["post-190559","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-champions-cup","category-rugby-a-xv","tag-antoine-dupont","tag-champions-cup","tag-stade-toulousain"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Antoine Dupont toujours absent de l&#039;entra\u00eenement et incertain pour les Wasps<\/title>\n<meta name=\"description\" content=\"CHAMPIONS CUP - Antoine Dupont n&#039;a toujours pas repris l&#039;entra\u00eenement avec le Stade Toulousain, et reste incertain pour le match face aux Wasps.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/antoine-dupont-toujours-absent-de-l-entrainement-et-incertain-pour-les-wasps\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Antoine Dupont toujours absent de l&#039;entra\u00eenement et incertain pour les Wasps\" \/>\n<meta property=\"og:description\" content=\"CHAMPIONS CUP - Antoine Dupont n&#039;a toujours pas repris l&#039;entra\u00eenement avec le Stade Toulousain, et reste incertain pour le match face aux Wasps.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/antoine-dupont-toujours-absent-de-l-entrainement-et-incertain-pour-les-wasps\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-11T18:33:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Antoine-Dupont-toujours-absent-de-lentrai\u0302nement-et-incertain-pour-les-Wasps.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Antoine Dupont toujours absent de l&#039;entra\u00eenement et incertain pour les Wasps\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/antoine-dupont-toujours-absent-de-l-entrainement-et-incertain-pour-les-wasps\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/antoine-dupont-toujours-absent-de-l-entrainement-et-incertain-pour-les-wasps\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Antoine Dupont toujours absent de l&rsquo;entra\u00eenement et incertain pour les Wasps\",\"datePublished\":\"2022-01-11T18:33:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/antoine-dupont-toujours-absent-de-l-entrainement-et-incertain-pour-les-wasps\\\/\"},\"wordCount\":186,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/antoine-dupont-toujours-absent-de-l-entrainement-et-incertain-pour-les-wasps\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Antoine-Dupont-toujours-absent-de-lentrai\u0302nement-et-incertain-pour-les-Wasps.png\",\"keywords\":[\"Antoine Dupont\",\"Champions Cup\",\"Stade Toulousain\"],\"articleSection\":[\"Champions Cup\",\"Rugby \u00e0 XV\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/antoine-dupont-toujours-absent-de-l-entrainement-et-incertain-pour-les-wasps\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/antoine-dupont-toujours-absent-de-l-entrainement-et-incertain-pour-les-wasps\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/antoine-dupont-toujours-absent-de-l-entrainement-et-incertain-pour-les-wasps\\\/\",\"name\":\"Antoine Dupont toujours absent de l'entra\u00eenement et incertain pour les Wasps\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/antoine-dupont-toujours-absent-de-l-entrainement-et-incertain-pour-les-wasps\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/antoine-dupont-toujours-absent-de-l-entrainement-et-incertain-pour-les-wasps\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Antoine-Dupont-toujours-absent-de-lentrai\u0302nement-et-incertain-pour-les-Wasps.png\",\"datePublished\":\"2022-01-11T18:33:28+00:00\",\"description\":\"CHAMPIONS CUP - Antoine Dupont n'a toujours pas repris l'entra\u00eenement avec le Stade Toulousain, et reste incertain pour le match face aux Wasps.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/antoine-dupont-toujours-absent-de-l-entrainement-et-incertain-pour-les-wasps\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/antoine-dupont-toujours-absent-de-l-entrainement-et-incertain-pour-les-wasps\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/antoine-dupont-toujours-absent-de-l-entrainement-et-incertain-pour-les-wasps\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Antoine-Dupont-toujours-absent-de-lentrai\u0302nement-et-incertain-pour-les-Wasps.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Antoine-Dupont-toujours-absent-de-lentrai\u0302nement-et-incertain-pour-les-Wasps.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/antoine-dupont-toujours-absent-de-l-entrainement-et-incertain-pour-les-wasps\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Antoine Dupont toujours absent de l&rsquo;entra\u00eenement et incertain pour les Wasps\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Antoine Dupont toujours absent de l'entra\u00eenement et incertain pour les Wasps","description":"CHAMPIONS CUP - Antoine Dupont n'a toujours pas repris l'entra\u00eenement avec le Stade Toulousain, et reste incertain pour le match face aux Wasps.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/antoine-dupont-toujours-absent-de-l-entrainement-et-incertain-pour-les-wasps\/","og_locale":"fr_FR","og_type":"article","og_title":"Antoine Dupont toujours absent de l'entra\u00eenement et incertain pour les Wasps","og_description":"CHAMPIONS CUP - Antoine Dupont n'a toujours pas repris l'entra\u00eenement avec le Stade Toulousain, et reste incertain pour le match face aux Wasps.","og_url":"https:\/\/dicodusport.fr\/blog\/antoine-dupont-toujours-absent-de-l-entrainement-et-incertain-pour-les-wasps\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2022-01-11T18:33:28+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Antoine-Dupont-toujours-absent-de-lentrai\u0302nement-et-incertain-pour-les-Wasps.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Antoine Dupont toujours absent de l'entra\u00eenement et incertain pour les Wasps","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/antoine-dupont-toujours-absent-de-l-entrainement-et-incertain-pour-les-wasps\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/antoine-dupont-toujours-absent-de-l-entrainement-et-incertain-pour-les-wasps\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Antoine Dupont toujours absent de l&rsquo;entra\u00eenement et incertain pour les Wasps","datePublished":"2022-01-11T18:33:28+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/antoine-dupont-toujours-absent-de-l-entrainement-et-incertain-pour-les-wasps\/"},"wordCount":186,"commentCount":1,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/antoine-dupont-toujours-absent-de-l-entrainement-et-incertain-pour-les-wasps\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Antoine-Dupont-toujours-absent-de-lentrai\u0302nement-et-incertain-pour-les-Wasps.png","keywords":["Antoine Dupont","Champions Cup","Stade Toulousain"],"articleSection":["Champions Cup","Rugby \u00e0 XV"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/antoine-dupont-toujours-absent-de-l-entrainement-et-incertain-pour-les-wasps\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/antoine-dupont-toujours-absent-de-l-entrainement-et-incertain-pour-les-wasps\/","url":"https:\/\/dicodusport.fr\/blog\/antoine-dupont-toujours-absent-de-l-entrainement-et-incertain-pour-les-wasps\/","name":"Antoine Dupont toujours absent de l'entra\u00eenement et incertain pour les Wasps","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/antoine-dupont-toujours-absent-de-l-entrainement-et-incertain-pour-les-wasps\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/antoine-dupont-toujours-absent-de-l-entrainement-et-incertain-pour-les-wasps\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Antoine-Dupont-toujours-absent-de-lentrai\u0302nement-et-incertain-pour-les-Wasps.png","datePublished":"2022-01-11T18:33:28+00:00","description":"CHAMPIONS CUP - Antoine Dupont n'a toujours pas repris l'entra\u00eenement avec le Stade Toulousain, et reste incertain pour le match face aux Wasps.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/antoine-dupont-toujours-absent-de-l-entrainement-et-incertain-pour-les-wasps\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/antoine-dupont-toujours-absent-de-l-entrainement-et-incertain-pour-les-wasps\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/antoine-dupont-toujours-absent-de-l-entrainement-et-incertain-pour-les-wasps\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Antoine-Dupont-toujours-absent-de-lentrai\u0302nement-et-incertain-pour-les-Wasps.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Antoine-Dupont-toujours-absent-de-lentrai\u0302nement-et-incertain-pour-les-Wasps.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/antoine-dupont-toujours-absent-de-l-entrainement-et-incertain-pour-les-wasps\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Antoine Dupont toujours absent de l&rsquo;entra\u00eenement et incertain pour les Wasps"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/190559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=190559"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/190559\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/190570"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=190559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=190559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=190559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}