{"id":194993,"date":"2022-01-28T15:34:38","date_gmt":"2022-01-28T14:34:38","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=194993&#038;preview=true&#038;preview_id=194993"},"modified":"2025-07-24T21:56:30","modified_gmt":"2025-07-24T19:56:30","slug":"formule-e-diriyah-stoffel-vandoorne-est-le-premier-poleman-de-la-saison","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/formule-e-diriyah-stoffel-vandoorne-est-le-premier-poleman-de-la-saison\/","title":{"rendered":"Formule E &#8211; Diriyah : Stoffel Vandoorne est le premier poleman de la saison"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong><a href=\"https:\/\/dicodusport.fr\/blog\/formule-e-ce-quil-faut-savoir-avant-le-debut-de-la-saison-2022\/\">FORMULE E 2022<\/a> &#8211; La nouvelle saison du championnat du monde de Formule E a d\u00e9marr\u00e9 ce week-end \u00e0 Diriyah en Arabie Saoudite. A l&rsquo;issue d&rsquo;une s\u00e9ance de qualification in\u00e9dite, le Belge Stoffel Vandoorne a d\u00e9croch\u00e9 la pole position avec sa Mercedes. Il devance le Britannique Jake Dennis (Avalanche Andretti) et son co\u00e9quipier Nick de Vries. La premi\u00e8re course a lieu aujourd&rsquo;hui \u00e0 18h00 !<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Cette s\u00e9ance de qualifications \u00e9tait la toute premi\u00e8re de la saison 2022 de Formule E et avait des r\u00e8gles in\u00e9dites. Deux groupes de 11 pilotes ont \u00e9t\u00e9 form\u00e9s en fonction du choix des \u00e9curies. D\u00e8s demain, ce sera en fonction de leur classement respectif au championnat du monde pilote. Dans chaque groupe, les quatre pilotes les plus performants ont atteint la phase des duels.<\/p>\n<h2 style=\"text-align: justify;\">Phase de groupes<\/h2>\n<p style=\"text-align: justify;\">Dans le Groupe A, les quatre qualifi\u00e9s sont dans l&rsquo;ordre <strong>Robin Frijns<\/strong> (Envision Racing), <strong>Sam Bird<\/strong> (Jaguar TCS Racing), <strong>Stoffel Vandoorne<\/strong> (Mercedes-EQ) et <strong>Oliver Rowland<\/strong> (Mahindra Racing). Dans le Groupe B, un drapeau jaune est intervenu \u00e0 2 minutes de la fin de la s\u00e9ance en raison de la sortie de piste du Suisse <strong>Edoardo Mortara<\/strong> (ROKiT Venturi Racing). De ce fait, personne n\u2019a pu am\u00e9liorer son temps et <strong>Nyck De Vries<\/strong> (Mercedes-EQ), <strong>Nick Cassidy<\/strong> (Envision Racing), <strong>Jake Dennis<\/strong> (Avalanche Andretti) et <strong>Andr\u00e9 Lotterer <\/strong>(TAG Heuer Porsche) sont pass\u00e9s.<\/p>\n<p style=\"text-align: justify;\">Ces huit pilotes se sont ensuite affront\u00e9s en un contre un dans une \u00e9preuve \u00e0 \u00e9limination directe. En quarts de finale, le 1<sup>er<\/sup> de chaque groupe \u00e9tait contre le 4<sup>\u00e8me<\/sup> de l\u2019autre groupe, et le deuxi\u00e8me d\u2019un groupe contre le 3<sup>\u00e8me<\/sup> de l\u2019autre groupe.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Get ready for the duels in the desert &#x1f440;&#x2694;&#xfe0f;<\/p>\n<p>Take a look at who is going head-to-head below!<\/p>\n<p>&#x1f1f8;&#x1f1e6;\u00a02022 <a href=\"https:\/\/twitter.com\/hashtag\/DiriyahEPrix?src=hash&amp;ref_src=twsrc%5Etfw\">#DiriyahEPrix<\/a> <a href=\"https:\/\/t.co\/vJUqJAaEtN\">pic.twitter.com\/vJUqJAaEtN<\/a><\/p>\n<p>\u2014 ABB FIA Formula E World Championship (@FIAFormulaE) <a href=\"https:\/\/twitter.com\/FIAFormulaE\/status\/1487052451622576132?ref_src=twsrc%5Etfw\">January 28, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Stoffel Vandoorne d\u00e9croche la premi\u00e8re pole de la saison \u00e0 l\u2019issue des duels<\/h2>\n<p style=\"text-align: justify;\"><strong>Andr\u00e9 Lotterer <\/strong>(TAG Heuer Porsche) et <strong>Robin Frijns<\/strong> (Envision Racing) ont ouvert le bal pour un duel serr\u00e9. L\u2019Allemand, au volant de la Porsche, a d\u00e9croch\u00e9 sa place en demi-finale et a \u00e9limin\u00e9 le Hollandais alors qu\u2019il \u00e9tait en t\u00eate en phase de groupes. M\u00eame sch\u00e9ma dans le deuxi\u00e8me duel, le Britannique <strong>Sam Bird<\/strong> (Jaguar TCS Racing), alors favori, a \u00e9chou\u00e9 face \u00e0 son compatriote <strong>Jake Dennis<\/strong> (Avalanche Andretti). Le troisi\u00e8me quart de finale \u00e9tait le plus serr\u00e9. Pour 78 milli\u00e8mes de secondes, <strong>Stoffel Vandoorne<\/strong> (Mercedes-EQ) a sorti l\u2019Australien <strong>Nick Cassidy<\/strong> (Envision Racing). Dans le dernier quart de finale, <strong>Oliver Rowland<\/strong> (Mahindra Racing) a bloqu\u00e9 ses roues en laissant un boulevard \u00e0 <strong>Nyck de Vries<\/strong> (Mercedes-EQ) pour se qualifier en demi-finale.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">HERE WE GO! Semi-finals incoming &#x26a1;&#xfe0f;<\/p>\n<p>1&#xfe0f;&#x20e3;- <a href=\"https:\/\/twitter.com\/Andre_Lotterer?ref_src=twsrc%5Etfw\">@Andre_Lotterer<\/a> &#x2694;&#xfe0f; <a href=\"https:\/\/twitter.com\/JakeDennis19?ref_src=twsrc%5Etfw\">@JakeDennis19<\/a><br \/>\n2&#xfe0f;&#x20e3; &#8211; <a href=\"https:\/\/twitter.com\/svandoorne?ref_src=twsrc%5Etfw\">@svandoorne<\/a> &#x2694;&#xfe0f; <a href=\"https:\/\/twitter.com\/nyckdevries?ref_src=twsrc%5Etfw\">@nyckdevries<\/a><\/p>\n<p>Follow LIVE timing here &#x1f449; <a href=\"https:\/\/t.co\/NqfsxKU5B4\">https:\/\/t.co\/NqfsxKU5B4<\/a><\/p>\n<p>&#x1f1f8;&#x1f1e6; 2022 <a href=\"https:\/\/twitter.com\/hashtag\/DiriyahEPrix?src=hash&amp;ref_src=twsrc%5Etfw\">#DiriyahEPrix<\/a> <a href=\"https:\/\/t.co\/V8KksqCn9Q\">pic.twitter.com\/V8KksqCn9Q<\/a><\/p>\n<p>\u2014 ABB FIA Formula E World Championship (@FIAFormulaE) <a href=\"https:\/\/twitter.com\/FIAFormulaE\/status\/1487058127438716934?ref_src=twsrc%5Etfw\">January 28, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">La premi\u00e8re place en finale revient \u00e0 <strong>Jake Dennis<\/strong> (Avalanche Andretti) qui a devanc\u00e9 de plus de 6 dixi\u00e8mes <strong>Andr\u00e9 Lotterer<\/strong> (TAG Heuer Porshe). Dans la deuxi\u00e8me demi-finale 100% Mercedes, <strong>Stoffel Vandoorne<\/strong> \u00e9limine avec plus de 4 dixi\u00e8mes d\u2019avance le Champion du Monde en titre : son co\u00e9quipier <strong>Nyck de Vries<\/strong>. La finale nous a offert un beau duel. Pour 3 dixi\u00e8mes de seconde tout pile, le Belge <strong>Stoffel Vandoorne<\/strong> s\u2019impose et d\u00e9croche la sixi\u00e8me pole position de sa carri\u00e8re en Formule E.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">INCREDIBLE! <a href=\"https:\/\/twitter.com\/svandoorne?ref_src=twsrc%5Etfw\">@svandoorne<\/a> WINS three intense duels to claim the <a href=\"https:\/\/twitter.com\/juliusbaer?ref_src=twsrc%5Etfw\">@juliusbaer<\/a> Pole Position for Round 1 &#x1f44f;&#x26a1;&#xfe0f;<\/p>\n<p>&#x1f1f8;&#x1f1e6;\u00a02022 <a href=\"https:\/\/twitter.com\/hashtag\/DiriyahEPrix?src=hash&amp;ref_src=twsrc%5Etfw\">#DiriyahEPrix<\/a> <a href=\"https:\/\/t.co\/jLjkubWFEj\">pic.twitter.com\/jLjkubWFEj<\/a><\/p>\n<p>\u2014 ABB FIA Formula E World Championship (@FIAFormulaE) <a href=\"https:\/\/twitter.com\/FIAFormulaE\/status\/1487061980246683649?ref_src=twsrc%5Etfw\">January 28, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2>La grille de d\u00e9part de la course 1<\/h2>\n<p style=\"text-align: justify;\">Les perdants des demi-finales partent en 3\u00e8me et 4\u00e8me en fonction de leur chrono, et pareil pour les perdants des quarts de finales qui prennent les places 5 \u00e0 8. Les pilotes n&rsquo;ayant pas atteint les duels sont plac\u00e9s en fonction du poleman. Nyck de Vries ayant couru dans le Groupe A, les pilotes class\u00e9s 5 \u00e0 11 de celui-ci partiront du c\u00f4t\u00e9 impair de la grille en fonction de leur chrono. A l\u2019inverse, le Groupe A se placera du c\u00f4t\u00e9 pair sur les places 10, 12, 14 etc\u2026<\/p>\n<p style=\"text-align: justify;\">\u00c0 noter que le Fran\u00e7ais <strong>Jean-Eric Vergne<\/strong> (DS Techeetah) partira en 13\u00e8me. Le pilote venu de Formule 2 <strong>Dan Ticktum<\/strong> (NIO 333 Racing) partira de la 20\u00e8me position. Rendez vous \u00e0 18h00 sur l\u2019Equipe LIVE et Eurosport 2 pour la premi\u00e8re course de la saison. Une nouvelle s\u00e9ance de qualifications aura lieu demain \u00e0 13h40 pour d\u00e9terminer la grille de d\u00e9part de la course 2.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">QUALIFYING RESULTS &#x2935;&#xfe0f;<\/p>\n<p>Here&rsquo;s how our grid will line up for the <a href=\"https:\/\/twitter.com\/hashtag\/DiriyahEPrix?src=hash&amp;ref_src=twsrc%5Etfw\">#DiriyahEPrix<\/a>!<\/p>\n<p>Who do YOU think will finish on the podium? &#x1f52e;&#x26a1;&#xfe0f; <a href=\"https:\/\/t.co\/qeWEKQiOV0\">pic.twitter.com\/qeWEKQiOV0<\/a><\/p>\n<p>\u2014 ABB FIA Formula E World Championship (@FIAFormulaE) <a href=\"https:\/\/twitter.com\/FIAFormulaE\/status\/1487071711266750470?ref_src=twsrc%5Etfw\">January 28, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\"><strong>\u00c0 lire aussi<\/strong><\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/formule-e-ce-quil-faut-savoir-avant-le-debut-de-la-saison-2022\/\"><strong>Formule E : Ce qu\u2019il faut savoir avant le d\u00e9but de la saison 2022<\/strong><\/a><\/li>\n<li><strong><a href=\"https:\/\/dicodusport.fr\/blog\/formule-e-que-retenir-de-cette-premiere-edition-du-championnat-du-monde\/\">Formule E : Que retenir de la premi\u00e8re \u00e9dition du Championnat du monde ?<\/a><\/strong><\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"https:\/\/dicodusport.fr\/blog\/championnat-de-formule-e-peut-il-concurrencer-la-formule-1\/\">Le championnat de Formule E peut-il concurrencer la Formule 1 ?<\/a><\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>FORMULE E 2022 &#8211; La nouvelle saison du championnat du monde de Formule E a d\u00e9marr\u00e9 ce week-end \u00e0 Diriyah en Arabie Saoudite. A l&rsquo;issue d&rsquo;une s\u00e9ance de qualification in\u00e9dite, le Belge Stoffel Vandoorne a d\u00e9croch\u00e9 la pole position avec sa Mercedes. Il devance le Britannique Jake Dennis (Avalanche Andretti) et son co\u00e9quipier Nyck de Vries. La premi\u00e8re course a lieu aujourd&rsquo;hui \u00e0 18h00 !<\/p>\n","protected":false},"author":54,"featured_media":195037,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2312],"tags":[5480],"class_list":["post-194993","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sports-mecaniques","tag-formule-e"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Formule E - Diriyah : Stoffel Vandoorne est le premier poleman de la saison<\/title>\n<meta name=\"description\" content=\"FORMULE E - La saison 2022 de Formule E a d\u00e9but\u00e9 ce week-end et le Belge Stoffel Vandoorne (Mercedes-EQ) a d\u00e9croch\u00e9 la premi\u00e8re pole position\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/formule-e-diriyah-stoffel-vandoorne-est-le-premier-poleman-de-la-saison\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Formule E - Diriyah : Stoffel Vandoorne est le premier poleman de la saison\" \/>\n<meta property=\"og:description\" content=\"FORMULE E - La saison 2022 de Formule E a d\u00e9but\u00e9 ce week-end et le Belge Stoffel Vandoorne (Mercedes-EQ) a d\u00e9croch\u00e9 la premi\u00e8re pole position\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/formule-e-diriyah-stoffel-vandoorne-est-le-premier-poleman-de-la-saison\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/roxane.lecacher\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-28T14:34:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-24T19:56:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Formule-E-Diriyah-Stoffel-Vandoorne-est-le-premier-poleman-de-la-saison.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Roxane Lecacher\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Formule E - Diriyah : Stoffel Vandoorne est le premier poleman de la saison\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/formule-e-diriyah-stoffel-vandoorne-est-le-premier-poleman-de-la-saison\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/formule-e-diriyah-stoffel-vandoorne-est-le-premier-poleman-de-la-saison\/\"},\"author\":{\"name\":\"Roxane Lecacher\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/819fb2545dd2715bd7c0580d6d4b411a\"},\"headline\":\"Formule E &#8211; Diriyah : Stoffel Vandoorne est le premier poleman de la saison\",\"datePublished\":\"2022-01-28T14:34:38+00:00\",\"dateModified\":\"2025-07-24T19:56:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/formule-e-diriyah-stoffel-vandoorne-est-le-premier-poleman-de-la-saison\/\"},\"wordCount\":909,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/formule-e-diriyah-stoffel-vandoorne-est-le-premier-poleman-de-la-saison\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Formule-E-Diriyah-Stoffel-Vandoorne-est-le-premier-poleman-de-la-saison.png\",\"keywords\":[\"Formule E\"],\"articleSection\":[\"Sports m\u00e9caniques\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/formule-e-diriyah-stoffel-vandoorne-est-le-premier-poleman-de-la-saison\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/formule-e-diriyah-stoffel-vandoorne-est-le-premier-poleman-de-la-saison\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/formule-e-diriyah-stoffel-vandoorne-est-le-premier-poleman-de-la-saison\/\",\"name\":\"Formule E - Diriyah : Stoffel Vandoorne est le premier poleman de la saison\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/formule-e-diriyah-stoffel-vandoorne-est-le-premier-poleman-de-la-saison\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/formule-e-diriyah-stoffel-vandoorne-est-le-premier-poleman-de-la-saison\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Formule-E-Diriyah-Stoffel-Vandoorne-est-le-premier-poleman-de-la-saison.png\",\"datePublished\":\"2022-01-28T14:34:38+00:00\",\"dateModified\":\"2025-07-24T19:56:30+00:00\",\"description\":\"FORMULE E - La saison 2022 de Formule E a d\u00e9but\u00e9 ce week-end et le Belge Stoffel Vandoorne (Mercedes-EQ) a d\u00e9croch\u00e9 la premi\u00e8re pole position\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/formule-e-diriyah-stoffel-vandoorne-est-le-premier-poleman-de-la-saison\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/formule-e-diriyah-stoffel-vandoorne-est-le-premier-poleman-de-la-saison\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/formule-e-diriyah-stoffel-vandoorne-est-le-premier-poleman-de-la-saison\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Formule-E-Diriyah-Stoffel-Vandoorne-est-le-premier-poleman-de-la-saison.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Formule-E-Diriyah-Stoffel-Vandoorne-est-le-premier-poleman-de-la-saison.png\",\"width\":800,\"height\":445,\"caption\":\"Formule E - Diriyah Stoffel Vandoorne est le premier poleman de la saison\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/formule-e-diriyah-stoffel-vandoorne-est-le-premier-poleman-de-la-saison\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Formule E &#8211; Diriyah : Stoffel Vandoorne est le premier poleman de la saison\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/819fb2545dd2715bd7c0580d6d4b411a\",\"name\":\"Roxane Lecacher\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Roxane-Lecacher-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Roxane-Lecacher-150x150.jpg\",\"caption\":\"Roxane Lecacher\"},\"description\":\"Journaliste\/r\u00e9dactrice depuis janvier 2021 - N\u00e9e quelques jours avant la premi\u00e8re \u00e9toile des Bleus, je baigne dans une famille tr\u00e8s sportive. Je n\u2019ai eu d\u2019autres choix que de me passionner pour le sujet. Pratiquante de l\u2019athl\u00e9tisme depuis toute petite, j\u2019ai aussi un attrait tout particulier pour la Formule 1, le biathlon et le foot. Pendant les grands \u00e9v\u00e9nements, il est impossible de d\u00e9crocher de ma t\u00e9l\u00e9. C\u2019est \u00e0 travers Dicodusport que j\u2019aime d\u00e9sormais vous transmettre mes \u00e9motions et ma passion.\",\"sameAs\":[\"https:\/\/www.facebook.com\/roxane.lecacher\",\"https:\/\/fr.linkedin.com\/in\/roxane-lecacher-23368313b\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/roxanel\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Formule E - Diriyah : Stoffel Vandoorne est le premier poleman de la saison","description":"FORMULE E - La saison 2022 de Formule E a d\u00e9but\u00e9 ce week-end et le Belge Stoffel Vandoorne (Mercedes-EQ) a d\u00e9croch\u00e9 la premi\u00e8re pole position","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/formule-e-diriyah-stoffel-vandoorne-est-le-premier-poleman-de-la-saison\/","og_locale":"fr_FR","og_type":"article","og_title":"Formule E - Diriyah : Stoffel Vandoorne est le premier poleman de la saison","og_description":"FORMULE E - La saison 2022 de Formule E a d\u00e9but\u00e9 ce week-end et le Belge Stoffel Vandoorne (Mercedes-EQ) a d\u00e9croch\u00e9 la premi\u00e8re pole position","og_url":"https:\/\/dicodusport.fr\/blog\/formule-e-diriyah-stoffel-vandoorne-est-le-premier-poleman-de-la-saison\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/roxane.lecacher","article_published_time":"2022-01-28T14:34:38+00:00","article_modified_time":"2025-07-24T19:56:30+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Formule-E-Diriyah-Stoffel-Vandoorne-est-le-premier-poleman-de-la-saison.png","type":"image\/png"}],"author":"Roxane Lecacher","twitter_card":"summary_large_image","twitter_title":"Formule E - Diriyah : Stoffel Vandoorne est le premier poleman de la saison","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/formule-e-diriyah-stoffel-vandoorne-est-le-premier-poleman-de-la-saison\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/formule-e-diriyah-stoffel-vandoorne-est-le-premier-poleman-de-la-saison\/"},"author":{"name":"Roxane Lecacher","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/819fb2545dd2715bd7c0580d6d4b411a"},"headline":"Formule E &#8211; Diriyah : Stoffel Vandoorne est le premier poleman de la saison","datePublished":"2022-01-28T14:34:38+00:00","dateModified":"2025-07-24T19:56:30+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/formule-e-diriyah-stoffel-vandoorne-est-le-premier-poleman-de-la-saison\/"},"wordCount":909,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/formule-e-diriyah-stoffel-vandoorne-est-le-premier-poleman-de-la-saison\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Formule-E-Diriyah-Stoffel-Vandoorne-est-le-premier-poleman-de-la-saison.png","keywords":["Formule E"],"articleSection":["Sports m\u00e9caniques"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/formule-e-diriyah-stoffel-vandoorne-est-le-premier-poleman-de-la-saison\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/formule-e-diriyah-stoffel-vandoorne-est-le-premier-poleman-de-la-saison\/","url":"https:\/\/dicodusport.fr\/blog\/formule-e-diriyah-stoffel-vandoorne-est-le-premier-poleman-de-la-saison\/","name":"Formule E - Diriyah : Stoffel Vandoorne est le premier poleman de la saison","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/formule-e-diriyah-stoffel-vandoorne-est-le-premier-poleman-de-la-saison\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/formule-e-diriyah-stoffel-vandoorne-est-le-premier-poleman-de-la-saison\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Formule-E-Diriyah-Stoffel-Vandoorne-est-le-premier-poleman-de-la-saison.png","datePublished":"2022-01-28T14:34:38+00:00","dateModified":"2025-07-24T19:56:30+00:00","description":"FORMULE E - La saison 2022 de Formule E a d\u00e9but\u00e9 ce week-end et le Belge Stoffel Vandoorne (Mercedes-EQ) a d\u00e9croch\u00e9 la premi\u00e8re pole position","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/formule-e-diriyah-stoffel-vandoorne-est-le-premier-poleman-de-la-saison\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/formule-e-diriyah-stoffel-vandoorne-est-le-premier-poleman-de-la-saison\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/formule-e-diriyah-stoffel-vandoorne-est-le-premier-poleman-de-la-saison\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Formule-E-Diriyah-Stoffel-Vandoorne-est-le-premier-poleman-de-la-saison.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Formule-E-Diriyah-Stoffel-Vandoorne-est-le-premier-poleman-de-la-saison.png","width":800,"height":445,"caption":"Formule E - Diriyah Stoffel Vandoorne est le premier poleman de la saison"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/formule-e-diriyah-stoffel-vandoorne-est-le-premier-poleman-de-la-saison\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Formule E &#8211; Diriyah : Stoffel Vandoorne est le premier poleman de la saison"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/819fb2545dd2715bd7c0580d6d4b411a","name":"Roxane Lecacher","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Roxane-Lecacher-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Roxane-Lecacher-150x150.jpg","caption":"Roxane Lecacher"},"description":"Journaliste\/r\u00e9dactrice depuis janvier 2021 - N\u00e9e quelques jours avant la premi\u00e8re \u00e9toile des Bleus, je baigne dans une famille tr\u00e8s sportive. Je n\u2019ai eu d\u2019autres choix que de me passionner pour le sujet. Pratiquante de l\u2019athl\u00e9tisme depuis toute petite, j\u2019ai aussi un attrait tout particulier pour la Formule 1, le biathlon et le foot. Pendant les grands \u00e9v\u00e9nements, il est impossible de d\u00e9crocher de ma t\u00e9l\u00e9. C\u2019est \u00e0 travers Dicodusport que j\u2019aime d\u00e9sormais vous transmettre mes \u00e9motions et ma passion.","sameAs":["https:\/\/www.facebook.com\/roxane.lecacher","https:\/\/fr.linkedin.com\/in\/roxane-lecacher-23368313b"],"url":"https:\/\/dicodusport.fr\/blog\/author\/roxanel\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/194993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/54"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=194993"}],"version-history":[{"count":1,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/194993\/revisions"}],"predecessor-version":[{"id":597728,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/194993\/revisions\/597728"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/195037"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=194993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=194993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=194993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}