{"id":195127,"date":"2022-01-28T20:32:55","date_gmt":"2022-01-28T19:32:55","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=195127&#038;preview=true&#038;preview_id=195127"},"modified":"2022-01-28T20:32:55","modified_gmt":"2022-01-28T19:32:55","slug":"francais-et-francaises-serieux-des-le-premier-jour-de-competition","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/francais-et-francaises-serieux-des-le-premier-jour-de-competition\/","title":{"rendered":"Sevens Series de S\u00e9ville : Les \u00e9quipes de France s\u00e9rieuses d\u00e8s le premier jour de comp\u00e9tition"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>SEVENS SERIES DE S\u00c9VILLE &#8211; Lors du premier jour de ce quatri\u00e8me tournoi des Sevens Series de la saison, qui a lieu \u00e0 S\u00e9ville (Espagne), les \u00e9quipes de France ont \u00e9t\u00e9 appliqu\u00e9es avant d&rsquo;aborder la deuxi\u00e8me journ\u00e9e. Les Bleues ont coll\u00e9 deux fanny \u00e0 leurs adversaires et les Bleus ont d\u00e9roul\u00e9 face au Pays de Galles.\u00a0<\/em><\/strong><\/p>\n<h2 style=\"text-align: justify;\">Deux adversaires tr\u00e8s abordables pour se mettre en jambes<\/h2>\n<p style=\"text-align: justify;\">88 pts marqu\u00e9s, 2 encaiss\u00e9s. Voil\u00e0 le bilan tr\u00e8s glorieux des joueuses de David Courteix apr\u00e8s le premier jour de ce deuxi\u00e8me tournoi espagnol. Les Bleues nous doivent une revanche par rapport \u00e0 la semaine derni\u00e8re o\u00f9 <a href=\"https:\/\/dicodusport.fr\/blog\/seven-series-malaga-bleues-quatriemes-bleus-cinquiemes\/\">elles m\u00e9ritaient de faire beaucoup mieux que cette quatri\u00e8me place<\/a>. Pour d\u00e9marrer un tournoi, rien de mieux que d&rsquo;affronter deux adversaires largement prenables sur le papier pour se mettre dans le tempo. D&rsquo;abord face \u00e0 l&rsquo;Espagne, <strong>Joanna Grisez<\/strong> et ses co\u00e9quipi\u00e8res ont d\u00e9roul\u00e9 (45-0) en inscrivant la bagatelle de 8 essais. <strong>Anne-C\u00e9cile Ciofani<\/strong> a inscrit un doubl\u00e9 tandis que <strong>Joanna Grisez<\/strong> a inscrit un tripl\u00e9.<\/p>\n<p style=\"text-align: justify;\">Face \u00e0 la Belgique, qui a termin\u00e9 avant-derni\u00e8re du tournoi de Malaga, ce fut le m\u00eame tarif ou presque. Une victoire nette et sans bavure 43-0 avec 7 essais marqu\u00e9s. Le collectif a parl\u00e9 avec six marqueuses diff\u00e9rentes : <strong>Coralie Bertrand<\/strong> a ouvert le bal, avant un doubl\u00e9 de <strong>Ian Jason<\/strong>, puis des essais de <strong>Valentine Lothoz<\/strong>, <strong>Joanna Grisez<\/strong>, <strong>Chlo\u00e9 Jacquet<\/strong> et <strong>Lou No\u00ebl<\/strong>, qui a par ailleurs inscrit son premier essai de sa carri\u00e8re. Demain, on passe \u00e0 un tout autre calibre puisque la France affrontera l&rsquo;Australie pour un match d\u00e9cisif afin de terminer premi\u00e8re de la poule. Ce sera \u00e9galement une revanche par rapport au tournoi de Malaga, o\u00f9 les co\u00e9quipi\u00e8res de <strong>Charlotte Caslick<\/strong> s&rsquo;\u00e9taient impos\u00e9es 33 \u00e0 7 pour le match de la troisi\u00e8me place.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">.<a href=\"https:\/\/twitter.com\/AnneCeCiofani?ref_src=twsrc%5Etfw\">@AnneCeCiofani<\/a> shows why she&rsquo;s the World Rugby Sevens Player of the Year! <a href=\"https:\/\/twitter.com\/hashtag\/ImpactMoment?src=hash&amp;ref_src=twsrc%5Etfw\">#ImpactMoment<\/a> | <a href=\"https:\/\/twitter.com\/DHLRugby?ref_src=twsrc%5Etfw\">@DHLrugby<\/a> | <a href=\"https:\/\/twitter.com\/FranceRugby?ref_src=twsrc%5Etfw\">@FranceRugby<\/a> <a href=\"https:\/\/t.co\/sDaoHybA42\">pic.twitter.com\/sDaoHybA42<\/a><\/p>\n<p>\u2014 World Rugby Sevens (@WorldRugby7s) <a href=\"https:\/\/twitter.com\/WorldRugby7s\/status\/1487049306523717646?ref_src=twsrc%5Etfw\">January 28, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Jordan S\u00e9pho d\u00e9ja en cannes<\/h2>\n<p style=\"text-align: justify;\">C\u00f4t\u00e9 masculin, seulement une rencontre disput\u00e9e aujourd&rsquo;hui avant les deux autres matchs de la poule qui auront lieu demain samedi, face au Japon et l&rsquo;Angleterre. Cet apr\u00e8s-midi, les Bleus ont balay\u00e9 le Pays de Galles 38 \u00e0 12 avec notamment un tripl\u00e9 de <strong>Jordan S\u00e9pho<\/strong> et un essai de <strong>Nelson Ep\u00e9e<\/strong>. Dans cette poule, les Bleus ont largement les moyens de terminer premiers, l&rsquo;Angleterre est l&rsquo;adversaire le plus coriace pour emp\u00eacher la France de terminer leader de la poule C. De plus, les Bleus voudront s\u00fbrement prendre leur revanche, eux qui ont \u00e9t\u00e9 \u00e9limin\u00e9s par ces m\u00eames Anglais en quarts \u00e0 Malaga la semaine derni\u00e8re.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Pace. To. Burn<\/p>\n<p>Nelson Epee scorching down the touchline is a sight to behold in Seville<a href=\"https:\/\/twitter.com\/hashtag\/HSBC7s?src=hash&amp;ref_src=twsrc%5Etfw\">#HSBC7s<\/a> | <a href=\"https:\/\/twitter.com\/hashtag\/Spain7s?src=hash&amp;ref_src=twsrc%5Etfw\">#Spain7s<\/a> | <a href=\"https:\/\/twitter.com\/FranceRugby?ref_src=twsrc%5Etfw\">@FranceRugby<\/a> <a href=\"https:\/\/t.co\/fE5EydlAVe\">pic.twitter.com\/fE5EydlAVe<\/a><\/p>\n<p>\u2014 World Rugby Sevens (@WorldRugby7s) <a href=\"https:\/\/twitter.com\/WorldRugby7s\/status\/1487076834202247170?ref_src=twsrc%5Etfw\">January 28, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>SEVENS SERIES DE S\u00c9VILLE &#8211; Lors du premier jour de ce quatri\u00e8me tournoi des Sevens Series de la saison, qui a lieu \u00e0 S\u00e9ville (Espagne), les \u00e9quipes de France ont \u00e9t\u00e9 appliqu\u00e9es avant d&rsquo;aborder la deuxi\u00e8me journ\u00e9e. Les Bleues ont coll\u00e9 deux fanny \u00e0 leurs adversaires et les Bleus ont d\u00e9roul\u00e9 face au Pays de Galles.\u00a0<\/p>\n","protected":false},"author":42,"featured_media":193423,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[9130],"tags":[],"class_list":["post-195127","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-7"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sevens Series de S\u00e9ville : Les \u00e9quipes de France s\u00e9rieuses d\u00e8s le premier jour de comp\u00e9tition<\/title>\n<meta name=\"description\" content=\"SEVENS SERIES - Pour ce premier jour du tournoi de S\u00e9ville, les Bleus et les Bleues ont parfaitement n\u00e9goci\u00e9 leur entr\u00e9e dans la comp\u00e9tition.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/francais-et-francaises-serieux-des-le-premier-jour-de-competition\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sevens Series de S\u00e9ville : Les \u00e9quipes de France s\u00e9rieuses d\u00e8s le premier jour de comp\u00e9tition\" \/>\n<meta property=\"og:description\" content=\"SEVENS SERIES - Pour ce premier jour du tournoi de S\u00e9ville, les Bleus et les Bleues ont parfaitement n\u00e9goci\u00e9 leur entr\u00e9e dans la comp\u00e9tition.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/francais-et-francaises-serieux-des-le-premier-jour-de-competition\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-28T19:32:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Sevens-Series-de-Malaga-Les-Bleues-en-demi-finale-apres-leur-succes-face-a-lIrlande.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Mezine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Sevens Series de S\u00e9ville : Les \u00e9quipes de France s\u00e9rieuses d\u00e8s le premier jour de comp\u00e9tition\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Lbiji13\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/francais-et-francaises-serieux-des-le-premier-jour-de-competition\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/francais-et-francaises-serieux-des-le-premier-jour-de-competition\/\"},\"author\":{\"name\":\"Nicolas Mezine\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/99fcf31b3ee0d51fed53ade78139bbbf\"},\"headline\":\"Sevens Series de S\u00e9ville : Les \u00e9quipes de France s\u00e9rieuses d\u00e8s le premier jour de comp\u00e9tition\",\"datePublished\":\"2022-01-28T19:32:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/francais-et-francaises-serieux-des-le-premier-jour-de-competition\/\"},\"wordCount\":519,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/francais-et-francaises-serieux-des-le-premier-jour-de-competition\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Sevens-Series-de-Malaga-Les-Bleues-en-demi-finale-apres-leur-succes-face-a-lIrlande.png\",\"articleSection\":[\"Rugby \u00e0 7\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/francais-et-francaises-serieux-des-le-premier-jour-de-competition\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/francais-et-francaises-serieux-des-le-premier-jour-de-competition\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/francais-et-francaises-serieux-des-le-premier-jour-de-competition\/\",\"name\":\"Sevens Series de S\u00e9ville : Les \u00e9quipes de France s\u00e9rieuses d\u00e8s le premier jour de comp\u00e9tition\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/francais-et-francaises-serieux-des-le-premier-jour-de-competition\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/francais-et-francaises-serieux-des-le-premier-jour-de-competition\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Sevens-Series-de-Malaga-Les-Bleues-en-demi-finale-apres-leur-succes-face-a-lIrlande.png\",\"datePublished\":\"2022-01-28T19:32:55+00:00\",\"description\":\"SEVENS SERIES - Pour ce premier jour du tournoi de S\u00e9ville, les Bleus et les Bleues ont parfaitement n\u00e9goci\u00e9 leur entr\u00e9e dans la comp\u00e9tition.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/francais-et-francaises-serieux-des-le-premier-jour-de-competition\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/francais-et-francaises-serieux-des-le-premier-jour-de-competition\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/francais-et-francaises-serieux-des-le-premier-jour-de-competition\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Sevens-Series-de-Malaga-Les-Bleues-en-demi-finale-apres-leur-succes-face-a-lIrlande.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Sevens-Series-de-Malaga-Les-Bleues-en-demi-finale-apres-leur-succes-face-a-lIrlande.png\",\"width\":800,\"height\":445,\"caption\":\"World Rugby Sevens Duba\u00ef Les deux \u00e9quipes de France en quarts de finale\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/francais-et-francaises-serieux-des-le-premier-jour-de-competition\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sevens Series de S\u00e9ville : Les \u00e9quipes de France s\u00e9rieuses d\u00e8s le premier jour de comp\u00e9tition\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/99fcf31b3ee0d51fed53ade78139bbbf\",\"name\":\"Nicolas Mezine\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/IMG_4655-e1631787111223-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/IMG_4655-e1631787111223-150x150.jpg\",\"caption\":\"Nicolas Mezine\"},\"description\":\"Passionn\u00e9 de sport, notamment de rugby dans toutes ses variantes (XV, XIII et VII). Fan du RC Toulon et de l'Olympique de Marseille.\",\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/nicolas-mezine-521380160\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/Lbiji13\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/nicolas-m\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sevens Series de S\u00e9ville : Les \u00e9quipes de France s\u00e9rieuses d\u00e8s le premier jour de comp\u00e9tition","description":"SEVENS SERIES - Pour ce premier jour du tournoi de S\u00e9ville, les Bleus et les Bleues ont parfaitement n\u00e9goci\u00e9 leur entr\u00e9e dans la comp\u00e9tition.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/francais-et-francaises-serieux-des-le-premier-jour-de-competition\/","og_locale":"fr_FR","og_type":"article","og_title":"Sevens Series de S\u00e9ville : Les \u00e9quipes de France s\u00e9rieuses d\u00e8s le premier jour de comp\u00e9tition","og_description":"SEVENS SERIES - Pour ce premier jour du tournoi de S\u00e9ville, les Bleus et les Bleues ont parfaitement n\u00e9goci\u00e9 leur entr\u00e9e dans la comp\u00e9tition.","og_url":"https:\/\/dicodusport.fr\/blog\/francais-et-francaises-serieux-des-le-premier-jour-de-competition\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2022-01-28T19:32:55+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Sevens-Series-de-Malaga-Les-Bleues-en-demi-finale-apres-leur-succes-face-a-lIrlande.png","type":"image\/png"}],"author":"Nicolas Mezine","twitter_card":"summary_large_image","twitter_title":"Sevens Series de S\u00e9ville : Les \u00e9quipes de France s\u00e9rieuses d\u00e8s le premier jour de comp\u00e9tition","twitter_creator":"@https:\/\/twitter.com\/Lbiji13","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/francais-et-francaises-serieux-des-le-premier-jour-de-competition\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/francais-et-francaises-serieux-des-le-premier-jour-de-competition\/"},"author":{"name":"Nicolas Mezine","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/99fcf31b3ee0d51fed53ade78139bbbf"},"headline":"Sevens Series de S\u00e9ville : Les \u00e9quipes de France s\u00e9rieuses d\u00e8s le premier jour de comp\u00e9tition","datePublished":"2022-01-28T19:32:55+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/francais-et-francaises-serieux-des-le-premier-jour-de-competition\/"},"wordCount":519,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/francais-et-francaises-serieux-des-le-premier-jour-de-competition\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Sevens-Series-de-Malaga-Les-Bleues-en-demi-finale-apres-leur-succes-face-a-lIrlande.png","articleSection":["Rugby \u00e0 7"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/francais-et-francaises-serieux-des-le-premier-jour-de-competition\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/francais-et-francaises-serieux-des-le-premier-jour-de-competition\/","url":"https:\/\/dicodusport.fr\/blog\/francais-et-francaises-serieux-des-le-premier-jour-de-competition\/","name":"Sevens Series de S\u00e9ville : Les \u00e9quipes de France s\u00e9rieuses d\u00e8s le premier jour de comp\u00e9tition","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/francais-et-francaises-serieux-des-le-premier-jour-de-competition\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/francais-et-francaises-serieux-des-le-premier-jour-de-competition\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Sevens-Series-de-Malaga-Les-Bleues-en-demi-finale-apres-leur-succes-face-a-lIrlande.png","datePublished":"2022-01-28T19:32:55+00:00","description":"SEVENS SERIES - Pour ce premier jour du tournoi de S\u00e9ville, les Bleus et les Bleues ont parfaitement n\u00e9goci\u00e9 leur entr\u00e9e dans la comp\u00e9tition.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/francais-et-francaises-serieux-des-le-premier-jour-de-competition\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/francais-et-francaises-serieux-des-le-premier-jour-de-competition\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/francais-et-francaises-serieux-des-le-premier-jour-de-competition\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Sevens-Series-de-Malaga-Les-Bleues-en-demi-finale-apres-leur-succes-face-a-lIrlande.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/01\/Sevens-Series-de-Malaga-Les-Bleues-en-demi-finale-apres-leur-succes-face-a-lIrlande.png","width":800,"height":445,"caption":"World Rugby Sevens Duba\u00ef Les deux \u00e9quipes de France en quarts de finale"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/francais-et-francaises-serieux-des-le-premier-jour-de-competition\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Sevens Series de S\u00e9ville : Les \u00e9quipes de France s\u00e9rieuses d\u00e8s le premier jour de comp\u00e9tition"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/99fcf31b3ee0d51fed53ade78139bbbf","name":"Nicolas Mezine","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/IMG_4655-e1631787111223-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/IMG_4655-e1631787111223-150x150.jpg","caption":"Nicolas Mezine"},"description":"Passionn\u00e9 de sport, notamment de rugby dans toutes ses variantes (XV, XIII et VII). Fan du RC Toulon et de l'Olympique de Marseille.","sameAs":["https:\/\/www.linkedin.com\/in\/nicolas-mezine-521380160\/","https:\/\/x.com\/https:\/\/twitter.com\/Lbiji13"],"url":"https:\/\/dicodusport.fr\/blog\/author\/nicolas-m\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/195127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=195127"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/195127\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/193423"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=195127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=195127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=195127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}