{"id":198877,"date":"2022-02-14T10:56:10","date_gmt":"2022-02-14T09:56:10","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=198877&#038;preview=true&#038;preview_id=198877"},"modified":"2022-02-14T11:14:03","modified_gmt":"2022-02-14T10:14:03","slug":"bonzi-mannarino-paire-tops-et-flops-tennis-francais-cette-semaine","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/bonzi-mannarino-paire-tops-et-flops-tennis-francais-cette-semaine\/","title":{"rendered":"Bonzi, Mannarino, Paire : les tops et flops du tennis fran\u00e7ais cette semaine"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><b>TENNIS 2022 &#8211; Tout au long de la saison, Dicodusport fera le point sur les performances des Fran\u00e7ais et Fran\u00e7aises sur le circuit professionnel. Une semaine compliqu\u00e9e pour les Tricolores, qui escompteront se relancer lors de l&rsquo;Open 13 de Marseille cette semaine notamment.\u00a0<\/b><\/em><\/p>\n<h2 style=\"text-align: justify;\">Les tops<\/h2>\n<p style=\"text-align: justify;\">Sur le circuit principal, les Bleus auront \u00e9t\u00e9 mis en difficult\u00e9 cette semaine. L&rsquo;une des satisfactions de l&rsquo;Open d&rsquo;Australie,<strong> Adrian Mannarino<\/strong>, aura lui tenu son rang. A Dallas, il aura pass\u00e9 deux tours avant de tomber en quarts de finale contre la t\u00eate de s\u00e9rie n\u00b02, <strong>Reilly Opelka<\/strong>, 23\u00e8me mondial et \u00e9norme serveur. Mais son bilan est de 7 victoires pour 5 d\u00e9faites depuis le d\u00e9but de saison, positif donc, tout comme son comportement sur le court.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">La nuit derni\u00e8re, Adrian <a href=\"https:\/\/twitter.com\/hashtag\/Mannarino?src=hash&amp;ref_src=twsrc%5Etfw\">#Mannarino<\/a> (n\u00b057) &#x1f1eb;&#x1f1f7; s&rsquo;est inclin\u00e9 en quarts de finale du <a href=\"https:\/\/twitter.com\/hashtag\/DALOpen?src=hash&amp;ref_src=twsrc%5Etfw\">#DALOpen<\/a> de Dallas ! T\u00eate de s\u00e9rie n\u00b05, il a perdu face \u00e0 Reilly <a href=\"https:\/\/twitter.com\/hashtag\/Opelka?src=hash&amp;ref_src=twsrc%5Etfw\">#Opelka<\/a> (n\u00b023) &#x1f1fa;&#x1f1f8;, t\u00eate de s\u00e9rie n\u00b02, en deux sets 6-3, 6-4. <a href=\"https:\/\/t.co\/uQWhHrZupK\">pic.twitter.com\/uQWhHrZupK<\/a><\/p>\n<p>\u2014 Jeu, Set Et Match (@jeu_set_etmatch) <a href=\"https:\/\/twitter.com\/jeu_set_etmatch\/status\/1492409576876126212?ref_src=twsrc%5Etfw\">February 12, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Heureusement, les Fran\u00e7ais engag\u00e9s sur le Challenger de Cherbourg ont fait bonne figure. A l&rsquo;issue d&rsquo;une finale 100% Tricolore, c&rsquo;est finalement <strong>Benjamin Bonzi<\/strong> <a href=\"https:\/\/dicodusport.fr\/blog\/atp-challenger-benjamin-bonzi-enleve-le-titre-a-constant-lestienne-a-cherbourg\/\">qui s&rsquo;est impos\u00e9 \u00e0 l&rsquo;arrach\u00e9e en trois manches<\/a> contre <strong>Constant Lestienne<\/strong>. Il confirme ainsi ses bonnes dispositions entrevues ces derni\u00e8res semaines, et remporte son 10\u00e8me titre en carri\u00e8re.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Champion in Cherbourg! &#x1f389;<a href=\"https:\/\/twitter.com\/BenjaminBonzi?ref_src=twsrc%5Etfw\">@BenjaminBonzi<\/a> captures the crown at the <a href=\"https:\/\/twitter.com\/ChallengerChbg?ref_src=twsrc%5Etfw\">@ChallengerChbg<\/a>, overcoming fellow &#x1f1eb;&#x1f1f7; Lestienne 64 26 64 for the &#x1f3c6;.<\/p>\n<p>Exactly one year after claiming his maiden <a href=\"https:\/\/twitter.com\/hashtag\/ATPChallenger?src=hash&amp;ref_src=twsrc%5Etfw\">#ATPChallenger<\/a> title, Bonzi wins No. 7&#x20e3;. <a href=\"https:\/\/t.co\/pmx3tuQThS\">pic.twitter.com\/pmx3tuQThS<\/a><\/p>\n<p>\u2014 ATP Challenger Tour (@ATPChallenger) <a href=\"https:\/\/twitter.com\/ATPChallenger\/status\/1492898357509074946?ref_src=twsrc%5Etfw\">February 13, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Sur le circuit ITF, c&rsquo;est la jeune (19 ans) <strong>Selena Janicijevic<\/strong> qui signe la performance de la semaine en remportant le W15 d&rsquo;Antalya, en Turquie. Elle n&rsquo;aura perdu qu&rsquo;un seul set au cours de la semaine et elle en est d\u00e9sormais \u00e0 21 succ\u00e8s sur ses 23 derniers matchs, raflant trois titres au passage ! On notera \u00e9galement la bonne forme de<strong> Sascha Gueymard Wayenburg,<\/strong> qui a trac\u00e9 sa route jusqu&rsquo;en finale du M15 de Grenoble avant de s&rsquo;incliner logiquement contre le Russe <strong>Vatutin<\/strong>, t\u00eate de s\u00e9rie n\u00b01.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">2nd titre en 2022 pour Selena Janicijevic \u00e0 <a href=\"https:\/\/twitter.com\/hashtag\/Antalya?src=hash&amp;ref_src=twsrc%5Etfw\">#Antalya<\/a> &#x1f1f9;&#x1f1f7; en battant en finale l&rsquo;Italienne Moratelli 6\/3 6\/2.<br \/>\nElle va faire son entr\u00e9e dans le top 400.<\/p>\n<p>\u2014 FrenchiesTennis (@FrenchiesTennis) <a href=\"https:\/\/twitter.com\/FrenchiesTennis\/status\/1492864570469277697?ref_src=twsrc%5Etfw\">February 13, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Les flops<\/h2>\n<p style=\"text-align: justify;\">Pour les athl\u00e8tes performants \u00e0 l&rsquo;Open d&rsquo;Australie, la reprise est dure. Lors de son premier match depuis son quart de finale \u00e0 Melbourne, <strong>Aliz\u00e9 Cornet<\/strong> aura livr\u00e9 un beau combat contre<strong> Elise Mertens<\/strong>, qui n&rsquo;est pas la premi\u00e8re venue, mais s&rsquo;est finalement inclin\u00e9e au troisi\u00e8me set apr\u00e8s plus de deux heures de jeu. Pas de panique toutefois, beaucoup de joueurs ont eu des difficult\u00e9s \u00e0 se relancer apr\u00e8s un tournoi australien r\u00e9ussi.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">So many long rallies &#x1f605;&#x1f4aa;<\/p>\n<p>Elise Mertens battles past <a href=\"https:\/\/twitter.com\/hashtag\/Ausopen?src=hash&amp;ref_src=twsrc%5Etfw\">#Ausopen<\/a> QFist Cornet, 3-6, 6-2, 6-4 to reach the 2nd round of <a href=\"https:\/\/twitter.com\/hashtag\/FORMULATX?src=hash&amp;ref_src=twsrc%5Etfw\">#FORMULATX<\/a>!! &#x1f44a;&#x1f44a; <a href=\"https:\/\/twitter.com\/elise_mertens?ref_src=twsrc%5Etfw\">@elise_mertens<\/a> <a href=\"https:\/\/t.co\/DmmOk8iwJD\">pic.twitter.com\/DmmOk8iwJD<\/a><\/p>\n<p>\u2014 \u304f\u308c\u3075\u3041 (@umbre_sports532) <a href=\"https:\/\/twitter.com\/umbre_sports532\/status\/1490698879775379465?ref_src=twsrc%5Etfw\">February 7, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">C&rsquo;est le cas pour <strong>Beno\u00eet Paire<\/strong>, qui nous a livr\u00e9 un craquage dont lui seul a le secret. Alors qu&rsquo;il avait le match en main contre <strong>Dusan Lajovic<\/strong> \u00e0 Buenos Aires, il a compl\u00e8tement manqu\u00e9 un smash facile sur balle de match et laiss\u00e9 passer sa chance. Il s&rsquo;est finalement inclin\u00e9 au tiebreak du troisi\u00e8me set, d\u00e8s le premier tour, et sa tourn\u00e9e sud-am\u00e9ricaine sur terre battue est pour l&rsquo;instant un \u00e9chec.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">10. Alors qu&rsquo;il menait 5\/4 40-0 sur son service dans le 3\u00e8me set, Benoit Paire s&rsquo;est inclin\u00e9 face \u00e0 Dusan Lajovic (N\u00b037). Le Fran\u00e7ais a conc\u00e9d\u00e9 sa 10\u00e8me d\u00e9faite sur le circuit principal apr\u00e8s s&rsquo;\u00eatre procur\u00e9 au moins une balle de match. <a href=\"https:\/\/twitter.com\/hashtag\/ArgOpen2022?src=hash&amp;ref_src=twsrc%5Etfw\">#ArgOpen2022<\/a> <a href=\"https:\/\/t.co\/4fnE9sp7oo\">pic.twitter.com\/4fnE9sp7oo<\/a><\/p>\n<p>\u2014 Jeu, Set et Maths (@JeuSetMaths) <a href=\"https:\/\/twitter.com\/JeuSetMaths\/status\/1490822361096265728?ref_src=twsrc%5Etfw\">February 7, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">A Rotterdam,<strong> Jo-Wilfried Tsonga<\/strong> avait re\u00e7u une invitation mais ne s&rsquo;est pas montr\u00e9 \u00e0 son maximum face au solide polonais <strong>Hubert Hurcakz,<\/strong> malgr\u00e9 une belle r\u00e9sistance dans la seconde manche. Quand \u00e0 <strong>Ugo Humbert<\/strong>, il n&rsquo;a pas vu le jour contre <strong>Cameron Norrie<\/strong>, qui n&rsquo;avait pourtant pas remport\u00e9 le moindre match cette ann\u00e9e! L&rsquo;espoir Fran\u00e7ais souffre apparemment d&rsquo;une blessure.<\/p>\n<p style=\"text-align: justify;\">Toujours sur courant alternatif, <strong>Corentin Moutet <\/strong>et <strong>Hugo Gaston<\/strong> se sont inclin\u00e9s au dernier tour des qualifications \u00e0 Rotterdam, face \u00e0 des adversaires pourtant abordables. <strong>Gaston<\/strong> a pourtant \u00e9t\u00e9 rep\u00each\u00e9 en tant que <em>lucky loser,<\/em> mais comme \u00e0 Montpellier, il n&rsquo;a rien pu faire face au Sud-Cor\u00e9en <strong>Kwon<\/strong>. Leur saison est pour l&rsquo;instant plus que frustrante.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TENNIS 2022 &#8211; Tout au long de la saison, Dicodusport fera le point sur les performances des Fran\u00e7ais et Fran\u00e7aises sur le circuit professionnel. Une semaine compliqu\u00e9e pour les Tricolores, qui escompteront se relancer lors de l&rsquo;Open 13 de Marseille cette semaine notamment.\u00a0<\/p>\n","protected":false},"author":59,"featured_media":200255,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2302],"tags":[4792],"class_list":["post-198877","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tennis","tag-tennis-francais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bonzi, Mannarino, Paire : les tops et flops du tennis fran\u00e7ais cette semaine<\/title>\n<meta name=\"description\" content=\"SAISON 2022 - Tout au long de la saison, Dicodusport fera le point sur les performances des Fran\u00e7ais et Fran\u00e7aises.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/bonzi-mannarino-paire-tops-et-flops-tennis-francais-cette-semaine\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bonzi, Mannarino, Paire : les tops et flops du tennis fran\u00e7ais cette semaine\" \/>\n<meta property=\"og:description\" content=\"SAISON 2022 - Tout au long de la saison, Dicodusport fera le point sur les performances des Fran\u00e7ais et Fran\u00e7aises.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/bonzi-mannarino-paire-tops-et-flops-tennis-francais-cette-semaine\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-14T09:56:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-14T10:14:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Bonzi-Mannarino-Paire-les-tops-et-flops-du-tennis-francais-cette-semaine.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Bonzi, Mannarino, Paire : les tops et flops du tennis fran\u00e7ais cette semaine\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/bonzi-mannarino-paire-tops-et-flops-tennis-francais-cette-semaine\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/bonzi-mannarino-paire-tops-et-flops-tennis-francais-cette-semaine\\\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Bonzi, Mannarino, Paire : les tops et flops du tennis fran\u00e7ais cette semaine\",\"datePublished\":\"2022-02-14T09:56:10+00:00\",\"dateModified\":\"2022-02-14T10:14:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/bonzi-mannarino-paire-tops-et-flops-tennis-francais-cette-semaine\\\/\"},\"wordCount\":831,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/bonzi-mannarino-paire-tops-et-flops-tennis-francais-cette-semaine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Bonzi-Mannarino-Paire-les-tops-et-flops-du-tennis-francais-cette-semaine.png\",\"keywords\":[\"Tennis fran\u00e7ais\"],\"articleSection\":[\"Tennis\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/bonzi-mannarino-paire-tops-et-flops-tennis-francais-cette-semaine\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/bonzi-mannarino-paire-tops-et-flops-tennis-francais-cette-semaine\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/bonzi-mannarino-paire-tops-et-flops-tennis-francais-cette-semaine\\\/\",\"name\":\"Bonzi, Mannarino, Paire : les tops et flops du tennis fran\u00e7ais cette semaine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/bonzi-mannarino-paire-tops-et-flops-tennis-francais-cette-semaine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/bonzi-mannarino-paire-tops-et-flops-tennis-francais-cette-semaine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Bonzi-Mannarino-Paire-les-tops-et-flops-du-tennis-francais-cette-semaine.png\",\"datePublished\":\"2022-02-14T09:56:10+00:00\",\"dateModified\":\"2022-02-14T10:14:03+00:00\",\"description\":\"SAISON 2022 - Tout au long de la saison, Dicodusport fera le point sur les performances des Fran\u00e7ais et Fran\u00e7aises.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/bonzi-mannarino-paire-tops-et-flops-tennis-francais-cette-semaine\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/bonzi-mannarino-paire-tops-et-flops-tennis-francais-cette-semaine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/bonzi-mannarino-paire-tops-et-flops-tennis-francais-cette-semaine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Bonzi-Mannarino-Paire-les-tops-et-flops-du-tennis-francais-cette-semaine.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Bonzi-Mannarino-Paire-les-tops-et-flops-du-tennis-francais-cette-semaine.png\",\"width\":800,\"height\":445,\"caption\":\"Bonzi, Mannarino, Paire les tops et flops du tennis fran\u00e7ais cette semaine\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/bonzi-mannarino-paire-tops-et-flops-tennis-francais-cette-semaine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bonzi, Mannarino, Paire : les tops et flops du tennis fran\u00e7ais cette semaine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sebastien.gente\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sebgente\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/sbastien-gente-a29583169\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sebastiengente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bonzi, Mannarino, Paire : les tops et flops du tennis fran\u00e7ais cette semaine","description":"SAISON 2022 - Tout au long de la saison, Dicodusport fera le point sur les performances des Fran\u00e7ais et Fran\u00e7aises.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/bonzi-mannarino-paire-tops-et-flops-tennis-francais-cette-semaine\/","og_locale":"fr_FR","og_type":"article","og_title":"Bonzi, Mannarino, Paire : les tops et flops du tennis fran\u00e7ais cette semaine","og_description":"SAISON 2022 - Tout au long de la saison, Dicodusport fera le point sur les performances des Fran\u00e7ais et Fran\u00e7aises.","og_url":"https:\/\/dicodusport.fr\/blog\/bonzi-mannarino-paire-tops-et-flops-tennis-francais-cette-semaine\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2022-02-14T09:56:10+00:00","article_modified_time":"2022-02-14T10:14:03+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Bonzi-Mannarino-Paire-les-tops-et-flops-du-tennis-francais-cette-semaine.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Bonzi, Mannarino, Paire : les tops et flops du tennis fran\u00e7ais cette semaine","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/bonzi-mannarino-paire-tops-et-flops-tennis-francais-cette-semaine\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/bonzi-mannarino-paire-tops-et-flops-tennis-francais-cette-semaine\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Bonzi, Mannarino, Paire : les tops et flops du tennis fran\u00e7ais cette semaine","datePublished":"2022-02-14T09:56:10+00:00","dateModified":"2022-02-14T10:14:03+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/bonzi-mannarino-paire-tops-et-flops-tennis-francais-cette-semaine\/"},"wordCount":831,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/bonzi-mannarino-paire-tops-et-flops-tennis-francais-cette-semaine\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Bonzi-Mannarino-Paire-les-tops-et-flops-du-tennis-francais-cette-semaine.png","keywords":["Tennis fran\u00e7ais"],"articleSection":["Tennis"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/bonzi-mannarino-paire-tops-et-flops-tennis-francais-cette-semaine\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/bonzi-mannarino-paire-tops-et-flops-tennis-francais-cette-semaine\/","url":"https:\/\/dicodusport.fr\/blog\/bonzi-mannarino-paire-tops-et-flops-tennis-francais-cette-semaine\/","name":"Bonzi, Mannarino, Paire : les tops et flops du tennis fran\u00e7ais cette semaine","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/bonzi-mannarino-paire-tops-et-flops-tennis-francais-cette-semaine\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/bonzi-mannarino-paire-tops-et-flops-tennis-francais-cette-semaine\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Bonzi-Mannarino-Paire-les-tops-et-flops-du-tennis-francais-cette-semaine.png","datePublished":"2022-02-14T09:56:10+00:00","dateModified":"2022-02-14T10:14:03+00:00","description":"SAISON 2022 - Tout au long de la saison, Dicodusport fera le point sur les performances des Fran\u00e7ais et Fran\u00e7aises.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/bonzi-mannarino-paire-tops-et-flops-tennis-francais-cette-semaine\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/bonzi-mannarino-paire-tops-et-flops-tennis-francais-cette-semaine\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/bonzi-mannarino-paire-tops-et-flops-tennis-francais-cette-semaine\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Bonzi-Mannarino-Paire-les-tops-et-flops-du-tennis-francais-cette-semaine.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Bonzi-Mannarino-Paire-les-tops-et-flops-du-tennis-francais-cette-semaine.png","width":800,"height":445,"caption":"Bonzi, Mannarino, Paire les tops et flops du tennis fran\u00e7ais cette semaine"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/bonzi-mannarino-paire-tops-et-flops-tennis-francais-cette-semaine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Bonzi, Mannarino, Paire : les tops et flops du tennis fran\u00e7ais cette semaine"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/198877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=198877"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/198877\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/200255"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=198877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=198877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=198877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}