{"id":200169,"date":"2022-02-14T10:07:37","date_gmt":"2022-02-14T09:07:37","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=200169&#038;preview=true&#038;preview_id=200169"},"modified":"2022-02-14T10:07:37","modified_gmt":"2022-02-14T09:07:37","slug":"johannes-boe-je-suis-vraiment-impressionne-par-ce-que-quentin-fillon-maillet-realise","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/johannes-boe-je-suis-vraiment-impressionne-par-ce-que-quentin-fillon-maillet-realise\/","title":{"rendered":"Johannes Boe : \u00ab\u00a0Je suis vraiment impressionn\u00e9 par ce que Quentin Fillon Maillet r\u00e9alise\u00a0\u00bb"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>JO P\u00c9KIN 2022 &#8211; BIATHLON &#8211; Longtemps en t\u00eate, Johannes Boe a fini par c\u00e9der face \u00e0 Quentin Fillon Maillet sur <a href=\"https:\/\/dicodusport.fr\/blog\/jo-pekin-2022-biathlon-quentin-fillon-maillet-champion-olympique-poursuite\/\">la poursuite des JO de P\u00e9kin<\/a>.\u00a0<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s un d\u00e9but de course id\u00e9al, le Norv\u00e9gien <strong>Johannes Boe<\/strong> est parti trois fois \u00e0 la faute sur son premier debout alors que Quentin Fillon Maillet \u00e9tait sur ses talons. En conf\u00e9rence de presse, le champion olympique du sprint a \u00e9t\u00e9 tr\u00e8s \u00e9logieux envers le double champion olympique fran\u00e7ais.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">Quentin fait une saison fantastique, il prend sa deuxi\u00e8me m\u00e9daille d&rsquo;or, je suis vraiment impressionn\u00e9 par ce qu&rsquo;il r\u00e9alise. C&rsquo;est un athl\u00e8te fantastique et surtout une bonne personne.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\"><strong>Martin Fourcade<\/strong>, <a href=\"https:\/\/www.eurosport.fr\/biathlon\/jeux-olympiques\/2022\/jo-pekin-2022-quentin-fillon-maillet-l-or-au-plus-que-parfait-sur-la-poursuite-malgre-les-conditions_sto8787561\/story.shtml\">consultant pour Eurosport<\/a> lors de ces JO, en a quant \u00e0 lui rajout\u00e9 une couche sur son compatriote.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">Il est tellement en confiance depuis le d\u00e9but de ces Jeux Olympiques. Il a vraiment progress\u00e9 au niveau du ski. Ce sont aussi des comp\u00e9titions et un stade qui lui conviennent \u00e0 merveille. On est en altitude, \u00e7a convient parfaitement aux qualit\u00e9s de Quentin et \u00e0 ses qualit\u00e9s de skieur assez fin, un peu moins en puissance que peuvent l&rsquo;\u00eatre de gros gabarits comme Emilien ou Christiansen. Et une confiance au niveau du tir et une ma\u00eetrise de la pression. Je suis impressionn\u00e9, parce que r\u00e9aliser le doubl\u00e9 individuel-poursuite, c&rsquo;est quelque chose de magnifique.<\/p>\n<\/blockquote>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">&#x1f1eb;&#x1f1f7; Quentin Fillon Maillet est d\u00e9j\u00e0 dans la l\u00e9gende du sport fran\u00e7ais, et il ne compte pas s&rsquo;arr\u00eater l\u00e0 ! &#x1f60d;&#x1f449; <a href=\"https:\/\/t.co\/AZqQYszwRH\">https:\/\/t.co\/AZqQYszwRH<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/Beijing2022?src=hash&amp;ref_src=twsrc%5Etfw\">#Beijing2022<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/Biathlon?src=hash&amp;ref_src=twsrc%5Etfw\">#Biathlon<\/a> <a href=\"https:\/\/t.co\/92C32rqiJT\">pic.twitter.com\/92C32rqiJT<\/a><\/p>\n<p>\u2014 Dicodusport &#x2b50;&#x2b50; (@dicodusport) <a href=\"https:\/\/twitter.com\/dicodusport\/status\/1492899592895184898?ref_src=twsrc%5Etfw\">February 13, 2022<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>JO P\u00c9KIN 2022 &#8211; BIATHLON &#8211; Longtemps en t\u00eate, Johannes Boe a fini par c\u00e9der face \u00e0 Quentin Fillon Maillet sur la poursuite des JO de P\u00e9kin.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":200171,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2426,20104],"tags":[21641,2433,3745],"class_list":["post-200169","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-biathlon","category-jo-hiver-pekin-2022","tag-jeux-olympiques-de-pekin","tag-johannes-boe","tag-quentin-fillon-maillet"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Johannes Boe : &quot;Je suis vraiment impressionn\u00e9 par ce que Quentin Fillon Maillet r\u00e9alise&quot;<\/title>\n<meta name=\"description\" content=\"JO P\u00c9KIN 2022 - BIATHLON - Longtemps en t\u00eate, Johannes Boe a fini par c\u00e9der face \u00e0 Quentin Fillon Maillet sur la poursuite des JO de P\u00e9kin.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/johannes-boe-je-suis-vraiment-impressionne-par-ce-que-quentin-fillon-maillet-realise\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Johannes Boe : &quot;Je suis vraiment impressionn\u00e9 par ce que Quentin Fillon Maillet r\u00e9alise&quot;\" \/>\n<meta property=\"og:description\" content=\"JO P\u00c9KIN 2022 - BIATHLON - Longtemps en t\u00eate, Johannes Boe a fini par c\u00e9der face \u00e0 Quentin Fillon Maillet sur la poursuite des JO de P\u00e9kin.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/johannes-boe-je-suis-vraiment-impressionne-par-ce-que-quentin-fillon-maillet-realise\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-14T09:07:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Johannes-Boe-Je-suis-vraiment-impressionne\u0301-par-ce-que-Quentin-Fillon-Maillet-re\u0301alise.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Johannes Boe : &quot;Je suis vraiment impressionn\u00e9 par ce que Quentin Fillon Maillet r\u00e9alise&quot;\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/johannes-boe-je-suis-vraiment-impressionne-par-ce-que-quentin-fillon-maillet-realise\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/johannes-boe-je-suis-vraiment-impressionne-par-ce-que-quentin-fillon-maillet-realise\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Johannes Boe : \u00ab\u00a0Je suis vraiment impressionn\u00e9 par ce que Quentin Fillon Maillet r\u00e9alise\u00a0\u00bb\",\"datePublished\":\"2022-02-14T09:07:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/johannes-boe-je-suis-vraiment-impressionne-par-ce-que-quentin-fillon-maillet-realise\/\"},\"wordCount\":304,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/johannes-boe-je-suis-vraiment-impressionne-par-ce-que-quentin-fillon-maillet-realise\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Johannes-Boe-Je-suis-vraiment-impressionne\u0301-par-ce-que-Quentin-Fillon-Maillet-re\u0301alise.png\",\"keywords\":[\"Jeux Olympiques de P\u00e9kin\",\"Johannes Boe\",\"Quentin Fillon Maillet\"],\"articleSection\":[\"Biathlon\",\"JO d'hiver P\u00e9kin 2022\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/johannes-boe-je-suis-vraiment-impressionne-par-ce-que-quentin-fillon-maillet-realise\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/johannes-boe-je-suis-vraiment-impressionne-par-ce-que-quentin-fillon-maillet-realise\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/johannes-boe-je-suis-vraiment-impressionne-par-ce-que-quentin-fillon-maillet-realise\/\",\"name\":\"Johannes Boe : \\\"Je suis vraiment impressionn\u00e9 par ce que Quentin Fillon Maillet r\u00e9alise\\\"\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/johannes-boe-je-suis-vraiment-impressionne-par-ce-que-quentin-fillon-maillet-realise\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/johannes-boe-je-suis-vraiment-impressionne-par-ce-que-quentin-fillon-maillet-realise\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Johannes-Boe-Je-suis-vraiment-impressionne\u0301-par-ce-que-Quentin-Fillon-Maillet-re\u0301alise.png\",\"datePublished\":\"2022-02-14T09:07:37+00:00\",\"description\":\"JO P\u00c9KIN 2022 - BIATHLON - Longtemps en t\u00eate, Johannes Boe a fini par c\u00e9der face \u00e0 Quentin Fillon Maillet sur la poursuite des JO de P\u00e9kin.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/johannes-boe-je-suis-vraiment-impressionne-par-ce-que-quentin-fillon-maillet-realise\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/johannes-boe-je-suis-vraiment-impressionne-par-ce-que-quentin-fillon-maillet-realise\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/johannes-boe-je-suis-vraiment-impressionne-par-ce-que-quentin-fillon-maillet-realise\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Johannes-Boe-Je-suis-vraiment-impressionne\u0301-par-ce-que-Quentin-Fillon-Maillet-re\u0301alise.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Johannes-Boe-Je-suis-vraiment-impressionne\u0301-par-ce-que-Quentin-Fillon-Maillet-re\u0301alise.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/johannes-boe-je-suis-vraiment-impressionne-par-ce-que-quentin-fillon-maillet-realise\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Johannes Boe : \u00ab\u00a0Je suis vraiment impressionn\u00e9 par ce que Quentin Fillon Maillet r\u00e9alise\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Johannes Boe : \"Je suis vraiment impressionn\u00e9 par ce que Quentin Fillon Maillet r\u00e9alise\"","description":"JO P\u00c9KIN 2022 - BIATHLON - Longtemps en t\u00eate, Johannes Boe a fini par c\u00e9der face \u00e0 Quentin Fillon Maillet sur la poursuite des JO de P\u00e9kin.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/johannes-boe-je-suis-vraiment-impressionne-par-ce-que-quentin-fillon-maillet-realise\/","og_locale":"fr_FR","og_type":"article","og_title":"Johannes Boe : \"Je suis vraiment impressionn\u00e9 par ce que Quentin Fillon Maillet r\u00e9alise\"","og_description":"JO P\u00c9KIN 2022 - BIATHLON - Longtemps en t\u00eate, Johannes Boe a fini par c\u00e9der face \u00e0 Quentin Fillon Maillet sur la poursuite des JO de P\u00e9kin.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/johannes-boe-je-suis-vraiment-impressionne-par-ce-que-quentin-fillon-maillet-realise\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2022-02-14T09:07:37+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Johannes-Boe-Je-suis-vraiment-impressionne\u0301-par-ce-que-Quentin-Fillon-Maillet-re\u0301alise.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Johannes Boe : \"Je suis vraiment impressionn\u00e9 par ce que Quentin Fillon Maillet r\u00e9alise\"","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/johannes-boe-je-suis-vraiment-impressionne-par-ce-que-quentin-fillon-maillet-realise\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/johannes-boe-je-suis-vraiment-impressionne-par-ce-que-quentin-fillon-maillet-realise\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Johannes Boe : \u00ab\u00a0Je suis vraiment impressionn\u00e9 par ce que Quentin Fillon Maillet r\u00e9alise\u00a0\u00bb","datePublished":"2022-02-14T09:07:37+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/johannes-boe-je-suis-vraiment-impressionne-par-ce-que-quentin-fillon-maillet-realise\/"},"wordCount":304,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/johannes-boe-je-suis-vraiment-impressionne-par-ce-que-quentin-fillon-maillet-realise\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Johannes-Boe-Je-suis-vraiment-impressionne\u0301-par-ce-que-Quentin-Fillon-Maillet-re\u0301alise.png","keywords":["Jeux Olympiques de P\u00e9kin","Johannes Boe","Quentin Fillon Maillet"],"articleSection":["Biathlon","JO d'hiver P\u00e9kin 2022"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/johannes-boe-je-suis-vraiment-impressionne-par-ce-que-quentin-fillon-maillet-realise\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/johannes-boe-je-suis-vraiment-impressionne-par-ce-que-quentin-fillon-maillet-realise\/","url":"https:\/\/dicodusport.fr\/blog\/johannes-boe-je-suis-vraiment-impressionne-par-ce-que-quentin-fillon-maillet-realise\/","name":"Johannes Boe : \"Je suis vraiment impressionn\u00e9 par ce que Quentin Fillon Maillet r\u00e9alise\"","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/johannes-boe-je-suis-vraiment-impressionne-par-ce-que-quentin-fillon-maillet-realise\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/johannes-boe-je-suis-vraiment-impressionne-par-ce-que-quentin-fillon-maillet-realise\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Johannes-Boe-Je-suis-vraiment-impressionne\u0301-par-ce-que-Quentin-Fillon-Maillet-re\u0301alise.png","datePublished":"2022-02-14T09:07:37+00:00","description":"JO P\u00c9KIN 2022 - BIATHLON - Longtemps en t\u00eate, Johannes Boe a fini par c\u00e9der face \u00e0 Quentin Fillon Maillet sur la poursuite des JO de P\u00e9kin.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/johannes-boe-je-suis-vraiment-impressionne-par-ce-que-quentin-fillon-maillet-realise\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/johannes-boe-je-suis-vraiment-impressionne-par-ce-que-quentin-fillon-maillet-realise\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/johannes-boe-je-suis-vraiment-impressionne-par-ce-que-quentin-fillon-maillet-realise\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Johannes-Boe-Je-suis-vraiment-impressionne\u0301-par-ce-que-Quentin-Fillon-Maillet-re\u0301alise.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Johannes-Boe-Je-suis-vraiment-impressionne\u0301-par-ce-que-Quentin-Fillon-Maillet-re\u0301alise.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/johannes-boe-je-suis-vraiment-impressionne-par-ce-que-quentin-fillon-maillet-realise\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Johannes Boe : \u00ab\u00a0Je suis vraiment impressionn\u00e9 par ce que Quentin Fillon Maillet r\u00e9alise\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/200169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=200169"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/200169\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/200171"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=200169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=200169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=200169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}