{"id":200407,"date":"2022-02-15T03:58:34","date_gmt":"2022-02-15T02:58:34","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=200407&#038;preview=true&#038;preview_id=200407"},"modified":"2022-02-15T04:10:18","modified_gmt":"2022-02-15T03:10:18","slug":"ski-slopestyle-jo-pekin-2022-classement-femmes","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/ski-slopestyle-jo-pekin-2022-classement-femmes\/","title":{"rendered":"Ski Slopestyle JO P\u00e9kin 2022 &#8211; Classement femmes"},"content":{"rendered":"<p style=\"text-align: justify;\"><b><i><a href=\"https:\/\/dicodusport.fr\/blog\/ski-freestyle-jo-pekin-2022-programme-resultats-et-medailles\/\">SKI FREESTYLE &#8211; JO P\u00c9KIN 2022<\/a> &#8211; D\u00e9couvrez le classement de l&rsquo;\u00e9preuve de ski slopestyle femmes (top 12) des Jeux Olympiques de P\u00e9kin, qui a eu lieu ce mardi 15 f\u00e9vrier 2022.<\/i><\/b><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px;\"><strong><em>Classement officiel.<\/em><\/strong><\/span><\/p>\n<div class=\"su-table su-table-alternate\">\n<table style=\"width: 800px;border-collapse: collapse\" border=\"1\">\n<tbody>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\">&#x1f3c6;<\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>SKIEUSES<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>POINTS<br \/>\n<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">1.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><b>&#x1f1e8;&#x1f1ed; MATHILDE GREMAUD<\/b><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">86.56<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">2.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><b>&#x1f1e8;&#x1f1f3; AILING EILEEN GU<\/b><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">86.23<\/span><\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">3.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">&#x1f1ea;&#x1f1ea; KELLY SILDARU<\/span><\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">82.06<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">4<\/span><span style=\"font-size: 0.9em\">.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-143866\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Comite-olympique-russe-591x1024.png\" alt=\"\" width=\"9\" height=\"15\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Comite-olympique-russe-591x1024.png 591w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Comite-olympique-russe-173x300.png 173w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Comite-olympique-russe-768x1331.png 768w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Comite-olympique-russe-887x1536.png 887w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Comite-olympique-russe-1182x2048.png 1182w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/07\/Comite-olympique-russe.png 2001w\" sizes=\"auto, (max-width: 9px) 100vw, 9px\" \/> ANASTASIA TATALINA<\/span><\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">75.51<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">5.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><b>&#x1f1fa;&#x1f1f8; MAGGIE VOISIN<\/b><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">74.28<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">6.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><b>&#x1f1f3;&#x1f1f4; JOHANNE KILLI<\/b><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">73.11<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">7.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><b>&#x1f1eb;&#x1f1f7; TESS LEDEUX<\/b><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">72.91<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">8.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><b>&#x1f1ec;&#x1f1e7; KIRSTY MUIR<\/b><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">71.30<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">9.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><b>&#x1f1ec;&#x1f1e7; KATIE SUMMERHAYES<\/b><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">64.75<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">10.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><b>&#x1f1ee;&#x1f1f9; SILVIA BERTAGNA<\/b><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">61.85<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">11.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><b>&#x1f1e8;&#x1f1e6; OLIVIA ASSELIN<\/b><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">16.83<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">12.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><b>&#x1f1fa;&#x1f1f8; MARIN HAMILL<\/b><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">DNS<\/span><\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<h2 style=\"text-align: justify;\"><strong>\u00c0 lire aussi<\/strong><\/h2>\n<ul>\n<li style=\"text-align: justify;\"><strong><a href=\"https:\/\/olympics.com\/beijing-2022\/olympic-games\/fr\/resultats\/ski-acrobatique\/resultats-freeski-slopestyle-femmes-fnl-.htm\" target=\"_blank\" rel=\"nofollow noopener\">Le d\u00e9tail des r\u00e9sultats<\/a>\u00a0<\/strong><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/jo-pekin-2022-tableau-des-medailles\/\"><strong>Le tableau des m\u00e9dailles des JO de P\u00e9kin 2022<\/strong><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SKI FREESTYLE &#8211; JO P\u00c9KIN 2022 &#8211; D\u00e9couvrez le classement de l&rsquo;\u00e9preuve de ski slopestyle femmes (top 12) des Jeux Olympiques de P\u00e9kin, qui a eu lieu ce mardi 15 f\u00e9vrier 2022.<\/p>\n","protected":false},"author":4,"featured_media":200408,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[20104,9217],"tags":[15570],"class_list":["post-200407","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jo-hiver-pekin-2022","category-ski","tag-ski-slopestyle"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ski Slopestyle JO P\u00e9kin 2022 - Classement femmes<\/title>\n<meta name=\"description\" content=\"SKI FREESTYLE - JO P\u00c9KIN 2022 - D\u00e9couvrez le classement de l&#039;\u00e9preuve de ski slopestyle femmes (top 12) des Jeux Olympiques de P\u00e9kin.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/ski-slopestyle-jo-pekin-2022-classement-femmes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ski Slopestyle JO P\u00e9kin 2022 - Classement femmes\" \/>\n<meta property=\"og:description\" content=\"SKI FREESTYLE - JO P\u00c9KIN 2022 - D\u00e9couvrez le classement de l&#039;\u00e9preuve de ski slopestyle femmes (top 12) des Jeux Olympiques de P\u00e9kin.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/ski-slopestyle-jo-pekin-2022-classement-femmes\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-15T02:58:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-15T03:10:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Ski-Slopestyle-JO-Pekin-2022-Classement-femmes.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Ski Slopestyle JO P\u00e9kin 2022 - Classement femmes\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ski-slopestyle-jo-pekin-2022-classement-femmes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ski-slopestyle-jo-pekin-2022-classement-femmes\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Ski Slopestyle JO P\u00e9kin 2022 &#8211; Classement femmes\",\"datePublished\":\"2022-02-15T02:58:34+00:00\",\"dateModified\":\"2022-02-15T03:10:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ski-slopestyle-jo-pekin-2022-classement-femmes\/\"},\"wordCount\":162,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ski-slopestyle-jo-pekin-2022-classement-femmes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Ski-Slopestyle-JO-Pekin-2022-Classement-femmes.png\",\"keywords\":[\"Ski slopestyle\"],\"articleSection\":[\"JO d'hiver P\u00e9kin 2022\",\"Ski\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/ski-slopestyle-jo-pekin-2022-classement-femmes\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ski-slopestyle-jo-pekin-2022-classement-femmes\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/ski-slopestyle-jo-pekin-2022-classement-femmes\/\",\"name\":\"Ski Slopestyle JO P\u00e9kin 2022 - Classement femmes\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ski-slopestyle-jo-pekin-2022-classement-femmes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ski-slopestyle-jo-pekin-2022-classement-femmes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Ski-Slopestyle-JO-Pekin-2022-Classement-femmes.png\",\"datePublished\":\"2022-02-15T02:58:34+00:00\",\"dateModified\":\"2022-02-15T03:10:18+00:00\",\"description\":\"SKI FREESTYLE - JO P\u00c9KIN 2022 - D\u00e9couvrez le classement de l'\u00e9preuve de ski slopestyle femmes (top 12) des Jeux Olympiques de P\u00e9kin.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ski-slopestyle-jo-pekin-2022-classement-femmes\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/ski-slopestyle-jo-pekin-2022-classement-femmes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ski-slopestyle-jo-pekin-2022-classement-femmes\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Ski-Slopestyle-JO-Pekin-2022-Classement-femmes.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Ski-Slopestyle-JO-Pekin-2022-Classement-femmes.png\",\"width\":1200,\"height\":670,\"caption\":\"Ski Slopestyle JO P\u00e9kin 2022 - Classement femmes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ski-slopestyle-jo-pekin-2022-classement-femmes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ski Slopestyle JO P\u00e9kin 2022 &#8211; Classement femmes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ski Slopestyle JO P\u00e9kin 2022 - Classement femmes","description":"SKI FREESTYLE - JO P\u00c9KIN 2022 - D\u00e9couvrez le classement de l'\u00e9preuve de ski slopestyle femmes (top 12) des Jeux Olympiques de P\u00e9kin.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/ski-slopestyle-jo-pekin-2022-classement-femmes\/","og_locale":"fr_FR","og_type":"article","og_title":"Ski Slopestyle JO P\u00e9kin 2022 - Classement femmes","og_description":"SKI FREESTYLE - JO P\u00c9KIN 2022 - D\u00e9couvrez le classement de l'\u00e9preuve de ski slopestyle femmes (top 12) des Jeux Olympiques de P\u00e9kin.","og_url":"https:\/\/dicodusport.fr\/blog\/ski-slopestyle-jo-pekin-2022-classement-femmes\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2022-02-15T02:58:34+00:00","article_modified_time":"2022-02-15T03:10:18+00:00","og_image":[{"width":1200,"height":670,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Ski-Slopestyle-JO-Pekin-2022-Classement-femmes.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Ski Slopestyle JO P\u00e9kin 2022 - Classement femmes","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/ski-slopestyle-jo-pekin-2022-classement-femmes\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/ski-slopestyle-jo-pekin-2022-classement-femmes\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Ski Slopestyle JO P\u00e9kin 2022 &#8211; Classement femmes","datePublished":"2022-02-15T02:58:34+00:00","dateModified":"2022-02-15T03:10:18+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ski-slopestyle-jo-pekin-2022-classement-femmes\/"},"wordCount":162,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ski-slopestyle-jo-pekin-2022-classement-femmes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Ski-Slopestyle-JO-Pekin-2022-Classement-femmes.png","keywords":["Ski slopestyle"],"articleSection":["JO d'hiver P\u00e9kin 2022","Ski"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/ski-slopestyle-jo-pekin-2022-classement-femmes\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/ski-slopestyle-jo-pekin-2022-classement-femmes\/","url":"https:\/\/dicodusport.fr\/blog\/ski-slopestyle-jo-pekin-2022-classement-femmes\/","name":"Ski Slopestyle JO P\u00e9kin 2022 - Classement femmes","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ski-slopestyle-jo-pekin-2022-classement-femmes\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ski-slopestyle-jo-pekin-2022-classement-femmes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Ski-Slopestyle-JO-Pekin-2022-Classement-femmes.png","datePublished":"2022-02-15T02:58:34+00:00","dateModified":"2022-02-15T03:10:18+00:00","description":"SKI FREESTYLE - JO P\u00c9KIN 2022 - D\u00e9couvrez le classement de l'\u00e9preuve de ski slopestyle femmes (top 12) des Jeux Olympiques de P\u00e9kin.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/ski-slopestyle-jo-pekin-2022-classement-femmes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/ski-slopestyle-jo-pekin-2022-classement-femmes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/ski-slopestyle-jo-pekin-2022-classement-femmes\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Ski-Slopestyle-JO-Pekin-2022-Classement-femmes.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Ski-Slopestyle-JO-Pekin-2022-Classement-femmes.png","width":1200,"height":670,"caption":"Ski Slopestyle JO P\u00e9kin 2022 - Classement femmes"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/ski-slopestyle-jo-pekin-2022-classement-femmes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Ski Slopestyle JO P\u00e9kin 2022 &#8211; Classement femmes"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/200407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=200407"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/200407\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/200408"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=200407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=200407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=200407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}