{"id":200778,"date":"2022-02-17T09:00:51","date_gmt":"2022-02-17T08:00:51","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=200778"},"modified":"2022-02-17T04:23:14","modified_gmt":"2022-02-17T03:23:14","slug":"plateau-meeting-de-lievin-accueille-les-stars-des-jo-de-tokyo","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/plateau-meeting-de-lievin-accueille-les-stars-des-jo-de-tokyo\/","title":{"rendered":"Le magnifique plateau du Meeting de Li\u00e9vin, qui accueille les stars des JO de Tokyo"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>ATHL\u00c9TISME &#8211; La vingt-septi\u00e8me \u00e9dition du Meeting de Li\u00e9vin se d\u00e9roule ce jeudi soir. Le premier meeting d&rsquo;athl\u00e9tisme en salle de France accueillera quelques champions olympiques ainsi que des stars tricolores.\u00a0<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Le programme est riche et all\u00e9chant. Pour cette vingt-septi\u00e8me \u00e9dition, le prestigieux meeting du Nord de la France a vu les choses en grand avec des courses et des concours qui seront tr\u00e8s relev\u00e9s. D\u00e9j\u00e0, sur le 60 m\u00e8tres masculin, le public aura la chance de voir courir le champion olympique du 100 m. En effet, l&rsquo;Italien <strong>Marcell Jacobs<\/strong> a \u00e9tabli un chrono de 6.49 en Pologne, la semaine pass\u00e9e. Il est tout proche de son record personnel qui est de 6.47. La grosse \u00e9mulation pourrait l&rsquo;aider \u00e0 am\u00e9liorer cette marque.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">&#x1f49a; ILS SERONT \u00c0 LI\u00c9VIN &#x1f49a;<br \/>\nMarcell JACOBS &#x1f1ee;&#x1f1f9;<br \/>\nDouble champ olympique, vainqueur du 60m \u00e0 Li\u00e9vin en 2021 sera au d\u00e9part du 60m<br \/>\npalmar\u00e8s :<br \/>\n&#x1f947;&#x1f947;champ Olympique 100m\/4x100m 2021<br \/>\n&#x1f947;Champ d\u2019Europe indoor du 60m 2021<br \/>\nRec d\u2019Europe 100m 9\u2019\u201980 Tokyo<br \/>\nVa t-il battre son record le 17 f\u00e9vrier ? <a href=\"https:\/\/t.co\/9Om3UNQMvo\">pic.twitter.com\/9Om3UNQMvo<\/a><\/p>\n<p>\u2014 Meeting Hauts-de-France Pas-de-Calais (@Meeting_Lievin) <a href=\"https:\/\/twitter.com\/Meeting_Lievin\/status\/1478830992240615435?ref_src=twsrc%5Etfw\">January 5, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Derri\u00e8re lui, les Am\u00e9ricains seront en nombre. <strong>Marvin Bracy<\/strong> (PB=6.48) et <strong>Ronnie Baker<\/strong> (6.40) ont d\u00e9j\u00e0 couru en dessous de 6.50 durant leur carri\u00e8re. Le v\u00e9t\u00e9ran <strong>Michael Rodgers<\/strong> (6.48) sera aussi pr\u00e9sent, tout comme le d\u00e9tenteur du record d&rsquo;Afrique du 100 m (9.77), le K\u00e9nyan <strong>Ferdinand Omanyala<\/strong> (6.60). Enfin, le tricolore <strong>Jimmy Vicaut<\/strong> (6.48) aura une carte \u00e0 jouer. Au d\u00e9but du mois, le Fran\u00e7ais a effectu\u00e9 sa rentr\u00e9e en 6.61 sur la petite ligne droite. <strong>Marvin Ren\u00e9<\/strong> (6.62) et <strong>Thomas Maurice<\/strong> (6.82) accompagneront la star fran\u00e7aise.<\/p>\n<h2 style=\"text-align: justify;\">Un gros bras de fer attendu sur le 60m haies<\/h2>\n<p style=\"text-align: justify;\">Si le 60 m a d\u00e9j\u00e0 une belle t\u00eate, le 60 m haies sera aussi tr\u00e8s int\u00e9ressant \u00e0 suivre. Les deux leaders fran\u00e7ais de la discipline <strong>Wilhem Belocian<\/strong> (PB=7.42) et <strong>Pascal Martinot-Lagarde<\/strong> (7.45) seront oppos\u00e9s au recordman de la discipline <strong>Grant Holloway<\/strong> (7.29). Nos deux tricolores ont d\u00e9j\u00e0 effectu\u00e9 de belles rentr\u00e9es avec des chronos respectifs de 7.52 et 7.51, tandis que le <em>season best<\/em> de l&rsquo;Am\u00e9ricain est en 7.37, pour le moment. A ce beau monde s&rsquo;ajoute la star du d\u00e9cathlon <strong>Kevin Mayer<\/strong> (7.68). Le champion du monde et double vice-champion olympique a perform\u00e9 en 7.73 en janvier dernier. Rajoutons aussi le jeune hurdler<strong> Just Kwaou-Mathey<\/strong> (7.71), qui n&rsquo;a que 22 ans.<\/p>\n<p style=\"text-align: justify;\">Du c\u00f4t\u00e9 des haies f\u00e9minines, la meilleure performeuse pr\u00e9sente sera la jeune p\u00e9pite fran\u00e7aise <strong>Cyr\u00e9na Samba-Mayela<\/strong>. Elle vient de battre son record personnel avec un chrono en 7.84, ce qui fait d&rsquo;elle la hurdleuse europ\u00e9enne la plus rapide de la saison pour l&rsquo;instant. Face \u00e0 elle, les principales concurrentes sont la Baham\u00e9enne <strong>Devynne Charlton<\/strong> (7.89) et la B\u00e9larusse<strong> Elvira Herman<\/strong> (7.91). <strong>Laetitia Bapt\u00e9<\/strong> (7.93), autre Tricolore, aura aussi une carte \u00e0 jouer. <strong>Pauline Lett<\/strong> (8.12)\u00a0 sera la troisi\u00e8me fran\u00e7aise au d\u00e9part de l&rsquo;\u00e9preuve jeudi soir.<\/p>\n<h2>Un programme dense en mati\u00e8re de demi-fond<\/h2>\n<p style=\"text-align: justify;\">A Li\u00e9vin, il faudra compter sur les nombreuses courses de demi-fond. Au programme : du 800 m, du 1500 m, du mile et du 3000 m. Sur cette derni\u00e8re course, chez les hommes, on assistera \u00e0 la rentr\u00e9e du champion olympique du 10 000 m\u00e8tres, l&rsquo;Ethiopien <strong>Selemon Barega<\/strong> (PB=7:26.10). Le Fran\u00e7ais <strong>Hugo Hay<\/strong> fera \u00e9galement sa rentr\u00e9e sur la distance (7:47.30). La course la plus relev\u00e9e devrait \u00eatre le 1500 m messieurs. En effet, l&rsquo;une des stars de l&rsquo;athl\u00e9tisme scandinave, le Norv\u00e9gien <strong>Jakob Ingebrigtsen<\/strong> (3:31.80) fera sa premi\u00e8re course de 2022. En face, l&rsquo;Ethiopien <strong>Samuel Tefera<\/strong>, recordman (3:31.04) et champion du monde de la distance en salle, sera son principal adversaire. <strong>Baptiste Mischler<\/strong> (3:38.85) sera le seul repr\u00e9sentant tricolore sur cette course.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">&#x1f49a; ILS SERONT \u00c0 LI\u00c9VIN &#x1f49a;<br \/>\nLe champion olympique du 10000m Selemon Barega &#x1f1ea;&#x1f1f9; qui avait r\u00e9alis\u00e9 la 3\u00e8 meilleure perf &#x1f30e; tout temps \u00e0 Li\u00e9vin en 2021 sur 3000m (7\u201926\u2019\u2019) revient pour s\u2019attaquer au record du &#x1f30d; &#x1f525; <a href=\"https:\/\/twitter.com\/hashtag\/WorldIndoorTour?src=hash&amp;ref_src=twsrc%5Etfw\">#WorldIndoorTour<\/a> <a href=\"https:\/\/twitter.com\/WorldAthletics?ref_src=twsrc%5Etfw\">@WorldAthletics<\/a> <a href=\"https:\/\/t.co\/wEsLG9t5F2\">pic.twitter.com\/wEsLG9t5F2<\/a><\/p>\n<p>\u2014 Meeting Hauts-de-France Pas-de-Calais (@Meeting_Lievin) <a href=\"https:\/\/twitter.com\/Meeting_Lievin\/status\/1483091591241908229?ref_src=twsrc%5Etfw\">January 17, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Ensuite, il faudra suivre le 800 m. Chez les femmes, c&rsquo;est le duel entre la Jama\u00efquaine <strong>Natoya Goule<\/strong> (1:59.13) et l&rsquo;Ougandaise <strong>Halimah Nakaayi<\/strong> (1:59.55) qui fait saliver. Pour le moment, les deux demi-fondeuses ont \u00e9tabli les meilleures performances en 2022. La Fran\u00e7aise<strong> Cynthia Ana\u00efs<\/strong> a r\u00e9alis\u00e9 le septi\u00e8me meilleur chrono de 2022 en 2:00.49. Chez les hommes, trois gros clients auront notre attention. L&rsquo;Espagnol <strong>Mariano Garcia<\/strong> a r\u00e9cemment battu son record en 1:45.12. Il en a profit\u00e9 pour \u00e9tablir la meilleure marque mondiale de l&rsquo;ann\u00e9e. A ses trousses, le Polonais <strong>Adam Kszczot<\/strong> (1:44.57), champion du monde en salle, et le Britannique <strong>Elliot Giles<\/strong> (1:43.63) voudront am\u00e9liorer leur marque. Les Fran\u00e7ais <strong>Benjamin Robert<\/strong> (1:46.06), <strong>Nasredine Katir<\/strong><strong>\u00a0<\/strong>(1:47.28) et <strong>Gabriel Tual<\/strong> (1:47.54) auront \u00e9galement de l&rsquo;ambition.<\/p>\n<p style=\"text-align: justify;\">Sur le 2000 m, on scrutera la performance des trois Fran\u00e7ais <strong>Jimmy Gressier<\/strong> (3:37.41)<strong>, Djilali Bedrani<\/strong> (3:40.27) et <strong>Azedine Habz<\/strong> (3:36.16). Enfin, le mile f\u00e9minin verra la rentr\u00e9e de l&rsquo;\u00c9thiopienne<strong> Gudaf Tsegai<\/strong> (3:53.09), m\u00e9daill\u00e9e de bronze sur le 5000 m\u00e8tres \u00e0 Tokyo, l&rsquo;\u00e9t\u00e9 dernier. La Fran\u00e7aise Aurore Fleury (4:10.09) sera aussi de la partie.<\/p>\n<h2 style=\"text-align: justify;\">Nageotte et Rojas en fer de lance des concours<\/h2>\n<p style=\"text-align: justify;\">Cette ann\u00e9e, le Meeting de Li\u00e9vin accueille quatre concours. La perche est notamment mise \u00e0 l&rsquo;honneur puisque deux champions olympiques seront pr\u00e9sents. Chez les dames, l&rsquo;Am\u00e9ricaine <strong>Katie Nageotte<\/strong>, titr\u00e9e cet \u00e9t\u00e9 \u00e0 Tokyo (PB=4.95 m) sera bien au rendez-vous. Elle jouera un beau duel face \u00e0 la championne du monde <strong>Anzhelika Sidorova<\/strong> (5.01 m), qui a termin\u00e9 juste derri\u00e8re elle \u00e0 Tokyo. La Russe est, pour le moment, celle qui a saut\u00e9 le plus haut en 2022, avec une barre effac\u00e9e \u00e0 4.80 m. Juste derri\u00e8re elle, la Bi\u00e9lorusse <strong>Iryna Zhuk<\/strong> est pass\u00e9e au dessus de 4.77, et a \u00e9tabli son nouveau record personnel. Enfin, les Fran\u00e7aises <strong>Ninon Chapelle<\/strong> (4.75 m) et <strong>Margot Chevrier<\/strong> (4.54) seront pr\u00e9sentes dans les Hauts-de-France.<\/p>\n<p style=\"text-align: justify;\">Chez les messieurs, le champion olympique de Rio, le Br\u00e9silien<strong> Thiago Braz<\/strong> (6.03 m) aura aussi de la concurrence. On pense principalement \u00e0 l&rsquo;Am\u00e9ricain <strong>Christopher Nilsen<\/strong>, vice-champion olympique, et qui a d\u00e9j\u00e0 franchi les 6 m\u00e8tres cette saison (6.02 m). On aura aussi un \u0153il sur le Polonais <strong>Piotr Lisek<\/strong> (6.02 m), ainsi que sur <strong>Valentin Lavillenie<\/strong> (5.82 m) et <strong>Alioune S\u00e8ne<\/strong> (5.74 m).<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">&#x1f49a; SAUT \u00c0 LA PERCHE MASCULIN &#x1f49a;<\/p>\n<p>Des allures de finale olympique pour le concours de perche avec 7 des finalistes olympiques de Tokyo &amp; 4 perchistes qui ont d\u00e9j\u00e0 franchi la barre des 6m &#x1f525;<br \/>\n&#x26a1;&#xfe0f;19h45<br \/>\n&#x26a1;&#xfe0f;d\u00e8s 20h45 sur <a href=\"https:\/\/twitter.com\/lachainelequipe?ref_src=twsrc%5Etfw\">@lachainelequipe<\/a><a href=\"https:\/\/twitter.com\/hashtag\/worldindoortour?src=hash&amp;ref_src=twsrc%5Etfw\">#worldindoortour<\/a> <a href=\"https:\/\/twitter.com\/WorldAthletics?ref_src=twsrc%5Etfw\">@WorldAthletics<\/a> <a href=\"https:\/\/t.co\/qFOzMAIuCK\">pic.twitter.com\/qFOzMAIuCK<\/a><\/p>\n<p>\u2014 Meeting Hauts-de-France Pas-de-Calais (@Meeting_Lievin) <a href=\"https:\/\/twitter.com\/Meeting_Lievin\/status\/1492478865452769280?ref_src=twsrc%5Etfw\">February 12, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Pour finir, il y aura du triple saut masculin, o\u00f9 se produira notamment <strong>Benjamin Campaor\u00e9<\/strong> (17.14 m), et de la longueur f\u00e9minine. Pour ce concours, la star de l&rsquo;athl\u00e9tisme v\u00e9n\u00e9zu\u00e9lien <strong>Yulimar Rojas<\/strong>, championne olympique et mondiale en titre sur triple saut, tentera d&rsquo;effacer sa meilleure marque qui est \u00e0 6.59 m. Les favorites sur cette \u00e9preuve restent tout de m\u00eame l&rsquo;Ukrainienne <strong>Maryna Bekh-Romanchuk<\/strong> (6.96 m) et la Bi\u00e9lorusse <strong>Nastassia Mironchyk-Ivanova<\/strong> (6.93 m). Enfin, la Fran\u00e7aise <strong>Ma\u00eblly Dalmat<\/strong> tentera d&rsquo;am\u00e9liorer son meilleur saut qui est \u00e0 6.45 m.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ATHL\u00c9TISME &#8211; La vingt-septi\u00e8me \u00e9dition du Meeting de Li\u00e9vin se d\u00e9roule ce jeudi soir. Le premier meeting d&rsquo;athl\u00e9tisme en salle de France accueillera quelques champions olympiques ainsi que des stars tricolores.\u00a0<\/p>\n","protected":false},"author":45,"featured_media":201084,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2308],"tags":[143],"class_list":["post-200778","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-athletisme","tag-athletisme"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le magnifique plateau du Meeting de Li\u00e9vin, qui accueille les stars des JO de Tokyo<\/title>\n<meta name=\"description\" content=\"La vingt-septi\u00e8me \u00e9dition du meeting de Li\u00e9vin se d\u00e9roule ce jeudi soir avec des champions olympiques et des stars fran\u00e7aises au rendez-vous.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/plateau-meeting-de-lievin-accueille-les-stars-des-jo-de-tokyo\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le magnifique plateau du Meeting de Li\u00e9vin, qui accueille les stars des JO de Tokyo\" \/>\n<meta property=\"og:description\" content=\"La vingt-septi\u00e8me \u00e9dition du meeting de Li\u00e9vin se d\u00e9roule ce jeudi soir avec des champions olympiques et des stars fran\u00e7aises au rendez-vous.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/plateau-meeting-de-lievin-accueille-les-stars-des-jo-de-tokyo\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/alexandre.jeffroy.3\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-17T08:00:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Le-magnifique-plateau-du-Meeting-de-Lievin-qui-accueille-les-stars-des-JO-de-Tokyo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Alexandre Jeffroy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Le magnifique plateau du Meeting de Li\u00e9vin, qui accueille les stars des JO de Tokyo\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/smokinalexjoe\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/plateau-meeting-de-lievin-accueille-les-stars-des-jo-de-tokyo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/plateau-meeting-de-lievin-accueille-les-stars-des-jo-de-tokyo\/\"},\"author\":{\"name\":\"Alexandre Jeffroy\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0e50be5ee9a0e6705846ac950257c4a0\"},\"headline\":\"Le magnifique plateau du Meeting de Li\u00e9vin, qui accueille les stars des JO de Tokyo\",\"datePublished\":\"2022-02-17T08:00:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/plateau-meeting-de-lievin-accueille-les-stars-des-jo-de-tokyo\/\"},\"wordCount\":1265,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/plateau-meeting-de-lievin-accueille-les-stars-des-jo-de-tokyo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Le-magnifique-plateau-du-Meeting-de-Lievin-qui-accueille-les-stars-des-JO-de-Tokyo.png\",\"keywords\":[\"Athl\u00e9tisme\"],\"articleSection\":[\"Athl\u00e9tisme\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/plateau-meeting-de-lievin-accueille-les-stars-des-jo-de-tokyo\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/plateau-meeting-de-lievin-accueille-les-stars-des-jo-de-tokyo\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/plateau-meeting-de-lievin-accueille-les-stars-des-jo-de-tokyo\/\",\"name\":\"Le magnifique plateau du Meeting de Li\u00e9vin, qui accueille les stars des JO de Tokyo\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/plateau-meeting-de-lievin-accueille-les-stars-des-jo-de-tokyo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/plateau-meeting-de-lievin-accueille-les-stars-des-jo-de-tokyo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Le-magnifique-plateau-du-Meeting-de-Lievin-qui-accueille-les-stars-des-JO-de-Tokyo.png\",\"datePublished\":\"2022-02-17T08:00:51+00:00\",\"description\":\"La vingt-septi\u00e8me \u00e9dition du meeting de Li\u00e9vin se d\u00e9roule ce jeudi soir avec des champions olympiques et des stars fran\u00e7aises au rendez-vous.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/plateau-meeting-de-lievin-accueille-les-stars-des-jo-de-tokyo\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/plateau-meeting-de-lievin-accueille-les-stars-des-jo-de-tokyo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/plateau-meeting-de-lievin-accueille-les-stars-des-jo-de-tokyo\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Le-magnifique-plateau-du-Meeting-de-Lievin-qui-accueille-les-stars-des-JO-de-Tokyo.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Le-magnifique-plateau-du-Meeting-de-Lievin-qui-accueille-les-stars-des-JO-de-Tokyo.png\",\"width\":800,\"height\":445,\"caption\":\"Le magnifique plateau du Meeting de Li\u00e9vin, qui accueille les stars des JO de Tokyo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/plateau-meeting-de-lievin-accueille-les-stars-des-jo-de-tokyo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le magnifique plateau du Meeting de Li\u00e9vin, qui accueille les stars des JO de Tokyo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0e50be5ee9a0e6705846ac950257c4a0\",\"name\":\"Alexandre Jeffroy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Alexandre-Jeffroy-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Alexandre-Jeffroy-150x150.jpg\",\"caption\":\"Alexandre Jeffroy\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis octobre 2020 - Bolt qui foudroie le record du monde du 100 m\u00e8tres, les derniers essais de Dominici, les premi\u00e8res charges d\u00e9vastatrices de Bastarocket... de beaux souvenirs pour une grande passion, celle du sport. L\u2019histoire du sport aussi. Comprendre le r\u00f4le qu\u2019il a eu, celui qu\u2019il a et celui qu\u2019il aura dans notre soci\u00e9t\u00e9. Le sport au pass\u00e9, au pr\u00e9sent, au futur. Le sport tous les jours, matin, midi et soir. A d\u00e9faut d\u2019\u00eatre un grand sportif, je suis et je raconte l\u2019actualit\u00e9 et l\u2019histoire des championnes et des champions qui savent se d\u00e9passer pour accomplir des merveilles.\",\"sameAs\":[\"https:\/\/www.facebook.com\/alexandre.jeffroy.3\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/smokinalexjoe\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/alexandrejeffroy\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le magnifique plateau du Meeting de Li\u00e9vin, qui accueille les stars des JO de Tokyo","description":"La vingt-septi\u00e8me \u00e9dition du meeting de Li\u00e9vin se d\u00e9roule ce jeudi soir avec des champions olympiques et des stars fran\u00e7aises au rendez-vous.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/plateau-meeting-de-lievin-accueille-les-stars-des-jo-de-tokyo\/","og_locale":"fr_FR","og_type":"article","og_title":"Le magnifique plateau du Meeting de Li\u00e9vin, qui accueille les stars des JO de Tokyo","og_description":"La vingt-septi\u00e8me \u00e9dition du meeting de Li\u00e9vin se d\u00e9roule ce jeudi soir avec des champions olympiques et des stars fran\u00e7aises au rendez-vous.","og_url":"https:\/\/dicodusport.fr\/blog\/plateau-meeting-de-lievin-accueille-les-stars-des-jo-de-tokyo\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/alexandre.jeffroy.3\/","article_published_time":"2022-02-17T08:00:51+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Le-magnifique-plateau-du-Meeting-de-Lievin-qui-accueille-les-stars-des-JO-de-Tokyo.png","type":"image\/png"}],"author":"Alexandre Jeffroy","twitter_card":"summary_large_image","twitter_title":"Le magnifique plateau du Meeting de Li\u00e9vin, qui accueille les stars des JO de Tokyo","twitter_creator":"@https:\/\/twitter.com\/smokinalexjoe","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/plateau-meeting-de-lievin-accueille-les-stars-des-jo-de-tokyo\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/plateau-meeting-de-lievin-accueille-les-stars-des-jo-de-tokyo\/"},"author":{"name":"Alexandre Jeffroy","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0e50be5ee9a0e6705846ac950257c4a0"},"headline":"Le magnifique plateau du Meeting de Li\u00e9vin, qui accueille les stars des JO de Tokyo","datePublished":"2022-02-17T08:00:51+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/plateau-meeting-de-lievin-accueille-les-stars-des-jo-de-tokyo\/"},"wordCount":1265,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/plateau-meeting-de-lievin-accueille-les-stars-des-jo-de-tokyo\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Le-magnifique-plateau-du-Meeting-de-Lievin-qui-accueille-les-stars-des-JO-de-Tokyo.png","keywords":["Athl\u00e9tisme"],"articleSection":["Athl\u00e9tisme"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/plateau-meeting-de-lievin-accueille-les-stars-des-jo-de-tokyo\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/plateau-meeting-de-lievin-accueille-les-stars-des-jo-de-tokyo\/","url":"https:\/\/dicodusport.fr\/blog\/plateau-meeting-de-lievin-accueille-les-stars-des-jo-de-tokyo\/","name":"Le magnifique plateau du Meeting de Li\u00e9vin, qui accueille les stars des JO de Tokyo","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/plateau-meeting-de-lievin-accueille-les-stars-des-jo-de-tokyo\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/plateau-meeting-de-lievin-accueille-les-stars-des-jo-de-tokyo\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Le-magnifique-plateau-du-Meeting-de-Lievin-qui-accueille-les-stars-des-JO-de-Tokyo.png","datePublished":"2022-02-17T08:00:51+00:00","description":"La vingt-septi\u00e8me \u00e9dition du meeting de Li\u00e9vin se d\u00e9roule ce jeudi soir avec des champions olympiques et des stars fran\u00e7aises au rendez-vous.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/plateau-meeting-de-lievin-accueille-les-stars-des-jo-de-tokyo\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/plateau-meeting-de-lievin-accueille-les-stars-des-jo-de-tokyo\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/plateau-meeting-de-lievin-accueille-les-stars-des-jo-de-tokyo\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Le-magnifique-plateau-du-Meeting-de-Lievin-qui-accueille-les-stars-des-JO-de-Tokyo.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Le-magnifique-plateau-du-Meeting-de-Lievin-qui-accueille-les-stars-des-JO-de-Tokyo.png","width":800,"height":445,"caption":"Le magnifique plateau du Meeting de Li\u00e9vin, qui accueille les stars des JO de Tokyo"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/plateau-meeting-de-lievin-accueille-les-stars-des-jo-de-tokyo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Le magnifique plateau du Meeting de Li\u00e9vin, qui accueille les stars des JO de Tokyo"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0e50be5ee9a0e6705846ac950257c4a0","name":"Alexandre Jeffroy","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Alexandre-Jeffroy-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Alexandre-Jeffroy-150x150.jpg","caption":"Alexandre Jeffroy"},"description":"Journaliste\/R\u00e9dacteur depuis octobre 2020 - Bolt qui foudroie le record du monde du 100 m\u00e8tres, les derniers essais de Dominici, les premi\u00e8res charges d\u00e9vastatrices de Bastarocket... de beaux souvenirs pour une grande passion, celle du sport. L\u2019histoire du sport aussi. Comprendre le r\u00f4le qu\u2019il a eu, celui qu\u2019il a et celui qu\u2019il aura dans notre soci\u00e9t\u00e9. Le sport au pass\u00e9, au pr\u00e9sent, au futur. Le sport tous les jours, matin, midi et soir. A d\u00e9faut d\u2019\u00eatre un grand sportif, je suis et je raconte l\u2019actualit\u00e9 et l\u2019histoire des championnes et des champions qui savent se d\u00e9passer pour accomplir des merveilles.","sameAs":["https:\/\/www.facebook.com\/alexandre.jeffroy.3\/","https:\/\/x.com\/https:\/\/twitter.com\/smokinalexjoe"],"url":"https:\/\/dicodusport.fr\/blog\/author\/alexandrejeffroy\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/200778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=200778"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/200778\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/201084"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=200778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=200778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=200778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}