{"id":201617,"date":"2022-02-18T17:20:36","date_gmt":"2022-02-18T16:20:36","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=201617&#038;preview=true&#038;preview_id=201617"},"modified":"2022-02-18T17:20:36","modified_gmt":"2022-02-18T16:20:36","slug":"athletisme-blessing-okagbare-suspendue-10-ans-par-laiu","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/athletisme-blessing-okagbare-suspendue-10-ans-par-laiu\/","title":{"rendered":"Athl\u00e9tisme : Blessing Okagbare suspendue 10 ans par l\u2019AIU"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>ATHL\u00c9TISME &#8211; D&rsquo;abord suspendue provisoirement juste avant sa demi-finale du 100 m\u00e8tres aux Jeux Olympiques de Tokyo, la sprinteuse nig\u00e9riane Blessing Okagbare a \u00e9cop\u00e9 d&rsquo;une sanction de 10 ans.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Ce vendredi apr\u00e8s-midi, l&rsquo;Unit\u00e9 d&rsquo;Int\u00e9grit\u00e9 de l&rsquo;Athl\u00e9tisme (AIU) a annonc\u00e9 la suspension de <strong>Blessing Okagbare<\/strong> pour une dur\u00e9e de 10 ans. La sprinteuse avait \u00e9t\u00e9 contr\u00f4l\u00e9e positive \u00e0 l&rsquo;EPO en juin puis \u00e0 une hormone de croissance, ce qui lui a valu d&rsquo;\u00eatre exclue des derniers Jeux Olympiques. La m\u00e9daill\u00e9e de bronze sur 200 m\u00e8tres aux Mondiaux 2013 a donc \u00e9t\u00e9 suspendue cinq ans pour prise de produits prohib\u00e9s puis cinq ann\u00e9es suppl\u00e9mentaires pour non-coop\u00e9ration \u00e0 l&rsquo;enqu\u00eate.<\/p>\n<p style=\"text-align: justify;\">Le grand patron de l&rsquo;AIU, <strong>Brett Clothier<\/strong>, se f\u00e9licite de cette d\u00e9cision. <em>\u00ab<\/em> <em>Une interdiction de 10 ans est un message fort contre les tentatives intentionnelles et coordonn\u00e9es de tricher au plus haut niveau de notre sport \u00bb. <\/em>Le communiqu\u00e9 annon\u00e7ant la retraite anticip\u00e9e de la Nig\u00e9riane de 33 ans est clair :\u00a0<strong>Okagbare\u00a0<\/strong>a particip\u00e9 \u00e0 un r\u00e9gime de dopage organis\u00e9 en pr\u00e9vision des Jeux Olympiques.<\/p>\n<p style=\"text-align: justify;\">En janvier dernier, un th\u00e9rapeute am\u00e9ricain nomm\u00e9 <strong>Eric Lira<\/strong> a \u00e9t\u00e9 inculp\u00e9 pour avoir fourni des produits dopants \u00e0 des athl\u00e8tes olympiques. M\u00eame si le nom de <strong>Blessing Okagbare<\/strong> n&rsquo;a pas fuit\u00e9 au moment de l&rsquo;\u00e9vocation de cette affaire, elle semble bien \u00eatre l&rsquo;une des sportives vis\u00e9es.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Blessing Okagbare suspendue dix ans pour dopage<\/p>\n<p>La sprinteuse nig\u00e9riane a \u00e9t\u00e9 suspendue dix ans pour usage de substances prohib\u00e9es et non-coop\u00e9ration dans l&rsquo;enqu\u00eate men\u00e9e par les autorit\u00e9s antidopage <a href=\"https:\/\/t.co\/FbGAsnn7Vz\">https:\/\/t.co\/FbGAsnn7Vz<\/a> <a href=\"https:\/\/t.co\/dilBn0Zltj\">pic.twitter.com\/dilBn0Zltj<\/a><\/p>\n<p>\u2014 L&rsquo;\u00c9QUIPE (@lequipe) <a href=\"https:\/\/twitter.com\/lequipe\/status\/1494704532395380742?ref_src=twsrc%5Etfw\">February 18, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>D&rsquo;abord suspendue provisoirement juste avant sa demi-finale du 100 m\u00e8tres aux Jeux Olympiques de Tokyo, la sprinteuse nig\u00e9riane Blessing Okagbare a \u00e9cop\u00e9 d&rsquo;une sanction de 10 ans.<\/p>\n","protected":false},"author":61,"featured_media":201633,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2308],"tags":[2886],"class_list":["post-201617","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-athletisme","tag-dopage"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Athl\u00e9tisme : Blessing Okagbare suspendue 10 ans par l\u2019AIU<\/title>\n<meta name=\"description\" content=\"Suspendue juste avant sa demi-finale du 100 m\u00e8tres aux Jeux Olympiques de Tokyo, Blessing Okagbare a \u00e9cop\u00e9 d&#039;une sanction de 10 ans.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/athletisme-blessing-okagbare-suspendue-10-ans-par-laiu\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Athl\u00e9tisme : Blessing Okagbare suspendue 10 ans par l\u2019AIU\" \/>\n<meta property=\"og:description\" content=\"Suspendue juste avant sa demi-finale du 100 m\u00e8tres aux Jeux Olympiques de Tokyo, Blessing Okagbare a \u00e9cop\u00e9 d&#039;une sanction de 10 ans.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/athletisme-blessing-okagbare-suspendue-10-ans-par-laiu\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-18T16:20:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Athletisme-Blessing-Okagbare-suspendue-10-ans-par-lAIU.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Pierre Gorce\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Athl\u00e9tisme : Blessing Okagbare suspendue 10 ans par l\u2019AIU\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/pierregorce12\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/athletisme-blessing-okagbare-suspendue-10-ans-par-laiu\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/athletisme-blessing-okagbare-suspendue-10-ans-par-laiu\/\"},\"author\":{\"name\":\"Pierre Gorce\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0eaf70b33d703a1a66b1155ac1bda018\"},\"headline\":\"Athl\u00e9tisme : Blessing Okagbare suspendue 10 ans par l\u2019AIU\",\"datePublished\":\"2022-02-18T16:20:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/athletisme-blessing-okagbare-suspendue-10-ans-par-laiu\/\"},\"wordCount\":306,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/athletisme-blessing-okagbare-suspendue-10-ans-par-laiu\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Athletisme-Blessing-Okagbare-suspendue-10-ans-par-lAIU.png\",\"keywords\":[\"dopage\"],\"articleSection\":[\"Athl\u00e9tisme\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/athletisme-blessing-okagbare-suspendue-10-ans-par-laiu\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/athletisme-blessing-okagbare-suspendue-10-ans-par-laiu\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/athletisme-blessing-okagbare-suspendue-10-ans-par-laiu\/\",\"name\":\"Athl\u00e9tisme : Blessing Okagbare suspendue 10 ans par l\u2019AIU\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/athletisme-blessing-okagbare-suspendue-10-ans-par-laiu\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/athletisme-blessing-okagbare-suspendue-10-ans-par-laiu\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Athletisme-Blessing-Okagbare-suspendue-10-ans-par-lAIU.png\",\"datePublished\":\"2022-02-18T16:20:36+00:00\",\"description\":\"Suspendue juste avant sa demi-finale du 100 m\u00e8tres aux Jeux Olympiques de Tokyo, Blessing Okagbare a \u00e9cop\u00e9 d'une sanction de 10 ans.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/athletisme-blessing-okagbare-suspendue-10-ans-par-laiu\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/athletisme-blessing-okagbare-suspendue-10-ans-par-laiu\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/athletisme-blessing-okagbare-suspendue-10-ans-par-laiu\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Athletisme-Blessing-Okagbare-suspendue-10-ans-par-lAIU.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Athletisme-Blessing-Okagbare-suspendue-10-ans-par-lAIU.png\",\"width\":800,\"height\":445,\"caption\":\"Athl\u00e9tisme Blessing Okagbare suspendue 10 ans par l\u2019AIU\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/athletisme-blessing-okagbare-suspendue-10-ans-par-laiu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Athl\u00e9tisme : Blessing Okagbare suspendue 10 ans par l\u2019AIU\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0eaf70b33d703a1a66b1155ac1bda018\",\"name\":\"Pierre Gorce\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_20211214_233053_722-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_20211214_233053_722-150x150.jpg\",\"caption\":\"Pierre Gorce\"},\"description\":\"Couteau suisse venant tout droit de Haute-Savoie. Habitu\u00e9 \u00e0 regarder du sport depuis petit, j'en ai maintenant fait mon m\u00e9tier. Des sports d'hiver au surf, en passant par le tennis, la F1, le handball et l'athl\u00e9tisme, j'essaie d'avoir mes yeux sur l'enti\u00e8ret\u00e9 de l'actualit\u00e9. Jeune homme berc\u00e9 par les exploits de Jean-Baptiste Grange, Sebastian Vettel et des Experts. Membre de la g\u00e9n\u00e9ration 1999 comme Luka Doncic, Sydney McLaughlin, Lando Norris et Loana Lecomte, mais avec beaucoup moins de talent qu'eux.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/pierregorce12\"],\"birthDate\":\"1999-08-29\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/pierreg\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Athl\u00e9tisme : Blessing Okagbare suspendue 10 ans par l\u2019AIU","description":"Suspendue juste avant sa demi-finale du 100 m\u00e8tres aux Jeux Olympiques de Tokyo, Blessing Okagbare a \u00e9cop\u00e9 d'une sanction de 10 ans.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/athletisme-blessing-okagbare-suspendue-10-ans-par-laiu\/","og_locale":"fr_FR","og_type":"article","og_title":"Athl\u00e9tisme : Blessing Okagbare suspendue 10 ans par l\u2019AIU","og_description":"Suspendue juste avant sa demi-finale du 100 m\u00e8tres aux Jeux Olympiques de Tokyo, Blessing Okagbare a \u00e9cop\u00e9 d'une sanction de 10 ans.","og_url":"https:\/\/dicodusport.fr\/blog\/athletisme-blessing-okagbare-suspendue-10-ans-par-laiu\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2022-02-18T16:20:36+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Athletisme-Blessing-Okagbare-suspendue-10-ans-par-lAIU.png","type":"image\/png"}],"author":"Pierre Gorce","twitter_card":"summary_large_image","twitter_title":"Athl\u00e9tisme : Blessing Okagbare suspendue 10 ans par l\u2019AIU","twitter_creator":"@https:\/\/twitter.com\/pierregorce12","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/athletisme-blessing-okagbare-suspendue-10-ans-par-laiu\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/athletisme-blessing-okagbare-suspendue-10-ans-par-laiu\/"},"author":{"name":"Pierre Gorce","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0eaf70b33d703a1a66b1155ac1bda018"},"headline":"Athl\u00e9tisme : Blessing Okagbare suspendue 10 ans par l\u2019AIU","datePublished":"2022-02-18T16:20:36+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/athletisme-blessing-okagbare-suspendue-10-ans-par-laiu\/"},"wordCount":306,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/athletisme-blessing-okagbare-suspendue-10-ans-par-laiu\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Athletisme-Blessing-Okagbare-suspendue-10-ans-par-lAIU.png","keywords":["dopage"],"articleSection":["Athl\u00e9tisme"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/athletisme-blessing-okagbare-suspendue-10-ans-par-laiu\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/athletisme-blessing-okagbare-suspendue-10-ans-par-laiu\/","url":"https:\/\/dicodusport.fr\/blog\/athletisme-blessing-okagbare-suspendue-10-ans-par-laiu\/","name":"Athl\u00e9tisme : Blessing Okagbare suspendue 10 ans par l\u2019AIU","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/athletisme-blessing-okagbare-suspendue-10-ans-par-laiu\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/athletisme-blessing-okagbare-suspendue-10-ans-par-laiu\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Athletisme-Blessing-Okagbare-suspendue-10-ans-par-lAIU.png","datePublished":"2022-02-18T16:20:36+00:00","description":"Suspendue juste avant sa demi-finale du 100 m\u00e8tres aux Jeux Olympiques de Tokyo, Blessing Okagbare a \u00e9cop\u00e9 d'une sanction de 10 ans.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/athletisme-blessing-okagbare-suspendue-10-ans-par-laiu\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/athletisme-blessing-okagbare-suspendue-10-ans-par-laiu\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/athletisme-blessing-okagbare-suspendue-10-ans-par-laiu\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Athletisme-Blessing-Okagbare-suspendue-10-ans-par-lAIU.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/02\/Athletisme-Blessing-Okagbare-suspendue-10-ans-par-lAIU.png","width":800,"height":445,"caption":"Athl\u00e9tisme Blessing Okagbare suspendue 10 ans par l\u2019AIU"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/athletisme-blessing-okagbare-suspendue-10-ans-par-laiu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Athl\u00e9tisme : Blessing Okagbare suspendue 10 ans par l\u2019AIU"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0eaf70b33d703a1a66b1155ac1bda018","name":"Pierre Gorce","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_20211214_233053_722-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_20211214_233053_722-150x150.jpg","caption":"Pierre Gorce"},"description":"Couteau suisse venant tout droit de Haute-Savoie. Habitu\u00e9 \u00e0 regarder du sport depuis petit, j'en ai maintenant fait mon m\u00e9tier. Des sports d'hiver au surf, en passant par le tennis, la F1, le handball et l'athl\u00e9tisme, j'essaie d'avoir mes yeux sur l'enti\u00e8ret\u00e9 de l'actualit\u00e9. Jeune homme berc\u00e9 par les exploits de Jean-Baptiste Grange, Sebastian Vettel et des Experts. Membre de la g\u00e9n\u00e9ration 1999 comme Luka Doncic, Sydney McLaughlin, Lando Norris et Loana Lecomte, mais avec beaucoup moins de talent qu'eux.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/pierregorce12"],"birthDate":"1999-08-29","url":"https:\/\/dicodusport.fr\/blog\/author\/pierreg\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/201617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=201617"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/201617\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/201633"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=201617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=201617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=201617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}