{"id":206144,"date":"2022-03-08T16:20:27","date_gmt":"2022-03-08T15:20:27","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=206144&#038;preview=true&#038;preview_id=206144"},"modified":"2022-03-08T16:30:12","modified_gmt":"2022-03-08T15:30:12","slug":"xv-de-france-antoine-dupont-touche-au-bras-avant-le-pays-de-galles","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/xv-de-france-antoine-dupont-touche-au-bras-avant-le-pays-de-galles\/","title":{"rendered":"XV de France : Antoine Dupont touch\u00e9 au bras avant le Pays de Galles"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/rugby\/rugby-a-xv\/xv-de-france\/\">XV DE FRANCE<\/a> &#8211; Selon nos confr\u00e8res de RMC Sport, Antoine Dupont s&rsquo;est bless\u00e9 \u00e0 l&rsquo;entra\u00eenement mardi, \u00e0 trois jours du match face au Pays de Galles.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Le capitaine de l&rsquo;\u00e9quipe de France, <strong>Antoine Dupont<\/strong>, n&rsquo;a pas pu aller au terme de la s\u00e9ance \u00e0 haute intensit\u00e9 ce mardi, apr\u00e8s avoir ressenti une douleur au bras gauche. Pas plus d&rsquo;informations pour le moment sur sa blessure du demi de m\u00eal\u00e9e, mais les Bleus jouent vendredi soir face au XV du Poireau (21h). Ce serait un vrai coup dur pour le XV de France s&rsquo;il \u00e9tait priv\u00e9 du meilleur joueur du monde, au regard notamment de sa prestation face \u00e0 l&rsquo;\u00c9cosse. \u00c0 noter que <strong>Ga\u00ebl Fickou<\/strong>, malade, n&rsquo;a pas particip\u00e9 \u00e0 la s\u00e9ance mardi, tout comme <strong>Baptiste Couilloud<\/strong>. La pr\u00e9sence du centre du Racing 92 n&rsquo;est pas remise en cause pour vendredi.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Le demi de m\u00eal\u00e9e toulousain des Bleus Antoine Dupont a d\u00fb arr\u00eater son entra\u00eenement ce mercredi apr\u00e8s-midi lors de la s\u00e9ance \u00e0 haute intensit\u00e9. Le meilleur joueur du monde se plaint du bras gauche trois jours avant le match contre le pays de Galles <a href=\"https:\/\/twitter.com\/hashtag\/XVdeFrance?src=hash&amp;ref_src=twsrc%5Etfw\">#XVdeFrance<\/a><\/p>\n<p>\u2014 JF Paturaud (@JFPaturaud) <a href=\"https:\/\/twitter.com\/JFPaturaud\/status\/1501210177273487366?ref_src=twsrc%5Etfw\">March 8, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>XV DE FRANCE &#8211; Selon nos confr\u00e8res de RMC Sport, Antoine Dupont s&rsquo;est bless\u00e9 \u00e0 l&rsquo;entra\u00eenement mardi, \u00e0 trois jours du match face au Pays de Galles.<\/p>\n","protected":false},"author":1,"featured_media":206145,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[9129,19951],"tags":[3085,2373,7278,338,1638],"class_list":["post-206144","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","category-xv-de-france","tag-6-nations","tag-antoine-dupont","tag-dupont","tag-pays-de-galles","tag-xv-de-france"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>XV de France : Antoine Dupont touch\u00e9 au bras avant le Pays de Galles<\/title>\n<meta name=\"description\" content=\"XV DE FRANCE - Selon nos confr\u00e8res de RMC Sport, Antoine Dupont s&#039;est bless\u00e9 \u00e0 l&#039;entra\u00eenement mardi, \u00e0 trois jours du match face au Pays de Galles.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/xv-de-france-antoine-dupont-touche-au-bras-avant-le-pays-de-galles\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"XV de France : Antoine Dupont touch\u00e9 au bras avant le Pays de Galles\" \/>\n<meta property=\"og:description\" content=\"XV DE FRANCE - Selon nos confr\u00e8res de RMC Sport, Antoine Dupont s&#039;est bless\u00e9 \u00e0 l&#039;entra\u00eenement mardi, \u00e0 trois jours du match face au Pays de Galles.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/xv-de-france-antoine-dupont-touche-au-bras-avant-le-pays-de-galles\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-08T15:20:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-08T15:30:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/XV-de-France-Antoine-Dupont-touche-au-bras-avant-le-Pays-de-Galles.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"XV de France : Antoine Dupont touch\u00e9 au bras avant le Pays de Galles\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-antoine-dupont-touche-au-bras-avant-le-pays-de-galles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-antoine-dupont-touche-au-bras-avant-le-pays-de-galles\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"XV de France : Antoine Dupont touch\u00e9 au bras avant le Pays de Galles\",\"datePublished\":\"2022-03-08T15:20:27+00:00\",\"dateModified\":\"2022-03-08T15:30:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-antoine-dupont-touche-au-bras-avant-le-pays-de-galles\\\/\"},\"wordCount\":220,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-antoine-dupont-touche-au-bras-avant-le-pays-de-galles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/XV-de-France-Antoine-Dupont-touche-au-bras-avant-le-Pays-de-Galles.png\",\"keywords\":[\"6 nations\",\"Antoine Dupont\",\"Dupont\",\"Pays De Galles\",\"XV de France\"],\"articleSection\":[\"Rugby \u00e0 XV\",\"XV de France\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-antoine-dupont-touche-au-bras-avant-le-pays-de-galles\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-antoine-dupont-touche-au-bras-avant-le-pays-de-galles\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-antoine-dupont-touche-au-bras-avant-le-pays-de-galles\\\/\",\"name\":\"XV de France : Antoine Dupont touch\u00e9 au bras avant le Pays de Galles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-antoine-dupont-touche-au-bras-avant-le-pays-de-galles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-antoine-dupont-touche-au-bras-avant-le-pays-de-galles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/XV-de-France-Antoine-Dupont-touche-au-bras-avant-le-Pays-de-Galles.png\",\"datePublished\":\"2022-03-08T15:20:27+00:00\",\"dateModified\":\"2022-03-08T15:30:12+00:00\",\"description\":\"XV DE FRANCE - Selon nos confr\u00e8res de RMC Sport, Antoine Dupont s'est bless\u00e9 \u00e0 l'entra\u00eenement mardi, \u00e0 trois jours du match face au Pays de Galles.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-antoine-dupont-touche-au-bras-avant-le-pays-de-galles\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-antoine-dupont-touche-au-bras-avant-le-pays-de-galles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-antoine-dupont-touche-au-bras-avant-le-pays-de-galles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/XV-de-France-Antoine-Dupont-touche-au-bras-avant-le-Pays-de-Galles.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/XV-de-France-Antoine-Dupont-touche-au-bras-avant-le-Pays-de-Galles.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-antoine-dupont-touche-au-bras-avant-le-pays-de-galles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"XV de France : Antoine Dupont touch\u00e9 au bras avant le Pays de Galles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"XV de France : Antoine Dupont touch\u00e9 au bras avant le Pays de Galles","description":"XV DE FRANCE - Selon nos confr\u00e8res de RMC Sport, Antoine Dupont s'est bless\u00e9 \u00e0 l'entra\u00eenement mardi, \u00e0 trois jours du match face au Pays de Galles.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/xv-de-france-antoine-dupont-touche-au-bras-avant-le-pays-de-galles\/","og_locale":"fr_FR","og_type":"article","og_title":"XV de France : Antoine Dupont touch\u00e9 au bras avant le Pays de Galles","og_description":"XV DE FRANCE - Selon nos confr\u00e8res de RMC Sport, Antoine Dupont s'est bless\u00e9 \u00e0 l'entra\u00eenement mardi, \u00e0 trois jours du match face au Pays de Galles.","og_url":"https:\/\/dicodusport.fr\/blog\/xv-de-france-antoine-dupont-touche-au-bras-avant-le-pays-de-galles\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2022-03-08T15:20:27+00:00","article_modified_time":"2022-03-08T15:30:12+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/XV-de-France-Antoine-Dupont-touche-au-bras-avant-le-Pays-de-Galles.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"XV de France : Antoine Dupont touch\u00e9 au bras avant le Pays de Galles","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-antoine-dupont-touche-au-bras-avant-le-pays-de-galles\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-antoine-dupont-touche-au-bras-avant-le-pays-de-galles\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"XV de France : Antoine Dupont touch\u00e9 au bras avant le Pays de Galles","datePublished":"2022-03-08T15:20:27+00:00","dateModified":"2022-03-08T15:30:12+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-antoine-dupont-touche-au-bras-avant-le-pays-de-galles\/"},"wordCount":220,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-antoine-dupont-touche-au-bras-avant-le-pays-de-galles\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/XV-de-France-Antoine-Dupont-touche-au-bras-avant-le-Pays-de-Galles.png","keywords":["6 nations","Antoine Dupont","Dupont","Pays De Galles","XV de France"],"articleSection":["Rugby \u00e0 XV","XV de France"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/xv-de-france-antoine-dupont-touche-au-bras-avant-le-pays-de-galles\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-antoine-dupont-touche-au-bras-avant-le-pays-de-galles\/","url":"https:\/\/dicodusport.fr\/blog\/xv-de-france-antoine-dupont-touche-au-bras-avant-le-pays-de-galles\/","name":"XV de France : Antoine Dupont touch\u00e9 au bras avant le Pays de Galles","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-antoine-dupont-touche-au-bras-avant-le-pays-de-galles\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-antoine-dupont-touche-au-bras-avant-le-pays-de-galles\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/XV-de-France-Antoine-Dupont-touche-au-bras-avant-le-Pays-de-Galles.png","datePublished":"2022-03-08T15:20:27+00:00","dateModified":"2022-03-08T15:30:12+00:00","description":"XV DE FRANCE - Selon nos confr\u00e8res de RMC Sport, Antoine Dupont s'est bless\u00e9 \u00e0 l'entra\u00eenement mardi, \u00e0 trois jours du match face au Pays de Galles.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-antoine-dupont-touche-au-bras-avant-le-pays-de-galles\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/xv-de-france-antoine-dupont-touche-au-bras-avant-le-pays-de-galles\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-antoine-dupont-touche-au-bras-avant-le-pays-de-galles\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/XV-de-France-Antoine-Dupont-touche-au-bras-avant-le-Pays-de-Galles.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/XV-de-France-Antoine-Dupont-touche-au-bras-avant-le-Pays-de-Galles.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-antoine-dupont-touche-au-bras-avant-le-pays-de-galles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"XV de France : Antoine Dupont touch\u00e9 au bras avant le Pays de Galles"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/206144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=206144"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/206144\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/206145"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=206144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=206144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=206144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}