{"id":20695,"date":"2018-06-22T08:24:33","date_gmt":"2018-06-22T06:24:33","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=20695"},"modified":"2018-06-22T08:24:33","modified_gmt":"2018-06-22T06:24:33","slug":"argentine-croatie-0-3-les-5-choses-a-retenir","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/argentine-croatie-0-3-les-5-choses-a-retenir\/","title":{"rendered":"Argentine &#8211; Croatie (0-3) : les 5 choses \u00e0 retenir"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>L&rsquo;Argentine a sombr\u00e9 face \u00e0 une Croatie convaincante. Pas encore \u00e9limin\u00e9e, l&rsquo;Albiceleste est au bord du pr\u00e9cipice. Voici ce qu&rsquo;il faut retenir du match.\u00a0<\/strong><\/em><\/p>\n<h4 style=\"text-align: justify;\">La Croatie au rendez-vous des huiti\u00e8mes de finale<\/h4>\n<p style=\"text-align: justify;\">Apr\u00e8s un Euro 2016 encourageant o\u00f9 les Croates nous avaient un peu laiss\u00e9s sur notre faim avec cette \u00e9limination contre les Portugais, ils confirment sur cette Coupe du monde. Apr\u00e8s une entr\u00e9e en lice r\u00e9ussie face au Nigeria, les co\u00e9quipiers de Luka Modric ont largement domin\u00e9 l&rsquo;Argentine dans un match \u00e0 sens unique. La Croatie sera au rendez-vous des huiti\u00e8mes de finale, en terminant probablement en t\u00eate du groupe.<\/p>\n<h4 style=\"text-align: justify;\">Modric, ce maestro<\/h4>\n<p style=\"text-align: justify;\">Une nouvelle performance aboutie pour le milieu de terrain du Real Madrid qui a \u00e9t\u00e9 le m\u00e9tronome de son \u00e9quipe. Pour couronner un match r\u00e9ussi, il marque un deuxi\u00e8me but somptueux, deux feintes devant Otamendi avant de l\u00e2cher une sublime frappe aux 25 m\u00e8tres qui finit dans le petit filet du gardien argentin. Pour ceux qui avaient encore quelques doutes, Luka Modric prouve qu&rsquo;il est au sommet de son art et l&rsquo;un des tous meilleurs au monde \u00e0 son poste.<\/p>\n<h4 style=\"text-align: justify;\">Caballero, gardien fant\u00f4me<\/h4>\n<p style=\"text-align: justify;\">Il \u00e9tait d\u00e9sign\u00e9 comme le point faible de l&rsquo;Argentine avant la comp\u00e9tition et on peut dire que les observateurs ne s&rsquo;\u00e9taient pas tromp\u00e9s. En plus de ne pas \u00eatre rassurant, il offre le premier but \u00e0 la Croatie sur une relance compl\u00e8tement rat\u00e9e, une passe d\u00e9cisive du gardien argentin. Sur le deuxi\u00e8me but, m\u00eame si la frappe de Modric est belle, elle vient de 25 m\u00e8tres et il met beaucoup de temps \u00e0 r\u00e9agir.<\/p>\n<h4 style=\"text-align: justify;\">Messi invisible<\/h4>\n<p style=\"text-align: justify;\">Alors que Cristiano Ronaldo brille avec 4 buts en 2 matchs, Lionel Messi n&rsquo;est que l&rsquo;ombre de lui-m\u00eame. Compl\u00e8tement transparent, le g\u00e9nie argentin s&rsquo;est mis au niveau de ses co\u00e9quipiers et ce n&rsquo;est pas glorieux. De grandes chances de voir une nouvelle retraite internationale de l&rsquo;Argentin si sa s\u00e9lection est \u00e9limin\u00e9e d\u00e8s la phase de groupes&#8230;<\/p>\n<h4 style=\"text-align: justify;\">Sampaoli, \u00e0 c\u00f4t\u00e9 de ses pompes<\/h4>\n<p style=\"text-align: justify;\">Consid\u00e9r\u00e9 comme un entra\u00eeneur de g\u00e9nie par certains, Sampaoli a condamn\u00e9 sa s\u00e9lection. D\u00e9j\u00e0, les qualifications ont \u00e9t\u00e9 compliqu\u00e9es (m\u00eame s&rsquo;il\u00a0a pris\u00a0cette aventure en cours), sa liste des 23 a \u00e9t\u00e9 critiqu\u00e9e, mais alors que dire de ses choix tactiques sur cette Coupe du monde ? L&rsquo;entra\u00eeneur s&rsquo;est tromp\u00e9 sur toute la ligne, Dybala a jou\u00e9 20 minutes en deux matchs, Lo Celso n&rsquo;a toujours pas \u00e9t\u00e9 vu et Di Maria\u00a0non\u00a0plus face \u00e0 la Croatie. Si vous ajoutez \u00e0 cela que le plan de jeu du s\u00e9lectionneur argentin est illisible, on peut confirmer qu&rsquo;il est en train de pousser son \u00e9quipe dans le pr\u00e9cipice.<\/p>\n<p style=\"text-align: justify;\"><em><strong>Nicolas Jacquemard<\/strong><br \/>\n<\/em><a style=\"color: #000000;\" href=\"https:\/\/twitter.com\/Nico_Jacquemard\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"color: #000000;\" href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;Argentine a sombr\u00e9 face \u00e0 une Croatie convaincante. Pas encore \u00e9limin\u00e9e, l&rsquo;Albiceleste est au bord du pr\u00e9cipice. Voici ce qu&rsquo;il faut retenir du match.<\/p>\n","protected":false},"author":1,"featured_media":20697,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[47043,2301],"tags":[4209,1530,362,75,3070],"class_list":["post-20695","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coupe-du-monde-de-football","category-football","tag-argentine","tag-coupe-du-monde","tag-croatie","tag-football","tag-messi"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Argentine - Croatie (0-3) : les 5 choses \u00e0 retenir<\/title>\n<meta name=\"description\" content=\"L&#039;Argentine a sombr\u00e9 face \u00e0 une Croatie convaincante. Pas encore \u00e9limin\u00e9e, l&#039;Albiceleste est au bord du pr\u00e9cipice. Voici ce qu&#039;il faut retenir du match.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/argentine-croatie-0-3-les-5-choses-a-retenir\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Argentine - Croatie (0-3) : les 5 choses \u00e0 retenir\" \/>\n<meta property=\"og:description\" content=\"L&#039;Argentine a sombr\u00e9 face \u00e0 une Croatie convaincante. Pas encore \u00e9limin\u00e9e, l&#039;Albiceleste est au bord du pr\u00e9cipice. Voici ce qu&#039;il faut retenir du match.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/argentine-croatie-0-3-les-5-choses-a-retenir\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-22T06:24:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/06\/Messi-Argentine.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/argentine-croatie-0-3-les-5-choses-a-retenir\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/argentine-croatie-0-3-les-5-choses-a-retenir\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Argentine &#8211; Croatie (0-3) : les 5 choses \u00e0 retenir\",\"datePublished\":\"2018-06-22T06:24:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/argentine-croatie-0-3-les-5-choses-a-retenir\/\"},\"wordCount\":490,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/argentine-croatie-0-3-les-5-choses-a-retenir\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/06\/Messi-Argentine.png\",\"keywords\":[\"Argentine\",\"Coupe du monde\",\"Croatie\",\"Football\",\"messi\"],\"articleSection\":[\"Coupe du monde de football\",\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/argentine-croatie-0-3-les-5-choses-a-retenir\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/argentine-croatie-0-3-les-5-choses-a-retenir\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/argentine-croatie-0-3-les-5-choses-a-retenir\/\",\"name\":\"Argentine - Croatie (0-3) : les 5 choses \u00e0 retenir\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/argentine-croatie-0-3-les-5-choses-a-retenir\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/argentine-croatie-0-3-les-5-choses-a-retenir\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/06\/Messi-Argentine.png\",\"datePublished\":\"2018-06-22T06:24:33+00:00\",\"description\":\"L'Argentine a sombr\u00e9 face \u00e0 une Croatie convaincante. Pas encore \u00e9limin\u00e9e, l'Albiceleste est au bord du pr\u00e9cipice. Voici ce qu'il faut retenir du match.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/argentine-croatie-0-3-les-5-choses-a-retenir\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/argentine-croatie-0-3-les-5-choses-a-retenir\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/argentine-croatie-0-3-les-5-choses-a-retenir\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/06\/Messi-Argentine.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/06\/Messi-Argentine.png\",\"width\":1200,\"height\":670,\"caption\":\"Messi Argentine\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/argentine-croatie-0-3-les-5-choses-a-retenir\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Argentine &#8211; Croatie (0-3) : les 5 choses \u00e0 retenir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Argentine - Croatie (0-3) : les 5 choses \u00e0 retenir","description":"L'Argentine a sombr\u00e9 face \u00e0 une Croatie convaincante. Pas encore \u00e9limin\u00e9e, l'Albiceleste est au bord du pr\u00e9cipice. Voici ce qu'il faut retenir du match.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/argentine-croatie-0-3-les-5-choses-a-retenir\/","og_locale":"fr_FR","og_type":"article","og_title":"Argentine - Croatie (0-3) : les 5 choses \u00e0 retenir","og_description":"L'Argentine a sombr\u00e9 face \u00e0 une Croatie convaincante. Pas encore \u00e9limin\u00e9e, l'Albiceleste est au bord du pr\u00e9cipice. Voici ce qu'il faut retenir du match.","og_url":"https:\/\/dicodusport.fr\/blog\/argentine-croatie-0-3-les-5-choses-a-retenir\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2018-06-22T06:24:33+00:00","og_image":[{"width":1200,"height":670,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/06\/Messi-Argentine.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/argentine-croatie-0-3-les-5-choses-a-retenir\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/argentine-croatie-0-3-les-5-choses-a-retenir\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Argentine &#8211; Croatie (0-3) : les 5 choses \u00e0 retenir","datePublished":"2018-06-22T06:24:33+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/argentine-croatie-0-3-les-5-choses-a-retenir\/"},"wordCount":490,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/argentine-croatie-0-3-les-5-choses-a-retenir\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/06\/Messi-Argentine.png","keywords":["Argentine","Coupe du monde","Croatie","Football","messi"],"articleSection":["Coupe du monde de football","Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/argentine-croatie-0-3-les-5-choses-a-retenir\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/argentine-croatie-0-3-les-5-choses-a-retenir\/","url":"https:\/\/dicodusport.fr\/blog\/argentine-croatie-0-3-les-5-choses-a-retenir\/","name":"Argentine - Croatie (0-3) : les 5 choses \u00e0 retenir","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/argentine-croatie-0-3-les-5-choses-a-retenir\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/argentine-croatie-0-3-les-5-choses-a-retenir\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/06\/Messi-Argentine.png","datePublished":"2018-06-22T06:24:33+00:00","description":"L'Argentine a sombr\u00e9 face \u00e0 une Croatie convaincante. Pas encore \u00e9limin\u00e9e, l'Albiceleste est au bord du pr\u00e9cipice. Voici ce qu'il faut retenir du match.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/argentine-croatie-0-3-les-5-choses-a-retenir\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/argentine-croatie-0-3-les-5-choses-a-retenir\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/argentine-croatie-0-3-les-5-choses-a-retenir\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/06\/Messi-Argentine.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/06\/Messi-Argentine.png","width":1200,"height":670,"caption":"Messi Argentine"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/argentine-croatie-0-3-les-5-choses-a-retenir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Argentine &#8211; Croatie (0-3) : les 5 choses \u00e0 retenir"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/20695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=20695"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/20695\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/20697"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=20695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=20695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=20695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}