{"id":215244,"date":"2022-04-11T10:42:39","date_gmt":"2022-04-11T08:42:39","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=215244&#038;preview=true&#038;preview_id=215244"},"modified":"2022-04-11T15:17:19","modified_gmt":"2022-04-11T13:17:19","slug":"frank-vogel-nest-plus-lentraineur-des-los-angeles-lakers","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/frank-vogel-nest-plus-lentraineur-des-los-angeles-lakers\/","title":{"rendered":"Frank Vogel n&rsquo;est plus l\u2019entra\u00eeneur des Los Angeles Lakers"},"content":{"rendered":"<div class=\"mvp-post-soc-in\">\n<div id=\"mvp-content-body\" class=\"left relative\">\n<div id=\"mvp-content-body-top\" class=\"left relative\">\n<div id=\"mvp-content-main\" class=\"left relative\">\n<p style=\"text-align: justify;\"><strong><em><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/basket-ball\/nba\/nba-2021-2022\/\">NBA 2021-2022<\/a> &#8211; Le coach des Lakers est la premi\u00e8re t\u00eate \u00e0 tomber au sein de la franchise californienne, victime des r\u00e9sultats pr\u00e9caires de son \u00e9quipe.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Avec un bilan de 33 victoires pour 49 d\u00e9faites, <strong>les Lakers ont r\u00e9alis\u00e9 une des pires saisons de leur histoire<\/strong>, surtout au vu de l&rsquo;effectif qui semblait prometteur en d\u00e9but de saison. \u00c9videmment, dans ce genre de situation, entrainement est toujours la premi\u00e8re personne \u00e0 bl\u00e2mer et c&rsquo;est ce qu&rsquo;a d\u00fb penser <strong>Jeanie Buss<\/strong>, la propri\u00e9taire des Lakers. <strong>Frank Vogel<\/strong> a donc \u00e9t\u00e9 pri\u00e9 de faire ses valises selon le journaliste <strong>Adrian Wojnarowski<\/strong>, toujours dans les petits secrets de la NBA. La franchise majeure de Los Angeles se donne au moins le temps de l&rsquo;intersaison pour trouver un nouveau coach et on peut \u00eatre certain que les noms seront nombreux \u00e0 circuler pour ce poste.<\/p>\n<p style=\"text-align: justify;\">Frank Vogel sera-t-il suivi par le General Manager <strong>Rob Pelinka<\/strong>, qui est d\u00e9sign\u00e9 lui aussi comme un des principaux responsables de cette d\u00e9b\u00e2cle ? \u00c0 suivre dans les prochains jours&#8230;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Frank Vogel has coached his final game for the Lakers, a decision that\u2019s expected to be shared with him as soon as Monday, sources tell ESPN. Lakers\u2019 search expected to be lengthy and expansive with no clear initial frontrunner.<\/p>\n<p>\u2014 Adrian Wojnarowski (@wojespn) <a href=\"https:\/\/twitter.com\/wojespn\/status\/1513374146234920962?ref_src=twsrc%5Etfw\">April 11, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>NBA 2021-2022 &#8211; Le coach des Lakers est la premi\u00e8re t\u00eate \u00e0 tomber au sein de la franchise californienne, victime des r\u00e9sultats pr\u00e9caires de son \u00e9quipe.<\/p>\n","protected":false},"author":21,"featured_media":215254,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[10533],"tags":[2054],"class_list":["post-215244","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nba","tag-los-angeles-lakers"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Frank Vogel n&#039;est plus l\u2019entra\u00eeneur des Los Angeles Lakers<\/title>\n<meta name=\"description\" content=\"NBA 2021-2022 - Le coach des Lakers, Frank Vogel, est la premi\u00e8re t\u00eate \u00e0 tomber, victime des r\u00e9sultats pr\u00e9caires de son \u00e9quipe.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/frank-vogel-nest-plus-lentraineur-des-los-angeles-lakers\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frank Vogel n&#039;est plus l\u2019entra\u00eeneur des Los Angeles Lakers\" \/>\n<meta property=\"og:description\" content=\"NBA 2021-2022 - Le coach des Lakers, Frank Vogel, est la premi\u00e8re t\u00eate \u00e0 tomber, victime des r\u00e9sultats pr\u00e9caires de son \u00e9quipe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/frank-vogel-nest-plus-lentraineur-des-los-angeles-lakers\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-11T08:42:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-11T13:17:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Frank-Vogel-nest-plus-lentraineur-des-Los-Angeles-Lakers.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mathieu Veillon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Frank Vogel n&#039;est plus l\u2019entra\u00eeneur des Los Angeles Lakers\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/MathieuVeillon\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/frank-vogel-nest-plus-lentraineur-des-los-angeles-lakers\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/frank-vogel-nest-plus-lentraineur-des-los-angeles-lakers\\\/\"},\"author\":{\"name\":\"Mathieu Veillon\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/9731cdc747db1ceb457a2bfa9180a806\"},\"headline\":\"Frank Vogel n&rsquo;est plus l\u2019entra\u00eeneur des Los Angeles Lakers\",\"datePublished\":\"2022-04-11T08:42:39+00:00\",\"dateModified\":\"2022-04-11T13:17:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/frank-vogel-nest-plus-lentraineur-des-los-angeles-lakers\\\/\"},\"wordCount\":237,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/frank-vogel-nest-plus-lentraineur-des-los-angeles-lakers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Frank-Vogel-nest-plus-lentraineur-des-Los-Angeles-Lakers.png\",\"keywords\":[\"Los Angeles Lakers\"],\"articleSection\":[\"NBA\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/frank-vogel-nest-plus-lentraineur-des-los-angeles-lakers\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/frank-vogel-nest-plus-lentraineur-des-los-angeles-lakers\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/frank-vogel-nest-plus-lentraineur-des-los-angeles-lakers\\\/\",\"name\":\"Frank Vogel n'est plus l\u2019entra\u00eeneur des Los Angeles Lakers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/frank-vogel-nest-plus-lentraineur-des-los-angeles-lakers\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/frank-vogel-nest-plus-lentraineur-des-los-angeles-lakers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Frank-Vogel-nest-plus-lentraineur-des-Los-Angeles-Lakers.png\",\"datePublished\":\"2022-04-11T08:42:39+00:00\",\"dateModified\":\"2022-04-11T13:17:19+00:00\",\"description\":\"NBA 2021-2022 - Le coach des Lakers, Frank Vogel, est la premi\u00e8re t\u00eate \u00e0 tomber, victime des r\u00e9sultats pr\u00e9caires de son \u00e9quipe.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/frank-vogel-nest-plus-lentraineur-des-los-angeles-lakers\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/frank-vogel-nest-plus-lentraineur-des-los-angeles-lakers\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/frank-vogel-nest-plus-lentraineur-des-los-angeles-lakers\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Frank-Vogel-nest-plus-lentraineur-des-Los-Angeles-Lakers.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Frank-Vogel-nest-plus-lentraineur-des-Los-Angeles-Lakers.png\",\"width\":800,\"height\":445,\"caption\":\"Frank Vogel n'est plus l\u2019entra\u00eeneur des Los Angeles Lakers\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/frank-vogel-nest-plus-lentraineur-des-los-angeles-lakers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frank Vogel n&rsquo;est plus l\u2019entra\u00eeneur des Los Angeles Lakers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/9731cdc747db1ceb457a2bfa9180a806\",\"name\":\"Mathieu Veillon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Mathieu-Veillon-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Mathieu-Veillon-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Mathieu-Veillon-150x150.jpg\",\"caption\":\"Mathieu Veillon\"},\"description\":\"Journaliste\\\/r\u00e9dacteur depuis septembre 2015 - Ma d\u00e9finition du bonheur ? Une galette-saucisse au Roazhon Park ou un caf\u00e9 devant un Lakers\\\/Celtics au petit matin. Fid\u00e8le membre de la team insomniaque de la r\u00e9dac, j\u2019ai le pouvoir de rester \u00e9veill\u00e9 jusqu\u2019\u00e0 l\u2019aube pour faire vivre aux lecteurs ma passion du sport. Ainsi, j\u2019\u00e9cris principalement sur la NBA, le biathlon, le cyclisme ou encore la F1. Comptez dans mes exploits sportifs le fait d\u2019avoir fait gagner le Tour de France 2018 \u00e0 Tony Gallopin sur Pro Cycling Manager, ou encore d\u2019avoir men\u00e9 l\u2019\u00e9quipe nationale de Bretagne en finale de Coupe du monde sur Football Manager.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/MathieuVeillon\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/mathieu\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Frank Vogel n'est plus l\u2019entra\u00eeneur des Los Angeles Lakers","description":"NBA 2021-2022 - Le coach des Lakers, Frank Vogel, est la premi\u00e8re t\u00eate \u00e0 tomber, victime des r\u00e9sultats pr\u00e9caires de son \u00e9quipe.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/frank-vogel-nest-plus-lentraineur-des-los-angeles-lakers\/","og_locale":"fr_FR","og_type":"article","og_title":"Frank Vogel n'est plus l\u2019entra\u00eeneur des Los Angeles Lakers","og_description":"NBA 2021-2022 - Le coach des Lakers, Frank Vogel, est la premi\u00e8re t\u00eate \u00e0 tomber, victime des r\u00e9sultats pr\u00e9caires de son \u00e9quipe.","og_url":"https:\/\/dicodusport.fr\/blog\/frank-vogel-nest-plus-lentraineur-des-los-angeles-lakers\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2022-04-11T08:42:39+00:00","article_modified_time":"2022-04-11T13:17:19+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Frank-Vogel-nest-plus-lentraineur-des-Los-Angeles-Lakers.png","type":"image\/png"}],"author":"Mathieu Veillon","twitter_card":"summary_large_image","twitter_title":"Frank Vogel n'est plus l\u2019entra\u00eeneur des Los Angeles Lakers","twitter_creator":"@https:\/\/twitter.com\/MathieuVeillon","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/frank-vogel-nest-plus-lentraineur-des-los-angeles-lakers\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/frank-vogel-nest-plus-lentraineur-des-los-angeles-lakers\/"},"author":{"name":"Mathieu Veillon","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/9731cdc747db1ceb457a2bfa9180a806"},"headline":"Frank Vogel n&rsquo;est plus l\u2019entra\u00eeneur des Los Angeles Lakers","datePublished":"2022-04-11T08:42:39+00:00","dateModified":"2022-04-11T13:17:19+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/frank-vogel-nest-plus-lentraineur-des-los-angeles-lakers\/"},"wordCount":237,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/frank-vogel-nest-plus-lentraineur-des-los-angeles-lakers\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Frank-Vogel-nest-plus-lentraineur-des-Los-Angeles-Lakers.png","keywords":["Los Angeles Lakers"],"articleSection":["NBA"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/frank-vogel-nest-plus-lentraineur-des-los-angeles-lakers\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/frank-vogel-nest-plus-lentraineur-des-los-angeles-lakers\/","url":"https:\/\/dicodusport.fr\/blog\/frank-vogel-nest-plus-lentraineur-des-los-angeles-lakers\/","name":"Frank Vogel n'est plus l\u2019entra\u00eeneur des Los Angeles Lakers","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/frank-vogel-nest-plus-lentraineur-des-los-angeles-lakers\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/frank-vogel-nest-plus-lentraineur-des-los-angeles-lakers\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Frank-Vogel-nest-plus-lentraineur-des-Los-Angeles-Lakers.png","datePublished":"2022-04-11T08:42:39+00:00","dateModified":"2022-04-11T13:17:19+00:00","description":"NBA 2021-2022 - Le coach des Lakers, Frank Vogel, est la premi\u00e8re t\u00eate \u00e0 tomber, victime des r\u00e9sultats pr\u00e9caires de son \u00e9quipe.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/frank-vogel-nest-plus-lentraineur-des-los-angeles-lakers\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/frank-vogel-nest-plus-lentraineur-des-los-angeles-lakers\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/frank-vogel-nest-plus-lentraineur-des-los-angeles-lakers\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Frank-Vogel-nest-plus-lentraineur-des-Los-Angeles-Lakers.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Frank-Vogel-nest-plus-lentraineur-des-Los-Angeles-Lakers.png","width":800,"height":445,"caption":"Frank Vogel n'est plus l\u2019entra\u00eeneur des Los Angeles Lakers"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/frank-vogel-nest-plus-lentraineur-des-los-angeles-lakers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Frank Vogel n&rsquo;est plus l\u2019entra\u00eeneur des Los Angeles Lakers"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/9731cdc747db1ceb457a2bfa9180a806","name":"Mathieu Veillon","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Mathieu-Veillon-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Mathieu-Veillon-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Mathieu-Veillon-150x150.jpg","caption":"Mathieu Veillon"},"description":"Journaliste\/r\u00e9dacteur depuis septembre 2015 - Ma d\u00e9finition du bonheur ? Une galette-saucisse au Roazhon Park ou un caf\u00e9 devant un Lakers\/Celtics au petit matin. Fid\u00e8le membre de la team insomniaque de la r\u00e9dac, j\u2019ai le pouvoir de rester \u00e9veill\u00e9 jusqu\u2019\u00e0 l\u2019aube pour faire vivre aux lecteurs ma passion du sport. Ainsi, j\u2019\u00e9cris principalement sur la NBA, le biathlon, le cyclisme ou encore la F1. Comptez dans mes exploits sportifs le fait d\u2019avoir fait gagner le Tour de France 2018 \u00e0 Tony Gallopin sur Pro Cycling Manager, ou encore d\u2019avoir men\u00e9 l\u2019\u00e9quipe nationale de Bretagne en finale de Coupe du monde sur Football Manager.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/MathieuVeillon"],"url":"https:\/\/dicodusport.fr\/blog\/author\/mathieu\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/215244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=215244"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/215244\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/215254"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=215244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=215244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=215244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}