{"id":218218,"date":"2022-04-24T09:13:34","date_gmt":"2022-04-24T07:13:34","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=218218&#038;preview=true&#038;preview_id=218218"},"modified":"2022-04-24T18:04:20","modified_gmt":"2022-04-24T16:04:20","slug":"top-14-notes-toulon-toulouse","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/top-14-notes-toulon-toulouse\/","title":{"rendered":"Top 14 : Les notes de Toulon &#8211; Toulouse"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/rugby\/rugby-a-xv\/top-14-2021-2022\/\">TOP 14 2021-2022<\/a> &#8211; Samedi soir, <a href=\"https:\/\/dicodusport.fr\/blog\/top-14-toulon-simpose-dans-la-douleur-face-au-stade-toulousain\/\">le RC Toulon est venu \u00e0 bout de Toulouse<\/a> au stade V\u00e9lodrome (19-15), lors de la 23\u00e8me journ\u00e9e de Top 14. D\u00e9couvrez les notes de ceux qui ont brill\u00e9, ou d\u00e9\u00e7u.<\/em><\/strong><\/p>\n<h2 style=\"text-align: justify;\">Les notes du RC Toulon<\/h2>\n<h3><strong>Ils ont brill\u00e9<\/strong><\/h3>\n<p style=\"text-align: justify;\"><strong>Gabin Villi\u00e8re &#8211; 8,5<\/strong><\/p>\n<p style=\"text-align: justify;\">Le + : Un essai d&rsquo;\u00e9quilibriste le long de la ligne de touche (71&prime;) o\u00f9 il se joue de la d\u00e9fense toulousaine \u00e0 merveille. 6 d\u00e9fenseurs battus sur ce match, avec en prime, 102 m\u00e8tres parcourus avec le ballon. D\u00e9fensivement, il a \u00e9t\u00e9 des plus solides, avec 5 plaquages r\u00e9ussis mais surtout, 2 ballons gratt\u00e9s.<\/p>\n<p style=\"text-align: justify;\">Le &#8211; : &#8211;<\/p>\n<p style=\"text-align: justify;\">En bref : Match XXL de la part de l&rsquo;ailier international.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Pouah Gabin Villi\u00e8re est INJOUABLE <a href=\"https:\/\/t.co\/5CFvN3ESwc\">pic.twitter.com\/5CFvN3ESwc<\/a><\/p>\n<p>\u2014 Gauthier Baudin (@GauthierBaudin) <a href=\"https:\/\/twitter.com\/GauthierBaudin\/status\/1517969955995664387?ref_src=twsrc%5Etfw\">April 23, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\"><strong>Charles Ollivon &#8211; 7<\/strong><\/p>\n<p style=\"text-align: justify;\">Le + : Pr\u00e8s de 40 m\u00e8tres gagn\u00e9s avec le ballon sur ce match, d\u00e9montrant une grosse envie et surtout, un retour en forme qui se confirme. D\u00e9fensivement, il n&rsquo;a pas donn\u00e9 sa part au chien, avec un 12\/13 au plaquage, en plus d&rsquo;un ballon r\u00e9cup\u00e9r\u00e9.<\/p>\n<p style=\"text-align: justify;\">Le &#8211; : Baisse de r\u00e9gime au retour des vestiaires.<\/p>\n<p style=\"text-align: justify;\">En bref : Ollivon est bien de retour au premier plan, et tant mieux pour Toulon !<\/p>\n<p style=\"text-align: justify;\"><strong>Louis Carbonel &#8211; 7<\/strong><\/p>\n<p style=\"text-align: justify;\">Le + : S&rsquo;il loupe un drop en d\u00e9but de match, il a ensuite fait un sans-faute face aux perches, et pas toujours dans des positions faciles (4\/4). D\u00e9cisif sur l&rsquo;essai de Villi\u00e8re (71&prime;), avec une feinte de jeu au pied et une parfaite lecture du jeu. D\u00e9fensivement, il a \u00e9galement fait son match, avec un 7\/7 au plaquage.<\/p>\n<p style=\"text-align: justify;\">Le &#8211; : Son drop loup\u00e9, en face des poteaux.<\/p>\n<p style=\"text-align: justify;\">En bref : Carbonel termine cette saison r\u00e9guli\u00e8re en taille patron, et l\u00e0 encore, c&rsquo;est tout bon pour le RCT.<\/p>\n<h3><strong>Ils ont d\u00e9\u00e7u<\/strong><\/h3>\n<p style=\"text-align: justify;\"><strong>Cornell Du Preez &#8211; 4,5<\/strong><\/p>\n<p style=\"text-align: justify;\">Le + : Solide d\u00e9fensivement (9\/9).<\/p>\n<p style=\"text-align: justify;\">Le &#8211; : Autrement, son match est beaucoup plus difficile. P\u00e9nalis\u00e9 \u00e0 deux reprises pour des hors-jeux, il n&rsquo;a pas eu d&rsquo;impact dans le jeu d&rsquo;attaque toulonnais (5 ballons touch\u00e9s pour aucun gain de terrain), manquant cruellement de mobilit\u00e9.<\/p>\n<p style=\"text-align: justify;\">En bref : Sur courant (trop) alternatif.<\/p>\n<p style=\"text-align: justify;\"><strong>Duncan Paia&rsquo;aua &#8211; 3,5<\/strong><\/p>\n<p style=\"text-align: justify;\">Le + : &#8211;<\/p>\n<p style=\"text-align: justify;\">Le &#8211; : Beaucoup de d\u00e9chet d\u00e9fensivement (4 plaquages manqu\u00e9s sur 13 tent\u00e9s). Il a souffert face \u00e0 ses adversaires au centre du terrain, et notamment Pierre Fouyssac. Offensivement, il n&rsquo;a rien apport\u00e9, malgr\u00e9 6 munitions int\u00e9ressantes.<\/p>\n<p style=\"text-align: justify;\">En bref : Un match rat\u00e9 pour le centre australien, n\u00e9 en Nouvelle-Z\u00e9lande.<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/dicodusport.fr\/blog\/top-14-notes-toulon-toulouse\/2\/#notestoulouse\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#0057ae;border-color:#00468c;border-radius:4px\" target=\"_self\"><span style=\"color:#FFFFFF;padding:0px 26px;font-size:20px;line-height:40px;border-color:#4d8ac7;border-radius:4px;text-shadow:none\"> Les notes du Stade Toulousain<\/span><\/a>\n<p style=\"text-align: justify;\"><!--nextpage--><a id=\"notestoulouse\"><\/a><strong><em>TOP 14 2021-2022 &#8211; Samedi soir, le RC Toulon est venu \u00e0 bout de Toulouse au stade V\u00e9lodrome (19-15), lors de la 23\u00e8me journ\u00e9e de Top 14. D\u00e9couvrez les notes de ceux qui ont brill\u00e9, ou d\u00e9\u00e7u.<\/em><\/strong><\/p>\n<h2 style=\"text-align: justify;\">Les notes du Stade Toulousain<\/h2>\n<h3><strong>Ils ont brill\u00e9<\/strong><\/h3>\n<p style=\"text-align: justify;\"><strong>Thomas Ramos &#8211; 7,5<\/strong><\/p>\n<p style=\"text-align: justify;\">Le + : Son drop plein de sang-froid (11&prime;). Son jeu au pied a fait \u00e9norm\u00e9ment de bien aux siens, tout au long du match, avec une occupation de qualit\u00e9, symbolis\u00e9e par une 50-22 trouv\u00e9e en premi\u00e8re p\u00e9riode. Offensivement, il a bien anim\u00e9 le jeu toulousain. Un sans-faute d\u00e9fensivement (7\/7).<\/p>\n<p style=\"text-align: justify;\">Le &#8211; : Cette p\u00e9nalit\u00e9 manqu\u00e9e (69&prime;), deux minutes avant l&rsquo;essai, qui aurait pu faire basculer le match en faveur des Stadistes.<\/p>\n<p style=\"text-align: justify;\">En bref : En l&rsquo;absence de Dupont et Ntamack, il est le taulier de cette \u00e9quipe dans la ligne de trois-quarts.<\/p>\n<p style=\"text-align: justify;\"><strong>Emmanuel Meafou &#8211; 7,5<\/strong><\/p>\n<p style=\"text-align: justify;\">Le + : Un vrai colosse ! 24 m\u00e8tres avec le ballon, \u00e0 chaque fois dans l&rsquo;avanc\u00e9e dans le jeu au ras. D\u00e9fensivement, il a \u00e9t\u00e9 un vrai poison pour les Varois, avec trois ballons gratt\u00e9s et un sans-faute au plaquage (7\/7).<\/p>\n<p style=\"text-align: justify;\">Le &#8211; : P\u00e9nalis\u00e9 une fois.<\/p>\n<p style=\"text-align: justify;\">En bref : Le pr\u00e9sent et le futur du Stade Toulousain en deuxi\u00e8me ligne.<\/p>\n<p style=\"text-align: justify;\"><strong>Julien Marchand &#8211; 7<\/strong><\/p>\n<p style=\"text-align: justify;\">Le + : De retour sur le pr\u00e9 apr\u00e8s une blessure au mollet, il a r\u00e9gn\u00e9, comme \u00e0 son habitude, dans le jeu au sol, avec trois ballons gratt\u00e9s. Mais outre ses qualit\u00e9s dans les rucks, il a aussi montr\u00e9 tout son punch, avec 30 m\u00e8tres parcourus ballon en mains.<\/p>\n<p style=\"text-align: justify;\">Le &#8211; : Trois ballons perdus sur ses lancers en touche.<\/p>\n<p style=\"text-align: justify;\">En bref : Un retour tr\u00e8s rassurant pour les Stadistes.<\/p>\n<h3><strong>Ils ont d\u00e9\u00e7u<\/strong><\/h3>\n<p style=\"text-align: justify;\"><strong>Baptiste Germain &#8211; 4<\/strong><\/p>\n<p style=\"text-align: justify;\">Le + : Un ballon gratt\u00e9.<\/p>\n<p style=\"text-align: justify;\">Le &#8211; : P\u00e9nalis\u00e9 \u00e0 trois reprises, il a \u00e9t\u00e9 en difficult\u00e9 sur certaines s\u00e9quences, et notamment dans le camp varois, o\u00f9 il a effectu\u00e9 quelques mauvais choix dans le sens du jeu. En d\u00e9fense, hormis son ballon vol\u00e9, il a souffert, avec deux plaquages manqu\u00e9s.<\/p>\n<p style=\"text-align: justify;\">En bref : Un match finalement tr\u00e8s moyen, malgr\u00e9 de bonnes intentions.<\/p>\n<p style=\"text-align: justify;\"><strong>Anthony Jelonch &#8211; 4<\/strong><\/p>\n<p style=\"text-align: justify;\">Le + : Un match solide en d\u00e9fense (9\/10 au plaquage), mais en trompe-l&rsquo;\u0153il.<\/p>\n<p style=\"text-align: justify;\">Le &#8211; : En revanche, dans le jeu courant, il a souffert, avec aucun apport offensif, ne touchant pas un ballon d&rsquo;attaque. On l&rsquo;a vu aussi \u00eatre en difficult\u00e9 dans les duels, se faisant mettre sur les fesses par deux fois par un certain Gabin Villi\u00e8re.<\/p>\n<p style=\"text-align: justify;\">En bref : Un coup de mou pour le troisi\u00e8me ligne du XV de France ?<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/dicodusport.fr\/blog\/top-14-notes-toulon-toulouse\/\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#0057ae;border-color:#00468c;border-radius:4px\" target=\"_self\"><span style=\"color:#FFFFFF;padding:0px 26px;font-size:20px;line-height:40px;border-color:#4d8ac7;border-radius:4px;text-shadow:none\"> Revenir aux notes du RC Toulon<\/span><\/a>\n<h2><strong>\u00c0 lire aussi<\/strong><\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/23eme-journee-top-14-programme-et-resultats\/\"><strong>Programme et r\u00e9sultats de la 23\u00e8me journ\u00e9e de Top 14<\/strong><\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/top-14-2021-2022-le-classement-complet\/\"><strong>Classement du Top 14<\/strong><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>TOP 14 2021-2022 &#8211; Samedi soir, le RC Toulon est venu \u00e0 bout de Toulouse au stade V\u00e9lodrome (19-15), lors de la 23\u00e8me journ\u00e9e de Top 14. D\u00e9couvrez les notes de ceux qui ont brill\u00e9, ou d\u00e9\u00e7u.<\/p>\n","protected":false},"author":4,"featured_media":218295,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[47050],"tags":[3078,4008,111,463],"class_list":["post-218218","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-top-14","tag-rc-toulon","tag-stade-toulousain","tag-top-14","tag-toulouse"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Top 14 : Les notes de Toulon - Toulouse<\/title>\n<meta name=\"description\" content=\"TOP 14 2021-2022 - Samedi soir, le RC Toulon est venu \u00e0 bout de Toulouse au stade V\u00e9lodrome (19-15). Les notes du match.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/top-14-notes-toulon-toulouse\/\" \/>\n<link rel=\"next\" href=\"https:\/\/dicodusport.fr\/blog\/top-14-notes-toulon-toulouse\/2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Top 14 : Les notes de Toulon - Toulouse\" \/>\n<meta property=\"og:description\" content=\"TOP 14 2021-2022 - Samedi soir, le RC Toulon est venu \u00e0 bout de Toulouse au stade V\u00e9lodrome (19-15). Les notes du match.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/top-14-notes-toulon-toulouse\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-24T07:13:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-24T16:04:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Top-14-Les-notes-de-Toulon-Toulouse.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Top 14 : Les notes de Toulon - Toulouse\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-notes-toulon-toulouse\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-notes-toulon-toulouse\\\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Top 14 : Les notes de Toulon &#8211; Toulouse\",\"datePublished\":\"2022-04-24T07:13:34+00:00\",\"dateModified\":\"2022-04-24T16:04:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-notes-toulon-toulouse\\\/\"},\"wordCount\":925,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-notes-toulon-toulouse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Top-14-Les-notes-de-Toulon-Toulouse.png\",\"keywords\":[\"RC Toulon\",\"Stade Toulousain\",\"Top 14\",\"Toulouse\"],\"articleSection\":[\"Top 14\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-notes-toulon-toulouse\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-notes-toulon-toulouse\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-notes-toulon-toulouse\\\/\",\"name\":\"Top 14 : Les notes de Toulon - Toulouse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-notes-toulon-toulouse\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-notes-toulon-toulouse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Top-14-Les-notes-de-Toulon-Toulouse.png\",\"datePublished\":\"2022-04-24T07:13:34+00:00\",\"dateModified\":\"2022-04-24T16:04:20+00:00\",\"description\":\"TOP 14 2021-2022 - Samedi soir, le RC Toulon est venu \u00e0 bout de Toulouse au stade V\u00e9lodrome (19-15). Les notes du match.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-notes-toulon-toulouse\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/top-14-notes-toulon-toulouse\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Top-14-Les-notes-de-Toulon-Toulouse.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Top-14-Les-notes-de-Toulon-Toulouse.png\",\"width\":800,\"height\":445,\"caption\":\"Top 14 Les notes de Toulon - Toulouse\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Flo-Ostermann-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\\\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/florent.ostermann\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/FlOstermann\",\"admin\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/flo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Top 14 : Les notes de Toulon - Toulouse","description":"TOP 14 2021-2022 - Samedi soir, le RC Toulon est venu \u00e0 bout de Toulouse au stade V\u00e9lodrome (19-15). Les notes du match.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/top-14-notes-toulon-toulouse\/","next":"https:\/\/dicodusport.fr\/blog\/top-14-notes-toulon-toulouse\/2\/","og_locale":"fr_FR","og_type":"article","og_title":"Top 14 : Les notes de Toulon - Toulouse","og_description":"TOP 14 2021-2022 - Samedi soir, le RC Toulon est venu \u00e0 bout de Toulouse au stade V\u00e9lodrome (19-15). Les notes du match.","og_url":"https:\/\/dicodusport.fr\/blog\/top-14-notes-toulon-toulouse\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2022-04-24T07:13:34+00:00","article_modified_time":"2022-04-24T16:04:20+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Top-14-Les-notes-de-Toulon-Toulouse.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Top 14 : Les notes de Toulon - Toulouse","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/top-14-notes-toulon-toulouse\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-notes-toulon-toulouse\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Top 14 : Les notes de Toulon &#8211; Toulouse","datePublished":"2022-04-24T07:13:34+00:00","dateModified":"2022-04-24T16:04:20+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-notes-toulon-toulouse\/"},"wordCount":925,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-notes-toulon-toulouse\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Top-14-Les-notes-de-Toulon-Toulouse.png","keywords":["RC Toulon","Stade Toulousain","Top 14","Toulouse"],"articleSection":["Top 14"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/top-14-notes-toulon-toulouse\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/top-14-notes-toulon-toulouse\/","url":"https:\/\/dicodusport.fr\/blog\/top-14-notes-toulon-toulouse\/","name":"Top 14 : Les notes de Toulon - Toulouse","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-notes-toulon-toulouse\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-notes-toulon-toulouse\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Top-14-Les-notes-de-Toulon-Toulouse.png","datePublished":"2022-04-24T07:13:34+00:00","dateModified":"2022-04-24T16:04:20+00:00","description":"TOP 14 2021-2022 - Samedi soir, le RC Toulon est venu \u00e0 bout de Toulouse au stade V\u00e9lodrome (19-15). Les notes du match.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/top-14-notes-toulon-toulouse\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/top-14-notes-toulon-toulouse\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Top-14-Les-notes-de-Toulon-Toulouse.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Top-14-Les-notes-de-Toulon-Toulouse.png","width":800,"height":445,"caption":"Top 14 Les notes de Toulon - Toulouse"},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/218218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=218218"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/218218\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/218295"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=218218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=218218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=218218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}