{"id":219328,"date":"2022-07-14T21:03:56","date_gmt":"2022-07-14T19:03:56","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=219328&#038;preview=true&#038;preview_id=219328"},"modified":"2022-07-15T21:02:15","modified_gmt":"2022-07-15T19:02:15","slug":"tour-de-france-2022-parcours-et-profil-14eme-etape","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-parcours-et-profil-14eme-etape\/","title":{"rendered":"Tour de France 2022 \u2013 Parcours et profil de la 14\u00e8me \u00e9tape"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/cyclisme\/cyclisme-sur-route-2022\/tour-de-france-2022\/\">TOUR DE FRANCE 2022<\/a> &#8211; La 14\u00e8me \u00e9tape entre Saint-\u00c9tienne et Mende de ce samedi 16 juillet sera une \u00e9tape vallonn\u00e9e, avec la C\u00f4te de la Croix-Neuve en juge de paix. Elle sera longue de 192,5 km. Parcours et profil.<\/strong><\/em><\/p>\n<h2 style=\"text-align: justify;\"><strong>Le parcours de la 14\u00e8me \u00e9tape du Tour de France 2022<\/strong><\/h2>\n<p style=\"text-align: justify;\">D&rsquo;abord, les coureurs s&rsquo;\u00e9lanceront depuis <strong>Saint-\u00c9tienne<\/strong>, au pied du stade Geoffroy-Guichard. Apr\u00e8s \u00eatre descendus sur Firminy, les coureurs feront face \u00e0 la premi\u00e8re difficult\u00e9 du jour : la <strong>C\u00f4te Saint-Just-Malmont<\/strong> (7,7 km \u00e0 3,9 %, class\u00e9e en troisi\u00e8me cat\u00e9gorie avec d\u00e8s son pied, des pentes \u00e0 pr\u00e8s de 7 %. Pas de descente au sommet, puisque les coureurs resteront sur un plateau en montagnes russes sur pr\u00e8s de 50 kilom\u00e8tres pour rejoindre\u00a0 <strong>Rosi\u00e8res <\/strong>avec l&rsquo;ascension de la <strong>C\u00f4te des Ch\u00e2taigniers<\/strong> (3,4 km \u00e0 5,7 % avec un passage \u00e0 10 % apr\u00e8s un kilom\u00e8tre d&rsquo;ascension).<\/p>\n<p style=\"text-align: justify;\">Ensuite, apr\u00e8s une portion en vall\u00e9e de 20 kilom\u00e8tres pour rejoindre <strong>Le-Puy-en-Velay<\/strong>, place \u00e0 un long faux-plat montant de pr\u00e8s de 25 kilom\u00e8tres afin d&rsquo;atteindre <strong>Le Bouchet-Saint-Nicolas<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Puis, apr\u00e8s \u00eatre descendus sur le Nouveau Monde et \u00eatre entr\u00e9s dans le d\u00e9partement de la Loz\u00e8re, les concurrents grimperont la <strong>C\u00f4te de Grandrieu<\/strong> (6,3 km \u00e0 4,1 %, class\u00e9e en troisi\u00e8me cat\u00e9gorie). Un nouvel fois, apr\u00e8s le sommet, il n&rsquo;y aura pas de descente pour rester sur des routes majoritairement montantes avant de s&rsquo;attaquer \u00e0 la <strong>C\u00f4te de la Fage<\/strong> (4,2 km \u00e0 6 %). Cette ascension sera r\u00e9guli\u00e8re avec des rampes entre 5 et 7 % et un replat sur les 800 derniers m\u00e8tres. Par la suite, les coureurs rejoindront Mende par une longue descente de pr\u00e8s de 20 kilom\u00e8tres.<\/p>\n<h3 style=\"text-align: justify;\"><strong>La C\u00f4te de la Croix-Neuve en juge de paix<\/strong><\/h3>\n<p style=\"text-align: justify;\">Apr\u00e8s avoir travers\u00e9 la pr\u00e9fecture du d\u00e9partement de la Loz\u00e8re, place \u00e0 la derni\u00e8re ascension avec la <strong>C\u00f4te de la Croix-Neuve Mont\u00e9e Laurent Jalabert<\/strong> &#8211; 3 km \u00e0 10,2 % -, sur la route permettant de rejoindre le Mont Mimat qui surplombe la ville de Mende. Cette mont\u00e9e porte le nom du coureur fran\u00e7ais en comm\u00e9moration de sa victoire sur la douzi\u00e8me \u00e9tape du Tour de France 1995, apr\u00e8s 198 km d\u2019\u00e9chapp\u00e9e. L&rsquo;ascension d\u00e9butera sur la Rues* des \u00c9coles avec des rampes \u00e0 plus de 8 % avec un petit pif paf dans un passage \u00e9troit.<\/p>\n<p style=\"text-align: justify;\">Les pourcentages s&rsquo;accentueront sur une route rectilignes pour p\u00e9n\u00e9trer dans une zone plus ombrag\u00e9e. Cette partie, dans les arbres, sera la plus dure avec trois lacets sur une route comprenant des pentes \u00e0 12 % sur un kilom\u00e8tre. La route redeviendra plus rectiligne pour le dernier kilom\u00e8tre avec une pente passant progressivement de 10 \u00e0 6 %. Cette difficile mont\u00e9e permettra de faire la diff\u00e9rence entre les baroudeurs et entre les pr\u00e9tendants au classement g\u00e9n\u00e9ral. Enfin, apr\u00e8s une courte descente, l&rsquo;arriv\u00e9e aura lieu sur l&rsquo;A\u00e9rodrome de Mende &#8211; Brenoux au bout d&rsquo;une <span class=\"tojvnm2t a6sixzi8 abs2jz4q a8s20v7p t1p8iaqh k5wvi7nf q3lfd5jv pk4s997a bipmatt0 cebpdrjk qowsmv63 owwhemhu dp1hu0rb dhp61c6y iyyx5f41\">ligne droite de 470 m\u00e8tres<\/span>.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/oJpwtB12-mo\" width=\"560\" height=\"314\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<h2 style=\"text-align: justify;\"><strong>La carte du parcours de la 14\u00e8me \u00e9tape du Tour de France 2022<\/strong><\/h2>\n<div id=\"attachment_243294\" style=\"width: 734px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/La-carte-du-parcours-de-la-14eme-etape-du-Tour-de-France-2022.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-243294\" class=\"size-large wp-image-243294\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/La-carte-du-parcours-de-la-14eme-etape-du-Tour-de-France-2022-724x1024.jpg\" alt=\"La carte du parcours de la 14\u00e8me \u00e9tape du Tour de France 2022\" width=\"724\" height=\"1024\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/La-carte-du-parcours-de-la-14eme-etape-du-Tour-de-France-2022-724x1024.jpg 724w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/La-carte-du-parcours-de-la-14eme-etape-du-Tour-de-France-2022-212x300.jpg 212w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/La-carte-du-parcours-de-la-14eme-etape-du-Tour-de-France-2022-768x1086.jpg 768w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/La-carte-du-parcours-de-la-14eme-etape-du-Tour-de-France-2022.jpg 960w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><\/a><p id=\"caption-attachment-243294\" class=\"wp-caption-text\">La carte du parcours de la 14\u00e8me \u00e9tape du Tour de France 2022 &#8211; Via ASO<\/p><\/div>\n<h2 style=\"text-align: justify;\"><strong>Le profil de la 14\u00e8me \u00e9tape du Tour de France 2022<\/strong><\/h2>\n<div id=\"attachment_243295\" style=\"width: 970px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Le-profil-de-la-14eme-etape-du-Tour-de-France-2022.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-243295\" class=\"size-full wp-image-243295\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Le-profil-de-la-14eme-etape-du-Tour-de-France-2022.jpg\" alt=\"Le profil de la 14\u00e8me \u00e9tape du Tour de France 2022\" width=\"960\" height=\"579\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Le-profil-de-la-14eme-etape-du-Tour-de-France-2022.jpg 960w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Le-profil-de-la-14eme-etape-du-Tour-de-France-2022-300x181.jpg 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Le-profil-de-la-14eme-etape-du-Tour-de-France-2022-768x463.jpg 768w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Le-profil-de-la-14eme-etape-du-Tour-de-France-2022-400x240.jpg 400w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><p id=\"caption-attachment-243295\" class=\"wp-caption-text\">Le profil de la 14\u00e8me \u00e9tape du Tour de France 2022 &#8211; Via ASO<\/p><\/div>\n<h2 style=\"text-align: justify;\">\u00c0 lire aussi<\/h2>\n<ul>\n<li style=\"text-align: justify;\"><strong><a href=\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-nos-favoris-pour-la-14eme-etape\/\">Nos favoris pour la 14\u00e8me \u00e9tape<\/a>\u00a0<\/strong><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/classement-general-tour-de-france-2022-maillot-jaune\/\"><strong>Classement g\u00e9n\u00e9ral du Tour de France 2022<\/strong><\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-programme-et-vainqueurs-etape\/\"><b>Programme des \u00e9tapes du Tour de France 2022<\/b><\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/toute-lactualite-du-tour-de-france-2022\/\"><strong>Toute l\u2019actualit\u00e9 du Tour de France 2022<\/strong><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>TOUR DE FRANCE 2022 &#8211; La 14\u00e8me \u00e9tape entre Saint-\u00c9tienne et Mende de ce samedi 16 juillet sera une \u00e9tape vallonn\u00e9e, avec la C\u00f4te de la Croix-Neuve en juge de paix. Elle sera longue de 192,5 km. Parcours et profil.<\/p>\n","protected":false},"author":48,"featured_media":243296,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[46995],"tags":[3119],"class_list":["post-219328","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tour-de-france","tag-actualite-cyclisme"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tour de France 2022 \u2013 Parcours et profil de la 14\u00e8me \u00e9tape<\/title>\n<meta name=\"description\" content=\"TOUR DE FRANCE 2022 - La 14\u00e8me \u00e9tape entre Saint-\u00c9tienne et Mende de ce samedi 16 juillet sera vallonn\u00e9e (192,5 km). Parcours et profil.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-parcours-et-profil-14eme-etape\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tour de France 2022 \u2013 Parcours et profil de la 14\u00e8me \u00e9tape\" \/>\n<meta property=\"og:description\" content=\"TOUR DE FRANCE 2022 - La 14\u00e8me \u00e9tape entre Saint-\u00c9tienne et Mende de ce samedi 16 juillet sera vallonn\u00e9e (192,5 km). Parcours et profil.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-parcours-et-profil-14eme-etape\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-14T19:03:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-15T19:02:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Tour-de-France-2022-\u2013-Parcours-et-profil-de-la-14eme-etape.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Emilien Descampiaux\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Tour de France 2022 \u2013 Parcours et profil de la 14\u00e8me \u00e9tape\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/LRoisDuPeloton\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-parcours-et-profil-14eme-etape\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-parcours-et-profil-14eme-etape\/\"},\"author\":{\"name\":\"Emilien Descampiaux\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7\"},\"headline\":\"Tour de France 2022 \u2013 Parcours et profil de la 14\u00e8me \u00e9tape\",\"datePublished\":\"2022-07-14T19:03:56+00:00\",\"dateModified\":\"2022-07-15T19:02:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-parcours-et-profil-14eme-etape\/\"},\"wordCount\":606,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-parcours-et-profil-14eme-etape\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Tour-de-France-2022-\u2013-Parcours-et-profil-de-la-14eme-etape.png\",\"keywords\":[\"Actualit\u00e9 Cyclisme\"],\"articleSection\":[\"Tour de France\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-parcours-et-profil-14eme-etape\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-parcours-et-profil-14eme-etape\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-parcours-et-profil-14eme-etape\/\",\"name\":\"Tour de France 2022 \u2013 Parcours et profil de la 14\u00e8me \u00e9tape\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-parcours-et-profil-14eme-etape\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-parcours-et-profil-14eme-etape\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Tour-de-France-2022-\u2013-Parcours-et-profil-de-la-14eme-etape.png\",\"datePublished\":\"2022-07-14T19:03:56+00:00\",\"dateModified\":\"2022-07-15T19:02:15+00:00\",\"description\":\"TOUR DE FRANCE 2022 - La 14\u00e8me \u00e9tape entre Saint-\u00c9tienne et Mende de ce samedi 16 juillet sera vallonn\u00e9e (192,5 km). Parcours et profil.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-parcours-et-profil-14eme-etape\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-parcours-et-profil-14eme-etape\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-parcours-et-profil-14eme-etape\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Tour-de-France-2022-\u2013-Parcours-et-profil-de-la-14eme-etape.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Tour-de-France-2022-\u2013-Parcours-et-profil-de-la-14eme-etape.png\",\"width\":800,\"height\":445,\"caption\":\"Tour de France 2022 \u2013 Parcours et profil de la 14\u00e8me \u00e9tape\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-parcours-et-profil-14eme-etape\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tour de France 2022 \u2013 Parcours et profil de la 14\u00e8me \u00e9tape\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7\",\"name\":\"Emilien Descampiaux\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg\",\"caption\":\"Emilien Descampiaux\"},\"description\":\"Journaliste\/r\u00e9dacteur depuis 2014 - Fan de la classe de Frank Vandenbroucke, je vis cyclisme (et de ses paysages) depuis plus de 20 ans. Je suis tr\u00e8s impliqu\u00e9 sur mes diff\u00e9rents r\u00e9seaux sociaux pour partager ma passion sur le monde et l'Histoire de la bicyclette avec ma voix sur les images en noir et blanc du succ\u00e8s de Rik Van Steenbergen lors du Ronde sur le V\u00e9lodrome de Gand.\",\"sameAs\":[\"https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton\",\"https:\/\/x.com\/https:\/\/twitter.com\/LRoisDuPeloton\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/emiliend\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tour de France 2022 \u2013 Parcours et profil de la 14\u00e8me \u00e9tape","description":"TOUR DE FRANCE 2022 - La 14\u00e8me \u00e9tape entre Saint-\u00c9tienne et Mende de ce samedi 16 juillet sera vallonn\u00e9e (192,5 km). Parcours et profil.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-parcours-et-profil-14eme-etape\/","og_locale":"fr_FR","og_type":"article","og_title":"Tour de France 2022 \u2013 Parcours et profil de la 14\u00e8me \u00e9tape","og_description":"TOUR DE FRANCE 2022 - La 14\u00e8me \u00e9tape entre Saint-\u00c9tienne et Mende de ce samedi 16 juillet sera vallonn\u00e9e (192,5 km). Parcours et profil.","og_url":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-parcours-et-profil-14eme-etape\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton","article_published_time":"2022-07-14T19:03:56+00:00","article_modified_time":"2022-07-15T19:02:15+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Tour-de-France-2022-\u2013-Parcours-et-profil-de-la-14eme-etape.png","type":"image\/png"}],"author":"Emilien Descampiaux","twitter_card":"summary_large_image","twitter_title":"Tour de France 2022 \u2013 Parcours et profil de la 14\u00e8me \u00e9tape","twitter_creator":"@https:\/\/twitter.com\/LRoisDuPeloton","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-parcours-et-profil-14eme-etape\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-parcours-et-profil-14eme-etape\/"},"author":{"name":"Emilien Descampiaux","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7"},"headline":"Tour de France 2022 \u2013 Parcours et profil de la 14\u00e8me \u00e9tape","datePublished":"2022-07-14T19:03:56+00:00","dateModified":"2022-07-15T19:02:15+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-parcours-et-profil-14eme-etape\/"},"wordCount":606,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-parcours-et-profil-14eme-etape\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Tour-de-France-2022-\u2013-Parcours-et-profil-de-la-14eme-etape.png","keywords":["Actualit\u00e9 Cyclisme"],"articleSection":["Tour de France"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-parcours-et-profil-14eme-etape\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-parcours-et-profil-14eme-etape\/","url":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-parcours-et-profil-14eme-etape\/","name":"Tour de France 2022 \u2013 Parcours et profil de la 14\u00e8me \u00e9tape","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-parcours-et-profil-14eme-etape\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-parcours-et-profil-14eme-etape\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Tour-de-France-2022-\u2013-Parcours-et-profil-de-la-14eme-etape.png","datePublished":"2022-07-14T19:03:56+00:00","dateModified":"2022-07-15T19:02:15+00:00","description":"TOUR DE FRANCE 2022 - La 14\u00e8me \u00e9tape entre Saint-\u00c9tienne et Mende de ce samedi 16 juillet sera vallonn\u00e9e (192,5 km). Parcours et profil.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-parcours-et-profil-14eme-etape\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-parcours-et-profil-14eme-etape\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-parcours-et-profil-14eme-etape\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Tour-de-France-2022-\u2013-Parcours-et-profil-de-la-14eme-etape.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/Tour-de-France-2022-\u2013-Parcours-et-profil-de-la-14eme-etape.png","width":800,"height":445,"caption":"Tour de France 2022 \u2013 Parcours et profil de la 14\u00e8me \u00e9tape"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-parcours-et-profil-14eme-etape\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Tour de France 2022 \u2013 Parcours et profil de la 14\u00e8me \u00e9tape"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7","name":"Emilien Descampiaux","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg","caption":"Emilien Descampiaux"},"description":"Journaliste\/r\u00e9dacteur depuis 2014 - Fan de la classe de Frank Vandenbroucke, je vis cyclisme (et de ses paysages) depuis plus de 20 ans. Je suis tr\u00e8s impliqu\u00e9 sur mes diff\u00e9rents r\u00e9seaux sociaux pour partager ma passion sur le monde et l'Histoire de la bicyclette avec ma voix sur les images en noir et blanc du succ\u00e8s de Rik Van Steenbergen lors du Ronde sur le V\u00e9lodrome de Gand.","sameAs":["https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton","https:\/\/x.com\/https:\/\/twitter.com\/LRoisDuPeloton"],"url":"https:\/\/dicodusport.fr\/blog\/author\/emiliend\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/219328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=219328"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/219328\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/243296"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=219328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=219328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=219328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}