{"id":222300,"date":"2022-05-09T09:24:07","date_gmt":"2022-05-09T07:24:07","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=222300"},"modified":"2022-05-09T19:34:36","modified_gmt":"2022-05-09T17:34:36","slug":"deaflympics-d-ete-2022-lor-pour-pamera-losange-et-marie-rivereau-en-athletisme","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/deaflympics-d-ete-2022-lor-pour-pamera-losange-et-marie-rivereau-en-athletisme\/","title":{"rendered":"Deaflympics d&rsquo;\u00e9t\u00e9 2022 : L&rsquo;or pour Pamera Losange et Marie Rivereau en athl\u00e9tisme"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>DEAFLYMPICS D&rsquo;\u00c9T\u00c9 2022 &#8211; Quelle incroyable journ\u00e9e pour les Fran\u00e7ais aux Deaflympics ! Steeve Touboul s&rsquo;en va sur une m\u00e9daille d&rsquo;argent et les \u00e9preuves d&rsquo;athl\u00e9tisme d\u00e9butent avec deux m\u00e9dailles d&rsquo;or.<\/strong><\/em><\/p>\n<h2 style=\"text-align: justify;\">L&rsquo;argent pour conclure une carri\u00e8re<\/h2>\n<p style=\"text-align: justify;\">Double champion deaflympic en une semaine, <strong>Steeve Touboul<\/strong> ne s&rsquo;est pas arr\u00eat\u00e9 en si bon chemin. Pour sa toute derni\u00e8re \u00e9preuve, le Biterrois, qui f\u00eatera ses 32 ans le 31 mai, a remport\u00e9 sa troisi\u00e8me m\u00e9daille \u00e0 Caxias do Sul. D\u00e9j\u00e0 m\u00e9daill\u00e9 \u00e0 trois reprises en 2009 (or et bronze par deux fois), il a cette fois d\u00e9croch\u00e9 le seul m\u00e9tal qui manquait \u00e0 son palmar\u00e8s : l&rsquo;argent lors de la course en ligne. Avec ses deux comp\u00e8res, ils ont apport\u00e9 six m\u00e9dailles \u00e0 la France.<\/p>\n<h2 style=\"text-align: justify;\">Nos athl\u00e8tes frappent fort<\/h2>\n<p style=\"text-align: justify;\">Pour les finales d&rsquo;athl\u00e9tisme, les Fran\u00e7aises ont frapp\u00e9 fort, tr\u00e8s fort ! Apr\u00e8s avoir outrageusement domin\u00e9 les s\u00e9ries du 100 m\u00e8tres f\u00e9minin, <strong>Pamera Losange<\/strong> se positionnait logiquement en tant que favorite pour la finale, il y avait de quoi. En signant un temps stratosph\u00e9rique de 11.68 sur la ligne droite, elle colle 57 centi\u00e8mes au deuxi\u00e8me meilleur temps. Bien \u00e9videmment, la jeune femme d&rsquo;\u00e0 peine 20 ans ne s&rsquo;est pas fait prier pour rafler la m\u00e9daille d&rsquo;or en finale. Quelques minutes plus tard, c&rsquo;est \u00e0 la perche qu&rsquo;on retrouve <strong>Marie Rivereau<\/strong>. Bien inspir\u00e9e par la performance de sa co\u00e9quipi\u00e8re, la perchiste s&rsquo;est envol\u00e9e \u00e0 4 m\u00e8tres de haut pour s&rsquo;offrir non seulement l&rsquo;or, mais un record du monde deaf !<\/p>\n<h2>Les footballeurs miracul\u00e9s<\/h2>\n<p style=\"text-align: justify;\">Pour parfaire cette journ\u00e9e splendide, l&rsquo;\u00e9quipe de foot s&rsquo;est qualifi\u00e9e en quarts de finale malgr\u00e9 des r\u00e9sultats en dents de scie. Dos \u00e0 dos (1-1) contre l&rsquo;Egypte, vaincus par l&rsquo;Ukraine (2-3), et victorieux au forceps contre l&rsquo;Argentine (1-0), les Bleus devaient battre la Cor\u00e9e du Sud avec 6 buts d&rsquo;\u00e9cart. Et ce fut un festival puisqu&rsquo;en menant 6-0 \u00e0 la mi-temps, les Fran\u00e7ais ont l\u00e2ch\u00e9 les chevaux pour s&rsquo;imposer 10-0. Au compteur, la France totalise 12 m\u00e9dailles dont 6 en or, meilleur r\u00e9sultat au 21\u00e8me si\u00e8cle, qui n&rsquo;est que provisoire.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">DEAFLYMPICS &#8211; ALERTE MEDAILLE &#x1f947;]\nMarie Rivereau suit les pas de Pamera Losange ce soir ! Avec un saut \u00e0 4m, l&rsquo;Angevine d\u00e9croche la m\u00e9daille d&rsquo;or et le record du monde Deaf !<br \/>\n&#x1f3c5; COMPTEUR MEDAILLE <a href=\"https:\/\/twitter.com\/hashtag\/FranceDeaflympics?src=hash&amp;ref_src=twsrc%5Etfw\">#FranceDeaflympics<\/a> : 12 M\u00e9dailles !<br \/>\n06&#x1f947; \/ 02&#x1f948; \/ 04&#x1f949;<a href=\"https:\/\/twitter.com\/FFHandisport?ref_src=twsrc%5Etfw\">@FFHandisport<\/a> <a href=\"https:\/\/t.co\/nr55OKNpwm\">pic.twitter.com\/nr55OKNpwm<\/a><\/p>\n<p>\u2014 France Deaflympics (@FRADeaflympics) <a href=\"https:\/\/twitter.com\/FRADeaflympics\/status\/1523416653874139136?ref_src=twsrc%5Etfw\">May 8, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DEAFLYMPICS D&rsquo;\u00c9T\u00c9 2022 &#8211; Quelle incroyable journ\u00e9e pour les Fran\u00e7ais aux Deaflympics ! Steeve Touboul s&rsquo;en va sur une m\u00e9daille d&rsquo;argent et les \u00e9preuves d&rsquo;athl\u00e9tisme d\u00e9butent avec deux m\u00e9dailles d&rsquo;or.<\/p>\n","protected":false},"author":43,"featured_media":222443,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2308,5753],"tags":[143,574,1265,24],"class_list":["post-222300","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-athletisme","category-handisport","tag-athletisme","tag-cyclisme","tag-handisport","tag-sport"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Deaflympics d&#039;\u00e9t\u00e9 2022 : L&#039;or pour Pamera Losange et Marie Rivereau en athl\u00e9tisme<\/title>\n<meta name=\"description\" content=\"DEAFLYMPIC D&#039;\u00c9T\u00c9 2022 - Doubl\u00e9 en or pour les Fran\u00e7aises en athl\u00e9tisme et nouvelle m\u00e9daille pour Steeve Touboul en cyclisme.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/deaflympics-d-ete-2022-lor-pour-pamera-losange-et-marie-rivereau-en-athletisme\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deaflympics d&#039;\u00e9t\u00e9 2022 : L&#039;or pour Pamera Losange et Marie Rivereau en athl\u00e9tisme\" \/>\n<meta property=\"og:description\" content=\"DEAFLYMPIC D&#039;\u00c9T\u00c9 2022 - Doubl\u00e9 en or pour les Fran\u00e7aises en athl\u00e9tisme et nouvelle m\u00e9daille pour Steeve Touboul en cyclisme.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/deaflympics-d-ete-2022-lor-pour-pamera-losange-et-marie-rivereau-en-athletisme\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Max.Bld2\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-09T07:24:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-09T17:34:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Deaflympics-dete-2022-Lor-pour-Pamera-Losange-et-Marie-Rivereau-en-athletisme-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Boulard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Deaflympics d&#039;\u00e9t\u00e9 2022 : L&#039;or pour Pamera Losange et Marie Rivereau en athl\u00e9tisme\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/MaximeB_2\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/deaflympics-d-ete-2022-lor-pour-pamera-losange-et-marie-rivereau-en-athletisme\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/deaflympics-d-ete-2022-lor-pour-pamera-losange-et-marie-rivereau-en-athletisme\/\"},\"author\":{\"name\":\"Maxime Boulard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/5aab10ee856e86ac63e9819a9da34784\"},\"headline\":\"Deaflympics d&rsquo;\u00e9t\u00e9 2022 : L&rsquo;or pour Pamera Losange et Marie Rivereau en athl\u00e9tisme\",\"datePublished\":\"2022-05-09T07:24:07+00:00\",\"dateModified\":\"2022-05-09T17:34:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/deaflympics-d-ete-2022-lor-pour-pamera-losange-et-marie-rivereau-en-athletisme\/\"},\"wordCount\":458,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/deaflympics-d-ete-2022-lor-pour-pamera-losange-et-marie-rivereau-en-athletisme\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Deaflympics-dete-2022-Lor-pour-Pamera-Losange-et-Marie-Rivereau-en-athletisme-1.png\",\"keywords\":[\"Athl\u00e9tisme\",\"Cyclisme\",\"handisport\",\"sport\"],\"articleSection\":[\"Athl\u00e9tisme\",\"Handisport\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/deaflympics-d-ete-2022-lor-pour-pamera-losange-et-marie-rivereau-en-athletisme\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/deaflympics-d-ete-2022-lor-pour-pamera-losange-et-marie-rivereau-en-athletisme\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/deaflympics-d-ete-2022-lor-pour-pamera-losange-et-marie-rivereau-en-athletisme\/\",\"name\":\"Deaflympics d'\u00e9t\u00e9 2022 : L'or pour Pamera Losange et Marie Rivereau en athl\u00e9tisme\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/deaflympics-d-ete-2022-lor-pour-pamera-losange-et-marie-rivereau-en-athletisme\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/deaflympics-d-ete-2022-lor-pour-pamera-losange-et-marie-rivereau-en-athletisme\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Deaflympics-dete-2022-Lor-pour-Pamera-Losange-et-Marie-Rivereau-en-athletisme-1.png\",\"datePublished\":\"2022-05-09T07:24:07+00:00\",\"dateModified\":\"2022-05-09T17:34:36+00:00\",\"description\":\"DEAFLYMPIC D'\u00c9T\u00c9 2022 - Doubl\u00e9 en or pour les Fran\u00e7aises en athl\u00e9tisme et nouvelle m\u00e9daille pour Steeve Touboul en cyclisme.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/deaflympics-d-ete-2022-lor-pour-pamera-losange-et-marie-rivereau-en-athletisme\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/deaflympics-d-ete-2022-lor-pour-pamera-losange-et-marie-rivereau-en-athletisme\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/deaflympics-d-ete-2022-lor-pour-pamera-losange-et-marie-rivereau-en-athletisme\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Deaflympics-dete-2022-Lor-pour-Pamera-Losange-et-Marie-Rivereau-en-athletisme-1.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Deaflympics-dete-2022-Lor-pour-Pamera-Losange-et-Marie-Rivereau-en-athletisme-1.png\",\"width\":800,\"height\":445,\"caption\":\"Deaflympics d\u2019\u00e9t\u00e9 2022 L\u2019or pour Pamera Losange et Marie Rivereau en athl\u00e9tisme\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/deaflympics-d-ete-2022-lor-pour-pamera-losange-et-marie-rivereau-en-athletisme\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Deaflympics d&rsquo;\u00e9t\u00e9 2022 : L&rsquo;or pour Pamera Losange et Marie Rivereau en athl\u00e9tisme\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/5aab10ee856e86ac63e9819a9da34784\",\"name\":\"Maxime Boulard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Boulard-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Boulard-150x150.jpg\",\"caption\":\"Maxime Boulard\"},\"description\":\"Journaliste\/r\u00e9dacteur depuis octobre 2020 - Si mon plus vieux souvenir de sport aurait pu m'en d\u00e9go\u00fbter, la finale de la Coupe du monde 2006 a \u00e9t\u00e9 tout le contraire. V\u00e9ritable d\u00e9clencheur d'une passion qui aujourd'hui ne fait que grandir avec le temps, mon leitmotiv est la France qui brille ! Je relate les exploits pass\u00e9s et pr\u00e9sents du sport bleu-blanc-rouge sans m\u00e9nagement depuis octobre 2020. Sport valide ou handisport, aucune diff\u00e9rence, il n'y a que du sport et plusieurs fa\u00e7ons de le pratiquer.\",\"sameAs\":[\"https:\/\/www.facebook.com\/Max.Bld2\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/MaximeB_2\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/maxime-b\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Deaflympics d'\u00e9t\u00e9 2022 : L'or pour Pamera Losange et Marie Rivereau en athl\u00e9tisme","description":"DEAFLYMPIC D'\u00c9T\u00c9 2022 - Doubl\u00e9 en or pour les Fran\u00e7aises en athl\u00e9tisme et nouvelle m\u00e9daille pour Steeve Touboul en cyclisme.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/deaflympics-d-ete-2022-lor-pour-pamera-losange-et-marie-rivereau-en-athletisme\/","og_locale":"fr_FR","og_type":"article","og_title":"Deaflympics d'\u00e9t\u00e9 2022 : L'or pour Pamera Losange et Marie Rivereau en athl\u00e9tisme","og_description":"DEAFLYMPIC D'\u00c9T\u00c9 2022 - Doubl\u00e9 en or pour les Fran\u00e7aises en athl\u00e9tisme et nouvelle m\u00e9daille pour Steeve Touboul en cyclisme.","og_url":"https:\/\/dicodusport.fr\/blog\/deaflympics-d-ete-2022-lor-pour-pamera-losange-et-marie-rivereau-en-athletisme\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/Max.Bld2\/","article_published_time":"2022-05-09T07:24:07+00:00","article_modified_time":"2022-05-09T17:34:36+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Deaflympics-dete-2022-Lor-pour-Pamera-Losange-et-Marie-Rivereau-en-athletisme-1.png","type":"image\/png"}],"author":"Maxime Boulard","twitter_card":"summary_large_image","twitter_title":"Deaflympics d'\u00e9t\u00e9 2022 : L'or pour Pamera Losange et Marie Rivereau en athl\u00e9tisme","twitter_creator":"@https:\/\/twitter.com\/MaximeB_2","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/deaflympics-d-ete-2022-lor-pour-pamera-losange-et-marie-rivereau-en-athletisme\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/deaflympics-d-ete-2022-lor-pour-pamera-losange-et-marie-rivereau-en-athletisme\/"},"author":{"name":"Maxime Boulard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/5aab10ee856e86ac63e9819a9da34784"},"headline":"Deaflympics d&rsquo;\u00e9t\u00e9 2022 : L&rsquo;or pour Pamera Losange et Marie Rivereau en athl\u00e9tisme","datePublished":"2022-05-09T07:24:07+00:00","dateModified":"2022-05-09T17:34:36+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/deaflympics-d-ete-2022-lor-pour-pamera-losange-et-marie-rivereau-en-athletisme\/"},"wordCount":458,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/deaflympics-d-ete-2022-lor-pour-pamera-losange-et-marie-rivereau-en-athletisme\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Deaflympics-dete-2022-Lor-pour-Pamera-Losange-et-Marie-Rivereau-en-athletisme-1.png","keywords":["Athl\u00e9tisme","Cyclisme","handisport","sport"],"articleSection":["Athl\u00e9tisme","Handisport"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/deaflympics-d-ete-2022-lor-pour-pamera-losange-et-marie-rivereau-en-athletisme\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/deaflympics-d-ete-2022-lor-pour-pamera-losange-et-marie-rivereau-en-athletisme\/","url":"https:\/\/dicodusport.fr\/blog\/deaflympics-d-ete-2022-lor-pour-pamera-losange-et-marie-rivereau-en-athletisme\/","name":"Deaflympics d'\u00e9t\u00e9 2022 : L'or pour Pamera Losange et Marie Rivereau en athl\u00e9tisme","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/deaflympics-d-ete-2022-lor-pour-pamera-losange-et-marie-rivereau-en-athletisme\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/deaflympics-d-ete-2022-lor-pour-pamera-losange-et-marie-rivereau-en-athletisme\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Deaflympics-dete-2022-Lor-pour-Pamera-Losange-et-Marie-Rivereau-en-athletisme-1.png","datePublished":"2022-05-09T07:24:07+00:00","dateModified":"2022-05-09T17:34:36+00:00","description":"DEAFLYMPIC D'\u00c9T\u00c9 2022 - Doubl\u00e9 en or pour les Fran\u00e7aises en athl\u00e9tisme et nouvelle m\u00e9daille pour Steeve Touboul en cyclisme.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/deaflympics-d-ete-2022-lor-pour-pamera-losange-et-marie-rivereau-en-athletisme\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/deaflympics-d-ete-2022-lor-pour-pamera-losange-et-marie-rivereau-en-athletisme\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/deaflympics-d-ete-2022-lor-pour-pamera-losange-et-marie-rivereau-en-athletisme\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Deaflympics-dete-2022-Lor-pour-Pamera-Losange-et-Marie-Rivereau-en-athletisme-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Deaflympics-dete-2022-Lor-pour-Pamera-Losange-et-Marie-Rivereau-en-athletisme-1.png","width":800,"height":445,"caption":"Deaflympics d\u2019\u00e9t\u00e9 2022 L\u2019or pour Pamera Losange et Marie Rivereau en athl\u00e9tisme"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/deaflympics-d-ete-2022-lor-pour-pamera-losange-et-marie-rivereau-en-athletisme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Deaflympics d&rsquo;\u00e9t\u00e9 2022 : L&rsquo;or pour Pamera Losange et Marie Rivereau en athl\u00e9tisme"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/5aab10ee856e86ac63e9819a9da34784","name":"Maxime Boulard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Boulard-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Boulard-150x150.jpg","caption":"Maxime Boulard"},"description":"Journaliste\/r\u00e9dacteur depuis octobre 2020 - Si mon plus vieux souvenir de sport aurait pu m'en d\u00e9go\u00fbter, la finale de la Coupe du monde 2006 a \u00e9t\u00e9 tout le contraire. V\u00e9ritable d\u00e9clencheur d'une passion qui aujourd'hui ne fait que grandir avec le temps, mon leitmotiv est la France qui brille ! Je relate les exploits pass\u00e9s et pr\u00e9sents du sport bleu-blanc-rouge sans m\u00e9nagement depuis octobre 2020. Sport valide ou handisport, aucune diff\u00e9rence, il n'y a que du sport et plusieurs fa\u00e7ons de le pratiquer.","sameAs":["https:\/\/www.facebook.com\/Max.Bld2\/","https:\/\/x.com\/https:\/\/twitter.com\/MaximeB_2"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maxime-b\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/222300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=222300"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/222300\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/222443"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=222300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=222300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=222300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}