{"id":222559,"date":"2022-05-10T14:24:29","date_gmt":"2022-05-10T12:24:29","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=222559&#038;preview=true&#038;preview_id=222559"},"modified":"2022-05-10T18:15:20","modified_gmt":"2022-05-10T16:15:20","slug":"les-6-nations-restent-sur-france-televisions-jusqu-en-2025","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/les-6-nations-restent-sur-france-televisions-jusqu-en-2025\/","title":{"rendered":"Les 6 Nations restent sur France T\u00e9l\u00e9visions jusqu&rsquo;en 2025 !"},"content":{"rendered":"<p style=\"text-align: justify;\"><b><i>TOURNOI DES 6 NATIONS &#8211; Ce mardi, l&rsquo;organisation des 6 Nations et France T\u00e9l\u00e9visions ont officialis\u00e9 la prolongation de la diffusion des Six Nations Masculin et F\u00e9minin sur les cha\u00eenes de France TV, et ce jusqu&rsquo;en 2025.<\/i><\/b><\/p>\n<p style=\"text-align: justify;\">L&rsquo;incertitude planait. Finalement, <strong>France T\u00e9l\u00e9visions<\/strong> va continuer de diffuser les <strong>Tournois des 6 Nations masculin et f\u00e9minin<\/strong> pour les trois prochaines \u00e9ditions, soit jusqu&rsquo;en 2025, et ce, en exclusivit\u00e9. L&rsquo;officialisation est intervenue ce mardi. Une sacr\u00e9e bonne nouvelle pour tous les fans de rugby en France. En effet, comme le rappellent nos confr\u00e8res de <em>Rugbyrama<\/em>, plusieurs dizaines de milliers de t\u00e9l\u00e9spectateurs ont suivi <a href=\"https:\/\/dicodusport.fr\/blog\/6-nations-la-victoire-et-le-grand-chelem-pour-le-xv-de-france\/\">le sacre du <strong>XV de France<\/strong><\/a> en mars dernier, avec le Grand Chelem \u00e0 la cl\u00e9, le premier depuis 2010. Toujours selon <em>Rugbyrama<\/em>, France TV aurait acquis les droits t\u00e9l\u00e9 de la comp\u00e9tition pour 100 millions d&rsquo;euros. Un temps en course pour obtenir les droits, TF1 va devoir attendre son tour, si ce dernier arrive un jour.<\/p>\n<p>\u00c0 noter que les trois matchs de la tourn\u00e9e de novembre prochain, lors de laquelle les Bleus affronteront l&rsquo;Australie, le Japon et l&rsquo;Afrique du Sud, seront \u00e9galement diffus\u00e9s sur France 2.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">&#x1f6a8; France T\u00e9l\u00e9visions reste le diffuseur exclusif du Tournoi des <a href=\"https:\/\/twitter.com\/hashtag\/SixNations?src=hash&amp;ref_src=twsrc%5Etfw\">#SixNations<\/a> jusqu&rsquo;en 2025 !<\/p>\n<p><a href=\"https:\/\/t.co\/FVP5F8Uw8Y\">https:\/\/t.co\/FVP5F8Uw8Y<\/a><\/p>\n<p>\u2014 francetvsport (@francetvsport) <a href=\"https:\/\/twitter.com\/francetvsport\/status\/1523983616929419264?ref_src=twsrc%5Etfw\">May 10, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TOURNOI DES 6 NATIONS &#8211; Ce mardi, l&rsquo;organisation des 6 Nations et France T\u00e9l\u00e9visions ont officialis\u00e9 la prolongation de la diffusion des Six Nations Masculin et F\u00e9minin, et ce jusqu&rsquo;en 2025.<\/p>\n","protected":false},"author":4,"featured_media":217354,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[9129],"tags":[9734],"class_list":["post-222559","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","tag-tournoi-des-6-nations"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rugby \u00e0 XV - Les 6 Nations restent sur France T\u00e9l\u00e9visions jusqu&#039;en 2025 ! - Dicodusport<\/title>\n<meta name=\"description\" content=\"Ce mardi, l&#039;organisation des 6 Nations et France T\u00e9l\u00e9visions ont officialis\u00e9 la prolongation de la diffusion des Six Nations Masculin et F\u00e9minin, et ce jusqu&#039;en 2025.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/les-6-nations-restent-sur-france-televisions-jusqu-en-2025\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les 6 Nations restent sur France T\u00e9l\u00e9visions jusqu&#039;en 2025 !\" \/>\n<meta property=\"og:description\" content=\"Ce mardi, l&#039;organisation des 6 Nations et France T\u00e9l\u00e9visions ont officialis\u00e9 la prolongation de la diffusion des Six Nations Masculin et F\u00e9minin, et ce jusqu&#039;en 2025.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/les-6-nations-restent-sur-france-televisions-jusqu-en-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-10T12:24:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-10T16:15:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/XV-de-France-Le-calendrier-des-Bleus-pour-le-6-Nations-2023.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Les 6 Nations restent sur France T\u00e9l\u00e9visions jusqu&#039;en 2025 !\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-6-nations-restent-sur-france-televisions-jusqu-en-2025\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-6-nations-restent-sur-france-televisions-jusqu-en-2025\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Les 6 Nations restent sur France T\u00e9l\u00e9visions jusqu&rsquo;en 2025 !\",\"datePublished\":\"2022-05-10T12:24:29+00:00\",\"dateModified\":\"2022-05-10T16:15:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-6-nations-restent-sur-france-televisions-jusqu-en-2025\/\"},\"wordCount\":238,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-6-nations-restent-sur-france-televisions-jusqu-en-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/XV-de-France-Le-calendrier-des-Bleus-pour-le-6-Nations-2023.png\",\"keywords\":[\"Tournoi des 6 Nations\"],\"articleSection\":[\"Rugby \u00e0 XV\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/les-6-nations-restent-sur-france-televisions-jusqu-en-2025\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-6-nations-restent-sur-france-televisions-jusqu-en-2025\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/les-6-nations-restent-sur-france-televisions-jusqu-en-2025\/\",\"name\":\"Rugby \u00e0 XV - Les 6 Nations restent sur France T\u00e9l\u00e9visions jusqu'en 2025 ! - Dicodusport\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-6-nations-restent-sur-france-televisions-jusqu-en-2025\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-6-nations-restent-sur-france-televisions-jusqu-en-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/XV-de-France-Le-calendrier-des-Bleus-pour-le-6-Nations-2023.png\",\"datePublished\":\"2022-05-10T12:24:29+00:00\",\"dateModified\":\"2022-05-10T16:15:20+00:00\",\"description\":\"Ce mardi, l'organisation des 6 Nations et France T\u00e9l\u00e9visions ont officialis\u00e9 la prolongation de la diffusion des Six Nations Masculin et F\u00e9minin, et ce jusqu'en 2025.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-6-nations-restent-sur-france-televisions-jusqu-en-2025\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/les-6-nations-restent-sur-france-televisions-jusqu-en-2025\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-6-nations-restent-sur-france-televisions-jusqu-en-2025\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/XV-de-France-Le-calendrier-des-Bleus-pour-le-6-Nations-2023.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/XV-de-France-Le-calendrier-des-Bleus-pour-le-6-Nations-2023.png\",\"width\":800,\"height\":445,\"caption\":\"XV de France : Les Bleus premiers au classement World Rugby !\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/les-6-nations-restent-sur-france-televisions-jusqu-en-2025\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les 6 Nations restent sur France T\u00e9l\u00e9visions jusqu&rsquo;en 2025 !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Rugby \u00e0 XV - Les 6 Nations restent sur France T\u00e9l\u00e9visions jusqu'en 2025 ! - Dicodusport","description":"Ce mardi, l'organisation des 6 Nations et France T\u00e9l\u00e9visions ont officialis\u00e9 la prolongation de la diffusion des Six Nations Masculin et F\u00e9minin, et ce jusqu'en 2025.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/les-6-nations-restent-sur-france-televisions-jusqu-en-2025\/","og_locale":"fr_FR","og_type":"article","og_title":"Les 6 Nations restent sur France T\u00e9l\u00e9visions jusqu'en 2025 !","og_description":"Ce mardi, l'organisation des 6 Nations et France T\u00e9l\u00e9visions ont officialis\u00e9 la prolongation de la diffusion des Six Nations Masculin et F\u00e9minin, et ce jusqu'en 2025.","og_url":"https:\/\/dicodusport.fr\/blog\/les-6-nations-restent-sur-france-televisions-jusqu-en-2025\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2022-05-10T12:24:29+00:00","article_modified_time":"2022-05-10T16:15:20+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/XV-de-France-Le-calendrier-des-Bleus-pour-le-6-Nations-2023.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Les 6 Nations restent sur France T\u00e9l\u00e9visions jusqu'en 2025 !","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/les-6-nations-restent-sur-france-televisions-jusqu-en-2025\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/les-6-nations-restent-sur-france-televisions-jusqu-en-2025\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Les 6 Nations restent sur France T\u00e9l\u00e9visions jusqu&rsquo;en 2025 !","datePublished":"2022-05-10T12:24:29+00:00","dateModified":"2022-05-10T16:15:20+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/les-6-nations-restent-sur-france-televisions-jusqu-en-2025\/"},"wordCount":238,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/les-6-nations-restent-sur-france-televisions-jusqu-en-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/XV-de-France-Le-calendrier-des-Bleus-pour-le-6-Nations-2023.png","keywords":["Tournoi des 6 Nations"],"articleSection":["Rugby \u00e0 XV"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/les-6-nations-restent-sur-france-televisions-jusqu-en-2025\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/les-6-nations-restent-sur-france-televisions-jusqu-en-2025\/","url":"https:\/\/dicodusport.fr\/blog\/les-6-nations-restent-sur-france-televisions-jusqu-en-2025\/","name":"Rugby \u00e0 XV - Les 6 Nations restent sur France T\u00e9l\u00e9visions jusqu'en 2025 ! - Dicodusport","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/les-6-nations-restent-sur-france-televisions-jusqu-en-2025\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/les-6-nations-restent-sur-france-televisions-jusqu-en-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/XV-de-France-Le-calendrier-des-Bleus-pour-le-6-Nations-2023.png","datePublished":"2022-05-10T12:24:29+00:00","dateModified":"2022-05-10T16:15:20+00:00","description":"Ce mardi, l'organisation des 6 Nations et France T\u00e9l\u00e9visions ont officialis\u00e9 la prolongation de la diffusion des Six Nations Masculin et F\u00e9minin, et ce jusqu'en 2025.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/les-6-nations-restent-sur-france-televisions-jusqu-en-2025\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/les-6-nations-restent-sur-france-televisions-jusqu-en-2025\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/les-6-nations-restent-sur-france-televisions-jusqu-en-2025\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/XV-de-France-Le-calendrier-des-Bleus-pour-le-6-Nations-2023.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/04\/XV-de-France-Le-calendrier-des-Bleus-pour-le-6-Nations-2023.png","width":800,"height":445,"caption":"XV de France : Les Bleus premiers au classement World Rugby !"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/les-6-nations-restent-sur-france-televisions-jusqu-en-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Les 6 Nations restent sur France T\u00e9l\u00e9visions jusqu&rsquo;en 2025 !"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/222559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=222559"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/222559\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/217354"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=222559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=222559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=222559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}