{"id":223224,"date":"2022-05-14T11:00:29","date_gmt":"2022-05-14T09:00:29","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=223224"},"modified":"2022-05-15T16:32:47","modified_gmt":"2022-05-15T14:32:47","slug":"boxe-charlo-vs-castano-une-revanche-indispensable-pour-le-trone-des-super-welters","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/boxe-charlo-vs-castano-une-revanche-indispensable-pour-le-trone-des-super-welters\/","title":{"rendered":"Boxe Charlo vs Casta\u00f1o : Une revanche indispensable pour le tr\u00f4ne des super-welters"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>BOXE POIDS SUPER-WELTERS &#8211;<\/strong><\/em> <em><b>Dans la nuit de samedi \u00e0 dimanche, c\u2019est une revanche \u00f4 combien attendue qui va avoir lieu en Californie. L\u2019Am\u00e9ricain Jermell Charlo et l\u2019Argentin Brian Casta\u00f1o, tous deux champions du monde, vont s\u2019affronter pour d\u00e9terminer le champion du monde incontest\u00e9 de la division des super-welters. Neuf mois auparavant, leur premier combat d\u2019unification s\u2019\u00e9tait termin\u00e9 sur un match nul discut\u00e9.<\/b><\/em><\/p>\n<p style=\"text-align: justify;\">Le premier combat a laiss\u00e9 beaucoup de regrets de part et d\u2019autre. Pour le champion du monde WBO <strong>Brian Casta\u00f1o<\/strong>, c\u2019est le r\u00e9sultat, \u00e0 savoir un match nul, qui lui a laiss\u00e9 un go\u00fbt amer. \u00ab <em>J\u2019aurais d\u00fb gagner le combat purement et simplement <\/em>\u00bb s\u2019\u00e9tait-il d\u00e9fendu en conf\u00e9rence de presse. <em>Charlo sait que j\u2019ai gagn\u00e9.<\/em> \u00bb Pour le champion du monde WBA, WBC et IBF <strong>Jermell Charlo<\/strong>, c\u2019est sa prestation lors du premier combat qu\u2019il regrette. \u00ab<em> Je n\u2019aime pas cela. Je n\u2019ai pas r\u00e9ussi \u00e0 amener le combat l\u00e0 o\u00f9 je souhaitais<\/em> \u00bb, regrettait-il. Ce samedi, ils auront l\u2019occasion de se rattraper et d\u2019en d\u00e9coudre pour de bon.<\/p>\n<h2 style=\"text-align: justify;\">Une revanche n\u00e9cessaire<\/h2>\n<p style=\"text-align: justify;\">La d\u00e9cision du premier combat fut controvers\u00e9e. D\u2019abord, parce que ce fut un match tr\u00e8s serr\u00e9, durant lequel les deux hommes ont eu chacun leurs temps forts. Ensuite, parce que beaucoup estiment l\u2019Argentin l\u00e9s\u00e9 par le r\u00e9sultat et ont pu voir quelque chose de pas tr\u00e8s net dans la notation des juges. En effet, l\u2019un d\u2019eux a accord\u00e9 un 117 \u00e0 111 en faveur de l\u2019Am\u00e9ricain, ce qui signifie que celui-ci aurait domin\u00e9 la partie en remportant neuf des douze rounds.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Just so you don\u2019t forget, it\u2019s Charlo-Casta\u00f1o II fight week. I\u2019m expecting another great fight for 12 rounds or less: <a href=\"https:\/\/t.co\/AMxtmoGtgm\">pic.twitter.com\/AMxtmoGtgm<\/a><\/p>\n<p>\u2014 Lord of The Fly&rsquo;s (@naotaBox) <a href=\"https:\/\/twitter.com\/naotaBox\/status\/1524074196627648512?ref_src=twsrc%5Etfw\">May 10, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Voil\u00e0 pourquoi la revanche est indispensable. Aussi, il y a le fait que ce match nul n\u2019ait pas permis d\u2019unifier une bonne fois pour toute la cat\u00e9gorie des poids super-welters. Aujourd\u2019hui, seules les divisions des poids super-l\u00e9gers et des poids super-moyens d\u00e9tiennent un champion unifi\u00e9. Dimanche matin, il y aura un troisi\u00e8me champion incontest\u00e9, ce qui permettra de clarifier davantage la hi\u00e9rarchie chez les 154 pounds (-69,9 kg). \u00ab <em>C\u2019est ce dont chaque combattant r\u00eave<\/em> \u00bb, expliquait notamment Casta\u00f1o en conf\u00e9rence de presse.<\/p>\n<h2 style=\"text-align: justify;\">Le num\u00e9ro un face au num\u00e9ro deux<\/h2>\n<p style=\"text-align: justify;\">Comme on vient de le voir, rares sont les cat\u00e9gories qui paraissent lisibles aujourd&rsquo;hui. Heureusement, chez les super-welters, on sait \u00e0 quoi s&rsquo;en tenir. On connait les deux meilleurs et il ne reste plus qu&rsquo;\u00e0 les d\u00e9partager. Le favori ce week-end, ce sera <strong>Jermell Charlo<\/strong>. L&rsquo;Am\u00e9ricain est le champion du monde unifi\u00e9, avec les ceintures WBC, WBA et IBF. \u00c0 31 ans, il poss\u00e8de un palmar\u00e8s de 34 victoires, une d\u00e9faite et un match nul. Selon <em>BoxRec<\/em> et <em>Ring<\/em>, c&rsquo;est le num\u00e9ro un chez les super-welters.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">&#x1f525; Unifinished Business: <a href=\"https:\/\/twitter.com\/FutureOfBoxing?ref_src=twsrc%5Etfw\">@FutureOfBoxing<\/a> vs. <a href=\"https:\/\/twitter.com\/briancastanobox?ref_src=twsrc%5Etfw\">@briancastanobox<\/a>&#x1f525;<a href=\"https:\/\/twitter.com\/hashtag\/CharloCasta%C3%B1o?src=hash&amp;ref_src=twsrc%5Etfw\">#CharloCasta\u00f1o<\/a> II for the 154 Lbs. Supremacy &#x1f1fa;&#x1f1f2; &#x1f1e6;&#x1f1f7;&#x1f451; <a href=\"https:\/\/t.co\/8todxD6Z1H\">pic.twitter.com\/8todxD6Z1H<\/a><\/p>\n<p>\u2014 World Boxing Council (@WBCBoxing) <a href=\"https:\/\/twitter.com\/WBCBoxing\/status\/1524967097926918173?ref_src=twsrc%5Etfw\">May 13, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">En face, <strong>Brian Casta\u00f1o<\/strong>, champion du monde WBO, est encore invaincu \u00e0 32 ans. En 19 rencontres professionnelles, il est parvenu \u00e0 triompher \u00e0 17 reprises. Pour le reste, il s&rsquo;agit de matchs nuls, face \u00e0 des pointures comme <strong>Erislandy Lara<\/strong> en 2017 ou <strong>Jermell Charlo<\/strong> l&rsquo;\u00e9t\u00e9 dernier.<\/p>\n<h2 style=\"text-align: justify;\">Deux boxes tr\u00e8s diff\u00e9rentes<\/h2>\n<p style=\"text-align: justify;\">Lors du premier combat, on a pu remarquer la diff\u00e9rence de style tr\u00e8s marqu\u00e9e entre les deux pugilistes. Pour le fr\u00e8re jumeau de<strong> Jermall Charlo<\/strong>, champion du monde chez les moyens, il s&rsquo;agit d&rsquo;une boxe qui mise sur une allonge avantageuse. En effet, la diff\u00e9rence de taille et d&rsquo;envergure sont assez cons\u00e9quentes. D&rsquo;un c\u00f4t\u00e9, Charlo mesure 1.83 m et ses bras peuvent s&rsquo;\u00e9tendre jusqu&rsquo;\u00e0 1.85m. De l&rsquo;autre c\u00f4t\u00e9, on parle d&rsquo;une taille et d&rsquo;une allonge d&rsquo;1.71 m pour Casta\u00f1o, ce qui fait une sacr\u00e9e diff\u00e9rence. Avec cette allonge, l&rsquo;Am\u00e9ricain peut boxer en gardant la distance et en travaillant avec son jab. C&rsquo;est \u00e9galement un boxeur tr\u00e8s efficace sur le plan technique.<\/p>\n<p style=\"text-align: justify;\">Techniquement, Brian Casta\u00f1o n&rsquo;est pas non plus en reste. Contrairement \u00e0 Charlo, <em>El Boxi<\/em> se bat en avan\u00e7ant et en faisant valoir des combinaisons rapides et dangereuses. Aussi, il est redoutable sur le plan physique. Enfin, la diff\u00e9rence est \u00e9galement pr\u00e9sente en termes de puissance. L\u00e0-dessus, c&rsquo;est l&rsquo;Argentin qui prend l&rsquo;avantage. Au-del\u00e0 du taux de KO plus \u00e9lev\u00e9 chez le Sud-Am\u00e9ricain (63% contre 50%), ce dernier donne l&rsquo;impression d&rsquo;\u00eatre un vrai puncheur sur le ring.<\/p>\n<h2 style=\"text-align: justify;\">Des le\u00e7ons \u00e0 retenir<\/h2>\n<p style=\"text-align: justify;\">Pour remporter ce match, nos deux boxeurs vont sans doute devoir se servir de leur premi\u00e8re confrontation commune. Dans leurs propos, les deux hommes ont d&rsquo;ailleurs bien signifi\u00e9 qu&rsquo;il faudra changer certaines choses pour ce nouveau duel. Pour <em>Iron Man<\/em>, il s&rsquo;agira de rester constant durant toute la partie et offrir moins d&rsquo;opportunit\u00e9s \u00e0 son adversaire afin de dominer la rencontre. \u00ab\u00a0<em>Je serai meilleur, plus rapide, plus fort et plus constant sur ce combat. Je ferai du Charlo old school.<\/em> \u00bb Ce dernier a \u00e9galement \u00e9voqu\u00e9 l&rsquo;importance de surprendre son rival lors de cette revanche. \u00ab<em> Je me consid\u00e8re comme un puncheur et un boxeur, et je pr\u00e9vois de sortir quelques tours de mon chapeau cette fois-ci.<\/em> \u00bb<\/p>\n<p style=\"text-align: justify;\">Pour Casta\u00f1o, la donne sera diff\u00e9rente. On ne peut oublier la carte des scores sur le premier combat et la notation tr\u00e8s \u00e9trange de l&rsquo;un des trois juges. Une nouvelle fois, l&rsquo;Argentin boxera \u00ab \u00e0 l&rsquo;ext\u00e9rieur \u00bb. Pour \u00e9viter d&rsquo;aller aux points, le natif d&rsquo;Isidro Casanova envisage d&rsquo;aller droit au but. \u00ab <em>Je veux le knockout.\u00a0 J\u2019en ai besoin. Le premier combat fut serr\u00e9, mais le second sera bien plus compliqu\u00e9 pour Charlo, parce que je vais le mettre KO.<\/em> \u00bb<\/p>\n<p style=\"text-align: justify;\">Voil\u00e0 \u00e0 quoi s&rsquo;en tenir pour cette revanche. Le match aller fut haletant et tr\u00e8s disput\u00e9. Cette revanche promet encore plus !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BOXE POIDS SUPER-WELTERS &#8211; Dans la nuit de samedi \u00e0 dimanche, c\u2019est une revanche \u00f4 combien attendue qui va avoir lieu en Californie. L\u2019Am\u00e9ricain Jermell Charlo et l\u2019Argentin Brian Casta\u00f1o, tous deux champions du monde, vont s\u2019affronter pour d\u00e9terminer le champion du monde incontest\u00e9 de la division des super-welters. Neuf mois auparavant, leur premier combat d\u2019unification s\u2019\u00e9tait termin\u00e9 sur un match nul discut\u00e9.<\/p>\n","protected":false},"author":45,"featured_media":223539,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[8672],"tags":[1696],"class_list":["post-223224","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boxe","tag-boxe-anglaise"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Boxe Charlo vs Casta\u00f1o : Une revanche indispensable pour le tr\u00f4ne des super-welters<\/title>\n<meta name=\"description\" content=\"Samedi, Jermell Charlo et Brian Casta\u00f1o vont s\u2019affronter pour d\u00e9terminer le champion du monde incontest\u00e9 de la division des super-welters.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/boxe-charlo-vs-castano-une-revanche-indispensable-pour-le-trone-des-super-welters\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Boxe Charlo vs Casta\u00f1o : Une revanche indispensable pour le tr\u00f4ne des super-welters\" \/>\n<meta property=\"og:description\" content=\"Samedi, Jermell Charlo et Brian Casta\u00f1o vont s\u2019affronter pour d\u00e9terminer le champion du monde incontest\u00e9 de la division des super-welters.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/boxe-charlo-vs-castano-une-revanche-indispensable-pour-le-trone-des-super-welters\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/alexandre.jeffroy.3\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-14T09:00:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-15T14:32:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Boxe-Charlo-vs-Castano-Une-revanche-indispensable-pour-le-trone-des-super-welters.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Alexandre Jeffroy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Boxe Charlo vs Casta\u00f1o : Une revanche indispensable pour le tr\u00f4ne des super-welters\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/smokinalexjoe\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-charlo-vs-castano-une-revanche-indispensable-pour-le-trone-des-super-welters\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-charlo-vs-castano-une-revanche-indispensable-pour-le-trone-des-super-welters\/\"},\"author\":{\"name\":\"Alexandre Jeffroy\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0e50be5ee9a0e6705846ac950257c4a0\"},\"headline\":\"Boxe Charlo vs Casta\u00f1o : Une revanche indispensable pour le tr\u00f4ne des super-welters\",\"datePublished\":\"2022-05-14T09:00:29+00:00\",\"dateModified\":\"2022-05-15T14:32:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-charlo-vs-castano-une-revanche-indispensable-pour-le-trone-des-super-welters\/\"},\"wordCount\":1070,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-charlo-vs-castano-une-revanche-indispensable-pour-le-trone-des-super-welters\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Boxe-Charlo-vs-Castano-Une-revanche-indispensable-pour-le-trone-des-super-welters.png\",\"keywords\":[\"boxe anglaise\"],\"articleSection\":[\"Boxe\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/boxe-charlo-vs-castano-une-revanche-indispensable-pour-le-trone-des-super-welters\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-charlo-vs-castano-une-revanche-indispensable-pour-le-trone-des-super-welters\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/boxe-charlo-vs-castano-une-revanche-indispensable-pour-le-trone-des-super-welters\/\",\"name\":\"Boxe Charlo vs Casta\u00f1o : Une revanche indispensable pour le tr\u00f4ne des super-welters\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-charlo-vs-castano-une-revanche-indispensable-pour-le-trone-des-super-welters\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-charlo-vs-castano-une-revanche-indispensable-pour-le-trone-des-super-welters\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Boxe-Charlo-vs-Castano-Une-revanche-indispensable-pour-le-trone-des-super-welters.png\",\"datePublished\":\"2022-05-14T09:00:29+00:00\",\"dateModified\":\"2022-05-15T14:32:47+00:00\",\"description\":\"Samedi, Jermell Charlo et Brian Casta\u00f1o vont s\u2019affronter pour d\u00e9terminer le champion du monde incontest\u00e9 de la division des super-welters.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-charlo-vs-castano-une-revanche-indispensable-pour-le-trone-des-super-welters\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/boxe-charlo-vs-castano-une-revanche-indispensable-pour-le-trone-des-super-welters\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-charlo-vs-castano-une-revanche-indispensable-pour-le-trone-des-super-welters\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Boxe-Charlo-vs-Castano-Une-revanche-indispensable-pour-le-trone-des-super-welters.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Boxe-Charlo-vs-Castano-Une-revanche-indispensable-pour-le-trone-des-super-welters.png\",\"width\":800,\"height\":445,\"caption\":\"Boxe Charlo vs Casta\u00f1o Une revanche indispensable pour le tr\u00f4ne des super-welters\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-charlo-vs-castano-une-revanche-indispensable-pour-le-trone-des-super-welters\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boxe Charlo vs Casta\u00f1o : Une revanche indispensable pour le tr\u00f4ne des super-welters\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0e50be5ee9a0e6705846ac950257c4a0\",\"name\":\"Alexandre Jeffroy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Alexandre-Jeffroy-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Alexandre-Jeffroy-150x150.jpg\",\"caption\":\"Alexandre Jeffroy\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis octobre 2020 - Bolt qui foudroie le record du monde du 100 m\u00e8tres, les derniers essais de Dominici, les premi\u00e8res charges d\u00e9vastatrices de Bastarocket... de beaux souvenirs pour une grande passion, celle du sport. L\u2019histoire du sport aussi. Comprendre le r\u00f4le qu\u2019il a eu, celui qu\u2019il a et celui qu\u2019il aura dans notre soci\u00e9t\u00e9. Le sport au pass\u00e9, au pr\u00e9sent, au futur. Le sport tous les jours, matin, midi et soir. A d\u00e9faut d\u2019\u00eatre un grand sportif, je suis et je raconte l\u2019actualit\u00e9 et l\u2019histoire des championnes et des champions qui savent se d\u00e9passer pour accomplir des merveilles.\",\"sameAs\":[\"https:\/\/www.facebook.com\/alexandre.jeffroy.3\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/smokinalexjoe\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/alexandrejeffroy\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Boxe Charlo vs Casta\u00f1o : Une revanche indispensable pour le tr\u00f4ne des super-welters","description":"Samedi, Jermell Charlo et Brian Casta\u00f1o vont s\u2019affronter pour d\u00e9terminer le champion du monde incontest\u00e9 de la division des super-welters.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/boxe-charlo-vs-castano-une-revanche-indispensable-pour-le-trone-des-super-welters\/","og_locale":"fr_FR","og_type":"article","og_title":"Boxe Charlo vs Casta\u00f1o : Une revanche indispensable pour le tr\u00f4ne des super-welters","og_description":"Samedi, Jermell Charlo et Brian Casta\u00f1o vont s\u2019affronter pour d\u00e9terminer le champion du monde incontest\u00e9 de la division des super-welters.","og_url":"https:\/\/dicodusport.fr\/blog\/boxe-charlo-vs-castano-une-revanche-indispensable-pour-le-trone-des-super-welters\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/alexandre.jeffroy.3\/","article_published_time":"2022-05-14T09:00:29+00:00","article_modified_time":"2022-05-15T14:32:47+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Boxe-Charlo-vs-Castano-Une-revanche-indispensable-pour-le-trone-des-super-welters.png","type":"image\/png"}],"author":"Alexandre Jeffroy","twitter_card":"summary_large_image","twitter_title":"Boxe Charlo vs Casta\u00f1o : Une revanche indispensable pour le tr\u00f4ne des super-welters","twitter_creator":"@https:\/\/twitter.com\/smokinalexjoe","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/boxe-charlo-vs-castano-une-revanche-indispensable-pour-le-trone-des-super-welters\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/boxe-charlo-vs-castano-une-revanche-indispensable-pour-le-trone-des-super-welters\/"},"author":{"name":"Alexandre Jeffroy","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0e50be5ee9a0e6705846ac950257c4a0"},"headline":"Boxe Charlo vs Casta\u00f1o : Une revanche indispensable pour le tr\u00f4ne des super-welters","datePublished":"2022-05-14T09:00:29+00:00","dateModified":"2022-05-15T14:32:47+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/boxe-charlo-vs-castano-une-revanche-indispensable-pour-le-trone-des-super-welters\/"},"wordCount":1070,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/boxe-charlo-vs-castano-une-revanche-indispensable-pour-le-trone-des-super-welters\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Boxe-Charlo-vs-Castano-Une-revanche-indispensable-pour-le-trone-des-super-welters.png","keywords":["boxe anglaise"],"articleSection":["Boxe"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/boxe-charlo-vs-castano-une-revanche-indispensable-pour-le-trone-des-super-welters\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/boxe-charlo-vs-castano-une-revanche-indispensable-pour-le-trone-des-super-welters\/","url":"https:\/\/dicodusport.fr\/blog\/boxe-charlo-vs-castano-une-revanche-indispensable-pour-le-trone-des-super-welters\/","name":"Boxe Charlo vs Casta\u00f1o : Une revanche indispensable pour le tr\u00f4ne des super-welters","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/boxe-charlo-vs-castano-une-revanche-indispensable-pour-le-trone-des-super-welters\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/boxe-charlo-vs-castano-une-revanche-indispensable-pour-le-trone-des-super-welters\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Boxe-Charlo-vs-Castano-Une-revanche-indispensable-pour-le-trone-des-super-welters.png","datePublished":"2022-05-14T09:00:29+00:00","dateModified":"2022-05-15T14:32:47+00:00","description":"Samedi, Jermell Charlo et Brian Casta\u00f1o vont s\u2019affronter pour d\u00e9terminer le champion du monde incontest\u00e9 de la division des super-welters.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/boxe-charlo-vs-castano-une-revanche-indispensable-pour-le-trone-des-super-welters\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/boxe-charlo-vs-castano-une-revanche-indispensable-pour-le-trone-des-super-welters\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/boxe-charlo-vs-castano-une-revanche-indispensable-pour-le-trone-des-super-welters\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Boxe-Charlo-vs-Castano-Une-revanche-indispensable-pour-le-trone-des-super-welters.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Boxe-Charlo-vs-Castano-Une-revanche-indispensable-pour-le-trone-des-super-welters.png","width":800,"height":445,"caption":"Boxe Charlo vs Casta\u00f1o Une revanche indispensable pour le tr\u00f4ne des super-welters"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/boxe-charlo-vs-castano-une-revanche-indispensable-pour-le-trone-des-super-welters\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Boxe Charlo vs Casta\u00f1o : Une revanche indispensable pour le tr\u00f4ne des super-welters"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0e50be5ee9a0e6705846ac950257c4a0","name":"Alexandre Jeffroy","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Alexandre-Jeffroy-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Alexandre-Jeffroy-150x150.jpg","caption":"Alexandre Jeffroy"},"description":"Journaliste\/R\u00e9dacteur depuis octobre 2020 - Bolt qui foudroie le record du monde du 100 m\u00e8tres, les derniers essais de Dominici, les premi\u00e8res charges d\u00e9vastatrices de Bastarocket... de beaux souvenirs pour une grande passion, celle du sport. L\u2019histoire du sport aussi. Comprendre le r\u00f4le qu\u2019il a eu, celui qu\u2019il a et celui qu\u2019il aura dans notre soci\u00e9t\u00e9. Le sport au pass\u00e9, au pr\u00e9sent, au futur. Le sport tous les jours, matin, midi et soir. A d\u00e9faut d\u2019\u00eatre un grand sportif, je suis et je raconte l\u2019actualit\u00e9 et l\u2019histoire des championnes et des champions qui savent se d\u00e9passer pour accomplir des merveilles.","sameAs":["https:\/\/www.facebook.com\/alexandre.jeffroy.3\/","https:\/\/x.com\/https:\/\/twitter.com\/smokinalexjoe"],"url":"https:\/\/dicodusport.fr\/blog\/author\/alexandrejeffroy\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/223224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=223224"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/223224\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/223539"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=223224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=223224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=223224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}