{"id":224297,"date":"2022-05-16T21:16:32","date_gmt":"2022-05-16T19:16:32","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=224297&#038;preview=true&#038;preview_id=224297"},"modified":"2022-05-16T21:25:29","modified_gmt":"2022-05-16T19:25:29","slug":"wta-250-strasbourg-dodin-pliskova-berberova-le-resume-de-la-journee-du-lundi","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/wta-250-strasbourg-dodin-pliskova-berberova-le-resume-de-la-journee-du-lundi\/","title":{"rendered":"WTA 250 Strasbourg : Dodin, Pliskova, Berberova, le r\u00e9sum\u00e9 de la journ\u00e9e du lundi"},"content":{"rendered":"<p style=\"text-align: justify;\"><b><i><a title=\"WTA 250 \u2013 Le tableau du tournoi de Strasbourg 2022\" href=\"https:\/\/dicodusport.fr\/blog\/wta-250-le-tableau-du-tournoi-de-strasbourg-2022\/\" target=\"_blank\" rel=\"noopener\">WTA 250 STRASBOURG 2022<\/a> &#8211; Perturb\u00e9e par une m\u00e9t\u00e9o capricieuse sur la capitale europ\u00e9enne aujourd&rsquo;hui, la premi\u00e8re journ\u00e9e du tournoi aura tout de m\u00eame permis de voir Oc\u00e9ane Dodin acc\u00e9der au tour suivant, tout comme Kristina Pliskova. En revanche, \u00e7a a coinc\u00e9 pour plusieurs tricolores, qui partaient avec le statut d&rsquo;outsiders avant leurs rencontres.<\/i><\/b><\/p>\n<h2 style=\"text-align: justify;\">\u00c7a passe pour Oc\u00e9ane Dodin<\/h2>\n<p style=\"text-align: justify;\"><strong>Oc\u00e9ane Dodin<\/strong> a eu l&rsquo;honneur d&rsquo;ouvrir la journ\u00e9e sur le court central du complexe Pierre de Coubertin. Oppos\u00e9e \u00e0 la Croate <strong>Ana Konjuh<\/strong>, la Lilloise a vu sa partie \u00eatre interrompue par la pluie continue qui est tomb\u00e9e sur le court entre 11h et 14h. Avant l&rsquo;interruption, la Fran\u00e7aise menait 5 jeux \u00e0 0 dans le premier set, son adversaire ayant \u00e9norm\u00e9ment de mal \u00e0 g\u00e9rer les conditions climatiques d\u00e9licates. \u00c0 la reprise du jeu, et \u00e0 la surprise g\u00e9n\u00e9rale, <strong>Ana Konjuh<\/strong> a fait sa loi sur le court, en retrouvant de l&rsquo;adresse notamment au service (80% de premi\u00e8res balles). Mais dans le troisi\u00e8me set, qui fut un chass\u00e9-crois\u00e9 de jeux de service perdus, c&rsquo;est finalement <strong>Oc\u00e9ane Dodin<\/strong> qui a \u00e9t\u00e9 la plus solide en breakant son adversaire \u00e0 6-5 dans le dernier jeu. La Croate a \u00e9t\u00e9 trahie par un service moins efficient dans le dernier set (40% de premi\u00e8res balles, 10 balles de breaks conc\u00e9d\u00e9es).<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">.<a href=\"https:\/\/twitter.com\/oceane_dodin?ref_src=twsrc%5Etfw\">@oceane_dodin<\/a> apr\u00e8s son match : \u00ab Je commen\u00e7ais \u00e0 fatiguer mentalement au troisi\u00e8me set donc merci au public de m\u2019avoir encourag\u00e9, c\u2019est gr\u00e2ce vous ! \u00bb <a href=\"https:\/\/twitter.com\/hashtag\/IS22?src=hash&amp;ref_src=twsrc%5Etfw\">#IS22<\/a><\/p>\n<p>&#x1f4f8; : Christoph de Barry \/ C\u2019est qui Maurice ? <a href=\"https:\/\/t.co\/IiV2vwVxZS\">pic.twitter.com\/IiV2vwVxZS<\/a><\/p>\n<p>\u2014 Internationaux de Strasbourg (@WTA_Strasbourg) <a href=\"https:\/\/twitter.com\/WTA_Strasbourg\/status\/1526201772867563522?ref_src=twsrc%5Etfw\">May 16, 2022<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">La belle histoire de Julie Gervais<\/h2>\n<p style=\"text-align: justify;\"><strong>Carole Monnet<\/strong> (249\u1d49 mondiale) b\u00e9n\u00e9ficiait d&rsquo;une wild-card sur ces Internationaux de Strasbourg. L&rsquo;Ukrainienne de naissance a eu les honneurs du central qui a pouss\u00e9 pour que la Fran\u00e7aise bouscule la Belge <strong>Elise Mertens<\/strong> (33\u1d49 mondiale). Malheureusement, il n&rsquo;y a pas eu de surprise, puisque <strong>Elise Mertens<\/strong> s&rsquo;est impos\u00e9e en deux sets pourtant accroch\u00e9s (7\/5 6\/4). La Fran\u00e7aise est revenue dans le premier set \u00e0 5-5, mais a finalement laiss\u00e9 son service au moment fatidique, \u00e0 6-5 pour la Belge. Dans le deuxi\u00e8me set, <strong>Elise Mertens<\/strong> a break\u00e9 d&rsquo;entr\u00e9 de manche, avant d&rsquo;assurer ses mises en jeu.<\/p>\n<p style=\"text-align: justify;\">Sur le court num\u00e9ro 1, en cl\u00f4ture du programme, les passionn\u00e9s de tennis et les Strasbourgeois pouvaient d\u00e9couvrir la belle histoire du tournoi. <strong>Julie Gervais<\/strong> (725\u1d49 mondiale). Habitu\u00e9e \u00e0 disputer des tournois ITF, <strong>Julie Gervais<\/strong> \u00e9tait sortie des qualifications, apr\u00e8s avoir \u00e9t\u00e9 rep\u00each\u00e9e des pr\u00e9-qualifications du tournoi. C&rsquo;\u00e9tait donc le jour de gloire pour la Fran\u00e7aise, qui disputait son premier match dans un grand tableau d&rsquo;un tournoi WTA, face \u00e0 la Bi\u00e9lorusse <strong>Aliaksandra<\/strong> <strong>Sasnovich<\/strong>. Dans le premier set, <strong>Julie Gervais<\/strong> pensait avoir fait le plus dur en breakant son adversaire \u00e0 4-3. Finalement, la Nordiste de 30 ans a conc\u00e9d\u00e9 son service \u00e0 deux reprises, dont ce fameux jeu \u00e0 4-5 qui a dur\u00e9 plus de dix minutes. Dans le deuxi\u00e8me set, la Bi\u00e9lorusse a break\u00e9 assez rapidement son adversaire pour finalement s&rsquo;imposer 6\/4 6\/2.<\/p>\n<p style=\"text-align: justify;\">Enfin, Diane Parry n&rsquo;a pas non plus r\u00e9alis\u00e9 de miracles face \u00e0 <strong>Angelique Kerber<\/strong>, qui reste une r\u00e9f\u00e9rence sur les circuits de la WTA. L&rsquo;Allemande, victorieuses \u00e0 trois reprises de tournois du Grand Chelem, s&rsquo;est impos\u00e9e en deux sets 6\/3 6\/4.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Malgr\u00e9 sa d\u00e9faite contre <a href=\"https:\/\/twitter.com\/hashtag\/EliseMertens?src=hash&amp;ref_src=twsrc%5Etfw\">#EliseMertens<\/a>, <a href=\"https:\/\/twitter.com\/MonnetCarole?ref_src=twsrc%5Etfw\">@MonnetCarole<\/a> a les yeux riv\u00e9s vers l\u2019avenir. <a href=\"https:\/\/twitter.com\/hashtag\/IS22?src=hash&amp;ref_src=twsrc%5Etfw\">#IS22<\/a> <a href=\"https:\/\/twitter.com\/WTA?ref_src=twsrc%5Etfw\">@WTA<\/a> <a href=\"https:\/\/t.co\/K4YZSczd3T\">pic.twitter.com\/K4YZSczd3T<\/a><\/p>\n<p>\u2014 Internationaux de Strasbourg (@WTA_Strasbourg) <a href=\"https:\/\/twitter.com\/WTA_Strasbourg\/status\/1526265729917526023?ref_src=twsrc%5Etfw\">May 16, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">La surprise Berberovic, Pliskova au rendez-vous<\/h2>\n<p style=\"text-align: justify;\">Sur le court num\u00e9ro 1, la Belge <strong>Maryna Zanevska<\/strong> n&rsquo;a eu aucun mal \u00e0 se d\u00e9faire de la Chinoise <strong>Shuai Zhang<\/strong> (6\/2 6\/3), en \u00e9tant tr\u00e8s souveraine sur les points chauds. Sur le court num\u00e9ro 2, la Britannique <strong>Heather Watson<\/strong> a \u00e9galement \u00e9t\u00e9 autoritaire pour s&rsquo;imposer en deux manches (6\/4 6\/1) face \u00e0 la lucky-loseuse <strong>Katharina Hobgarski<\/strong>. La premi\u00e8re surprise de la journ\u00e9e est venue de la Bosniaque <strong>Nefisa Berberovic<\/strong>. En trois sets, la joueuse class\u00e9e 306\u1d49 \u00e0 la WTA a \u00e9cart\u00e9 Sloane Stephens (2\/6 6\/4 6\/1), pourtant t\u00eate de s\u00e9rie num\u00e9ro 6 du tournoi. Malgr\u00e9 la perte du premier set, la Bosniaque a \u00e9t\u00e9 tr\u00e8s solide sur ces jeux de services et a break\u00e9 aux bons moments. Battue au 2\u00e8me tour des qualifications puis rep\u00each\u00e9e, <strong>Nefisa Berberovic<\/strong> r\u00e9alise donc l&rsquo;exploit du jour. Les ennuis continuent pour l&rsquo;Am\u00e9ricaine, qui compte d\u00e9sormais quatre d\u00e9faites de rang (Charleston, Madrid, Rome, Strasbourg).<\/p>\n<p style=\"text-align: justify;\">Pas de soucis en revanche pour la t\u00eate de s\u00e9rie num\u00e9ro 1 de ce tournoi de Strasbourg. Sur le court central, <strong>Karolina<\/strong> <strong>Pliskova<\/strong> a dispos\u00e9 de l&rsquo;Ukrainienne<strong> Marta Kostyuk<\/strong> en un peu plus d&rsquo;une heure (6\/4 6\/2). Elle tentera de succ\u00e9der \u00e0 sa compatriote Barbora Krejcikova, vainqueur du tournoi l&rsquo;an dernier. Pour le dernier match de la journ\u00e9e programm\u00e9 sur le court num\u00e9ro 2, la jeune Slov\u00e8ne <strong>Kaja Juvan<\/strong> a remport\u00e9 son affrontement contre l&rsquo;Isra\u00e9lienne<strong> Lina Glushko<\/strong>, et ce malgr\u00e9 plusieurs balles de breaks conc\u00e9d\u00e9es sur son propre service (12). Enfin, <strong>Viktoria Golubic<\/strong> a pass\u00e9 l&rsquo;\u00e9cueil du premier tour en s&rsquo;imposant 6\/0 6\/4 face \u00e0 la lucky-loseuse <strong>Yana Moderger<\/strong>, rep\u00each\u00e9e suite au forfait d&rsquo;Ekaterina Makarova.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">[Court 1] <a href=\"https:\/\/twitter.com\/hashtag\/NefisaBerberovic?src=hash&amp;ref_src=twsrc%5Etfw\">#NefisaBerberovic<\/a> &#x1f1e7;&#x1f1e6; vient \u00e0 bout de ce match et l\u2019emporte 2-6, 6-4, 6-1 face \u00e0 l\u2019Am\u00e9ricaine Sloane Stephens &#x1f1fa;&#x1f1f8;<\/p>\n<p>&#x1f4f8; : Christoph de Barry \/ C\u2019est qui Maurice ? <a href=\"https:\/\/t.co\/bbAEeouShI\">pic.twitter.com\/bbAEeouShI<\/a><\/p>\n<p>\u2014 Internationaux de Strasbourg (@WTA_Strasbourg) <a href=\"https:\/\/twitter.com\/WTA_Strasbourg\/status\/1526211283338637314?ref_src=twsrc%5Etfw\">May 16, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>WTA 250 STRASBOURG 2022 &#8211; Perturb\u00e9e par une m\u00e9t\u00e9o capricieuse sur la capitale europ\u00e9enne aujourd&rsquo;hui, la premi\u00e8re journ\u00e9e du tournoi aura tout de m\u00eame permis de voir Oc\u00e9ane Dodin acc\u00e9der au tour suivant, tout comme Kristina Pliskova. En revanche, \u00e7a a coinc\u00e9 pour plusieurs tricolores, qui partaient avec le statut d&rsquo;outsiders avant leurs rencontres.<\/p>\n","protected":false},"author":42,"featured_media":224353,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2302],"tags":[16834],"class_list":["post-224297","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tennis","tag-wta-250-strasbourg"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tennis - WTA 250 Strasbourg : Dodin, Pliskova, Berberova, le r\u00e9sum\u00e9 de la journ\u00e9e du lundi - Dicodusport<\/title>\n<meta name=\"description\" content=\"WTA 250 STRABOURG 2022 - Le r\u00e9sum\u00e9 de la journ\u00e9e du lundi des Internationaux de Strasbourg, avec une grosse surprise ce lundi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/wta-250-strasbourg-dodin-pliskova-berberova-le-resume-de-la-journee-du-lundi\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WTA 250 Strasbourg : Dodin, Pliskova, Berberova, le r\u00e9sum\u00e9 de la journ\u00e9e du lundi\" \/>\n<meta property=\"og:description\" content=\"WTA 250 STRABOURG 2022 - Le r\u00e9sum\u00e9 de la journ\u00e9e du lundi des Internationaux de Strasbourg, avec une grosse surprise ce lundi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/wta-250-strasbourg-dodin-pliskova-berberova-le-resume-de-la-journee-du-lundi\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-16T19:16:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-16T19:25:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/WTA-250-Strasbourg-Dodin-Pliskova-Berberova-le-resume-de-la-journee-du-lundi.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Mezine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"WTA 250 Strasbourg : Dodin, Pliskova, Berberova, le r\u00e9sum\u00e9 de la journ\u00e9e du lundi\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Lbiji13\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/wta-250-strasbourg-dodin-pliskova-berberova-le-resume-de-la-journee-du-lundi\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/wta-250-strasbourg-dodin-pliskova-berberova-le-resume-de-la-journee-du-lundi\/\"},\"author\":{\"name\":\"Nicolas Mezine\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/99fcf31b3ee0d51fed53ade78139bbbf\"},\"headline\":\"WTA 250 Strasbourg : Dodin, Pliskova, Berberova, le r\u00e9sum\u00e9 de la journ\u00e9e du lundi\",\"datePublished\":\"2022-05-16T19:16:32+00:00\",\"dateModified\":\"2022-05-16T19:25:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/wta-250-strasbourg-dodin-pliskova-berberova-le-resume-de-la-journee-du-lundi\/\"},\"wordCount\":963,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/wta-250-strasbourg-dodin-pliskova-berberova-le-resume-de-la-journee-du-lundi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/WTA-250-Strasbourg-Dodin-Pliskova-Berberova-le-resume-de-la-journee-du-lundi.png\",\"keywords\":[\"WTA 250 Strasbourg\"],\"articleSection\":[\"Tennis\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/wta-250-strasbourg-dodin-pliskova-berberova-le-resume-de-la-journee-du-lundi\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/wta-250-strasbourg-dodin-pliskova-berberova-le-resume-de-la-journee-du-lundi\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wta-250-strasbourg-dodin-pliskova-berberova-le-resume-de-la-journee-du-lundi\/\",\"name\":\"Tennis - WTA 250 Strasbourg : Dodin, Pliskova, Berberova, le r\u00e9sum\u00e9 de la journ\u00e9e du lundi - Dicodusport\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/wta-250-strasbourg-dodin-pliskova-berberova-le-resume-de-la-journee-du-lundi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/wta-250-strasbourg-dodin-pliskova-berberova-le-resume-de-la-journee-du-lundi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/WTA-250-Strasbourg-Dodin-Pliskova-Berberova-le-resume-de-la-journee-du-lundi.png\",\"datePublished\":\"2022-05-16T19:16:32+00:00\",\"dateModified\":\"2022-05-16T19:25:29+00:00\",\"description\":\"WTA 250 STRABOURG 2022 - Le r\u00e9sum\u00e9 de la journ\u00e9e du lundi des Internationaux de Strasbourg, avec une grosse surprise ce lundi.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/wta-250-strasbourg-dodin-pliskova-berberova-le-resume-de-la-journee-du-lundi\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/wta-250-strasbourg-dodin-pliskova-berberova-le-resume-de-la-journee-du-lundi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/wta-250-strasbourg-dodin-pliskova-berberova-le-resume-de-la-journee-du-lundi\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/WTA-250-Strasbourg-Dodin-Pliskova-Berberova-le-resume-de-la-journee-du-lundi.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/WTA-250-Strasbourg-Dodin-Pliskova-Berberova-le-resume-de-la-journee-du-lundi.png\",\"width\":800,\"height\":445,\"caption\":\"WTA 250 Strasbourg Dodin, Pliskova, Berberova, le r\u00e9sum\u00e9 de la journ\u00e9e du lundi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/wta-250-strasbourg-dodin-pliskova-berberova-le-resume-de-la-journee-du-lundi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WTA 250 Strasbourg : Dodin, Pliskova, Berberova, le r\u00e9sum\u00e9 de la journ\u00e9e du lundi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/99fcf31b3ee0d51fed53ade78139bbbf\",\"name\":\"Nicolas Mezine\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/IMG_4655-e1631787111223-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/IMG_4655-e1631787111223-150x150.jpg\",\"caption\":\"Nicolas Mezine\"},\"description\":\"Passionn\u00e9 de sport, notamment de rugby dans toutes ses variantes (XV, XIII et VII). Fan du RC Toulon et de l'Olympique de Marseille.\",\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/nicolas-mezine-521380160\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/Lbiji13\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/nicolas-m\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tennis - WTA 250 Strasbourg : Dodin, Pliskova, Berberova, le r\u00e9sum\u00e9 de la journ\u00e9e du lundi - Dicodusport","description":"WTA 250 STRABOURG 2022 - Le r\u00e9sum\u00e9 de la journ\u00e9e du lundi des Internationaux de Strasbourg, avec une grosse surprise ce lundi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/wta-250-strasbourg-dodin-pliskova-berberova-le-resume-de-la-journee-du-lundi\/","og_locale":"fr_FR","og_type":"article","og_title":"WTA 250 Strasbourg : Dodin, Pliskova, Berberova, le r\u00e9sum\u00e9 de la journ\u00e9e du lundi","og_description":"WTA 250 STRABOURG 2022 - Le r\u00e9sum\u00e9 de la journ\u00e9e du lundi des Internationaux de Strasbourg, avec une grosse surprise ce lundi.","og_url":"https:\/\/dicodusport.fr\/blog\/wta-250-strasbourg-dodin-pliskova-berberova-le-resume-de-la-journee-du-lundi\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2022-05-16T19:16:32+00:00","article_modified_time":"2022-05-16T19:25:29+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/WTA-250-Strasbourg-Dodin-Pliskova-Berberova-le-resume-de-la-journee-du-lundi.png","type":"image\/png"}],"author":"Nicolas Mezine","twitter_card":"summary_large_image","twitter_title":"WTA 250 Strasbourg : Dodin, Pliskova, Berberova, le r\u00e9sum\u00e9 de la journ\u00e9e du lundi","twitter_creator":"@https:\/\/twitter.com\/Lbiji13","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/wta-250-strasbourg-dodin-pliskova-berberova-le-resume-de-la-journee-du-lundi\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/wta-250-strasbourg-dodin-pliskova-berberova-le-resume-de-la-journee-du-lundi\/"},"author":{"name":"Nicolas Mezine","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/99fcf31b3ee0d51fed53ade78139bbbf"},"headline":"WTA 250 Strasbourg : Dodin, Pliskova, Berberova, le r\u00e9sum\u00e9 de la journ\u00e9e du lundi","datePublished":"2022-05-16T19:16:32+00:00","dateModified":"2022-05-16T19:25:29+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/wta-250-strasbourg-dodin-pliskova-berberova-le-resume-de-la-journee-du-lundi\/"},"wordCount":963,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/wta-250-strasbourg-dodin-pliskova-berberova-le-resume-de-la-journee-du-lundi\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/WTA-250-Strasbourg-Dodin-Pliskova-Berberova-le-resume-de-la-journee-du-lundi.png","keywords":["WTA 250 Strasbourg"],"articleSection":["Tennis"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/wta-250-strasbourg-dodin-pliskova-berberova-le-resume-de-la-journee-du-lundi\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/wta-250-strasbourg-dodin-pliskova-berberova-le-resume-de-la-journee-du-lundi\/","url":"https:\/\/dicodusport.fr\/blog\/wta-250-strasbourg-dodin-pliskova-berberova-le-resume-de-la-journee-du-lundi\/","name":"Tennis - WTA 250 Strasbourg : Dodin, Pliskova, Berberova, le r\u00e9sum\u00e9 de la journ\u00e9e du lundi - Dicodusport","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/wta-250-strasbourg-dodin-pliskova-berberova-le-resume-de-la-journee-du-lundi\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/wta-250-strasbourg-dodin-pliskova-berberova-le-resume-de-la-journee-du-lundi\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/WTA-250-Strasbourg-Dodin-Pliskova-Berberova-le-resume-de-la-journee-du-lundi.png","datePublished":"2022-05-16T19:16:32+00:00","dateModified":"2022-05-16T19:25:29+00:00","description":"WTA 250 STRABOURG 2022 - Le r\u00e9sum\u00e9 de la journ\u00e9e du lundi des Internationaux de Strasbourg, avec une grosse surprise ce lundi.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/wta-250-strasbourg-dodin-pliskova-berberova-le-resume-de-la-journee-du-lundi\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/wta-250-strasbourg-dodin-pliskova-berberova-le-resume-de-la-journee-du-lundi\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wta-250-strasbourg-dodin-pliskova-berberova-le-resume-de-la-journee-du-lundi\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/WTA-250-Strasbourg-Dodin-Pliskova-Berberova-le-resume-de-la-journee-du-lundi.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/WTA-250-Strasbourg-Dodin-Pliskova-Berberova-le-resume-de-la-journee-du-lundi.png","width":800,"height":445,"caption":"WTA 250 Strasbourg Dodin, Pliskova, Berberova, le r\u00e9sum\u00e9 de la journ\u00e9e du lundi"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/wta-250-strasbourg-dodin-pliskova-berberova-le-resume-de-la-journee-du-lundi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"WTA 250 Strasbourg : Dodin, Pliskova, Berberova, le r\u00e9sum\u00e9 de la journ\u00e9e du lundi"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/99fcf31b3ee0d51fed53ade78139bbbf","name":"Nicolas Mezine","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/IMG_4655-e1631787111223-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/IMG_4655-e1631787111223-150x150.jpg","caption":"Nicolas Mezine"},"description":"Passionn\u00e9 de sport, notamment de rugby dans toutes ses variantes (XV, XIII et VII). Fan du RC Toulon et de l'Olympique de Marseille.","sameAs":["https:\/\/www.linkedin.com\/in\/nicolas-mezine-521380160\/","https:\/\/x.com\/https:\/\/twitter.com\/Lbiji13"],"url":"https:\/\/dicodusport.fr\/blog\/author\/nicolas-m\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/224297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=224297"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/224297\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/224353"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=224297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=224297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=224297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}