{"id":225100,"date":"2022-05-21T08:46:21","date_gmt":"2022-05-21T06:46:21","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=225100"},"modified":"2022-05-21T08:46:21","modified_gmt":"2022-05-21T06:46:21","slug":"boxe-top-5-des-meilleures-categories-a-lheure-actuelle","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/boxe-top-5-des-meilleures-categories-a-lheure-actuelle\/","title":{"rendered":"Boxe : Top 5 des meilleures cat\u00e9gories \u00e0 l&rsquo;heure actuelle"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>BOXE &#8211; Ces derni\u00e8res semaines, les beaux combats de boxe s&rsquo;encha\u00eenent et ravissent les fans. Plusieurs combattants prouvent leur valeur et mettent le feu \u00e0 certaines cat\u00e9gories. Voici le top 5 des cat\u00e9gories les plus relev\u00e9es dans le monde du noble, \u00e0 l&rsquo;heure actuelle.\u00a0<\/strong><\/em><\/p>\n<h2>5. Moyens (-73 kg)<\/h2>\n<p style=\"text-align: justify;\">Historiquement relev\u00e9e, la cat\u00e9gorie des poids moyens couve toujours d\u2019excellents boxeurs. Aujourd\u2019hui, la star de la division qui a connu les <strong>Carlos Monzon<\/strong> ou autres <strong>Marvin Hagler<\/strong> se nomme <strong>Gennady Golovkin<\/strong>. Si le Kazakh commence \u00e0 se faire vieux \u00e0 40 ans, il a tout de m\u00eame prouv\u00e9 qu\u2019il \u00e9tait toujours capable de sortir des grandes performances comme lors de son triomphe face au Japonais <strong>Ryota Murata<\/strong>, l\u2019un des cadors de la division. Ensuite, on notera, bien \u00e9videmment, la pr\u00e9sence des deux champions du monde am\u00e9ricains <a href=\"https:\/\/dicodusport.fr\/blog\/boxe-super-welters-jermell-charlo-champion-inconteste-apres-sa-victoire-face-a-brian-castano\/\"><strong>Jermall Charlo<\/strong><\/a> et <strong>Demetrius Andrade<\/strong>, encore invaincus apr\u00e8s une trentaine de combats pros. Enfin, le Mexicain <strong>Jaime Munguia<\/strong> et le Britannique <strong>Chris Eubank Jr<\/strong>, qui poss\u00e8dent de belles r\u00e9putations, ne sont plus tr\u00e8s loin de saisir l&rsquo;occasion de d\u00e9crocher un titre mondial.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Still got it! &#x1f525;<\/p>\n<p>Gennady Golovkin stops Ryota Murata in round 9 a day after his 40th birthday. <a href=\"https:\/\/t.co\/RJCqBOUtE3\">pic.twitter.com\/RJCqBOUtE3<\/a><\/p>\n<p>\u2014 Boxing on BT Sport &#x1f94a; (@BTSportBoxing) <a href=\"https:\/\/twitter.com\/BTSportBoxing\/status\/1512777792743690243?ref_src=twsrc%5Etfw\">April 9, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2>4. Mi-lourds (-79,4 kg)<\/h2>\n<p style=\"text-align: justify;\">Chez les mi-lourds, la concurrence est rude et la r\u00e9putation de certains pugilistes est d\u00e9j\u00e0 bien \u00e9tablie. R\u00e9cemment, nul autre que le num\u00e9ro un toutes cat\u00e9gories confondues, le Mexicain <strong>Saul<\/strong> <strong>Alvarez<\/strong>, s\u2019y est cass\u00e9 les dents, alors qu\u2019il avait d\u00e9j\u00e0 battu le dangereux <strong>Sergey Kovalev<\/strong> quelques ann\u00e9es auparavant. <a href=\"https:\/\/dicodusport.fr\/blog\/boxe-poids-mi-lourds-dmitry-bivol-renverse-saul-alvarez\/\">Celui-ci qui a cr\u00e9\u00e9 la sensation en faisant tomber le <em>Canelo<\/em>, c\u2019est le Russe<strong> Dmitry Bivol<\/strong><\/a>, qui demeure encore invaincu chez les pros. N\u00e9anmoins, chez les 175 pounds, un autre combattant inspire \u00e9norm\u00e9ment de craintes : <strong>Artur Beterbiev<\/strong>. Invaincu en 17 rencontres, le Russe est parvenu \u00e0 vaincre l&rsquo;int\u00e9gralit\u00e9 de ses adversaires avant la limite ! Mi-juin, il tentera d\u2019unifier les titres WBO, WBC et IBF de la cat\u00e9gorie face \u00e0 l&rsquo;Am\u00e9ricain <strong>Joe Smith Jr<\/strong>, l\u2019une des valeurs sures de la division. Enfin, le Britannique <strong>Callum Smith<\/strong> est r\u00e9cemment mont\u00e9 chez les mi-lourds pour apporter davantage de piment \u00e0 la cat\u00e9gorie.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">C\u2019EST FAIT &#x1f976;<\/p>\n<p>Artur Beterbiev c\u2019est d\u00e9sormais 17 victoires 17 KO\u2019s &#x1f92f; <a href=\"https:\/\/twitter.com\/hashtag\/BeterbievBrowne?src=hash&amp;ref_src=twsrc%5Etfw\">#BeterbievBrowne<\/a><a href=\"https:\/\/t.co\/cVQQnIMSr4\">pic.twitter.com\/cVQQnIMSr4<\/a><\/p>\n<p>\u2014 La Sueur (@LaSueur_off) <a href=\"https:\/\/twitter.com\/LaSueur_off\/status\/1472073174225403910?ref_src=twsrc%5Etfw\">December 18, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2>3. Super-Mouches (-51,7 kg)<\/h2>\n<p style=\"text-align: justify;\">Comme<em> Triple G<\/em>, <em>Chocolatito<\/em> est une l\u00e9gende vieillissante. Toutefois, au m\u00eame titre que le Kazakh, <strong>Roman Gonzalez<\/strong> est encore capable de filer des roustes \u00e0 des jeunes boxeurs prometteurs et ambitieux. Derni\u00e8rement, le Nicaraguayen s\u2019est offert le scalp du Mexicain <strong>Julio Cesar Martinez<\/strong>, que beaucoup voyaient gagner. Quelques autres \u00e9pouvantails sont aussi pr\u00e9sents dans cette division. Premi\u00e8rement, il y a le Mexicain <strong>Juan Francisco Estrada<\/strong>, champion du monde et souvent pr\u00e9sent dans le top 10 <em>pound for pound<\/em> (toutes cat\u00e9gories confondues) des classements r\u00e9f\u00e9rences. Ensuite, on \u00e9voquera le nom du Tha\u00eflandais <strong>Wisaksil Wangek<\/strong>, qui fut le bourreau de <em>Chocolatito<\/em> quelques ann\u00e9es auparavant. Enfin, le Japonais<strong> Kazuko Ioka<\/strong>, champion du monde dans quatre divisions diff\u00e9rentes, fait \u00e9galement office de boxeur d&rsquo;exception.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Chocolatito is putting on a SHOW &#x1f525;<a href=\"https:\/\/twitter.com\/hashtag\/ChocolatitoMartinez?src=hash&amp;ref_src=twsrc%5Etfw\">#ChocolatitoMartinez<\/a> <a href=\"https:\/\/t.co\/9G3vbAONyK\">pic.twitter.com\/9G3vbAONyK<\/a><\/p>\n<p>\u2014 DAZN Boxing (@DAZNBoxing) <a href=\"https:\/\/twitter.com\/DAZNBoxing\/status\/1500338869371379715?ref_src=twsrc%5Etfw\">March 6, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">2. L\u00e9gers (-61,2 kg)<\/h2>\n<p style=\"text-align: justify;\">Dans cette cat\u00e9gorie, il existe une effervescence hors du commun, qui fait qu\u2019elle est fortement suivie par les m\u00e9dias et les fans. Les deux champions du monde vont s\u2019affronter au d\u00e9but du mois de juin. En effet, la star montante de la boxe am\u00e9ricaine <strong>Devin Haney<\/strong> tentera de faire tomber l\u2019Australien <strong>George Kambosos Jr<\/strong>, \u00e0 Melbourne. <a href=\"https:\/\/dicodusport.fr\/blog\/boxe-poids-legers-george-kambosos-jr-renverse-teofimo-lopez\/\">Ce dernier s\u2019est illustr\u00e9 en ravissant tous les titres \u00e0 <strong>Teofimo Lopez<\/strong>, en octobre 2021<\/a>. L\u2019Am\u00e9ricain avait lui-m\u00eame fait tomber l\u2019Ukrainien <strong>Vasyl Lomachenko<\/strong> un an auparavant. Ensuite, le combattant le plus vendeur de cette division est certainement le surpuissant <strong>Gervonta Davis<\/strong>. Derri\u00e8re, il faut aussi compter sur\u00a0 des noms comme <strong>Ryan Garcia<\/strong>,<strong> Isaac Cruz<\/strong>, <strong>Joseph Diaz<\/strong> ou encore <strong>Richard Commey<\/strong>. Enfin, personne n&rsquo;est \u00e0 l&rsquo;abri de voir la jeune p\u00e9pite am\u00e9ricaine <strong>Shakur Stevenson<\/strong> d\u00e9barquer dans cette division. En bref, une division de dingue m\u00eame si l\u2019on souhaiterait que tous ces beaux noms se rencontrent davantage.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">LightWeight :<\/p>\n<p>&#x1f451; George Kambosos Jr.<br \/>\n1&#xfe0f;&#x20e3; Teofimo Lopez<br \/>\n2&#xfe0f;&#x20e3; Vasiliy Lomachenko<br \/>\n3&#xfe0f;&#x20e3; Devin Haney<br \/>\n4&#xfe0f;&#x20e3; Gervonta Davis<br \/>\n5&#xfe0f;&#x20e3; Ryan Garcia<br \/>\n6&#xfe0f;&#x20e3; Isaac Cruz<br \/>\n7&#xfe0f;&#x20e3; Joseph Diaz Jr.<br \/>\n8&#xfe0f;&#x20e3; Richard Commey<br \/>\n9&#xfe0f;&#x20e3; Javier Fortuna<br \/>\n&#x1f51f; William Zepeda &#x1f195;<\/p>\n<p>\u2014 Ring Ratings (@ringp4p) <a href=\"https:\/\/twitter.com\/ringp4p\/status\/1526998981640966144?ref_src=twsrc%5Etfw\">May 18, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2>1. Welters (-66,7 kg)<\/h2>\n<p style=\"text-align: justify;\">Si on met la cat\u00e9gorie des poids welters en premi\u00e8re position, c\u2019est parce que deux des tous meilleurs pugilistes au monde y font leur loi. En effet,<strong> Terence Crawford<\/strong> et <strong>Errol Spence Jr<\/strong> repr\u00e9sentent ce qui se fait de mieux dans le monde du noble art \u00e0 l\u2019heure actuelle. Tous deux champions du monde invaincus, les Am\u00e9ricains ont d\u00fb \u00e9carter de leur chemin des noms comme <strong>Shawn Porter<\/strong>, <strong>Yordenis Ugas<\/strong>, <strong>Kell Brook<\/strong>, <strong>Amir Khan<\/strong>, <strong>Keith Thurman<\/strong>, <strong>Mikey Garcia<\/strong>\u2026 Tout cela t\u00e9moigne bien de la forte \u00e9mulation qui \u00e9mane au sein de cette division. Derri\u00e8re ces deux hommes, des jeunes boxeurs tr\u00e8s talentueux aux dents longues seront bient\u00f4t pr\u00eats \u00e0 devenir les stars de la cat\u00e9gorie. On pense, par exemple, \u00e0 l&rsquo;Am\u00e9ricain <strong>Jaron Ennis<\/strong> ou au Britannique<strong> Conor Benn<\/strong>.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Crawford has his eyes set on becoming the undisputed champ &#x1f624;<\/p>\n<p>(via <a href=\"https:\/\/twitter.com\/ThePorterWayPod?ref_src=twsrc%5Etfw\">@theporterwaypod<\/a>) <a href=\"https:\/\/t.co\/knZgROQRUC\">pic.twitter.com\/knZgROQRUC<\/a><\/p>\n<p>\u2014 ESPN Ringside (@ESPNRingside) <a href=\"https:\/\/twitter.com\/ESPNRingside\/status\/1527369976343998467?ref_src=twsrc%5Etfw\">May 19, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>BOXE &#8211; Voici le top 5 des cat\u00e9gories les plus relev\u00e9es dans le monde du noble art, \u00e0 l&rsquo;heure actuelle.\u00a0 <\/p>\n","protected":false},"author":45,"featured_media":225345,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[8672],"tags":[622,1696],"class_list":["post-225100","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boxe","tag-boxe","tag-boxe-anglaise"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Boxe : Top 5 des meilleures cat\u00e9gories \u00e0 l&#039;heure actuelle<\/title>\n<meta name=\"description\" content=\"BOXE - D\u00e9couvrez notre top 5 des cat\u00e9gories les plus relev\u00e9es dans le monde du noble art, \u00e0 l&#039;heure actuelle.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/boxe-top-5-des-meilleures-categories-a-lheure-actuelle\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Boxe : Top 5 des meilleures cat\u00e9gories \u00e0 l&#039;heure actuelle\" \/>\n<meta property=\"og:description\" content=\"BOXE - D\u00e9couvrez notre top 5 des cat\u00e9gories les plus relev\u00e9es dans le monde du noble art, \u00e0 l&#039;heure actuelle.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/boxe-top-5-des-meilleures-categories-a-lheure-actuelle\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/alexandre.jeffroy.3\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-21T06:46:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Boxe-Top-5-des-meilleures-categories-a-lheure-actuelle.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Alexandre Jeffroy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Boxe : Top 5 des meilleures cat\u00e9gories \u00e0 l&#039;heure actuelle\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/smokinalexjoe\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-top-5-des-meilleures-categories-a-lheure-actuelle\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-top-5-des-meilleures-categories-a-lheure-actuelle\/\"},\"author\":{\"name\":\"Alexandre Jeffroy\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0e50be5ee9a0e6705846ac950257c4a0\"},\"headline\":\"Boxe : Top 5 des meilleures cat\u00e9gories \u00e0 l&rsquo;heure actuelle\",\"datePublished\":\"2022-05-21T06:46:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-top-5-des-meilleures-categories-a-lheure-actuelle\/\"},\"wordCount\":985,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-top-5-des-meilleures-categories-a-lheure-actuelle\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Boxe-Top-5-des-meilleures-categories-a-lheure-actuelle.png\",\"keywords\":[\"boxe\",\"boxe anglaise\"],\"articleSection\":[\"Boxe\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/boxe-top-5-des-meilleures-categories-a-lheure-actuelle\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-top-5-des-meilleures-categories-a-lheure-actuelle\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/boxe-top-5-des-meilleures-categories-a-lheure-actuelle\/\",\"name\":\"Boxe : Top 5 des meilleures cat\u00e9gories \u00e0 l'heure actuelle\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-top-5-des-meilleures-categories-a-lheure-actuelle\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-top-5-des-meilleures-categories-a-lheure-actuelle\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Boxe-Top-5-des-meilleures-categories-a-lheure-actuelle.png\",\"datePublished\":\"2022-05-21T06:46:21+00:00\",\"description\":\"BOXE - D\u00e9couvrez notre top 5 des cat\u00e9gories les plus relev\u00e9es dans le monde du noble art, \u00e0 l'heure actuelle.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-top-5-des-meilleures-categories-a-lheure-actuelle\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/boxe-top-5-des-meilleures-categories-a-lheure-actuelle\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-top-5-des-meilleures-categories-a-lheure-actuelle\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Boxe-Top-5-des-meilleures-categories-a-lheure-actuelle.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Boxe-Top-5-des-meilleures-categories-a-lheure-actuelle.png\",\"width\":800,\"height\":445,\"caption\":\"Boxe Top 5 des meilleures cat\u00e9gories \u00e0 l'heure actuelle\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-top-5-des-meilleures-categories-a-lheure-actuelle\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boxe : Top 5 des meilleures cat\u00e9gories \u00e0 l&rsquo;heure actuelle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0e50be5ee9a0e6705846ac950257c4a0\",\"name\":\"Alexandre Jeffroy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Alexandre-Jeffroy-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Alexandre-Jeffroy-150x150.jpg\",\"caption\":\"Alexandre Jeffroy\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis octobre 2020 - Bolt qui foudroie le record du monde du 100 m\u00e8tres, les derniers essais de Dominici, les premi\u00e8res charges d\u00e9vastatrices de Bastarocket... de beaux souvenirs pour une grande passion, celle du sport. L\u2019histoire du sport aussi. Comprendre le r\u00f4le qu\u2019il a eu, celui qu\u2019il a et celui qu\u2019il aura dans notre soci\u00e9t\u00e9. Le sport au pass\u00e9, au pr\u00e9sent, au futur. Le sport tous les jours, matin, midi et soir. A d\u00e9faut d\u2019\u00eatre un grand sportif, je suis et je raconte l\u2019actualit\u00e9 et l\u2019histoire des championnes et des champions qui savent se d\u00e9passer pour accomplir des merveilles.\",\"sameAs\":[\"https:\/\/www.facebook.com\/alexandre.jeffroy.3\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/smokinalexjoe\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/alexandrejeffroy\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Boxe : Top 5 des meilleures cat\u00e9gories \u00e0 l'heure actuelle","description":"BOXE - D\u00e9couvrez notre top 5 des cat\u00e9gories les plus relev\u00e9es dans le monde du noble art, \u00e0 l'heure actuelle.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/boxe-top-5-des-meilleures-categories-a-lheure-actuelle\/","og_locale":"fr_FR","og_type":"article","og_title":"Boxe : Top 5 des meilleures cat\u00e9gories \u00e0 l'heure actuelle","og_description":"BOXE - D\u00e9couvrez notre top 5 des cat\u00e9gories les plus relev\u00e9es dans le monde du noble art, \u00e0 l'heure actuelle.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/boxe-top-5-des-meilleures-categories-a-lheure-actuelle\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/alexandre.jeffroy.3\/","article_published_time":"2022-05-21T06:46:21+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Boxe-Top-5-des-meilleures-categories-a-lheure-actuelle.png","type":"image\/png"}],"author":"Alexandre Jeffroy","twitter_card":"summary_large_image","twitter_title":"Boxe : Top 5 des meilleures cat\u00e9gories \u00e0 l'heure actuelle","twitter_creator":"@https:\/\/twitter.com\/smokinalexjoe","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/boxe-top-5-des-meilleures-categories-a-lheure-actuelle\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/boxe-top-5-des-meilleures-categories-a-lheure-actuelle\/"},"author":{"name":"Alexandre Jeffroy","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0e50be5ee9a0e6705846ac950257c4a0"},"headline":"Boxe : Top 5 des meilleures cat\u00e9gories \u00e0 l&rsquo;heure actuelle","datePublished":"2022-05-21T06:46:21+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/boxe-top-5-des-meilleures-categories-a-lheure-actuelle\/"},"wordCount":985,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/boxe-top-5-des-meilleures-categories-a-lheure-actuelle\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Boxe-Top-5-des-meilleures-categories-a-lheure-actuelle.png","keywords":["boxe","boxe anglaise"],"articleSection":["Boxe"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/boxe-top-5-des-meilleures-categories-a-lheure-actuelle\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/boxe-top-5-des-meilleures-categories-a-lheure-actuelle\/","url":"https:\/\/dicodusport.fr\/blog\/boxe-top-5-des-meilleures-categories-a-lheure-actuelle\/","name":"Boxe : Top 5 des meilleures cat\u00e9gories \u00e0 l'heure actuelle","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/boxe-top-5-des-meilleures-categories-a-lheure-actuelle\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/boxe-top-5-des-meilleures-categories-a-lheure-actuelle\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Boxe-Top-5-des-meilleures-categories-a-lheure-actuelle.png","datePublished":"2022-05-21T06:46:21+00:00","description":"BOXE - D\u00e9couvrez notre top 5 des cat\u00e9gories les plus relev\u00e9es dans le monde du noble art, \u00e0 l'heure actuelle.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/boxe-top-5-des-meilleures-categories-a-lheure-actuelle\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/boxe-top-5-des-meilleures-categories-a-lheure-actuelle\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/boxe-top-5-des-meilleures-categories-a-lheure-actuelle\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Boxe-Top-5-des-meilleures-categories-a-lheure-actuelle.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Boxe-Top-5-des-meilleures-categories-a-lheure-actuelle.png","width":800,"height":445,"caption":"Boxe Top 5 des meilleures cat\u00e9gories \u00e0 l'heure actuelle"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/boxe-top-5-des-meilleures-categories-a-lheure-actuelle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Boxe : Top 5 des meilleures cat\u00e9gories \u00e0 l&rsquo;heure actuelle"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0e50be5ee9a0e6705846ac950257c4a0","name":"Alexandre Jeffroy","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Alexandre-Jeffroy-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Alexandre-Jeffroy-150x150.jpg","caption":"Alexandre Jeffroy"},"description":"Journaliste\/R\u00e9dacteur depuis octobre 2020 - Bolt qui foudroie le record du monde du 100 m\u00e8tres, les derniers essais de Dominici, les premi\u00e8res charges d\u00e9vastatrices de Bastarocket... de beaux souvenirs pour une grande passion, celle du sport. L\u2019histoire du sport aussi. Comprendre le r\u00f4le qu\u2019il a eu, celui qu\u2019il a et celui qu\u2019il aura dans notre soci\u00e9t\u00e9. Le sport au pass\u00e9, au pr\u00e9sent, au futur. Le sport tous les jours, matin, midi et soir. A d\u00e9faut d\u2019\u00eatre un grand sportif, je suis et je raconte l\u2019actualit\u00e9 et l\u2019histoire des championnes et des champions qui savent se d\u00e9passer pour accomplir des merveilles.","sameAs":["https:\/\/www.facebook.com\/alexandre.jeffroy.3\/","https:\/\/x.com\/https:\/\/twitter.com\/smokinalexjoe"],"url":"https:\/\/dicodusport.fr\/blog\/author\/alexandrejeffroy\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/225100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=225100"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/225100\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/225345"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=225100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=225100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=225100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}