{"id":225343,"date":"2022-05-21T12:34:27","date_gmt":"2022-05-21T10:34:27","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=225343&#038;preview=true&#038;preview_id=225343"},"modified":"2022-05-21T13:32:06","modified_gmt":"2022-05-21T11:32:06","slug":"roland-garros-homme-2022-favoris-joueurs-a-suivre-et-francais-en-lice","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/roland-garros-homme-2022-favoris-joueurs-a-suivre-et-francais-en-lice\/","title":{"rendered":"Roland-Garros hommes 2022 : Favoris, joueurs \u00e0 suivre et Fran\u00e7ais en lice"},"content":{"rendered":"<p style=\"text-align: justify;\"><b><i><a href=\"https:\/\/dicodusport.fr\/blog\/roland-garros-2022-le-tableau-de-simple-hommes\/\">ROLAND-GARROS HOMMES 2022<\/a> &#8211; La guerre des \u00e9toiles aura bien lieu sur la terre battue parisienne. Mais le tirage au sort a d\u00e9livr\u00e9 un haut de tableau impitoyable, dont pourrait bien profiter Stefanos Tsitsipas. Sans leur atout n\u00b01, les Fran\u00e7ais feront leur maximum pour bien figurer.\u00a0<\/i><\/b><\/p>\n<h2>Le favori<\/h2>\n<p style=\"text-align: justify;\">Si on pouvait h\u00e9siter sur la d\u00e9signation d&rsquo;un favori\u00a0 n\u00b01 au vu du pedigree des pr\u00e9tendants, la magie du tirage au sort pourrait bien avoir conf\u00e9r\u00e9 ce statut \u00e0 <strong>Stefanos Tsitsipas.<\/strong> <a href=\"https:\/\/dicodusport.fr\/blog\/novak-djokovic-remporte-roland-garros\/\">Finaliste en titre,<\/a> le Grec effectue une saison extr\u00eamement solide, notamment sur terre battue. <a href=\"https:\/\/dicodusport.fr\/blog\/masters-1000-monte-carlo-stefanos-tsitsipas-conserve-son-titre\/\">Apr\u00e8s avoir conserv\u00e9 son titre \u00e0 Monte-Carlo<\/a>, il est all\u00e9 en demi-finale \u00e0 Madrid, puis en finale \u00e0 Rome. La progression du n\u00b04 mondial est lin\u00e9aire, et il ne lui manque plus qu&rsquo;un Grand Chelem pour valider son entr\u00e9e dans le gotha du tennis mondial. Il faudra n\u00e9anmoins surveiller son premier tour contre le prometteur<strong> Lorenzo Musetti,<\/strong> et son mental, qui lui avait notamment jou\u00e9 des tours en finale l&rsquo;an dernier. Mais beaucoup de voyants sont au vert pour le voir remporter ce Roland-Garros qui s&rsquo;annonce dantesque.<\/p>\n<h2 style=\"text-align: justify;\">Les principaux outsiders<\/h2>\n<p style=\"text-align: justify;\"><strong>Novak Djokovic &#8211; Rafael Nadal<\/strong> et <strong>Alexander Zverev &#8211; Carlos Alcaraz :<\/strong> voici les deux quarts de finale th\u00e9oriques du haut de tableau pour ce Roland-Garros. Si tous ces joueurs pouvaient pr\u00e9tendre au statut de favori, on sait d\u00e9sormais qu&rsquo;un seul aura une chance de rejoindre la finale. <a href=\"https:\/\/dicodusport.fr\/blog\/masters-1000-hommes-de-rome-nouveau-sacre-pour-novak-djokovic\/\">Le Serbe vient de s&rsquo;imposer \u00e0 Rome<\/a>, mais des doutes subsistent sur sa tenue physique lors de matchs en trois sets, m\u00eame si sa saison est ax\u00e9e sur ce tournoi. La remarque s&rsquo;applique encore plus \u00e0 l&rsquo;Espagnol, inqui\u00e9tant <a href=\"https:\/\/dicodusport.fr\/blog\/masters-1000-de-rome-jabeur-nadal-resultats-journee-de-jeudi\/\">par son abandon en Italie,<\/a> et clairement en manque de comp\u00e9tition. Reste \u00e0 savoir si sa hargne et sa combativit\u00e9 suffiront pour lui. <a href=\"https:\/\/dicodusport.fr\/blog\/roland-garros-novak-djokovic-vient-a-bout-de-rafael-nadal-dans-un-match-d-anthologie\/\">Le souvenir de la demi-finale de l&rsquo;an dernier<\/a> entre ces deux monstres est dans toutes les t\u00eates, et l&rsquo;on esp\u00e8re autant de spectacle cette fois encore.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Zoom sur l\u2019\u00e9norme performance du num\u00e9ro un mondial Novak Djokovic, face \u00e0 Rafael Nadal, chez lui, en demi-finale de Roland Garros 2021 &#x1f1f7;&#x1f1f8;&#x1f3be; &#x2b07;&#xfe0f;&#x2b07;&#xfe0f;&#x2b07;&#xfe0f; <a href=\"https:\/\/t.co\/s4M5gsDOjR\">pic.twitter.com\/s4M5gsDOjR<\/a><\/p>\n<p>\u2014 60SecondesTennis (@60SecTennis) <a href=\"https:\/\/twitter.com\/60SecTennis\/status\/1421208295055011842?ref_src=twsrc%5Etfw\">July 30, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\"><strong>Alexander Zverev<\/strong> est r\u00e9gulier sur terre (finale \u00e0 Madrid, demi-finale \u00e0 Monte-Carlo et Rome), mais semble pour l&rsquo;instant encore bloqu\u00e9 pour passer au niveau sup\u00e9rieur. L&rsquo;explosion est attendue depuis des ann\u00e9es, et ce serait une \u00e9norme performance de le voir sortir de ce haut de tableau. Enfin, on attend avec impatience de voir le comportement de <strong>Carlos Alcaraz<\/strong>. Port\u00e9 aux nues depuis ses succ\u00e8s lors des Masters 1000 de <a href=\"https:\/\/dicodusport.fr\/blog\/masters-1000-miami-2022-carlos-alcaraz-bat-casper-ruud-et-remporte-le-titre\/\">Miami<\/a> puis <a href=\"https:\/\/dicodusport.fr\/blog\/masters-1000-masculin-de-madrid-triomphe-a-domicile-pour-carlos-alcaraz\/\">Madrid<\/a>, l&rsquo;Espagnol est un vrai pr\u00e9tendant au titre ici. Mais on ignore encore son comportement sur un Grand Chelem complet, en plus de la densit\u00e9 de son tableau. Sa jeunesse triomphante va se confronter ici a des joueurs \u00e0 l&rsquo;exp\u00e9rience d\u00e9mesur\u00e9e dans les grands chelems, et l&rsquo;on a h\u00e2te de voir le r\u00e9sultat.<\/p>\n<h2>Les joueurs \u00e0 suivre<\/h2>\n<p style=\"text-align: justify;\">Fatalement, il faut regarder dans le bas de tableau pour trouver quelques noms susceptibles de troubler l&rsquo;ordre \u00e9tabli. La pr\u00e9sence du n\u00b02 mondial <strong>Daniil Medvedev<\/strong> dans cette cat\u00e9gorie peut surprendre, mais le Russe vient \u00e0 peine de revenir \u00e0 la comp\u00e9tition, et Roland-Garros est loin d&rsquo;\u00eatre son tournoi pr\u00e9f\u00e9r\u00e9. <strong>Casper Ruud<\/strong> poss\u00e8de un boulevard vers les quarts de finale, o\u00f9 il pourrait retrouver le favori grec, mais il est d\u00e9cevant jusqu&rsquo;ici sur terre. La remarque s&rsquo;applique aussi \u00e0 <strong>Andrey Rublev,<\/strong> qui semble d\u00e9cliner apr\u00e8s un d\u00e9but de saison r\u00e9ussi. Coinc\u00e9s dans la mauvaise partie de tableau, <strong>Diego Schwartzman<\/strong> et <strong>F\u00e9lix Auger-Aliassime<\/strong> devront se surpasser pour franchir les 8\u00e8mes de finale. Les grosses cotes se nomment <strong>Denis Shapovalov,<\/strong> en progr\u00e8s sur la surface, et <strong>Pablo Carreno Busta<\/strong>, digne repr\u00e9sentant de l&rsquo;\u00e9cole espagnole sur terre.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Le tableau masculin de Roland-Garros !<\/p>\n<p>Vos pronostics ? <a href=\"https:\/\/t.co\/p6ahSOKlwu\">pic.twitter.com\/p6ahSOKlwu<\/a><\/p>\n<p>\u2014 Charlotte &#x1f3be; (@MadameTennis) <a href=\"https:\/\/twitter.com\/MadameTennis\/status\/1527347610276986881?ref_src=twsrc%5Etfw\">May 19, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2>Les absents<\/h2>\n<p style=\"text-align: justify;\">Le principal nom manquant ici est <strong>Matteo Berrettini.<\/strong> L&rsquo;Italien a tout tent\u00e9 pour \u00eatre pr\u00e9sent, mais n&rsquo;a pu r\u00e9cup\u00e9rer de sa blessure \u00e0 la main. Toujours dangereux sur la surface, <strong>Roberto Bautista Agut<\/strong> ne sera pas pr\u00e9sent \u00e0 Paris. Comme on s&rsquo;y attendait, <strong>Andy Murray<\/strong> a fait l&rsquo;impasse sur le tournoi. Bien \u00e9videmment, <strong>Roger Federer<\/strong> n&rsquo;est toujours pas pr\u00e9sent, m\u00eame si les derni\u00e8res informations donnent de l&rsquo;espoir sur un prochain retour. Enfin, la d\u00e9ception est immense c\u00f4t\u00e9 Fran\u00e7ais avec le forfait de <strong>Ga\u00ebl Monfils,<\/strong> insuffisamment remis de sa blessure au pied.<\/p>\n<h2>Les Fran\u00e7ais<\/h2>\n<p style=\"text-align: justify;\">L&rsquo;absence du n\u00b01 Fran\u00e7ais a ruin\u00e9 les espoirs tricolores d&rsquo;avoir une t\u00eate de s\u00e9rie \u00e0 Roland-Garros. Le Fran\u00e7ais le mieux class\u00e9 se nomme <strong>Ugo Humbert,<\/strong> mais sa saison est loin d&rsquo;\u00eatre \u00e0 la hauteur. <strong>Benjamin Bonzi<\/strong> aura d&rsquo;entr\u00e9e un test int\u00e9ressant contre <strong>Frances Tiafoe<\/strong>, surprenant sur la surface r\u00e9cemment. Le souvenir du parcours d&rsquo;<strong>Hugo Gaston<\/strong> \u00e0 Roland-Garros en 2020 devrait malheureusement se heurter d&rsquo;entr\u00e9e de jeu \u00e0 <strong>Alex de Minaur<\/strong>, bien sup\u00e9rieur sur le papier. \u00c0 voir si le Bleu arrive une nouvelle fois \u00e0 se transcender. <strong>Beno\u00eet Paire<\/strong>, attaquera contre <strong>Ilya Ivashka<\/strong>, avec pour objectif d&rsquo;aller retrouver <strong>Andrey Rublev<\/strong> au troisi\u00e8me tour.<\/p>\n<p style=\"text-align: justify;\">Les autres Fran\u00e7ais disposent de chances secondaires. <strong>Quentin Halys<\/strong> aura toutefois une belle opportunit\u00e9 contre <strong>John Isner<\/strong>, tout sauf sp\u00e9cialiste de terre. Invit\u00e9, <strong>Gr\u00e9goire Barr\u00e8re<\/strong> sera en danger contre <strong>Taro Daniel. Manuel Guinard,<\/strong> pour son premier Grand Chelem, devrait subir la loi de <strong>Cameron Norrie,<\/strong> 11\u00e8me mondial. <strong>Lucas Pouille<\/strong> aura la chance d&rsquo;affronter le qualifi\u00e9 <strong>Zdenek Kolar,<\/strong> mais sa pr\u00e9sence au second tour n&rsquo;est pas pour autant garantie. <strong>Adrian Mannarino<\/strong> a malheureusement h\u00e9rit\u00e9 de <strong>Federico Delbonis,<\/strong> sp\u00e9cialiste de la surface. <strong>Arthur Rinderknech<\/strong>, lui, aura une opportunit\u00e9 contre <strong>Alexander Bublik<\/strong>, alors que <a href=\"https:\/\/dicodusport.fr\/blog\/qualifications-roland-garros-geoffrey-blancaneaux-seul-elu-tricolore\/\">le seul Fran\u00e7ais issu des qualifications,<\/a> <strong>Geoffrey Blancaneaux<\/strong>, s&rsquo;en sort bien au tirage avec <strong>Marton Fucsovics<\/strong>.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Geoffrey Blancaneaux qualifi\u00e9 pour le grand tableau \u00e0 <a href=\"https:\/\/twitter.com\/hashtag\/RolandGarros?src=hash&amp;ref_src=twsrc%5Etfw\">#RolandGarros<\/a> &#x1f525;<\/p>\n<p>Titr\u00e9 \u00e0 Roland Garros junior en 2016 face \u00e0 Auger-Aliassime, il n&rsquo;avait JAMAIS r\u00e9ussi \u00e0 atteindre le tableau principal chez les pros.<\/p>\n<p>R\u00eave r\u00e9alis\u00e9, il sera le seul fran\u00e7ais issu des qualifs \u00e0 l&rsquo;int\u00e9grer &#x1f1e8;&#x1f1f5;&#x1f44f; <a href=\"https:\/\/t.co\/AtLik5QpOO\">pic.twitter.com\/AtLik5QpOO<\/a><\/p>\n<p>\u2014 Univers Tennis &#x1f3be; (@UniversTennis) <a href=\"https:\/\/twitter.com\/UniversTennis\/status\/1527673377703485442?ref_src=twsrc%5Etfw\">May 20, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Lui aussi b\u00e9n\u00e9ficiaire d&rsquo;une invitation, <strong>Corentin Moutet<\/strong> aura l&rsquo;honneur d&rsquo;affronter le revenant <strong>Stan Wawrinka<\/strong>. Revenu \u00e0 un bon niveau sur terre battue, <strong>Richard Gasquet<\/strong> devra se m\u00e9fier de <strong>Lloyd Harris,<\/strong> en retrait r\u00e9cemment cependant. Enfin, pour leur dernier Roland-Garros, <strong>Gilles Simon<\/strong> et <strong>Jo-Wilfried Tsonga<\/strong> ont \u00e9t\u00e9 g\u00e2t\u00e9s. Le premier d\u00e9fiera <strong>Pablo Carreno Busta<\/strong>, alors que le second a h\u00e9rit\u00e9 de <strong>Casper Rudd.<\/strong> Sans doute pour des matchs en night session, pour des adieux \u00e0 la hauteur de leur immense carri\u00e8re.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROLAND-GARROS HOMMES 2022 &#8211; La guerre des \u00e9toiles aura bien lieu sur la terre battue Parisienne. Mais le tirage au sort a d\u00e9livr\u00e9 un haut de tableau impitoyable, dont pourrait bien profiter Stefanos Tsitsipas. Sans leur atout n\u00b01, les Fran\u00e7ais feront leur maximum pour bien figurer.\u00a0<\/p>\n","protected":false},"author":59,"featured_media":225361,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[47090],"tags":[24,4693,136],"class_list":["post-225343","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-roland-garros","tag-sport","tag-stefanos-tsitsipas","tag-tennis"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>- Roland-Garros hommes 2022 : Favoris, joueurs \u00e0 suivre et Fran\u00e7ais en lice - Dicodusport<\/title>\n<meta name=\"description\" content=\"ROLAND-GARROS HOMEMES 2022 - Le tirage au sort a d\u00e9livr\u00e9 un haut de tableau impitoyable, dont pourrait bien profiter Stefanos Tsitsipas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/roland-garros-homme-2022-favoris-joueurs-a-suivre-et-francais-en-lice\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Roland-Garros hommes 2022 : Favoris, joueurs \u00e0 suivre et Fran\u00e7ais en lice\" \/>\n<meta property=\"og:description\" content=\"ROLAND-GARROS HOMEMES 2022 - Le tirage au sort a d\u00e9livr\u00e9 un haut de tableau impitoyable, dont pourrait bien profiter Stefanos Tsitsipas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/roland-garros-homme-2022-favoris-joueurs-a-suivre-et-francais-en-lice\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-21T10:34:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-21T11:32:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Roland-Garros-Homme-2022-Favoris-joueurs-a-suivre-et-Francais-en-lice.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Roland-Garros hommes 2022 : Favoris, joueurs \u00e0 suivre et Fran\u00e7ais en lice\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-homme-2022-favoris-joueurs-a-suivre-et-francais-en-lice\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-homme-2022-favoris-joueurs-a-suivre-et-francais-en-lice\\\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Roland-Garros hommes 2022 : Favoris, joueurs \u00e0 suivre et Fran\u00e7ais en lice\",\"datePublished\":\"2022-05-21T10:34:27+00:00\",\"dateModified\":\"2022-05-21T11:32:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-homme-2022-favoris-joueurs-a-suivre-et-francais-en-lice\\\/\"},\"wordCount\":1207,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-homme-2022-favoris-joueurs-a-suivre-et-francais-en-lice\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Roland-Garros-Homme-2022-Favoris-joueurs-a-suivre-et-Francais-en-lice.png\",\"keywords\":[\"sport\",\"Stefanos Tsitsipas\",\"Tennis\"],\"articleSection\":[\"Roland-Garros\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-homme-2022-favoris-joueurs-a-suivre-et-francais-en-lice\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-homme-2022-favoris-joueurs-a-suivre-et-francais-en-lice\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-homme-2022-favoris-joueurs-a-suivre-et-francais-en-lice\\\/\",\"name\":\"- Roland-Garros hommes 2022 : Favoris, joueurs \u00e0 suivre et Fran\u00e7ais en lice - Dicodusport\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-homme-2022-favoris-joueurs-a-suivre-et-francais-en-lice\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-homme-2022-favoris-joueurs-a-suivre-et-francais-en-lice\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Roland-Garros-Homme-2022-Favoris-joueurs-a-suivre-et-Francais-en-lice.png\",\"datePublished\":\"2022-05-21T10:34:27+00:00\",\"dateModified\":\"2022-05-21T11:32:06+00:00\",\"description\":\"ROLAND-GARROS HOMEMES 2022 - Le tirage au sort a d\u00e9livr\u00e9 un haut de tableau impitoyable, dont pourrait bien profiter Stefanos Tsitsipas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-homme-2022-favoris-joueurs-a-suivre-et-francais-en-lice\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-homme-2022-favoris-joueurs-a-suivre-et-francais-en-lice\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-homme-2022-favoris-joueurs-a-suivre-et-francais-en-lice\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Roland-Garros-Homme-2022-Favoris-joueurs-a-suivre-et-Francais-en-lice.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Roland-Garros-Homme-2022-Favoris-joueurs-a-suivre-et-Francais-en-lice.png\",\"width\":800,\"height\":445,\"caption\":\"Roland-Garros Homme 2022 Favoris, joueurs \u00e0 suivre et Fran\u00e7ais en lice\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-homme-2022-favoris-joueurs-a-suivre-et-francais-en-lice\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Roland-Garros hommes 2022 : Favoris, joueurs \u00e0 suivre et Fran\u00e7ais en lice\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sebastien.gente\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sebgente\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/sbastien-gente-a29583169\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sebastiengente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"- Roland-Garros hommes 2022 : Favoris, joueurs \u00e0 suivre et Fran\u00e7ais en lice - Dicodusport","description":"ROLAND-GARROS HOMEMES 2022 - Le tirage au sort a d\u00e9livr\u00e9 un haut de tableau impitoyable, dont pourrait bien profiter Stefanos Tsitsipas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/roland-garros-homme-2022-favoris-joueurs-a-suivre-et-francais-en-lice\/","og_locale":"fr_FR","og_type":"article","og_title":"Roland-Garros hommes 2022 : Favoris, joueurs \u00e0 suivre et Fran\u00e7ais en lice","og_description":"ROLAND-GARROS HOMEMES 2022 - Le tirage au sort a d\u00e9livr\u00e9 un haut de tableau impitoyable, dont pourrait bien profiter Stefanos Tsitsipas.","og_url":"https:\/\/dicodusport.fr\/blog\/roland-garros-homme-2022-favoris-joueurs-a-suivre-et-francais-en-lice\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2022-05-21T10:34:27+00:00","article_modified_time":"2022-05-21T11:32:06+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Roland-Garros-Homme-2022-Favoris-joueurs-a-suivre-et-Francais-en-lice.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Roland-Garros hommes 2022 : Favoris, joueurs \u00e0 suivre et Fran\u00e7ais en lice","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-homme-2022-favoris-joueurs-a-suivre-et-francais-en-lice\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-homme-2022-favoris-joueurs-a-suivre-et-francais-en-lice\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Roland-Garros hommes 2022 : Favoris, joueurs \u00e0 suivre et Fran\u00e7ais en lice","datePublished":"2022-05-21T10:34:27+00:00","dateModified":"2022-05-21T11:32:06+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-homme-2022-favoris-joueurs-a-suivre-et-francais-en-lice\/"},"wordCount":1207,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-homme-2022-favoris-joueurs-a-suivre-et-francais-en-lice\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Roland-Garros-Homme-2022-Favoris-joueurs-a-suivre-et-Francais-en-lice.png","keywords":["sport","Stefanos Tsitsipas","Tennis"],"articleSection":["Roland-Garros"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/roland-garros-homme-2022-favoris-joueurs-a-suivre-et-francais-en-lice\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-homme-2022-favoris-joueurs-a-suivre-et-francais-en-lice\/","url":"https:\/\/dicodusport.fr\/blog\/roland-garros-homme-2022-favoris-joueurs-a-suivre-et-francais-en-lice\/","name":"- Roland-Garros hommes 2022 : Favoris, joueurs \u00e0 suivre et Fran\u00e7ais en lice - Dicodusport","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-homme-2022-favoris-joueurs-a-suivre-et-francais-en-lice\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-homme-2022-favoris-joueurs-a-suivre-et-francais-en-lice\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Roland-Garros-Homme-2022-Favoris-joueurs-a-suivre-et-Francais-en-lice.png","datePublished":"2022-05-21T10:34:27+00:00","dateModified":"2022-05-21T11:32:06+00:00","description":"ROLAND-GARROS HOMEMES 2022 - Le tirage au sort a d\u00e9livr\u00e9 un haut de tableau impitoyable, dont pourrait bien profiter Stefanos Tsitsipas.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-homme-2022-favoris-joueurs-a-suivre-et-francais-en-lice\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/roland-garros-homme-2022-favoris-joueurs-a-suivre-et-francais-en-lice\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-homme-2022-favoris-joueurs-a-suivre-et-francais-en-lice\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Roland-Garros-Homme-2022-Favoris-joueurs-a-suivre-et-Francais-en-lice.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Roland-Garros-Homme-2022-Favoris-joueurs-a-suivre-et-Francais-en-lice.png","width":800,"height":445,"caption":"Roland-Garros Homme 2022 Favoris, joueurs \u00e0 suivre et Fran\u00e7ais en lice"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-homme-2022-favoris-joueurs-a-suivre-et-francais-en-lice\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Roland-Garros hommes 2022 : Favoris, joueurs \u00e0 suivre et Fran\u00e7ais en lice"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/225343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=225343"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/225343\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/225361"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=225343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=225343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=225343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}