{"id":227324,"date":"2022-05-28T10:30:49","date_gmt":"2022-05-28T08:30:49","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=227324"},"modified":"2022-05-28T09:43:09","modified_gmt":"2022-05-28T07:43:09","slug":"boxe-poids-legers-la-machine-gervonta-davis-est-de-sortie-ce-week-end","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/boxe-poids-legers-la-machine-gervonta-davis-est-de-sortie-ce-week-end\/","title":{"rendered":"Boxe Poids l\u00e9gers : La machine Gervonta Davis est de sortie ce week-end"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>BOXE POIDS L\u00c9GERS &#8211; Dans la nuit de samedi \u00e0 dimanche, la star am\u00e9ricaine Gervonta Davis sera pr\u00e9sente sur le ring du Barclays Center, \u00e0 Brooklyn, pour d\u00e9fendre sa ceinture WBA int\u00e9rimaire des poids l\u00e9gers. Tank, l&rsquo;un des plus gros vendeurs de spectacle au monde, fera face \u00e0 son compatriote Rolando Romero.\u00a0<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">\u00c0 chaque fois que <strong>Gervonta Davis<\/strong> s&rsquo;appr\u00eate \u00e0 disputer un combat, un l\u00e9ger frisson parcours le monde de la boxe. En effet, l&rsquo;Am\u00e9ricain est un pugiliste spectaculaire et ses KO font souvent le tour du monde. A 27 ans, il totalise 26 combats professionnels pour 26 victoires, dont 24 avant la limite ! Pourtant, \u00e0 la poursuite d&rsquo;un titre de champion du monde et d&rsquo;un nom prestigieux \u00e0 afficher \u00e0 son palmar\u00e8s, il doit se contenter d&rsquo;affronter <strong>Rolando Romero<\/strong>, un boxeur puissant, mais encore inexp\u00e9riment\u00e9.<\/p>\n<h2 style=\"text-align: justify;\">Gervonta Davis veut guider sa carri\u00e8re<\/h2>\n<p style=\"text-align: justify;\">C&rsquo;est ce que l&rsquo;on peut reprocher \u00e0 Gervonta Davis. En effet, \u00e0 27 ans, <em>Tank<\/em> poss\u00e8de un beau bilan au niveau professionnel, mais les noms qu&rsquo;il a affich\u00e9s \u00e0 son palmar\u00e8s manquent encore de prestige. Alors que des combattants comme <strong>Vasyl Lomanchenko<\/strong>, <strong>Teofimo Lopez<\/strong>,<strong> Devin Haney<\/strong> ou encore <strong>George Kambosos<\/strong> se rencontrent pour jouer les ceintures mondiales, Davis n&rsquo;a pas encore b\u00e9n\u00e9fici\u00e9 de chance pour un titre mondial. Une chose qui risque de changer apr\u00e8s son combat de samedi ?<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Week end prochain retour de Gervonta Davis face \u00e0 Rolando Romero. Vos pronostics pour ce combat ? <a href=\"https:\/\/twitter.com\/hashtag\/DavisRomero?src=hash&amp;ref_src=twsrc%5Etfw\">#DavisRomero<\/a> <a href=\"https:\/\/t.co\/xTsJD4tPuS\">pic.twitter.com\/xTsJD4tPuS<\/a><\/p>\n<p>\u2014 Just&rsquo;Boxe (@justboxe) <a href=\"https:\/\/twitter.com\/justboxe\/status\/1527924756837765120?ref_src=twsrc%5Etfw\">May 21, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">On peut bien se poser la question puisque sa situation va sans doute \u00e9voluer. Effectivement, le combat face \u00e0 Romero devrait \u00eatre la derni\u00e8re affiche mise sur pied par <em>Mayweather Promotions<\/em>. Apr\u00e8s cela, Gervonta Davis devrait se s\u00e9parer de la l\u00e9gende am\u00e9ricaine <strong>Floyd Mayweather<\/strong>. \u00ab <em>C\u2019est ma carri\u00e8re et je pense avoir besoin d\u2019\u00eatre le seul \u00e0 la contr\u00f4ler. C\u2019est le moment !<\/em> \u00bb R\u00e9cemment, Gervonta Davis a m\u00eame d\u00e9fi\u00e9 le champion du monde WBC <strong>Devin Haney<\/strong>, qui s&rsquo;appr\u00eate \u00e0 disputer un combat d&rsquo;unification totale pour les titres des poids l\u00e9gers face \u00e0 <strong>George Kambosos<\/strong>.<\/p>\n<h2 style=\"text-align: justify;\">Romero peut-il \u00eatre une menace ?<\/h2>\n<p style=\"text-align: justify;\">On le sait, Gervonta Davis est une machine, aussi bien sur le plan \u00e9conomique que sur le ring. Pourtant, il ressort d&rsquo;une prestation tr\u00e8s compliqu\u00e9e face \u00e0 <strong>Isaac Cruz<\/strong>, en d\u00e9cembre dernier. En effet, le Mexicain avait pos\u00e9 beaucoup de probl\u00e8mes \u00e0 l&rsquo;Am\u00e9ricain et, chose rare dans les combats de <em>Tank<\/em>, la partie est all\u00e9e au terme des douze rounds. Samedi, il aura l&rsquo;Am\u00e9ricain <strong>Rolando Romero<\/strong> face \u00e0 lui. A 26 ans, <em>Rolly<\/em> a disput\u00e9 14 combats pros. Il est encore invaincu et s&rsquo;est impos\u00e9 \u00e0 douze reprises avant la limite. <em>BoxRec<\/em> le classe dix-neuvi\u00e8me de son classement chez les 135 pounds (-61,2 kg). Toutefois, peut-il vraiment \u00eatre une menace pour la fausse patte originaire de Baltimore ?<\/p>\n<p style=\"text-align: justify;\">Romero est catalogu\u00e9 comme un puncheur. N\u00e9anmoins, il semble beaucoup moins exp\u00e9riment\u00e9 qu&rsquo;<strong>Isaac Cruz<\/strong>, qui a pos\u00e9 des probl\u00e8mes \u00e0 Davis, et pourrait se montrer vuln\u00e9rable face \u00e0 ce dernier. Cependant, il s&rsquo;est loin d&rsquo;\u00eatre favori, l&rsquo;homme du Nevada affiche une \u00e9norme confiance dans ses discours. \u00ab <em>Je vais le mettre KO en un seul round. Il sera mis KO avec le premier coup qu\u2019il prendra. Je n\u2019aime pas Tank en tant que personne, et je pense qu\u2019il va se faire cogner durant ce combat.\u00a0<\/em>\u00bb On n&rsquo;\u00e9voquera pas les nombreuses provocations lanc\u00e9es \u00e0 son homologue, depuis que l&rsquo;affiche a \u00e9t\u00e9 officialis\u00e9e, mais on peut dire que Romero fait ce qu&rsquo;il faut pour tenter d&rsquo;exister aupr\u00e8s d&rsquo;une star comme Gervonta Davis.<\/p>\n<h2 style=\"text-align: justify;\">Le plus gros vendeur des USA<\/h2>\n<p style=\"text-align: justify;\">Moins bavard, Davis a tout de m\u00eame r\u00e9agi \u00e0 toutes ces provocations dans la semaine. \u00ab<em> Des gens sont capables de r\u00e9aliser ces choses-l\u00e0 et d\u2019autres sont justes capables d\u2019en parler. \u00bb <\/em>Pour illustrer l&rsquo;affrontement qui va avoir lieu, le champion int\u00e9rimaire WBA a m\u00eame parl\u00e9 d&rsquo;un \u00ab <em>massacre<\/em> \u00bb. Malgr\u00e9 la confiance affich\u00e9e par Romero, Davis est largement favori et le match semble d\u00e9s\u00e9quilibr\u00e9. Pourtant, ce duel va bien faire recette puisque <em>Tank<\/em> est le plus gros vendeur des \u00c9tats-Unis parmi les boxeurs du monde entier. La forte probabilit\u00e9 de voir un KO spectaculaire semble plaire aux fans.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Pes\u00e9e &#x2705; et face \u00e0 face finale &#x1f525;<\/p>\n<p>Gervonta Davis : 60,6kg<br \/>\nRolando Romero : 60,8kg<\/p>\n<p>Rendez vous demain soir pour le combat &#x1f94a;<a href=\"https:\/\/twitter.com\/hashtag\/DavisRomero?src=hash&amp;ref_src=twsrc%5Etfw\">#DavisRomero<\/a> <a href=\"https:\/\/t.co\/qn87GrpFPX\">pic.twitter.com\/qn87GrpFPX<\/a><\/p>\n<p>\u2014 Just&rsquo;Boxe (@justboxe) <a href=\"https:\/\/twitter.com\/justboxe\/status\/1530229820797296641?ref_src=twsrc%5Etfw\">May 27, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>BOXE POIDS L\u00c9GERS &#8211; Dans la nuit de samedi \u00e0 dimanche, la star am\u00e9ricaine Gervonta Davis sera pr\u00e9sente sur le ring du Barclays Center, \u00e0 Brooklyn, pour d\u00e9fendre sa ceinture WBA int\u00e9rimaire des poids l\u00e9gers. Tank, l&rsquo;un des plus gros vendeurs de spectacle au monde, fera face \u00e0 son compatriote Rolando Romero.\u00a0<\/p>\n","protected":false},"author":45,"featured_media":227384,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[8672],"tags":[1696,16283,20653],"class_list":["post-227324","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boxe","tag-boxe-anglaise","tag-boxe-poids-legers","tag-gervonta-davis"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Boxe Poids l\u00e9gers : La machine Gervonta Davis est de sortie ce week-end<\/title>\n<meta name=\"description\" content=\"Dans la nuit de samedi \u00e0 dimanche, Gervonta Davis d\u00e9fendra sa ceinture WBA int\u00e9rimaire des poids l\u00e9gers face \u00e0 Rolando Romero.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/boxe-poids-legers-la-machine-gervonta-davis-est-de-sortie-ce-week-end\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Boxe Poids l\u00e9gers : La machine Gervonta Davis est de sortie ce week-end\" \/>\n<meta property=\"og:description\" content=\"Dans la nuit de samedi \u00e0 dimanche, Gervonta Davis d\u00e9fendra sa ceinture WBA int\u00e9rimaire des poids l\u00e9gers face \u00e0 Rolando Romero.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/boxe-poids-legers-la-machine-gervonta-davis-est-de-sortie-ce-week-end\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/alexandre.jeffroy.3\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-28T08:30:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Boxe-Poids-legers-La-machine-Gervonta-Davis-est-de-sortie-ce-week-end.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Alexandre Jeffroy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Boxe Poids l\u00e9gers : La machine Gervonta Davis est de sortie ce week-end\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/smokinalexjoe\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-poids-legers-la-machine-gervonta-davis-est-de-sortie-ce-week-end\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-poids-legers-la-machine-gervonta-davis-est-de-sortie-ce-week-end\/\"},\"author\":{\"name\":\"Alexandre Jeffroy\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0e50be5ee9a0e6705846ac950257c4a0\"},\"headline\":\"Boxe Poids l\u00e9gers : La machine Gervonta Davis est de sortie ce week-end\",\"datePublished\":\"2022-05-28T08:30:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-poids-legers-la-machine-gervonta-davis-est-de-sortie-ce-week-end\/\"},\"wordCount\":785,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-poids-legers-la-machine-gervonta-davis-est-de-sortie-ce-week-end\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Boxe-Poids-legers-La-machine-Gervonta-Davis-est-de-sortie-ce-week-end.png\",\"keywords\":[\"boxe anglaise\",\"boxe poids l\u00e9gers\",\"Gervonta Davis\"],\"articleSection\":[\"Boxe\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/boxe-poids-legers-la-machine-gervonta-davis-est-de-sortie-ce-week-end\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-poids-legers-la-machine-gervonta-davis-est-de-sortie-ce-week-end\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/boxe-poids-legers-la-machine-gervonta-davis-est-de-sortie-ce-week-end\/\",\"name\":\"Boxe Poids l\u00e9gers : La machine Gervonta Davis est de sortie ce week-end\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-poids-legers-la-machine-gervonta-davis-est-de-sortie-ce-week-end\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-poids-legers-la-machine-gervonta-davis-est-de-sortie-ce-week-end\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Boxe-Poids-legers-La-machine-Gervonta-Davis-est-de-sortie-ce-week-end.png\",\"datePublished\":\"2022-05-28T08:30:49+00:00\",\"description\":\"Dans la nuit de samedi \u00e0 dimanche, Gervonta Davis d\u00e9fendra sa ceinture WBA int\u00e9rimaire des poids l\u00e9gers face \u00e0 Rolando Romero.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-poids-legers-la-machine-gervonta-davis-est-de-sortie-ce-week-end\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/boxe-poids-legers-la-machine-gervonta-davis-est-de-sortie-ce-week-end\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-poids-legers-la-machine-gervonta-davis-est-de-sortie-ce-week-end\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Boxe-Poids-legers-La-machine-Gervonta-Davis-est-de-sortie-ce-week-end.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Boxe-Poids-legers-La-machine-Gervonta-Davis-est-de-sortie-ce-week-end.png\",\"width\":800,\"height\":445,\"caption\":\"Boxe Poids l\u00e9gers La machine Gervonta Davis est de sortie ce week-end\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-poids-legers-la-machine-gervonta-davis-est-de-sortie-ce-week-end\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boxe Poids l\u00e9gers : La machine Gervonta Davis est de sortie ce week-end\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0e50be5ee9a0e6705846ac950257c4a0\",\"name\":\"Alexandre Jeffroy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Alexandre-Jeffroy-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Alexandre-Jeffroy-150x150.jpg\",\"caption\":\"Alexandre Jeffroy\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis octobre 2020 - Bolt qui foudroie le record du monde du 100 m\u00e8tres, les derniers essais de Dominici, les premi\u00e8res charges d\u00e9vastatrices de Bastarocket... de beaux souvenirs pour une grande passion, celle du sport. L\u2019histoire du sport aussi. Comprendre le r\u00f4le qu\u2019il a eu, celui qu\u2019il a et celui qu\u2019il aura dans notre soci\u00e9t\u00e9. Le sport au pass\u00e9, au pr\u00e9sent, au futur. Le sport tous les jours, matin, midi et soir. A d\u00e9faut d\u2019\u00eatre un grand sportif, je suis et je raconte l\u2019actualit\u00e9 et l\u2019histoire des championnes et des champions qui savent se d\u00e9passer pour accomplir des merveilles.\",\"sameAs\":[\"https:\/\/www.facebook.com\/alexandre.jeffroy.3\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/smokinalexjoe\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/alexandrejeffroy\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Boxe Poids l\u00e9gers : La machine Gervonta Davis est de sortie ce week-end","description":"Dans la nuit de samedi \u00e0 dimanche, Gervonta Davis d\u00e9fendra sa ceinture WBA int\u00e9rimaire des poids l\u00e9gers face \u00e0 Rolando Romero.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/boxe-poids-legers-la-machine-gervonta-davis-est-de-sortie-ce-week-end\/","og_locale":"fr_FR","og_type":"article","og_title":"Boxe Poids l\u00e9gers : La machine Gervonta Davis est de sortie ce week-end","og_description":"Dans la nuit de samedi \u00e0 dimanche, Gervonta Davis d\u00e9fendra sa ceinture WBA int\u00e9rimaire des poids l\u00e9gers face \u00e0 Rolando Romero.","og_url":"https:\/\/dicodusport.fr\/blog\/boxe-poids-legers-la-machine-gervonta-davis-est-de-sortie-ce-week-end\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/alexandre.jeffroy.3\/","article_published_time":"2022-05-28T08:30:49+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Boxe-Poids-legers-La-machine-Gervonta-Davis-est-de-sortie-ce-week-end.png","type":"image\/png"}],"author":"Alexandre Jeffroy","twitter_card":"summary_large_image","twitter_title":"Boxe Poids l\u00e9gers : La machine Gervonta Davis est de sortie ce week-end","twitter_creator":"@https:\/\/twitter.com\/smokinalexjoe","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/boxe-poids-legers-la-machine-gervonta-davis-est-de-sortie-ce-week-end\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/boxe-poids-legers-la-machine-gervonta-davis-est-de-sortie-ce-week-end\/"},"author":{"name":"Alexandre Jeffroy","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0e50be5ee9a0e6705846ac950257c4a0"},"headline":"Boxe Poids l\u00e9gers : La machine Gervonta Davis est de sortie ce week-end","datePublished":"2022-05-28T08:30:49+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/boxe-poids-legers-la-machine-gervonta-davis-est-de-sortie-ce-week-end\/"},"wordCount":785,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/boxe-poids-legers-la-machine-gervonta-davis-est-de-sortie-ce-week-end\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Boxe-Poids-legers-La-machine-Gervonta-Davis-est-de-sortie-ce-week-end.png","keywords":["boxe anglaise","boxe poids l\u00e9gers","Gervonta Davis"],"articleSection":["Boxe"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/boxe-poids-legers-la-machine-gervonta-davis-est-de-sortie-ce-week-end\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/boxe-poids-legers-la-machine-gervonta-davis-est-de-sortie-ce-week-end\/","url":"https:\/\/dicodusport.fr\/blog\/boxe-poids-legers-la-machine-gervonta-davis-est-de-sortie-ce-week-end\/","name":"Boxe Poids l\u00e9gers : La machine Gervonta Davis est de sortie ce week-end","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/boxe-poids-legers-la-machine-gervonta-davis-est-de-sortie-ce-week-end\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/boxe-poids-legers-la-machine-gervonta-davis-est-de-sortie-ce-week-end\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Boxe-Poids-legers-La-machine-Gervonta-Davis-est-de-sortie-ce-week-end.png","datePublished":"2022-05-28T08:30:49+00:00","description":"Dans la nuit de samedi \u00e0 dimanche, Gervonta Davis d\u00e9fendra sa ceinture WBA int\u00e9rimaire des poids l\u00e9gers face \u00e0 Rolando Romero.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/boxe-poids-legers-la-machine-gervonta-davis-est-de-sortie-ce-week-end\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/boxe-poids-legers-la-machine-gervonta-davis-est-de-sortie-ce-week-end\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/boxe-poids-legers-la-machine-gervonta-davis-est-de-sortie-ce-week-end\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Boxe-Poids-legers-La-machine-Gervonta-Davis-est-de-sortie-ce-week-end.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Boxe-Poids-legers-La-machine-Gervonta-Davis-est-de-sortie-ce-week-end.png","width":800,"height":445,"caption":"Boxe Poids l\u00e9gers La machine Gervonta Davis est de sortie ce week-end"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/boxe-poids-legers-la-machine-gervonta-davis-est-de-sortie-ce-week-end\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Boxe Poids l\u00e9gers : La machine Gervonta Davis est de sortie ce week-end"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0e50be5ee9a0e6705846ac950257c4a0","name":"Alexandre Jeffroy","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Alexandre-Jeffroy-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Alexandre-Jeffroy-150x150.jpg","caption":"Alexandre Jeffroy"},"description":"Journaliste\/R\u00e9dacteur depuis octobre 2020 - Bolt qui foudroie le record du monde du 100 m\u00e8tres, les derniers essais de Dominici, les premi\u00e8res charges d\u00e9vastatrices de Bastarocket... de beaux souvenirs pour une grande passion, celle du sport. L\u2019histoire du sport aussi. Comprendre le r\u00f4le qu\u2019il a eu, celui qu\u2019il a et celui qu\u2019il aura dans notre soci\u00e9t\u00e9. Le sport au pass\u00e9, au pr\u00e9sent, au futur. Le sport tous les jours, matin, midi et soir. A d\u00e9faut d\u2019\u00eatre un grand sportif, je suis et je raconte l\u2019actualit\u00e9 et l\u2019histoire des championnes et des champions qui savent se d\u00e9passer pour accomplir des merveilles.","sameAs":["https:\/\/www.facebook.com\/alexandre.jeffroy.3\/","https:\/\/x.com\/https:\/\/twitter.com\/smokinalexjoe"],"url":"https:\/\/dicodusport.fr\/blog\/author\/alexandrejeffroy\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/227324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=227324"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/227324\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/227384"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=227324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=227324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=227324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}