{"id":228381,"date":"2022-05-31T09:23:40","date_gmt":"2022-05-31T07:23:40","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=228381&#038;preview=true&#038;preview_id=228381"},"modified":"2022-05-31T12:23:10","modified_gmt":"2022-05-31T10:23:10","slug":"betclic-elite-le-bilan-des-quarts-de-finale","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/betclic-elite-le-bilan-des-quarts-de-finale\/","title":{"rendered":"Betclic \u00c9lite : Le bilan des quarts de finale"},"content":{"rendered":"<p style=\"text-align: justify;\"><b><i>BETCLIC \u00c9LITE &#8211; Les grands favoris ont eu tr\u00e8s chaud lors des quarts de finale, puisque l&rsquo;ASVEL et Monaco ont fr\u00f4l\u00e9 l&rsquo;\u00e9limination et ont d\u00fb passer par un match d&rsquo;appui. Dijon et Pau-Orthez, de leur c\u00f4t\u00e9, ont \u00e9t\u00e9 impressionnants.<\/i><\/b><\/p>\n<p style=\"text-align: justify;\">Monaco a \u00e9t\u00e9 la derni\u00e8re \u00e9quipe \u00e0 se qualifier pour les demi-finales de Betclic \u00c9lite en s&rsquo;imposant contre Strasbourg hier soir. Mais dieu que\u00a0 ce fut dur ! Largement domin\u00e9s lors du match 1 \u00e0 domicile, ils ont renvers\u00e9 la situation lors des deux matchs suivants, tous deux remport\u00e9s apr\u00e8s prolongations. Le match 2, sensationnel, porte le sceau de <strong>Mike James<\/strong>. Absent au match 1, le meneur am\u00e9ricain a livr\u00e9 une performance sensationnelle (30 points + le tir de la victoire) avant de rentrer le tir pour aller en prolongation au match 3 (24 points). Monaco a eu tr\u00e8s chaud, mais se qualifie au forceps en demi-finale. Battue \u00e0 ce stade l&rsquo;an dernier, la Roca Team tentera de franchir cette \u00e9tape face \u00e0 Pau-Orthez.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">&#x1f631; \u00c9GALISATION PUIS GAME WINNER &#x1f631;<\/p>\n<p>LA FIN DE MATCH LA PLUS INCROYABLE DE LA SAISON !<a href=\"https:\/\/twitter.com\/hashtag\/PlayoffsBetclicELITE?src=hash&amp;ref_src=twsrc%5Etfw\">#PlayoffsBetclicELITE<\/a> <a href=\"https:\/\/t.co\/t7lSjgxhZy\">pic.twitter.com\/t7lSjgxhZy<\/a><\/p>\n<p>\u2014 LNB (@LNBofficiel) <a href=\"https:\/\/twitter.com\/LNBofficiel\/status\/1530573753733656577?ref_src=twsrc%5Etfw\">May 28, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Les Palois, seulement sixi\u00e8mes de la saison r\u00e9guli\u00e8re, ont r\u00e9alis\u00e9 un tour de force en sortant Boulogne-Levallois en deux manches. Ils sont all\u00e9s dominer le match 1 de 17 points dans la salle adverse, puis ont boucl\u00e9 l&rsquo;affaire \u00e0 la maison sans v\u00e9ritablement trembler &#8211; leurs adversaires n&rsquo;auront jamais men\u00e9 au score durant la rencontre. Discret au match 1, <strong>Brandon Jefferson<\/strong>, meilleur marqueur de la saison r\u00e9guli\u00e8re, a port\u00e9 l&rsquo;estocade \u00e0 domicile (28 points). Boulogne-Levallois n&rsquo;aura jamais \u00e9t\u00e9 dans le coup, et peut maudire son adresse \u00e0 3 points (29% sur la s\u00e9rie). <a href=\"https:\/\/dicodusport.fr\/blog\/basket-coupe-de-france-sixieme-sacre-pour-elan-bearnais-pau-lacq-orthez\/\">Vainqueur de la Coupe de France en avril,<\/a> Pau-Orthez est toujours en course pour un doubl\u00e9 qui serait une monstrueuse surprise.<\/p>\n<h2 style=\"text-align: justify;\">L&rsquo;ASVEL a d\u00fb cravacher<\/h2>\n<p style=\"text-align: justify;\">La stup\u00e9faction \u00e9tait totale quand l&rsquo;ASVEL, n\u00b01 de la saison r\u00e9guli\u00e8re, s&rsquo;\u00e9tait inclin\u00e9e au match 1 \u00e0 domicile contre Cholet, qualifi\u00e9 de justesse pour ces quart de finale de Betclic \u00c9lite. Les Villeurbannais ont r\u00e9agi en allant largement s&rsquo;imposer dans le Maine et Loire pour \u00e9galiser \u00e0 1-1. Mais ils ont fr\u00f4l\u00e9 la correctionnelle lors du match d&rsquo;appui dimanche \u00e0 l&rsquo;Astroballe. Alors qu&rsquo;ils menaient de 11 points en milieu de dernier quart-temps, ils ont laiss\u00e9 les Choletais, men\u00e9s par un excellent <strong>Yoan Makoundou<\/strong> (20 points \u00e0 7\/10), revenir sur leurs talons en fin de match. A l&rsquo;arriv\u00e9e, un succ\u00e8s <strong>84-82<\/strong> \u00e0 l&rsquo;arrach\u00e9e, une place en demi-finales et la possibilit\u00e9 de conserver leur titre. Mais il faudra pour cela se d\u00e9barrasser de surprenants Dijonnais.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">&#x1f51e; OH LA VIOLENCE DE JAMES GIST !<a href=\"https:\/\/twitter.com\/hashtag\/PlayoffsBetclicELITE?src=hash&amp;ref_src=twsrc%5Etfw\">#PlayoffsBetclicELITE<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/LNBextra?src=hash&amp;ref_src=twsrc%5Etfw\">#LNBextra<\/a> <a href=\"https:\/\/t.co\/g0vsJmJZEf\">pic.twitter.com\/g0vsJmJZEf<\/a><\/p>\n<p>\u2014 LNB (@LNBofficiel) <a href=\"https:\/\/twitter.com\/LNBofficiel\/status\/1530985248124637184?ref_src=twsrc%5Etfw\">May 29, 2022<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">N\u00b01 de la saison r\u00e9guli\u00e8re en 2020\/2021, Dijon avait \u00e9chou\u00e9 en finale contre l&rsquo;ASVEL. L&rsquo;occasion leur est donn\u00e9e de prendre leur revanche, apr\u00e8s une s\u00e9rie \u00e0 deux visages contre le CSP Limoges. Les Bourguignons sont all\u00e9s s&rsquo;imposer de 24 points dans la salle limousine au match 1, gr\u00e2ce \u00e0 <strong>45.5%<\/strong> de r\u00e9ussite \u00e0 3 points et 18 pertes de balle adverses. Mais l&rsquo;affaire a \u00e9t\u00e9 tout autre \u00e0 domicile, puisque les Limougeauds se sont accroch\u00e9s jusqu&rsquo;au bout. Dijon a finalement emport\u00e9 la d\u00e9cision sur un ultime shoot de <strong>Simon Chase<\/strong>. Une belle performance pour les Dijonnais, seulement cinqui\u00e8mes de la saison r\u00e9guli\u00e8re. Troisi\u00e8me qualification d&rsquo;affil\u00e9e en demi-finale pour la JDA Dijon, qui sera outsider contre l&rsquo;ASVEL. Un statut qui semble lui aller \u00e0 merveille.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BETCLIC \u00c9LITE &#8211; Les grands favoris ont eu tr\u00e8s chaud lors des quarts de finale, puisque l&rsquo;ASVEL et Monaco ont fr\u00f4l\u00e9 l&rsquo;\u00e9limination et ont d\u00fb passer par un match d&rsquo;appui. Dijon et Pau-Orthez, de leur c\u00f4t\u00e9, ont \u00e9t\u00e9 impressionnants.<\/p>\n","protected":false},"author":59,"featured_media":228399,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[46998],"tags":[7864,19698,21350],"class_list":["post-228381","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-betclic-elite","tag-asvel","tag-jda-dijon","tag-monaco-basket"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>- Betclic \u00c9lite : Le bilan des quarts de finale - Dicodusport<\/title>\n<meta name=\"description\" content=\"BETCLIC \u00c9LITE - L&#039;ASVEL et Monaco ont fr\u00f4l\u00e9 l&#039;\u00e9limination et ont d\u00fb passer par un match d&#039;appui, contrairement \u00e0 Dijon et Pau-Orthez.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/betclic-elite-le-bilan-des-quarts-de-finale\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Betclic \u00c9lite : Le bilan des quarts de finale\" \/>\n<meta property=\"og:description\" content=\"BETCLIC \u00c9LITE - L&#039;ASVEL et Monaco ont fr\u00f4l\u00e9 l&#039;\u00e9limination et ont d\u00fb passer par un match d&#039;appui, contrairement \u00e0 Dijon et Pau-Orthez.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/betclic-elite-le-bilan-des-quarts-de-finale\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-31T07:23:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-31T10:23:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Betclic-Elite-Le-bilan-des-quarts-de-finale.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Betclic \u00c9lite : Le bilan des quarts de finale\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-le-bilan-des-quarts-de-finale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-le-bilan-des-quarts-de-finale\\\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Betclic \u00c9lite : Le bilan des quarts de finale\",\"datePublished\":\"2022-05-31T07:23:40+00:00\",\"dateModified\":\"2022-05-31T10:23:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-le-bilan-des-quarts-de-finale\\\/\"},\"wordCount\":610,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-le-bilan-des-quarts-de-finale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Betclic-Elite-Le-bilan-des-quarts-de-finale.png\",\"keywords\":[\"ASVEL\",\"JDA Dijon\",\"Monaco basket\"],\"articleSection\":[\"Betclic \u00c9lite\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-le-bilan-des-quarts-de-finale\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-le-bilan-des-quarts-de-finale\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-le-bilan-des-quarts-de-finale\\\/\",\"name\":\"- Betclic \u00c9lite : Le bilan des quarts de finale - Dicodusport\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-le-bilan-des-quarts-de-finale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-le-bilan-des-quarts-de-finale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Betclic-Elite-Le-bilan-des-quarts-de-finale.png\",\"datePublished\":\"2022-05-31T07:23:40+00:00\",\"dateModified\":\"2022-05-31T10:23:10+00:00\",\"description\":\"BETCLIC \u00c9LITE - L'ASVEL et Monaco ont fr\u00f4l\u00e9 l'\u00e9limination et ont d\u00fb passer par un match d'appui, contrairement \u00e0 Dijon et Pau-Orthez.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-le-bilan-des-quarts-de-finale\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-le-bilan-des-quarts-de-finale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-le-bilan-des-quarts-de-finale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Betclic-Elite-Le-bilan-des-quarts-de-finale.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Betclic-Elite-Le-bilan-des-quarts-de-finale.png\",\"width\":800,\"height\":445,\"caption\":\"Betclic \u00c9lite Le bilan des quarts de finale\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-le-bilan-des-quarts-de-finale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Betclic \u00c9lite : Le bilan des quarts de finale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sebastien.gente\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sebgente\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/sbastien-gente-a29583169\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sebastiengente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"- Betclic \u00c9lite : Le bilan des quarts de finale - Dicodusport","description":"BETCLIC \u00c9LITE - L'ASVEL et Monaco ont fr\u00f4l\u00e9 l'\u00e9limination et ont d\u00fb passer par un match d'appui, contrairement \u00e0 Dijon et Pau-Orthez.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/betclic-elite-le-bilan-des-quarts-de-finale\/","og_locale":"fr_FR","og_type":"article","og_title":"Betclic \u00c9lite : Le bilan des quarts de finale","og_description":"BETCLIC \u00c9LITE - L'ASVEL et Monaco ont fr\u00f4l\u00e9 l'\u00e9limination et ont d\u00fb passer par un match d'appui, contrairement \u00e0 Dijon et Pau-Orthez.","og_url":"https:\/\/dicodusport.fr\/blog\/betclic-elite-le-bilan-des-quarts-de-finale\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2022-05-31T07:23:40+00:00","article_modified_time":"2022-05-31T10:23:10+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Betclic-Elite-Le-bilan-des-quarts-de-finale.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Betclic \u00c9lite : Le bilan des quarts de finale","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-le-bilan-des-quarts-de-finale\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-le-bilan-des-quarts-de-finale\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Betclic \u00c9lite : Le bilan des quarts de finale","datePublished":"2022-05-31T07:23:40+00:00","dateModified":"2022-05-31T10:23:10+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-le-bilan-des-quarts-de-finale\/"},"wordCount":610,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-le-bilan-des-quarts-de-finale\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Betclic-Elite-Le-bilan-des-quarts-de-finale.png","keywords":["ASVEL","JDA Dijon","Monaco basket"],"articleSection":["Betclic \u00c9lite"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/betclic-elite-le-bilan-des-quarts-de-finale\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-le-bilan-des-quarts-de-finale\/","url":"https:\/\/dicodusport.fr\/blog\/betclic-elite-le-bilan-des-quarts-de-finale\/","name":"- Betclic \u00c9lite : Le bilan des quarts de finale - Dicodusport","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-le-bilan-des-quarts-de-finale\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-le-bilan-des-quarts-de-finale\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Betclic-Elite-Le-bilan-des-quarts-de-finale.png","datePublished":"2022-05-31T07:23:40+00:00","dateModified":"2022-05-31T10:23:10+00:00","description":"BETCLIC \u00c9LITE - L'ASVEL et Monaco ont fr\u00f4l\u00e9 l'\u00e9limination et ont d\u00fb passer par un match d'appui, contrairement \u00e0 Dijon et Pau-Orthez.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-le-bilan-des-quarts-de-finale\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/betclic-elite-le-bilan-des-quarts-de-finale\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-le-bilan-des-quarts-de-finale\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Betclic-Elite-Le-bilan-des-quarts-de-finale.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/05\/Betclic-Elite-Le-bilan-des-quarts-de-finale.png","width":800,"height":445,"caption":"Betclic \u00c9lite Le bilan des quarts de finale"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-le-bilan-des-quarts-de-finale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Betclic \u00c9lite : Le bilan des quarts de finale"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/228381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=228381"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/228381\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/228399"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=228381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=228381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=228381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}