{"id":228951,"date":"2022-06-02T16:14:54","date_gmt":"2022-06-02T14:14:54","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=228951&#038;preview=true&#038;preview_id=228951"},"modified":"2022-06-02T16:38:57","modified_gmt":"2022-06-02T14:38:57","slug":"roland-garros-2022-iga-swiatek-se-qualifie-facilement-en-finale","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/roland-garros-2022-iga-swiatek-se-qualifie-facilement-en-finale\/","title":{"rendered":"Roland-Garros 2022 : Iga Swiatek se qualifie facilement en finale"},"content":{"rendered":"<p style=\"text-align: justify;\"><i><a style=\"font-weight: bold;\" href=\"https:\/\/dicodusport.fr\/blog\/roland-garros-2022-le-tableau-de-simple-femmes\/\">ROLAND-GARROS FEMMES 2022<\/a><b> &#8211; Sans sourciller, la n\u00b01 mondiale, Iga Swiatek, a \u00e9cart\u00e9 la Russe Daria Kasatkina en deux manches et se qualifie pour la finale, sa deuxi\u00e8me en trois ans. Ce 34\u00e8me succ\u00e8s cons\u00e9cutif la place en position de force pour la finale.\u00a0<\/b><\/i><\/p>\n<p style=\"text-align: justify;\"><strong>Iga Swiatek<\/strong> n&rsquo;\u00e9tait plus qu&rsquo;a deux marches d&rsquo;un deuxi\u00e8me succ\u00e8s \u00e0 Roland-Garros en trois ans. Si elle a parfois sembl\u00e9 emprunt\u00e9e, <a href=\"https:\/\/dicodusport.fr\/blog\/roland-garros-2022-iga-swiatek-en-demi-finales-avec-un-33eme-succes-consecutif\/\">comme hier face \u00e0 <strong>Jessica Pegula<\/strong>,<\/a> elle semble disposer d&rsquo;une \u00e9norme marge sur le reste de la concurrence. Deux succ\u00e8s qui lui permettraient d&rsquo;\u00e9galer la meilleure s\u00e9rie de victoires depuis 2000 (<strong>35<\/strong>), d\u00e9tenue par <strong>Venus Williams<\/strong>. Mais <strong>Daria Kasatkina<\/strong> n&rsquo;allait certainement pas se pr\u00e9senter en victime expiatoire. N\u00e9anmoins, la Russe, <a href=\"https:\/\/dicodusport.fr\/blog\/roland-garros-2022-daria-kasatkina-en-demi-finales-sans-trembler\/\">convaincante hier,<\/a> avait le d\u00e9savantage d&rsquo;effectuer sa premi\u00e8re apparition \u00e0 ce niveau de comp\u00e9tition en Grand Chelem.<\/p>\n<h2 style=\"text-align: justify;\">La machine Swiatek<\/h2>\n<p style=\"text-align: justify;\">La Russe paie cher cette inexp\u00e9rience en conc\u00e9dant d&rsquo;entr\u00e9e un jeu de service qu&rsquo;elle avait pourtant en main. Cependant, <strong>Iga Swiatek<\/strong> n&rsquo;est pas transcendante depuis trois matchs et conc\u00e8de le d\u00e9break imm\u00e9diatement. Le niveau de jeu tarde \u00e0 monter, les deux joueuses commettant beaucoup plus de fautes qu&rsquo;\u00e0 l&rsquo;accoutum\u00e9e. Mais m\u00eame sans \u00eatre \u00e0 son meilleur niveau, la Polonaise garde un ascendant qui fait que l&rsquo;adversaire doit jouer impeccablement bien pour avoir une chance.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">&#x1f44f; Le d\u00e9break de Kasatkina !<br \/>\n&#x1f4a5; Daria Kasatkina r\u00e9alise le d\u00e9break en prenant Swiatek \u00e0 contre-pied<br \/>\n&#x25b6;&#xfe0f; Le DIRECT : <a href=\"https:\/\/t.co\/hUXLdjAQjC\">https:\/\/t.co\/hUXLdjAQjC<\/a> <a href=\"https:\/\/t.co\/of9nS2Rl8z\">pic.twitter.com\/of9nS2Rl8z<\/a><\/p>\n<p>\u2014 francetvsport (@francetvsport) <a href=\"https:\/\/twitter.com\/francetvsport\/status\/1532353729357283331?ref_src=twsrc%5Etfw\">June 2, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Ce qui n&rsquo;est pas forc\u00e9ment le cas de<strong> Daria Kasatkina<\/strong> dans cette premi\u00e8re manche, o\u00f9 elle commet 15 fautes directes. La n\u00b01 mondiale prend \u00e0 nouveau le service adverse au 6\u00e8me jeu, break cette fois confirm\u00e9. Men\u00e9e<strong> 5-2<\/strong>, la Russe s&rsquo;effondre, et conc\u00e8de \u00e0 nouveau son engagement, cette fois sur un jeu blanc. Elle c\u00e8de le set <strong>6-2<\/strong> en 35 minutes et perd son premier set dans ce Roland-Garros.<\/p>\n<h2 style=\"text-align: justify;\">Implacable Swiatek<\/h2>\n<p style=\"text-align: justify;\"><strong>Daria Kasatkina<\/strong> n&rsquo;est pourtant pas ridicule dans ce match. Mais le d\u00e9ficit de puissance dont elle souffre est probl\u00e9matique. Elle compense en jouant le contre-pied, ou en tentant de faire bouger la Polonaise. Mais elle peine \u00e0 menacer cette derni\u00e8re sur son engagement, et doit se battre pour conserver le sien, \u00e0 cause d&rsquo;une deuxi\u00e8me balle trop faible. In\u00e9luctablement, elle c\u00e8de son service au quatri\u00e8me jeu, break confirm\u00e9 par la Polonaise qui m\u00e8ne alors <strong>4-1<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Compl\u00e8tement r\u00e9sign\u00e9e, la Russe renonce et c\u00e8de \u00e0 nouveau son service blanc, laissant la n\u00b01 mondiale servir pour le match. Chose faite sans coup f\u00e9rir par <strong>Iga Swiatek,<\/strong> qui l&#8217;emporte donc <strong>6-2, 6-1<\/strong> en \u00e0 peine plus d&rsquo;une heure. Un succ\u00e8s implacable, le 34\u00e8me d&rsquo;affil\u00e9e, pour la Polonaise, qui sera la grandissime favorite de la finale samedi (15h). Que ce soit <strong>Coco Gauff<\/strong> ou <strong>Martina Trevisan<\/strong> en finale, son adversaire devra jouer au-del\u00e0 de son meilleur niveau pour avoir ne serait-ce qu&rsquo;une chance.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">SWIATEK EN FINALE<\/p>\n<p>La n\u00b01 \u00e9trille Kasatkina et jouera sa deuxi\u00e8me finale en Grand Chelem. Avec 34 victoires cons\u00e9cutives, elle \u00e9gale la deuxi\u00e8me plus grosse s\u00e9rie de victoires depuis les ann\u00e9es 2000 (Serena Williams) &#x2728;&#xfe0f;<\/p>\n<p>Plus qu&rsquo;une victoire pour son deuxi\u00e8me <a href=\"https:\/\/twitter.com\/hashtag\/RolandGarros?src=hash&amp;ref_src=twsrc%5Etfw\">#RolandGarros<\/a> &#x1f31f;&#x1f31f; <a href=\"https:\/\/t.co\/M1QsFf3eUC\">pic.twitter.com\/M1QsFf3eUC<\/a><\/p>\n<p>\u2014 Univers Tennis &#x1f3be; (@UniversTennis) <a href=\"https:\/\/twitter.com\/UniversTennis\/status\/1532365066833625088?ref_src=twsrc%5Etfw\">June 2, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROLAND-GARROS FEMMES 2022 &#8211; Sans sourciller, la n\u00b01 mondiale a \u00e9cart\u00e9 la Russe Daria Kasatkina en deux manches et se qualifie pour la finale, sa deuxi\u00e8me en trois ans. Ce 34\u00e8me succ\u00e8s cons\u00e9cutif la place en position de force pour la finale.\u00a0<\/p>\n","protected":false},"author":59,"featured_media":229016,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[47090],"tags":[4189,8022,23618,24],"class_list":["post-228951","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-roland-garros","tag-daria-kasatkina","tag-iga-swiatek","tag-roland-garros-femmes","tag-sport"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Roland-Garros 2022 : Iga Swiatek se qualifie facilement en finale<\/title>\n<meta name=\"description\" content=\"ROLAND-GARROS FEMMES 2022 - Sans sourciller, la n\u00b01 mondiale a \u00e9cart\u00e9 la Russe Daria Kasatkina en deux manches et se qualifie pour la finale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/roland-garros-2022-iga-swiatek-se-qualifie-facilement-en-finale\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Roland-Garros 2022 : Iga Swiatek se qualifie facilement en finale\" \/>\n<meta property=\"og:description\" content=\"ROLAND-GARROS FEMMES 2022 - Sans sourciller, la n\u00b01 mondiale a \u00e9cart\u00e9 la Russe Daria Kasatkina en deux manches et se qualifie pour la finale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/roland-garros-2022-iga-swiatek-se-qualifie-facilement-en-finale\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-02T14:14:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-02T14:38:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Roland-Garros-2022-Iga-Swiatek-se-qualifie-facilement-en-finale.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Roland-Garros 2022 : Iga Swiatek se qualifie facilement en finale\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2022-iga-swiatek-se-qualifie-facilement-en-finale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2022-iga-swiatek-se-qualifie-facilement-en-finale\\\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Roland-Garros 2022 : Iga Swiatek se qualifie facilement en finale\",\"datePublished\":\"2022-06-02T14:14:54+00:00\",\"dateModified\":\"2022-06-02T14:38:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2022-iga-swiatek-se-qualifie-facilement-en-finale\\\/\"},\"wordCount\":602,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2022-iga-swiatek-se-qualifie-facilement-en-finale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Roland-Garros-2022-Iga-Swiatek-se-qualifie-facilement-en-finale.png\",\"keywords\":[\"Daria Kasatkina\",\"Iga Swiatek\",\"Roland-Garros femmes\",\"sport\"],\"articleSection\":[\"Roland-Garros\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2022-iga-swiatek-se-qualifie-facilement-en-finale\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2022-iga-swiatek-se-qualifie-facilement-en-finale\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2022-iga-swiatek-se-qualifie-facilement-en-finale\\\/\",\"name\":\"Roland-Garros 2022 : Iga Swiatek se qualifie facilement en finale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2022-iga-swiatek-se-qualifie-facilement-en-finale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2022-iga-swiatek-se-qualifie-facilement-en-finale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Roland-Garros-2022-Iga-Swiatek-se-qualifie-facilement-en-finale.png\",\"datePublished\":\"2022-06-02T14:14:54+00:00\",\"dateModified\":\"2022-06-02T14:38:57+00:00\",\"description\":\"ROLAND-GARROS FEMMES 2022 - Sans sourciller, la n\u00b01 mondiale a \u00e9cart\u00e9 la Russe Daria Kasatkina en deux manches et se qualifie pour la finale.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2022-iga-swiatek-se-qualifie-facilement-en-finale\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2022-iga-swiatek-se-qualifie-facilement-en-finale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2022-iga-swiatek-se-qualifie-facilement-en-finale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Roland-Garros-2022-Iga-Swiatek-se-qualifie-facilement-en-finale.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Roland-Garros-2022-Iga-Swiatek-se-qualifie-facilement-en-finale.png\",\"width\":800,\"height\":445,\"caption\":\"Roland-Garros 2022 Iga Swiatek se qualifie facilement en finale\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2022-iga-swiatek-se-qualifie-facilement-en-finale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Roland-Garros 2022 : Iga Swiatek se qualifie facilement en finale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sebastien.gente\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sebgente\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/sbastien-gente-a29583169\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sebastiengente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Roland-Garros 2022 : Iga Swiatek se qualifie facilement en finale","description":"ROLAND-GARROS FEMMES 2022 - Sans sourciller, la n\u00b01 mondiale a \u00e9cart\u00e9 la Russe Daria Kasatkina en deux manches et se qualifie pour la finale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/roland-garros-2022-iga-swiatek-se-qualifie-facilement-en-finale\/","og_locale":"fr_FR","og_type":"article","og_title":"Roland-Garros 2022 : Iga Swiatek se qualifie facilement en finale","og_description":"ROLAND-GARROS FEMMES 2022 - Sans sourciller, la n\u00b01 mondiale a \u00e9cart\u00e9 la Russe Daria Kasatkina en deux manches et se qualifie pour la finale.","og_url":"https:\/\/dicodusport.fr\/blog\/roland-garros-2022-iga-swiatek-se-qualifie-facilement-en-finale\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2022-06-02T14:14:54+00:00","article_modified_time":"2022-06-02T14:38:57+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Roland-Garros-2022-Iga-Swiatek-se-qualifie-facilement-en-finale.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Roland-Garros 2022 : Iga Swiatek se qualifie facilement en finale","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2022-iga-swiatek-se-qualifie-facilement-en-finale\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2022-iga-swiatek-se-qualifie-facilement-en-finale\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Roland-Garros 2022 : Iga Swiatek se qualifie facilement en finale","datePublished":"2022-06-02T14:14:54+00:00","dateModified":"2022-06-02T14:38:57+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2022-iga-swiatek-se-qualifie-facilement-en-finale\/"},"wordCount":602,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2022-iga-swiatek-se-qualifie-facilement-en-finale\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Roland-Garros-2022-Iga-Swiatek-se-qualifie-facilement-en-finale.png","keywords":["Daria Kasatkina","Iga Swiatek","Roland-Garros femmes","sport"],"articleSection":["Roland-Garros"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/roland-garros-2022-iga-swiatek-se-qualifie-facilement-en-finale\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2022-iga-swiatek-se-qualifie-facilement-en-finale\/","url":"https:\/\/dicodusport.fr\/blog\/roland-garros-2022-iga-swiatek-se-qualifie-facilement-en-finale\/","name":"Roland-Garros 2022 : Iga Swiatek se qualifie facilement en finale","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2022-iga-swiatek-se-qualifie-facilement-en-finale\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2022-iga-swiatek-se-qualifie-facilement-en-finale\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Roland-Garros-2022-Iga-Swiatek-se-qualifie-facilement-en-finale.png","datePublished":"2022-06-02T14:14:54+00:00","dateModified":"2022-06-02T14:38:57+00:00","description":"ROLAND-GARROS FEMMES 2022 - Sans sourciller, la n\u00b01 mondiale a \u00e9cart\u00e9 la Russe Daria Kasatkina en deux manches et se qualifie pour la finale.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2022-iga-swiatek-se-qualifie-facilement-en-finale\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/roland-garros-2022-iga-swiatek-se-qualifie-facilement-en-finale\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2022-iga-swiatek-se-qualifie-facilement-en-finale\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Roland-Garros-2022-Iga-Swiatek-se-qualifie-facilement-en-finale.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Roland-Garros-2022-Iga-Swiatek-se-qualifie-facilement-en-finale.png","width":800,"height":445,"caption":"Roland-Garros 2022 Iga Swiatek se qualifie facilement en finale"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2022-iga-swiatek-se-qualifie-facilement-en-finale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Roland-Garros 2022 : Iga Swiatek se qualifie facilement en finale"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/228951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=228951"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/228951\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/229016"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=228951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=228951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=228951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}