{"id":229306,"date":"2022-06-03T15:41:43","date_gmt":"2022-06-03T13:41:43","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=229306&#038;preview=true&#038;preview_id=229306"},"modified":"2022-06-05T16:57:41","modified_gmt":"2022-06-05T14:57:41","slug":"ronde-de-l-oise-2022-classement-2eme-etape","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/ronde-de-l-oise-2022-classement-2eme-etape\/","title":{"rendered":"Ronde de l&rsquo;Oise 2022 &#8211; Classement 2\u00e8me \u00e9tape"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/cyclisme\/cyclisme-sur-route-2022\/\">CYCLISME SUR ROUTE 2022<\/a> &#8211; D\u00e9couvrez le classement de la 2\u00e8me \u00e9tape (top 20) de la Ronde de l&rsquo;Oise 2022, disput\u00e9e ce vendredi 3 juin 2022 entre <span class=\"red\">Le Plessis-Belleville et <\/span><span class=\"red\">Rib\u00e9court Dreslincourt <\/span><span class=\"red fw400\">(199 km).<\/span><\/strong><\/em><\/p>\n<div class=\"su-table su-table-alternate\">\n<table style=\"width: 800px;border-collapse: collapse\" border=\"1\">\n<tbody>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\">&#x1f3c6;<\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>COUREURS<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>TEMPS \/ \u00c9CART<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">1.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong><strong style=\"font-size: 14.4px\">&#x1f1f5;&#x1f1f9;<\/strong> IURI LEITAO<br \/>\n<\/strong><span style=\"font-size: 0.8em\">CAJA RURAL &#8211; SEGUROS RGA<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>4h48m45s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">2.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><strong style=\"font-size: 14.4px\"><span style=\"font-size: 0.9em\"><strong>&#x1f1eb;&#x1f1f7;<\/strong><\/span> JASON TESSON<\/strong><br style=\"font-size: 14.4px\" \/><span style=\"font-size: 0.8em\">ST MICHEL &#8211; AUBER93<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">3.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>&#x1f1eb;&#x1f1f7; VALENTIN TABELLION<br \/>\n<\/strong><span style=\"font-size: 0.8em\">GO SPORT &#8211; ROUBAIX LILLE M\u00c9TROPOLE<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">4.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><strong style=\"font-size: 14.4px\">&#x1f1f3;&#x1f1f1; JOREN BLOEM<\/strong><br style=\"font-size: 14.4px\" \/><span style=\"font-size: 0.8em\">A BLOC CT<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">5.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><strong style=\"font-size: 14.4px\">&#x1f1f3;&#x1f1f1; HARTTHIJS DE VRIES<\/strong><br style=\"font-size: 14.4px\" \/><span style=\"font-size: 0.8em\">METEC &#8211; SOLARWATT P\/B MANTEL<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">6.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>&#x1f1eb;&#x1f1f7; SAMUEL LEROUX<br \/>\n<\/strong><span style=\"font-size: 0.8em\">GO SPORT &#8211; ROUBAIX LILLE M\u00c9TROPOLE<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">7.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>&#x1f1eb;&#x1f1f7;<\/strong> <strong>KILLIAN TH\u00c9OT<\/strong><br \/>\n<span style=\"font-size: 0.8em\">V.C.ROUEN 76<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">8.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>&#x1f1eb;&#x1f1f7;<\/strong> <strong>SEBASTIEN HAVOT<\/strong><br \/>\n<span style=\"font-size: 0.8em\">V.C.ROUEN 76<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">9.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>&#x1f1ea;&#x1f1f8; XAVIER CANELLAS<\/strong><br \/>\n<span style=\"font-size: 0.8em\">JAVA KIWI ATLANTICO<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">10.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><strong style=\"font-size: 14.4px\">&#x1f1eb;&#x1f1ee; ANTTI-JUSSI JUNTUNEN<\/strong><br style=\"font-size: 14.4px\" \/><span style=\"font-size: 0.8em\">A BLOC CT<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<h2 style=\"text-align: justify;\"><strong>\u00c0 lire aussi<\/strong><\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/www.procyclingstats.com\/race\/ronde-de-l-oise\/2022\/stage-2\" target=\"_blank\" rel=\"nofollow noopener\"><strong>Le classement complet de la 2\u00e8me \u00e9tape<\/strong><\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/ronde-de-l-oise-2022-classement-general\/\" target=\"_blank\" rel=\"noopener\"><strong>Le classement g\u00e9n\u00e9ral de la Ronde de l&rsquo;Oise<\/strong><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>CYCLISME SUR ROUTE 2022 &#8211; D\u00e9couvrez le classement de la 2\u00e8me \u00e9tape (top 20) de la Ronde de l&rsquo;Oise 2022, disput\u00e9e ce vendredi 3 juin 2022 entre Le Plessis-Belleville et Rib\u00e9court Dreslincourt (199 km).<\/p>\n","protected":false},"author":4,"featured_media":229310,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[46994],"tags":[23864],"class_list":["post-229306","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cyclisme-sur-route","tag-ronde-de-loise"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ronde de l&#039;Oise 2022 - Classement 2\u00e8me \u00e9tape<\/title>\n<meta name=\"description\" content=\"CYCLISME SUR ROUTE 2022 - D\u00e9couvrez le classement de la 2\u00e8me \u00e9tape (top 20) de la Ronde de l&#039;Oise 2022, disput\u00e9e ce vendredi 3 juin 2022.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/ronde-de-l-oise-2022-classement-2eme-etape\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ronde de l&#039;Oise 2022 - Classement 2\u00e8me \u00e9tape\" \/>\n<meta property=\"og:description\" content=\"CYCLISME SUR ROUTE 2022 - D\u00e9couvrez le classement de la 2\u00e8me \u00e9tape (top 20) de la Ronde de l&#039;Oise 2022, disput\u00e9e ce vendredi 3 juin 2022.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/ronde-de-l-oise-2022-classement-2eme-etape\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-03T13:41:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-05T14:57:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Ronde-de-lOise-2022-Classement-2eme-etape.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Ronde de l&#039;Oise 2022 - Classement 2\u00e8me \u00e9tape\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ronde-de-l-oise-2022-classement-2eme-etape\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ronde-de-l-oise-2022-classement-2eme-etape\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Ronde de l&rsquo;Oise 2022 &#8211; Classement 2\u00e8me \u00e9tape\",\"datePublished\":\"2022-06-03T13:41:43+00:00\",\"dateModified\":\"2022-06-05T14:57:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ronde-de-l-oise-2022-classement-2eme-etape\/\"},\"wordCount\":208,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ronde-de-l-oise-2022-classement-2eme-etape\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Ronde-de-lOise-2022-Classement-2eme-etape.png\",\"keywords\":[\"Ronde de l'Oise\"],\"articleSection\":[\"Cyclisme sur route\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/ronde-de-l-oise-2022-classement-2eme-etape\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ronde-de-l-oise-2022-classement-2eme-etape\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/ronde-de-l-oise-2022-classement-2eme-etape\/\",\"name\":\"Ronde de l'Oise 2022 - Classement 2\u00e8me \u00e9tape\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ronde-de-l-oise-2022-classement-2eme-etape\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ronde-de-l-oise-2022-classement-2eme-etape\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Ronde-de-lOise-2022-Classement-2eme-etape.png\",\"datePublished\":\"2022-06-03T13:41:43+00:00\",\"dateModified\":\"2022-06-05T14:57:41+00:00\",\"description\":\"CYCLISME SUR ROUTE 2022 - D\u00e9couvrez le classement de la 2\u00e8me \u00e9tape (top 20) de la Ronde de l'Oise 2022, disput\u00e9e ce vendredi 3 juin 2022.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ronde-de-l-oise-2022-classement-2eme-etape\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/ronde-de-l-oise-2022-classement-2eme-etape\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ronde-de-l-oise-2022-classement-2eme-etape\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Ronde-de-lOise-2022-Classement-2eme-etape.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Ronde-de-lOise-2022-Classement-2eme-etape.png\",\"width\":1200,\"height\":670,\"caption\":\"Ronde de l'Oise 2022 - Classement 2\u00e8me \u00e9tape\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ronde-de-l-oise-2022-classement-2eme-etape\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ronde de l&rsquo;Oise 2022 &#8211; Classement 2\u00e8me \u00e9tape\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ronde de l'Oise 2022 - Classement 2\u00e8me \u00e9tape","description":"CYCLISME SUR ROUTE 2022 - D\u00e9couvrez le classement de la 2\u00e8me \u00e9tape (top 20) de la Ronde de l'Oise 2022, disput\u00e9e ce vendredi 3 juin 2022.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/ronde-de-l-oise-2022-classement-2eme-etape\/","og_locale":"fr_FR","og_type":"article","og_title":"Ronde de l'Oise 2022 - Classement 2\u00e8me \u00e9tape","og_description":"CYCLISME SUR ROUTE 2022 - D\u00e9couvrez le classement de la 2\u00e8me \u00e9tape (top 20) de la Ronde de l'Oise 2022, disput\u00e9e ce vendredi 3 juin 2022.","og_url":"https:\/\/dicodusport.fr\/blog\/ronde-de-l-oise-2022-classement-2eme-etape\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2022-06-03T13:41:43+00:00","article_modified_time":"2022-06-05T14:57:41+00:00","og_image":[{"width":1200,"height":670,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Ronde-de-lOise-2022-Classement-2eme-etape.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Ronde de l'Oise 2022 - Classement 2\u00e8me \u00e9tape","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/ronde-de-l-oise-2022-classement-2eme-etape\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/ronde-de-l-oise-2022-classement-2eme-etape\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Ronde de l&rsquo;Oise 2022 &#8211; Classement 2\u00e8me \u00e9tape","datePublished":"2022-06-03T13:41:43+00:00","dateModified":"2022-06-05T14:57:41+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ronde-de-l-oise-2022-classement-2eme-etape\/"},"wordCount":208,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ronde-de-l-oise-2022-classement-2eme-etape\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Ronde-de-lOise-2022-Classement-2eme-etape.png","keywords":["Ronde de l'Oise"],"articleSection":["Cyclisme sur route"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/ronde-de-l-oise-2022-classement-2eme-etape\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/ronde-de-l-oise-2022-classement-2eme-etape\/","url":"https:\/\/dicodusport.fr\/blog\/ronde-de-l-oise-2022-classement-2eme-etape\/","name":"Ronde de l'Oise 2022 - Classement 2\u00e8me \u00e9tape","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ronde-de-l-oise-2022-classement-2eme-etape\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ronde-de-l-oise-2022-classement-2eme-etape\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Ronde-de-lOise-2022-Classement-2eme-etape.png","datePublished":"2022-06-03T13:41:43+00:00","dateModified":"2022-06-05T14:57:41+00:00","description":"CYCLISME SUR ROUTE 2022 - D\u00e9couvrez le classement de la 2\u00e8me \u00e9tape (top 20) de la Ronde de l'Oise 2022, disput\u00e9e ce vendredi 3 juin 2022.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/ronde-de-l-oise-2022-classement-2eme-etape\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/ronde-de-l-oise-2022-classement-2eme-etape\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/ronde-de-l-oise-2022-classement-2eme-etape\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Ronde-de-lOise-2022-Classement-2eme-etape.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Ronde-de-lOise-2022-Classement-2eme-etape.png","width":1200,"height":670,"caption":"Ronde de l'Oise 2022 - Classement 2\u00e8me \u00e9tape"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/ronde-de-l-oise-2022-classement-2eme-etape\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Ronde de l&rsquo;Oise 2022 &#8211; Classement 2\u00e8me \u00e9tape"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/229306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=229306"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/229306\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/229310"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=229306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=229306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=229306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}