{"id":229468,"date":"2022-06-03T22:04:29","date_gmt":"2022-06-03T20:04:29","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=229468&#038;preview=true&#038;preview_id=229468"},"modified":"2022-06-03T22:40:50","modified_gmt":"2022-06-03T20:40:50","slug":"basket-ball-finale-nationale-1-l-a-rochelle-prend-lavantage-contre-mulhouse-dans-le-premier-acte","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/basket-ball-finale-nationale-1-l-a-rochelle-prend-lavantage-contre-mulhouse-dans-le-premier-acte\/","title":{"rendered":"Basket-Ball Finale Nationale 1 : La Rochelle prend l&rsquo;avantage contre Mulhouse dans le premier acte"},"content":{"rendered":"<p style=\"text-align: justify;\"><b><i>BASKET-BALL NATIONALE MASCULINE 1 &#8211; Dans une rencontre serr\u00e9e entre Mulhouse et La Rochelle o\u00f9 les deux formations ont encha\u00een\u00e9 les points au compte goutte, le suspense a plan\u00e9 jusqu&rsquo;au bout. Dans les 60 derni\u00e8res secondes, tout sc\u00e9nario \u00e9tait encore \u00e9crivable. Jusqu&rsquo;\u00e0 30 secondes avant le terme de la confrontation o\u00f9 le Stade Rochelais Basket a fait la diff\u00e9rence en s&rsquo;imposant sur le score de 78-82. Le premier match de cette finale sourit aux Rochelais.\u00a0<\/i><\/b><\/p>\n<p style=\"text-align: justify;\">Mulhouse a livr\u00e9 un beau combat dans le cadre du match aller de la finale de Nationale Masculine 1. Malheureusement pour le Petit Poucet alsacien depuis les huiti\u00e8mes de finale des playoffs du championnat, le combat \u00e9tait d&rsquo;un cran trop haut dans la fin de rencontre malgr\u00e9 la satisfaction d&rsquo;avoir men\u00e9 la vie dure \u00e0 son adversaire du soir. Mulhouse s&rsquo;incline ainsi 78 \u00e0 82 avant de prendre la route pour La Rochelle dans une semaine pour tenter d&rsquo;inverser la tendance.<\/p>\n<h2 style=\"text-align: justify;\">Mulhouse lance parfaitement les festivit\u00e9s<\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Mulhouse rentre bien dans la rencontre malgr\u00e9 le fait d\u2019avoir conc\u00e9d\u00e9 l\u2019ouverture du score, l\u2019\u00e9galisation intervient dans la foul\u00e9e gr\u00e2ce \u00e0 <strong>Momar Ndoye<\/strong> (2-2). Mais le club alsacien fait le spectacle avec le panier qui vaut trois points inscrit par William Mensah pour courir apr\u00e8s le score (5-6). Les compteurs sont remis \u00e0 \u00e9galit\u00e9 avec le lancer franc de <strong>Momar Ndoye<\/strong> (6-6). Mulhouse est de nouveau devanc\u00e9 mais fait une bonne op\u00e9ration sur les trois lancers francs inscrits par le capitaine<strong> Quentin Diehl<\/strong> (9-11). <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Trois points qui font du bien et qui pr\u00e9c\u00e8de les deux paniers \u00e0 trois points de <strong>Momar Ndoye<\/strong> qui permet aux Redboys de prendre l\u2019avantage (15-13). Victor Serrano conserve ce pr\u00e9cieux avantage avec son panier (17-16). Mais la Rochelle reprend les r\u00eanes de la rencontre, obligeant <strong>Morgan Durand<\/strong> \u00e0 s\u2019appliquer sur ses deux lancers francs transform\u00e9s (21-22). Les Mulhousiens repartent de l\u2019avant au tableau d\u2019affichage sous l\u2019impulsion de<strong> Victor Manuel<\/strong> Serrano (23-22). Puis la formation alsacienne sort du premier quart-temps avec un avantage qui tient qu\u2019\u00e0 un fil gr\u00e2ce au panier trois points de <strong>Quentin Diehl<\/strong> (26-25).\u00a0<\/span><\/p>\n<h2 style=\"text-align: justify;\">Un Stade Rochelais \u00e0 r\u00e9action<\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Dans le second quart-temps, Mulhouse d\u00e9bute bien les op\u00e9rations avec <strong>Momar Ndoye<\/strong> qui maintient un avantage de trois points (28-25). Un score bonifi\u00e9 avec les deux lancers francs de <strong>Johan Grebongo<\/strong> (30-25) ainsi que les deux paniers dans la foul\u00e9e pour le h\u00e9ros du match pr\u00e9c\u00e9dent au Palais des Sports o\u00f9 Mulhouse s\u2019\u00e9tait impos\u00e9 avec un petit point d\u2019avance face \u00e0 Lorient. <strong>Morgan Durand<\/strong> s\u2019illustre \u00e9galement avec deux paniers successifs, mais les Rochelais ont repris le contr\u00f4le du match (38-42). <strong>Momar Ndoye<\/strong>, premier \u00e0 marquer dans cette finale aller pour les Mulhousiens valide les deux lancers francs (40-44). Mais Mulhouse termine cette p\u00e9riode en \u00e9tant men\u00e9 d\u2019une diff\u00e9rence de sept unit\u00e9s (43-50).\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Le troisi\u00e8me quart-temps est favorable \u00e0 Mulhouse avec le panier de trois points de<strong> William Mensah<\/strong> (51-55). Puis le capitaine <strong>Quentin Diehl<\/strong> imite son co\u00e9quipier en trouvant \u00e9galement la voie des trois points (58-64). Deux lancers francs de <strong>Morgan Durand<\/strong> apportent deux points pr\u00e9cieux (62-66). Ce troisi\u00e8me acte est conclu par le panier de <strong>William Mensah<\/strong> (64-68). L\u2019espoir est l\u00e0 et quatre unit\u00e9s s\u00e9parent les deux finalistes.\u00a0<\/span><\/p>\n<h2 style=\"text-align: justify;\">Le sc\u00e9nario o\u00f9 tout est possible offre une fin de rencontre de folie<\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Le dernier quart-temps est un festival mulhousien o\u00f9 le Palais des Sports rentre en \u00e9ruption avec les deux paniers du capitaine <strong>Quentin Diehl<\/strong>. Le premier est synonyme d\u2019\u00e9galisation 70-70 puis le second marqu\u00e9 dans la zone des trois points, offre un avantage \u00e0 la formation mulhousienne (73-72).<strong> William Mensah<\/strong> d\u00e9clenche m\u00eame les vagues des olas dans le Palais des Sports avec sa r\u00e9alisation o\u00f9 il trouve \u00e9galement les trois points (76-74). Malheureusement, le match bascule en faveur des Rochelais entre 60 et 30 secondes du d\u00e9nouement de la rencontre. La Rochelle s\u2019impose 82 \u00e0 78 et remporte le premier duel de cette finale au Palais des Sports mulhousien. Reste \u00e0 finir le travail dans une semaine en Charente-Maritime.<\/span><\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">QUE DIRE DE CETTE \u00c9QUIPE&#8230;. &#x1f970;<\/p>\n<p>Encore une fois exceptionnels, les co\u00e9quipiers d&rsquo;un Ga\u00ebtan Clerc une nouvelle fois magistral en fin de rencontre se sont impos\u00e9s avec brio sur le parquet de <a href=\"https:\/\/twitter.com\/mbaprobasket?ref_src=twsrc%5Etfw\">@mbaprobasket<\/a> ! &#x2728; <a href=\"https:\/\/twitter.com\/hashtag\/NM1?src=hash&amp;ref_src=twsrc%5Etfw\">#NM1<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/FievreSR?src=hash&amp;ref_src=twsrc%5Etfw\">#FievreSR<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/basketball?src=hash&amp;ref_src=twsrc%5Etfw\">#basketball<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/larochelle?src=hash&amp;ref_src=twsrc%5Etfw\">#larochelle<\/a> <a href=\"https:\/\/t.co\/YLo6fTQlXw\">pic.twitter.com\/YLo6fTQlXw<\/a><\/p>\n<p>\u2014 Stade Rochelais Basket (@SR_Rupella) <a href=\"https:\/\/twitter.com\/SR_Rupella\/status\/1532812138632323072?ref_src=twsrc%5Etfw\">June 3, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>BASKET-BALL NATIONALE MASCULINE 1 &#8211; Dans une rencontre serr\u00e9e entre Mulhouse et La Rochelle o\u00f9 les deux formations ont encha\u00een\u00e9 les points au compte goutte, le suspense a plan\u00e9 jusqu&rsquo;au bout. Dans les 60 derni\u00e8res secondes, tout sc\u00e9nario \u00e9tait encore \u00e9crivable. Jusqu&rsquo;\u00e0 30 secondes avant le terme de la confrontation o\u00f9 le Stade Rochelais Basket a fait la diff\u00e9rence en s&rsquo;imposant sur le score de 78-82. Le premier match de cette finale sourit aux Rochelais.\u00a0<\/p>\n","protected":false},"author":62,"featured_media":229489,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2305],"tags":[],"class_list":["post-229468","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basket-ball"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Basket-Ball Finale Nationale 1 : La Rochelle prend l&#039;avantage contre Mulhouse dans le premier acte<\/title>\n<meta name=\"description\" content=\"Dans une rencontre serr\u00e9e entre Mulhouse et La Rochelle o\u00f9 les deux formations ont encha\u00een\u00e9 les points au compte goutte, le suspense a plan\u00e9 jusqu&#039;au bout.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/basket-ball-finale-nationale-1-l-a-rochelle-prend-lavantage-contre-mulhouse-dans-le-premier-acte\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Basket-Ball Finale Nationale 1 : La Rochelle prend l&#039;avantage contre Mulhouse dans le premier acte\" \/>\n<meta property=\"og:description\" content=\"Dans une rencontre serr\u00e9e entre Mulhouse et La Rochelle o\u00f9 les deux formations ont encha\u00een\u00e9 les points au compte goutte, le suspense a plan\u00e9 jusqu&#039;au bout.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/basket-ball-finale-nationale-1-l-a-rochelle-prend-lavantage-contre-mulhouse-dans-le-premier-acte\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-03T20:04:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-03T20:40:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Basket-Ball-Finale-Nationale-1-La-Rochelle-prend-lavantage-contre-Mulhouse-dans-le-premier-acte.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Andr\u00e9a Lamy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Basket-Ball Finale Nationale 1 : La Rochelle prend l&#039;avantage contre Mulhouse dans le premier acte\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-ball-finale-nationale-1-l-a-rochelle-prend-lavantage-contre-mulhouse-dans-le-premier-acte\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-ball-finale-nationale-1-l-a-rochelle-prend-lavantage-contre-mulhouse-dans-le-premier-acte\/\"},\"author\":{\"name\":\"Andr\u00e9a Lamy\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/5b73f4b55b8683f37e9f75d6dc039f31\"},\"headline\":\"Basket-Ball Finale Nationale 1 : La Rochelle prend l&rsquo;avantage contre Mulhouse dans le premier acte\",\"datePublished\":\"2022-06-03T20:04:29+00:00\",\"dateModified\":\"2022-06-03T20:40:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-ball-finale-nationale-1-l-a-rochelle-prend-lavantage-contre-mulhouse-dans-le-premier-acte\/\"},\"wordCount\":763,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-ball-finale-nationale-1-l-a-rochelle-prend-lavantage-contre-mulhouse-dans-le-premier-acte\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Basket-Ball-Finale-Nationale-1-La-Rochelle-prend-lavantage-contre-Mulhouse-dans-le-premier-acte.png\",\"articleSection\":[\"Basket-ball\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/basket-ball-finale-nationale-1-l-a-rochelle-prend-lavantage-contre-mulhouse-dans-le-premier-acte\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-ball-finale-nationale-1-l-a-rochelle-prend-lavantage-contre-mulhouse-dans-le-premier-acte\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/basket-ball-finale-nationale-1-l-a-rochelle-prend-lavantage-contre-mulhouse-dans-le-premier-acte\/\",\"name\":\"Basket-Ball Finale Nationale 1 : La Rochelle prend l'avantage contre Mulhouse dans le premier acte\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-ball-finale-nationale-1-l-a-rochelle-prend-lavantage-contre-mulhouse-dans-le-premier-acte\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-ball-finale-nationale-1-l-a-rochelle-prend-lavantage-contre-mulhouse-dans-le-premier-acte\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Basket-Ball-Finale-Nationale-1-La-Rochelle-prend-lavantage-contre-Mulhouse-dans-le-premier-acte.png\",\"datePublished\":\"2022-06-03T20:04:29+00:00\",\"dateModified\":\"2022-06-03T20:40:50+00:00\",\"description\":\"Dans une rencontre serr\u00e9e entre Mulhouse et La Rochelle o\u00f9 les deux formations ont encha\u00een\u00e9 les points au compte goutte, le suspense a plan\u00e9 jusqu'au bout.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-ball-finale-nationale-1-l-a-rochelle-prend-lavantage-contre-mulhouse-dans-le-premier-acte\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/basket-ball-finale-nationale-1-l-a-rochelle-prend-lavantage-contre-mulhouse-dans-le-premier-acte\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-ball-finale-nationale-1-l-a-rochelle-prend-lavantage-contre-mulhouse-dans-le-premier-acte\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Basket-Ball-Finale-Nationale-1-La-Rochelle-prend-lavantage-contre-Mulhouse-dans-le-premier-acte.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Basket-Ball-Finale-Nationale-1-La-Rochelle-prend-lavantage-contre-Mulhouse-dans-le-premier-acte.png\",\"width\":800,\"height\":445,\"caption\":\"Basket-Ball Finale Nationale 1 La Rochelle prend l'avantage contre Mulhouse dans le premier acte\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-ball-finale-nationale-1-l-a-rochelle-prend-lavantage-contre-mulhouse-dans-le-premier-acte\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Basket-Ball Finale Nationale 1 : La Rochelle prend l&rsquo;avantage contre Mulhouse dans le premier acte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/5b73f4b55b8683f37e9f75d6dc039f31\",\"name\":\"Andr\u00e9a Lamy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/Andrea-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/Andrea-150x150.jpg\",\"caption\":\"Andr\u00e9a Lamy\"},\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/andrea-lamy\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Basket-Ball Finale Nationale 1 : La Rochelle prend l'avantage contre Mulhouse dans le premier acte","description":"Dans une rencontre serr\u00e9e entre Mulhouse et La Rochelle o\u00f9 les deux formations ont encha\u00een\u00e9 les points au compte goutte, le suspense a plan\u00e9 jusqu'au bout.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/basket-ball-finale-nationale-1-l-a-rochelle-prend-lavantage-contre-mulhouse-dans-le-premier-acte\/","og_locale":"fr_FR","og_type":"article","og_title":"Basket-Ball Finale Nationale 1 : La Rochelle prend l'avantage contre Mulhouse dans le premier acte","og_description":"Dans une rencontre serr\u00e9e entre Mulhouse et La Rochelle o\u00f9 les deux formations ont encha\u00een\u00e9 les points au compte goutte, le suspense a plan\u00e9 jusqu'au bout.","og_url":"https:\/\/dicodusport.fr\/blog\/basket-ball-finale-nationale-1-l-a-rochelle-prend-lavantage-contre-mulhouse-dans-le-premier-acte\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2022-06-03T20:04:29+00:00","article_modified_time":"2022-06-03T20:40:50+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Basket-Ball-Finale-Nationale-1-La-Rochelle-prend-lavantage-contre-Mulhouse-dans-le-premier-acte.png","type":"image\/png"}],"author":"Andr\u00e9a Lamy","twitter_card":"summary_large_image","twitter_title":"Basket-Ball Finale Nationale 1 : La Rochelle prend l'avantage contre Mulhouse dans le premier acte","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/basket-ball-finale-nationale-1-l-a-rochelle-prend-lavantage-contre-mulhouse-dans-le-premier-acte\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/basket-ball-finale-nationale-1-l-a-rochelle-prend-lavantage-contre-mulhouse-dans-le-premier-acte\/"},"author":{"name":"Andr\u00e9a Lamy","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/5b73f4b55b8683f37e9f75d6dc039f31"},"headline":"Basket-Ball Finale Nationale 1 : La Rochelle prend l&rsquo;avantage contre Mulhouse dans le premier acte","datePublished":"2022-06-03T20:04:29+00:00","dateModified":"2022-06-03T20:40:50+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/basket-ball-finale-nationale-1-l-a-rochelle-prend-lavantage-contre-mulhouse-dans-le-premier-acte\/"},"wordCount":763,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/basket-ball-finale-nationale-1-l-a-rochelle-prend-lavantage-contre-mulhouse-dans-le-premier-acte\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Basket-Ball-Finale-Nationale-1-La-Rochelle-prend-lavantage-contre-Mulhouse-dans-le-premier-acte.png","articleSection":["Basket-ball"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/basket-ball-finale-nationale-1-l-a-rochelle-prend-lavantage-contre-mulhouse-dans-le-premier-acte\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/basket-ball-finale-nationale-1-l-a-rochelle-prend-lavantage-contre-mulhouse-dans-le-premier-acte\/","url":"https:\/\/dicodusport.fr\/blog\/basket-ball-finale-nationale-1-l-a-rochelle-prend-lavantage-contre-mulhouse-dans-le-premier-acte\/","name":"Basket-Ball Finale Nationale 1 : La Rochelle prend l'avantage contre Mulhouse dans le premier acte","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/basket-ball-finale-nationale-1-l-a-rochelle-prend-lavantage-contre-mulhouse-dans-le-premier-acte\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/basket-ball-finale-nationale-1-l-a-rochelle-prend-lavantage-contre-mulhouse-dans-le-premier-acte\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Basket-Ball-Finale-Nationale-1-La-Rochelle-prend-lavantage-contre-Mulhouse-dans-le-premier-acte.png","datePublished":"2022-06-03T20:04:29+00:00","dateModified":"2022-06-03T20:40:50+00:00","description":"Dans une rencontre serr\u00e9e entre Mulhouse et La Rochelle o\u00f9 les deux formations ont encha\u00een\u00e9 les points au compte goutte, le suspense a plan\u00e9 jusqu'au bout.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/basket-ball-finale-nationale-1-l-a-rochelle-prend-lavantage-contre-mulhouse-dans-le-premier-acte\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/basket-ball-finale-nationale-1-l-a-rochelle-prend-lavantage-contre-mulhouse-dans-le-premier-acte\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/basket-ball-finale-nationale-1-l-a-rochelle-prend-lavantage-contre-mulhouse-dans-le-premier-acte\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Basket-Ball-Finale-Nationale-1-La-Rochelle-prend-lavantage-contre-Mulhouse-dans-le-premier-acte.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Basket-Ball-Finale-Nationale-1-La-Rochelle-prend-lavantage-contre-Mulhouse-dans-le-premier-acte.png","width":800,"height":445,"caption":"Basket-Ball Finale Nationale 1 La Rochelle prend l'avantage contre Mulhouse dans le premier acte"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/basket-ball-finale-nationale-1-l-a-rochelle-prend-lavantage-contre-mulhouse-dans-le-premier-acte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Basket-Ball Finale Nationale 1 : La Rochelle prend l&rsquo;avantage contre Mulhouse dans le premier acte"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/5b73f4b55b8683f37e9f75d6dc039f31","name":"Andr\u00e9a Lamy","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/Andrea-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/Andrea-150x150.jpg","caption":"Andr\u00e9a Lamy"},"url":"https:\/\/dicodusport.fr\/blog\/author\/andrea-lamy\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/229468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=229468"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/229468\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/229489"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=229468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=229468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=229468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}