{"id":230123,"date":"2022-06-05T16:39:16","date_gmt":"2022-06-05T14:39:16","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=230123&#038;preview=true&#038;preview_id=230123"},"modified":"2022-06-05T16:39:16","modified_gmt":"2022-06-05T14:39:16","slug":"prix-du-jockey-club-vadeni-monte-par-christophe-soumillon-ecrase-la-concurrence","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/prix-du-jockey-club-vadeni-monte-par-christophe-soumillon-ecrase-la-concurrence\/","title":{"rendered":"Prix du Jockey Club : Vadeni, mont\u00e9 par Christophe Soumillon, \u00e9crase la concurrence"},"content":{"rendered":"<p style=\"text-align: justify;\"><b><i>QATAR PRIX DU JOCKEY CLUB 2022 &#8211; Les quinze meilleurs poulains de 3 ans d&rsquo;Europe s&rsquo;\u00e9taient donn\u00e9s rendez-vous \u00e0 Chantilly aujourd&rsquo;hui, pour la 182\u00e8me \u00e9dition du Prix du Jockey Club. Troisi\u00e8me favori au d\u00e9part, Vadeni, mont\u00e9 par Christophe Soumillon et entra\u00een\u00e9 par Jean-Claude Rouget, s&rsquo;est impos\u00e9 dans un v\u00e9ritable canter.\u00a0<\/i><\/b><\/p>\n<p style=\"text-align: justify;\">Ils \u00e9taient nombreux au d\u00e9part de la deuxi\u00e8me course la plus richement dot\u00e9e de l&rsquo;ann\u00e9e. Le pensionnaire de <strong>Charlie Appleby<\/strong>, <strong>Modern Games<\/strong>, laur\u00e9at de la Poule d&rsquo;Essai des Poulains \u00e0 Longchamp en mai dernier, souhaitait imiter <strong>St Mark&rsquo;s Bisilica<\/strong>, qui a r\u00e9alis\u00e9 le doubl\u00e9 Poule d&rsquo;Essai des Poulains &#8211; Jockey Club l&rsquo;an dernier. D\u00e9j\u00e0 vainqueur de deux groupes I, le poulain irlandais de la casaque Godolphin \u00e9tait le favori logique au d\u00e9part.<\/p>\n<p style=\"text-align: justify;\">Derri\u00e8re, il y avait plusieurs chances fran\u00e7aises. <strong>Jean-Claude Rouget<\/strong>, vainqueur en 2019 avec <strong>Sotsass<\/strong>, pr\u00e9sentait quatre participants, dont deux tops chances. <strong>Al Hakeem<\/strong>, qui s&rsquo;\u00e9tait impos\u00e9 tr\u00e8s facilement d\u00e9but mai dans un groupe III, \u00e9tait sa meilleure chance, ainsi que <strong>Lassaut<\/strong>, cinqui\u00e8me malheureux de la \u00a0\u00bb Poule \u00a0\u00bb. Enfin, <strong>Vadeni<\/strong>, repr\u00e9sentant de la casaque classique Aga Khan, \u00e9tait associ\u00e9 \u00e0<strong> Christophe Soumillon<\/strong>, qui attendait un succ\u00e8s dans cette \u00e9preuve depuis 2006.<\/p>\n<h2 style=\"text-align: justify;\">Vadeni a survol\u00e9 l&rsquo;opposition<\/h2>\n<p style=\"text-align: justify;\">Malgr\u00e9 son num\u00e9ro 13 \u00e0 la corde, le favori <strong>Modern Games<\/strong> menait les d\u00e9bats d\u00e8s le d\u00e9but de cette course longue de 2100 m. <strong>Vadeni<\/strong>, <strong>Yoozuna<\/strong> ou encore <strong>El Bodegon<\/strong> \u00e9taient dans le premier tiers du peloton, tandis que <strong>Lassault<\/strong> fermait la marche. Dans la derni\u00e8re ligne droite, <strong>Vadeni<\/strong> a fait \u00e9tat de toute sa classe. Aux trois cents m\u00e8tres, <strong>Christophe Soumillon<\/strong> l&rsquo;a d\u00e9cal\u00e9 \u00e0 l&rsquo;ext\u00e9rieur pour ne pas se faire enfermer \u00e0 la corde o\u00f9 le peloton \u00e9tait group\u00e9. Sur son changement de jambe, le poulain de la casaque Aga Khan a d\u00e9pos\u00e9 l&rsquo;opposition et s&rsquo;est impos\u00e9 de quatre longueurs en v\u00e9ritable crack.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">&#x1f3c6; VADENI IMPRESSIONNANT ! &#x1f3c6;<\/p>\n<p>Vadeni (<a href=\"https:\/\/twitter.com\/CSoumillon?ref_src=twsrc%5Etfw\">@CSoumillon<\/a> &#8211; J-C. Rouget) triomphe facilement dans le <a href=\"https:\/\/twitter.com\/hashtag\/Qatar?src=hash&amp;ref_src=twsrc%5Etfw\">#Qatar<\/a> Prix du <a href=\"https:\/\/twitter.com\/hashtag\/JockeyClub?src=hash&amp;ref_src=twsrc%5Etfw\">#JockeyClub<\/a> (Gr.1) \u00e0 Chantilly. El Bodegon et Modern Games compl\u00e8tent le podium. <a href=\"https:\/\/t.co\/mWERWyzQ2q\">pic.twitter.com\/mWERWyzQ2q<\/a><\/p>\n<p>\u2014 Equidia (@equidia) <a href=\"https:\/\/twitter.com\/equidia\/status\/1533451870815014913?ref_src=twsrc%5Etfw\">June 5, 2022<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\"><strong>El Bod\u00e9gon<\/strong>, mont\u00e9 par <strong>Ioritz Mendizaba<\/strong>l, termine deuxi\u00e8me, devant<strong> Modern Games<\/strong>, qui a impos\u00e9 le rythme dans cette course et a beaucoup d\u00e9pens\u00e9 d&rsquo;\u00e9nergie. <strong>Al Hakeem<\/strong> termine bon quatri\u00e8me, ce qui permet \u00e0 <strong>Jean-Claude Rouget<\/strong> de placer deux de ses repr\u00e9sentants dans le quint\u00e9. L&rsquo;entraineur Normand remporte sa cinqui\u00e8me victoire dans le Jockey Club apr\u00e8s les succ\u00e8s r\u00e9cents de <strong>Sotsass<\/strong> en 2019 ou <strong>Almanzor<\/strong> en 2016. Quant \u00e0 <strong>Christophe Soumillon<\/strong>, le jockey belge remporte cette course pour la quatri\u00e8me fois.<\/p>\n<div data-oembed-url=\"https:\/\/www.equidia.fr\/articles\/reportage\/les-4-mousquetaires-de-jean-claude-rouget-a-lassaut-du-prix-du-jockey-club\">\n<div class=\"iframely-embed\">\n<div>\n<div>\n<div class=\"body\">\n<div class=\"w __wc _thl _ls _sm _od _alsd _alcd _lh14 _xm _xi _tm _dm __wc-600\">\n<div class=\"wf\">\n<div class=\"wc\">\n<div class=\"e\">\n<div class=\"em\" style=\"text-align: justify;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>QATAR PRIX DU JOCKEY CLUB 2022 &#8211; Les quinze meilleurs poulains de 3 ans d&rsquo;Europe s&rsquo;\u00e9taient donn\u00e9s rendez-vous \u00e0 Chantilly aujourd&rsquo;hui, pour la 182\u00e8me \u00e9dition du Prix du Jockey Club. Troisi\u00e8me favori au d\u00e9part, Vadeni, mont\u00e9 par Christophe Soumillon et entrain\u00e9 par Jean-Claude Rouget, s&rsquo;est impos\u00e9 dans un v\u00e9ritable canter.\u00a0<\/p>\n","protected":false},"author":42,"featured_media":230151,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2311],"tags":[19667,9658],"class_list":["post-230123","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sports-equestres","tag-courses-hippiques","tag-hippisme"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Prix du Jockey Club : Vadeni, mont\u00e9 par Christophe Soumillon, \u00e9crase la concurrence<\/title>\n<meta name=\"description\" content=\"QATAR PRIX DU JOCKEY CLUB 2022 - Vadeni, mont\u00e9 par Christophe Soumillon et entra\u00een\u00e9 par Jean-Claude Rouget, s&#039;est impos\u00e9 facilement\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/prix-du-jockey-club-vadeni-monte-par-christophe-soumillon-ecrase-la-concurrence\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prix du Jockey Club : Vadeni, mont\u00e9 par Christophe Soumillon, \u00e9crase la concurrence\" \/>\n<meta property=\"og:description\" content=\"QATAR PRIX DU JOCKEY CLUB 2022 - Vadeni, mont\u00e9 par Christophe Soumillon et entra\u00een\u00e9 par Jean-Claude Rouget, s&#039;est impos\u00e9 facilement\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/prix-du-jockey-club-vadeni-monte-par-christophe-soumillon-ecrase-la-concurrence\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-05T14:39:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Prix-du-Jockey-Club-Vadeni-monte-par-Christophe-Soumillon-ecrase-la-concurrence.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Mezine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Prix du Jockey Club : Vadeni, mont\u00e9 par Christophe Soumillon, \u00e9crase la concurrence\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Lbiji13\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/prix-du-jockey-club-vadeni-monte-par-christophe-soumillon-ecrase-la-concurrence\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/prix-du-jockey-club-vadeni-monte-par-christophe-soumillon-ecrase-la-concurrence\\\/\"},\"author\":{\"name\":\"Nicolas Mezine\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/99fcf31b3ee0d51fed53ade78139bbbf\"},\"headline\":\"Prix du Jockey Club : Vadeni, mont\u00e9 par Christophe Soumillon, \u00e9crase la concurrence\",\"datePublished\":\"2022-06-05T14:39:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/prix-du-jockey-club-vadeni-monte-par-christophe-soumillon-ecrase-la-concurrence\\\/\"},\"wordCount\":473,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/prix-du-jockey-club-vadeni-monte-par-christophe-soumillon-ecrase-la-concurrence\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Prix-du-Jockey-Club-Vadeni-monte-par-Christophe-Soumillon-ecrase-la-concurrence.png\",\"keywords\":[\"courses hippiques\",\"Hippisme\"],\"articleSection\":[\"Sports \u00e9questres\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/prix-du-jockey-club-vadeni-monte-par-christophe-soumillon-ecrase-la-concurrence\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/prix-du-jockey-club-vadeni-monte-par-christophe-soumillon-ecrase-la-concurrence\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/prix-du-jockey-club-vadeni-monte-par-christophe-soumillon-ecrase-la-concurrence\\\/\",\"name\":\"Prix du Jockey Club : Vadeni, mont\u00e9 par Christophe Soumillon, \u00e9crase la concurrence\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/prix-du-jockey-club-vadeni-monte-par-christophe-soumillon-ecrase-la-concurrence\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/prix-du-jockey-club-vadeni-monte-par-christophe-soumillon-ecrase-la-concurrence\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Prix-du-Jockey-Club-Vadeni-monte-par-Christophe-Soumillon-ecrase-la-concurrence.png\",\"datePublished\":\"2022-06-05T14:39:16+00:00\",\"description\":\"QATAR PRIX DU JOCKEY CLUB 2022 - Vadeni, mont\u00e9 par Christophe Soumillon et entra\u00een\u00e9 par Jean-Claude Rouget, s'est impos\u00e9 facilement\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/prix-du-jockey-club-vadeni-monte-par-christophe-soumillon-ecrase-la-concurrence\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/prix-du-jockey-club-vadeni-monte-par-christophe-soumillon-ecrase-la-concurrence\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/prix-du-jockey-club-vadeni-monte-par-christophe-soumillon-ecrase-la-concurrence\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Prix-du-Jockey-Club-Vadeni-monte-par-Christophe-Soumillon-ecrase-la-concurrence.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Prix-du-Jockey-Club-Vadeni-monte-par-Christophe-Soumillon-ecrase-la-concurrence.png\",\"width\":800,\"height\":445,\"caption\":\"Prix du Jockey Club Vadeni, mont\u00e9 par Christophe Soumillon, \u00e9crase la concurrence\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/prix-du-jockey-club-vadeni-monte-par-christophe-soumillon-ecrase-la-concurrence\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prix du Jockey Club : Vadeni, mont\u00e9 par Christophe Soumillon, \u00e9crase la concurrence\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/99fcf31b3ee0d51fed53ade78139bbbf\",\"name\":\"Nicolas Mezine\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/IMG_4655-e1631787111223-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/IMG_4655-e1631787111223-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/IMG_4655-e1631787111223-150x150.jpg\",\"caption\":\"Nicolas Mezine\"},\"description\":\"Passionn\u00e9 de sport, notamment de rugby dans toutes ses variantes (XV, XIII et VII). Fan du RC Toulon et de l'Olympique de Marseille.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/nicolas-mezine-521380160\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Lbiji13\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/nicolas-m\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Prix du Jockey Club : Vadeni, mont\u00e9 par Christophe Soumillon, \u00e9crase la concurrence","description":"QATAR PRIX DU JOCKEY CLUB 2022 - Vadeni, mont\u00e9 par Christophe Soumillon et entra\u00een\u00e9 par Jean-Claude Rouget, s'est impos\u00e9 facilement","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/prix-du-jockey-club-vadeni-monte-par-christophe-soumillon-ecrase-la-concurrence\/","og_locale":"fr_FR","og_type":"article","og_title":"Prix du Jockey Club : Vadeni, mont\u00e9 par Christophe Soumillon, \u00e9crase la concurrence","og_description":"QATAR PRIX DU JOCKEY CLUB 2022 - Vadeni, mont\u00e9 par Christophe Soumillon et entra\u00een\u00e9 par Jean-Claude Rouget, s'est impos\u00e9 facilement","og_url":"https:\/\/dicodusport.fr\/blog\/prix-du-jockey-club-vadeni-monte-par-christophe-soumillon-ecrase-la-concurrence\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2022-06-05T14:39:16+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Prix-du-Jockey-Club-Vadeni-monte-par-Christophe-Soumillon-ecrase-la-concurrence.png","type":"image\/png"}],"author":"Nicolas Mezine","twitter_card":"summary_large_image","twitter_title":"Prix du Jockey Club : Vadeni, mont\u00e9 par Christophe Soumillon, \u00e9crase la concurrence","twitter_creator":"@https:\/\/twitter.com\/Lbiji13","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/prix-du-jockey-club-vadeni-monte-par-christophe-soumillon-ecrase-la-concurrence\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/prix-du-jockey-club-vadeni-monte-par-christophe-soumillon-ecrase-la-concurrence\/"},"author":{"name":"Nicolas Mezine","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/99fcf31b3ee0d51fed53ade78139bbbf"},"headline":"Prix du Jockey Club : Vadeni, mont\u00e9 par Christophe Soumillon, \u00e9crase la concurrence","datePublished":"2022-06-05T14:39:16+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/prix-du-jockey-club-vadeni-monte-par-christophe-soumillon-ecrase-la-concurrence\/"},"wordCount":473,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/prix-du-jockey-club-vadeni-monte-par-christophe-soumillon-ecrase-la-concurrence\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Prix-du-Jockey-Club-Vadeni-monte-par-Christophe-Soumillon-ecrase-la-concurrence.png","keywords":["courses hippiques","Hippisme"],"articleSection":["Sports \u00e9questres"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/prix-du-jockey-club-vadeni-monte-par-christophe-soumillon-ecrase-la-concurrence\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/prix-du-jockey-club-vadeni-monte-par-christophe-soumillon-ecrase-la-concurrence\/","url":"https:\/\/dicodusport.fr\/blog\/prix-du-jockey-club-vadeni-monte-par-christophe-soumillon-ecrase-la-concurrence\/","name":"Prix du Jockey Club : Vadeni, mont\u00e9 par Christophe Soumillon, \u00e9crase la concurrence","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/prix-du-jockey-club-vadeni-monte-par-christophe-soumillon-ecrase-la-concurrence\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/prix-du-jockey-club-vadeni-monte-par-christophe-soumillon-ecrase-la-concurrence\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Prix-du-Jockey-Club-Vadeni-monte-par-Christophe-Soumillon-ecrase-la-concurrence.png","datePublished":"2022-06-05T14:39:16+00:00","description":"QATAR PRIX DU JOCKEY CLUB 2022 - Vadeni, mont\u00e9 par Christophe Soumillon et entra\u00een\u00e9 par Jean-Claude Rouget, s'est impos\u00e9 facilement","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/prix-du-jockey-club-vadeni-monte-par-christophe-soumillon-ecrase-la-concurrence\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/prix-du-jockey-club-vadeni-monte-par-christophe-soumillon-ecrase-la-concurrence\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/prix-du-jockey-club-vadeni-monte-par-christophe-soumillon-ecrase-la-concurrence\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Prix-du-Jockey-Club-Vadeni-monte-par-Christophe-Soumillon-ecrase-la-concurrence.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Prix-du-Jockey-Club-Vadeni-monte-par-Christophe-Soumillon-ecrase-la-concurrence.png","width":800,"height":445,"caption":"Prix du Jockey Club Vadeni, mont\u00e9 par Christophe Soumillon, \u00e9crase la concurrence"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/prix-du-jockey-club-vadeni-monte-par-christophe-soumillon-ecrase-la-concurrence\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Prix du Jockey Club : Vadeni, mont\u00e9 par Christophe Soumillon, \u00e9crase la concurrence"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/99fcf31b3ee0d51fed53ade78139bbbf","name":"Nicolas Mezine","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/IMG_4655-e1631787111223-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/IMG_4655-e1631787111223-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/IMG_4655-e1631787111223-150x150.jpg","caption":"Nicolas Mezine"},"description":"Passionn\u00e9 de sport, notamment de rugby dans toutes ses variantes (XV, XIII et VII). Fan du RC Toulon et de l'Olympique de Marseille.","sameAs":["https:\/\/www.linkedin.com\/in\/nicolas-mezine-521380160\/","https:\/\/x.com\/https:\/\/twitter.com\/Lbiji13"],"url":"https:\/\/dicodusport.fr\/blog\/author\/nicolas-m\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/230123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=230123"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/230123\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/230151"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=230123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=230123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=230123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}