{"id":230710,"date":"2022-06-07T12:13:54","date_gmt":"2022-06-07T10:13:54","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=230710&#038;preview=true&#038;preview_id=230710"},"modified":"2022-06-07T12:42:51","modified_gmt":"2022-06-07T10:42:51","slug":"alexander-zverev-sera-absent-entre-six-et-huit-semaines","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/alexander-zverev-sera-absent-entre-six-et-huit-semaines\/","title":{"rendered":"Alexander Zverev sera absent entre six et huit semaines"},"content":{"rendered":"<p style=\"text-align: justify;\"><b><i>TENNIS &#8211; SAISON ATP 2022 &#8211; Bless\u00e9 durant sa demi-finale de Roland-Garros contre Rafael Nadal, Alexander Zverev sera absent entre six et huit semaines selon le journal L&rsquo;Equipe.<\/i><\/b><\/p>\n<p style=\"text-align: justify;\">Auteur d&rsquo;un bon Roland-Garros, <a href=\"https:\/\/dicodusport.fr\/blog\/roland-garros-2022-alexander-zverev-elimine-carlos-alcaraz-et-rallie-les-demi-finales\/\">o\u00f9 il avait notamment sorti <\/a><strong>Carlos Alcaraz, Alexander Zverev<\/strong> avait vu son parcours prendre fin brutalement. En demi-finale, il avait d\u00fb abandonner lors de sa demi-finale contre <strong>Rafael Nadal<\/strong>, <a href=\"https:\/\/dicodusport.fr\/blog\/roland-garros-2022-coup-du-sort-pour-alexander-zverev-qui-abandonne-sur-blessure-face-a-nadal\/\">\u00e0 cause d&rsquo;une impressionnante blessure \u00e0 la cheville<\/a>. Selon le journal L&rsquo;Equipe, il souffre d&rsquo;une d\u00e9chirure de plusieurs ligaments. Cela lui vaudra d&rsquo;\u00eatre absent entre six et huit semaines. Il fait donc d&rsquo;ores et d\u00e9j\u00e0 une croix sur le prochain Wimbledon. Son retour, s&rsquo;il a lieu, pourrait intervenir en ao\u00fbt, pour la tourn\u00e9e am\u00e9ricaine. Son objectif principal \u00e9tant bien \u00e9videmment d&rsquo;\u00eatre r\u00e9tabli pour le prochain US Open, dernier tournoi du grand chelem de la saison (du 29 ao\u00fbt au 11 septembre).<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Selon nos informations, la dur\u00e9e d&rsquo;indisponibilit\u00e9 d&rsquo;Alexander Zverev est estim\u00e9e entre six et huit semaines. Forfait pour Wimbledon, il esp\u00e8re \u00eatre de retour, d\u00e9but ao\u00fbt, avec la tourn\u00e9e aux \u00c9tats-Unis. Son objectif : \u00eatre r\u00e9tabli en vue de l&rsquo;US Open.<a href=\"https:\/\/t.co\/RyiV8RKpiz\">https:\/\/t.co\/RyiV8RKpiz<\/a><\/p>\n<p>\u2014 Quentin Moynet (@QuentinMoynet) <a href=\"https:\/\/twitter.com\/QuentinMoynet\/status\/1533905612253315076?ref_src=twsrc%5Etfw\">June 6, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TENNIS &#8211; SAISON ATP 2022 &#8211; Bless\u00e9 durant sa demi-finale de Roland-Garros contre Rafael Nadal, Alexander Zverev sera absent entre six et huit semaines selon le journal L&rsquo;Equipe.<\/p>\n","protected":false},"author":59,"featured_media":230711,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2302],"tags":[4371,136],"class_list":["post-230710","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tennis","tag-alexander-zverev","tag-tennis"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Alexander Zverev sera absent entre six et huit semaines<\/title>\n<meta name=\"description\" content=\"TENNIS - SAISON ATP 2022 - Alexander Zverev sera absent entre six et huit semaines selon le journal L&#039;Equipe.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/alexander-zverev-sera-absent-entre-six-et-huit-semaines\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alexander Zverev sera absent entre six et huit semaines\" \/>\n<meta property=\"og:description\" content=\"TENNIS - SAISON ATP 2022 - Alexander Zverev sera absent entre six et huit semaines selon le journal L&#039;Equipe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/alexander-zverev-sera-absent-entre-six-et-huit-semaines\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-07T10:13:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-07T10:42:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Alexander-Zverev-sera-absent-entre-six-et-huit-semaines.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Alexander Zverev sera absent entre six et huit semaines\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/alexander-zverev-sera-absent-entre-six-et-huit-semaines\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/alexander-zverev-sera-absent-entre-six-et-huit-semaines\\\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Alexander Zverev sera absent entre six et huit semaines\",\"datePublished\":\"2022-06-07T10:13:54+00:00\",\"dateModified\":\"2022-06-07T10:42:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/alexander-zverev-sera-absent-entre-six-et-huit-semaines\\\/\"},\"wordCount\":220,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/alexander-zverev-sera-absent-entre-six-et-huit-semaines\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Alexander-Zverev-sera-absent-entre-six-et-huit-semaines.png\",\"keywords\":[\"Alexander Zverev\",\"Tennis\"],\"articleSection\":[\"Tennis\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/alexander-zverev-sera-absent-entre-six-et-huit-semaines\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/alexander-zverev-sera-absent-entre-six-et-huit-semaines\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/alexander-zverev-sera-absent-entre-six-et-huit-semaines\\\/\",\"name\":\"Alexander Zverev sera absent entre six et huit semaines\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/alexander-zverev-sera-absent-entre-six-et-huit-semaines\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/alexander-zverev-sera-absent-entre-six-et-huit-semaines\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Alexander-Zverev-sera-absent-entre-six-et-huit-semaines.png\",\"datePublished\":\"2022-06-07T10:13:54+00:00\",\"dateModified\":\"2022-06-07T10:42:51+00:00\",\"description\":\"TENNIS - SAISON ATP 2022 - Alexander Zverev sera absent entre six et huit semaines selon le journal L'Equipe.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/alexander-zverev-sera-absent-entre-six-et-huit-semaines\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/alexander-zverev-sera-absent-entre-six-et-huit-semaines\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/alexander-zverev-sera-absent-entre-six-et-huit-semaines\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Alexander-Zverev-sera-absent-entre-six-et-huit-semaines.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Alexander-Zverev-sera-absent-entre-six-et-huit-semaines.png\",\"width\":800,\"height\":445,\"caption\":\"Alexander Zverev sera absent entre six et huit semaines\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/alexander-zverev-sera-absent-entre-six-et-huit-semaines\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alexander Zverev sera absent entre six et huit semaines\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sebastien.gente\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sebgente\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/sbastien-gente-a29583169\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sebastiengente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Alexander Zverev sera absent entre six et huit semaines","description":"TENNIS - SAISON ATP 2022 - Alexander Zverev sera absent entre six et huit semaines selon le journal L'Equipe.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/alexander-zverev-sera-absent-entre-six-et-huit-semaines\/","og_locale":"fr_FR","og_type":"article","og_title":"Alexander Zverev sera absent entre six et huit semaines","og_description":"TENNIS - SAISON ATP 2022 - Alexander Zverev sera absent entre six et huit semaines selon le journal L'Equipe.","og_url":"https:\/\/dicodusport.fr\/blog\/alexander-zverev-sera-absent-entre-six-et-huit-semaines\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2022-06-07T10:13:54+00:00","article_modified_time":"2022-06-07T10:42:51+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Alexander-Zverev-sera-absent-entre-six-et-huit-semaines.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Alexander Zverev sera absent entre six et huit semaines","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/alexander-zverev-sera-absent-entre-six-et-huit-semaines\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/alexander-zverev-sera-absent-entre-six-et-huit-semaines\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Alexander Zverev sera absent entre six et huit semaines","datePublished":"2022-06-07T10:13:54+00:00","dateModified":"2022-06-07T10:42:51+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/alexander-zverev-sera-absent-entre-six-et-huit-semaines\/"},"wordCount":220,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/alexander-zverev-sera-absent-entre-six-et-huit-semaines\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Alexander-Zverev-sera-absent-entre-six-et-huit-semaines.png","keywords":["Alexander Zverev","Tennis"],"articleSection":["Tennis"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/alexander-zverev-sera-absent-entre-six-et-huit-semaines\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/alexander-zverev-sera-absent-entre-six-et-huit-semaines\/","url":"https:\/\/dicodusport.fr\/blog\/alexander-zverev-sera-absent-entre-six-et-huit-semaines\/","name":"Alexander Zverev sera absent entre six et huit semaines","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/alexander-zverev-sera-absent-entre-six-et-huit-semaines\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/alexander-zverev-sera-absent-entre-six-et-huit-semaines\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Alexander-Zverev-sera-absent-entre-six-et-huit-semaines.png","datePublished":"2022-06-07T10:13:54+00:00","dateModified":"2022-06-07T10:42:51+00:00","description":"TENNIS - SAISON ATP 2022 - Alexander Zverev sera absent entre six et huit semaines selon le journal L'Equipe.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/alexander-zverev-sera-absent-entre-six-et-huit-semaines\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/alexander-zverev-sera-absent-entre-six-et-huit-semaines\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/alexander-zverev-sera-absent-entre-six-et-huit-semaines\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Alexander-Zverev-sera-absent-entre-six-et-huit-semaines.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Alexander-Zverev-sera-absent-entre-six-et-huit-semaines.png","width":800,"height":445,"caption":"Alexander Zverev sera absent entre six et huit semaines"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/alexander-zverev-sera-absent-entre-six-et-huit-semaines\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Alexander Zverev sera absent entre six et huit semaines"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/230710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=230710"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/230710\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/230711"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=230710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=230710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=230710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}