{"id":230749,"date":"2022-06-07T15:14:44","date_gmt":"2022-06-07T13:14:44","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=230749&#038;preview=true&#038;preview_id=230749"},"modified":"2022-06-07T19:30:55","modified_gmt":"2022-06-07T17:30:55","slug":"zlm-tour-2022-le-profil-des-etapes","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/zlm-tour-2022-le-profil-des-etapes\/","title":{"rendered":"ZLM Tour 2022 : le profil des \u00e9tapes"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/cyclisme\/\" target=\"_blank\" rel=\"noopener\">CYCLISME<\/a> &#8211; C&rsquo;est ce mercredi 8 juin que d\u00e9bute le ZLM Tour 2022. D\u00e9couvrez le profil des \u00e9tapes de cette 33\u00e8me \u00e9dition<\/strong><\/em><em><strong>.<br \/>\n<\/strong><\/em><\/p>\n<h2 style=\"text-align: justify;\">1\u00e8re \u00e9tape &#8211; Kapelle &#8211; Kapelle : Mercredi 8 juin 2022<\/h2>\n<p style=\"text-align: justify;\">\u00c9tape plate longue de 100,9 km.<\/p>\n<div id=\"attachment_230759\" style=\"width: 1260px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-Etape-1.jpeg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-230759\" class=\"size-full wp-image-230759\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-Etape-1.jpeg\" alt=\"\" width=\"1250\" height=\"625\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-Etape-1.jpeg 1250w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-Etape-1-300x150.jpeg 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-Etape-1-1024x512.jpeg 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-Etape-1-768x384.jpeg 768w\" sizes=\"auto, (max-width: 1250px) 100vw, 1250px\" \/><\/a><p id=\"caption-attachment-230759\" class=\"wp-caption-text\">\u00a9 Pro Cycling Stats<\/p><\/div>\n<p style=\"text-align: center;\"><a href=\"http:\/\/dicodusport.fr\/blog\/zlm-tour-2022-le-profil-des-etapes\/2\/#deux\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#005f9b;border-color:#004c7c;border-radius:4px\" target=\"_self\"><span style=\"color:#FFFFFF;padding:0px 20px;font-size:16px;line-height:32px;border-color:#4d8fb9;border-radius:4px;text-shadow:none\"> Deuxi\u00e8me \u00e9tape<\/span><\/a><!--nextpage--><\/p>\n<h2 style=\"text-align: justify;\"><a id=\"deux\"><\/a>2\u00e8me \u00e9tape &#8211; Veere &#8211; Goes : Jeudi 9 juin 2022<\/h2>\n<p style=\"text-align: justify;\">\u00c9tape plate longue de 183,2 km.<\/p>\n<div id=\"attachment_230758\" style=\"width: 1460px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-Etape-2.jpeg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-230758\" class=\"size-full wp-image-230758\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-Etape-2.jpeg\" alt=\"\" width=\"1450\" height=\"625\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-Etape-2.jpeg 1450w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-Etape-2-300x129.jpeg 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-Etape-2-1024x441.jpeg 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-Etape-2-768x331.jpeg 768w\" sizes=\"auto, (max-width: 1450px) 100vw, 1450px\" \/><\/a><p id=\"caption-attachment-230758\" class=\"wp-caption-text\">\u00a9 Pro Cycling Stats<\/p><\/div>\n<p style=\"text-align: center;\"><a href=\"http:\/\/dicodusport.fr\/blog\/zlm-tour-2022-le-profil-des-etapes\/3\/#trois\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#005f9b;border-color:#004c7c;border-radius:4px\" target=\"_self\"><span style=\"color:#FFFFFF;padding:0px 20px;font-size:16px;line-height:32px;border-color:#4d8fb9;border-radius:4px;text-shadow:none\"> Troisi\u00e8me \u00e9tape<\/span><\/a>\n<p><!--nextpage--><\/p>\n<h2 style=\"text-align: justify;\"><a id=\"trois\"><\/a>3\u00e8me \u00e9tape &#8211; Heythuysen &#8211; Buchten : Vendredi 10 juin 2022<\/h2>\n<p style=\"text-align: justify;\">\u00c9tape accident\u00e9e longue de 192,5 km.<\/p>\n<div id=\"attachment_230757\" style=\"width: 1460px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-Etape-3.jpeg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-230757\" class=\"size-full wp-image-230757\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-Etape-3.jpeg\" alt=\"\" width=\"1450\" height=\"625\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-Etape-3.jpeg 1450w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-Etape-3-300x129.jpeg 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-Etape-3-1024x441.jpeg 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-Etape-3-768x331.jpeg 768w\" sizes=\"auto, (max-width: 1450px) 100vw, 1450px\" \/><\/a><p id=\"caption-attachment-230757\" class=\"wp-caption-text\">\u00a9 Pro Cycling Stats<\/p><\/div>\n<p style=\"text-align: center;\"><a href=\"http:\/\/dicodusport.fr\/blog\/zlm-tour-2022-le-profil-des-etapes\/4\/#quatre\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#005f9b;border-color:#004c7c;border-radius:4px\" target=\"_self\"><span style=\"color:#FFFFFF;padding:0px 20px;font-size:16px;line-height:32px;border-color:#4d8fb9;border-radius:4px;text-shadow:none\"> Quatri\u00e8me \u00e9tape<\/span><\/a>\n<p><!--nextpage--><\/p>\n<h2 style=\"text-align: justify;\"><a id=\"quatre\"><\/a>4\u00e8me \u00e9tape &#8211; Sint Willebrord &#8211; Mierlo : Samedi 11 juin 2022<\/h2>\n<p style=\"text-align: justify;\">\u00c9tape plate longue de 196,5 km.<\/p>\n<div id=\"attachment_230756\" style=\"width: 1460px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-Etape-4.jpeg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-230756\" class=\"size-full wp-image-230756\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-Etape-4.jpeg\" alt=\"\" width=\"1450\" height=\"625\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-Etape-4.jpeg 1450w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-Etape-4-300x129.jpeg 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-Etape-4-1024x441.jpeg 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-Etape-4-768x331.jpeg 768w\" sizes=\"auto, (max-width: 1450px) 100vw, 1450px\" \/><\/a><p id=\"caption-attachment-230756\" class=\"wp-caption-text\">\u00a9 Pro Cycling Stats<\/p><\/div>\n<p style=\"text-align: center;\"><a href=\"http:\/\/dicodusport.fr\/blog\/zlm-tour-2022-le-profil-des-etapes\/5\/#cinq\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#005f9b;border-color:#004c7c;border-radius:4px\" target=\"_self\"><span style=\"color:#FFFFFF;padding:0px 20px;font-size:16px;line-height:32px;border-color:#4d8fb9;border-radius:4px;text-shadow:none\"> Cinqui\u00e8me \u00e9tape<\/span><\/a>\n<p><!--nextpage--><\/p>\n<h2 style=\"text-align: justify;\"><a id=\"cinq\"><\/a>5\u00e8me \u00e9tape &#8211; Made &#8211; Rijsbergen : Dimanche 12 juin 2022<\/h2>\n<p style=\"text-align: justify;\">\u00c9tape plate longue de 160,5 km.<\/p>\n<div id=\"attachment_230755\" style=\"width: 1260px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-Etape-5.jpeg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-230755\" class=\"size-full wp-image-230755\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-Etape-5.jpeg\" alt=\"\" width=\"1250\" height=\"625\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-Etape-5.jpeg 1250w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-Etape-5-300x150.jpeg 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-Etape-5-1024x512.jpeg 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-Etape-5-768x384.jpeg 768w\" sizes=\"auto, (max-width: 1250px) 100vw, 1250px\" \/><\/a><p id=\"caption-attachment-230755\" class=\"wp-caption-text\">\u00a9 Pro Cycling Stats<\/p><\/div>\n<p style=\"text-align: center;\"><a href=\"http:\/\/dicodusport.fr\/blog\/zlm-tour-2022-le-profil-des-etapes\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#005f9b;border-color:#004c7c;border-radius:4px\" target=\"_self\"><span style=\"color:#FFFFFF;padding:0px 20px;font-size:16px;line-height:32px;border-color:#4d8fb9;border-radius:4px;text-shadow:none\"> Revenir au d\u00e9but<\/span><\/a>\n<h2 style=\"text-align: justify;\">\u00c0 lire aussi<\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/les-engages-du-zlm-tour-2022\/\" target=\"_blank\" rel=\"noopener\"><strong>ZLM Tour 2022 : la liste des engag\u00e9s<\/strong><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>CYCLISME &#8211; C&rsquo;est ce mercredi 8 juin que d\u00e9bute le ZLM Tour 2022. D\u00e9couvrez le profil des \u00e9tapes de cette 33\u00e8me \u00e9dition.<\/p>\n","protected":false},"author":1,"featured_media":230761,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[46994],"tags":[24042],"class_list":["post-230749","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cyclisme-sur-route","tag-zlm-tour"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ZLM Tour 2022 : le profil des \u00e9tapes<\/title>\n<meta name=\"description\" content=\"CYCLISME - C&#039;est ce mercredi 8 juin que d\u00e9bute le ZLM Tour 2022. D\u00e9couvrez le profil des \u00e9tapes de cette 33\u00e8me \u00e9dition.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/zlm-tour-2022-le-profil-des-etapes\/\" \/>\n<link rel=\"next\" href=\"https:\/\/dicodusport.fr\/blog\/zlm-tour-2022-le-profil-des-etapes\/2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ZLM Tour 2022 : le profil des \u00e9tapes\" \/>\n<meta property=\"og:description\" content=\"CYCLISME - C&#039;est ce mercredi 8 juin que d\u00e9bute le ZLM Tour 2022. D\u00e9couvrez le profil des \u00e9tapes de cette 33\u00e8me \u00e9dition.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/zlm-tour-2022-le-profil-des-etapes\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-07T13:14:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-07T17:30:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-2022-le-profil-des-e\u0301tapes.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"ZLM Tour 2022 : le profil des \u00e9tapes\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/zlm-tour-2022-le-profil-des-etapes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/zlm-tour-2022-le-profil-des-etapes\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"ZLM Tour 2022 : le profil des \u00e9tapes\",\"datePublished\":\"2022-06-07T13:14:44+00:00\",\"dateModified\":\"2022-06-07T17:30:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/zlm-tour-2022-le-profil-des-etapes\/\"},\"wordCount\":265,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/zlm-tour-2022-le-profil-des-etapes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-2022-le-profil-des-e\u0301tapes.png\",\"keywords\":[\"ZLM tour\"],\"articleSection\":[\"Cyclisme sur route\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/zlm-tour-2022-le-profil-des-etapes\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/zlm-tour-2022-le-profil-des-etapes\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/zlm-tour-2022-le-profil-des-etapes\/\",\"name\":\"ZLM Tour 2022 : le profil des \u00e9tapes\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/zlm-tour-2022-le-profil-des-etapes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/zlm-tour-2022-le-profil-des-etapes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-2022-le-profil-des-e\u0301tapes.png\",\"datePublished\":\"2022-06-07T13:14:44+00:00\",\"dateModified\":\"2022-06-07T17:30:55+00:00\",\"description\":\"CYCLISME - C'est ce mercredi 8 juin que d\u00e9bute le ZLM Tour 2022. D\u00e9couvrez le profil des \u00e9tapes de cette 33\u00e8me \u00e9dition.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/zlm-tour-2022-le-profil-des-etapes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/zlm-tour-2022-le-profil-des-etapes\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-2022-le-profil-des-e\u0301tapes.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-2022-le-profil-des-e\u0301tapes.png\",\"width\":800,\"height\":445},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ZLM Tour 2022 : le profil des \u00e9tapes","description":"CYCLISME - C'est ce mercredi 8 juin que d\u00e9bute le ZLM Tour 2022. D\u00e9couvrez le profil des \u00e9tapes de cette 33\u00e8me \u00e9dition.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/zlm-tour-2022-le-profil-des-etapes\/","next":"https:\/\/dicodusport.fr\/blog\/zlm-tour-2022-le-profil-des-etapes\/2\/","og_locale":"fr_FR","og_type":"article","og_title":"ZLM Tour 2022 : le profil des \u00e9tapes","og_description":"CYCLISME - C'est ce mercredi 8 juin que d\u00e9bute le ZLM Tour 2022. D\u00e9couvrez le profil des \u00e9tapes de cette 33\u00e8me \u00e9dition.","og_url":"https:\/\/dicodusport.fr\/blog\/zlm-tour-2022-le-profil-des-etapes\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2022-06-07T13:14:44+00:00","article_modified_time":"2022-06-07T17:30:55+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-2022-le-profil-des-e\u0301tapes.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"ZLM Tour 2022 : le profil des \u00e9tapes","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/zlm-tour-2022-le-profil-des-etapes\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/zlm-tour-2022-le-profil-des-etapes\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"ZLM Tour 2022 : le profil des \u00e9tapes","datePublished":"2022-06-07T13:14:44+00:00","dateModified":"2022-06-07T17:30:55+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/zlm-tour-2022-le-profil-des-etapes\/"},"wordCount":265,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/zlm-tour-2022-le-profil-des-etapes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-2022-le-profil-des-e\u0301tapes.png","keywords":["ZLM tour"],"articleSection":["Cyclisme sur route"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/zlm-tour-2022-le-profil-des-etapes\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/zlm-tour-2022-le-profil-des-etapes\/","url":"https:\/\/dicodusport.fr\/blog\/zlm-tour-2022-le-profil-des-etapes\/","name":"ZLM Tour 2022 : le profil des \u00e9tapes","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/zlm-tour-2022-le-profil-des-etapes\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/zlm-tour-2022-le-profil-des-etapes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-2022-le-profil-des-e\u0301tapes.png","datePublished":"2022-06-07T13:14:44+00:00","dateModified":"2022-06-07T17:30:55+00:00","description":"CYCLISME - C'est ce mercredi 8 juin que d\u00e9bute le ZLM Tour 2022. D\u00e9couvrez le profil des \u00e9tapes de cette 33\u00e8me \u00e9dition.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/zlm-tour-2022-le-profil-des-etapes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/zlm-tour-2022-le-profil-des-etapes\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-2022-le-profil-des-e\u0301tapes.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/ZLM-Tour-2022-le-profil-des-e\u0301tapes.png","width":800,"height":445},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/230749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=230749"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/230749\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/230761"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=230749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=230749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=230749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}