{"id":230943,"date":"2022-06-08T11:00:03","date_gmt":"2022-06-08T09:00:03","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=230943&#038;preview=true&#038;preview_id=230943"},"modified":"2022-11-30T08:39:59","modified_gmt":"2022-11-30T07:39:59","slug":"tour-de-france-2024-vers-une-edition-historique-avec-une-arrivee-finale-a-nice","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2024-vers-une-edition-historique-avec-une-arrivee-finale-a-nice\/","title":{"rendered":"Tour de France 2024 : Vers une \u00e9dition historique, avec une arriv\u00e9e finale \u00e0 Nice"},"content":{"rendered":"<p style=\"text-align: justify;\"><b><i>TOUR DE FRANCE 2024 &#8211; Selon les informations de la Gazzetta dello Sport, la 111\u00e8me \u00e9dition du Tour de France pourrait \u00eatre historique \u00e0 plus d&rsquo;un titre.<\/i><\/b><\/p>\n<p style=\"text-align: justify;\">2024 rimera avec \u00e9t\u00e9 de folie en termes d&rsquo;\u00e9v\u00e9nements sportifs en France. Car outre le <strong>Tour de France<\/strong>, ce sont bien s\u00fbr les <a href=\"https:\/\/dicodusport.fr\/blog\/jo-paris-2024\/\"><strong>Jeux Olympiques<\/strong> <strong>2024<\/strong><\/a> qui seront organis\u00e9s dans l&rsquo;Hexagone (26 juillet au 11 ao\u00fbt). Ainsi, l&rsquo;arriv\u00e9e de la 111\u00e8me \u00e9dition de la Grande Boucle, pr\u00e9vue le dimanche 21 juillet, pourrait \u00eatre d\u00e9localis\u00e9e. C&rsquo;est, en tout cas, ce qu&rsquo;avance la <a href=\"https:\/\/www.gazzetta.it\/ciclismo\/tour-de-france\/08-06-2022\/tour-de-france-2024-italia-partenza-firenze-440885902270.shtml\" target=\"_blank\" rel=\"nofollow noopener\"><em>Gazzetta dello Sport<\/em><\/a> ce mercredi. L&rsquo;arriv\u00e9e finale traditionnelle, qui a lieu sur les Champs-\u00c9lys\u00e9es, serait alors d\u00e9plac\u00e9e sur la Promenade des Anglais, \u00e0 Nice. Une information qui est, d\u00e9sormais, amen\u00e9e \u00e0 \u00eatre confirm\u00e9e prochainement, lors de l&rsquo;annonce du Grand D\u00e9part du Tour 2024.<\/p>\n<p style=\"text-align: justify;\">\u00c0 ce propos, le quotidien italien confirme que le <strong>Tour de France 2024<\/strong> partira bien d&rsquo;Italie, et plus pr\u00e9cis\u00e9ment de <strong>Florence<\/strong>. Les trois premi\u00e8res \u00e9tapes seraient m\u00eame 100% transalpines, puisque la premi\u00e8re journ\u00e9e devrait mener le peloton jusqu&rsquo;\u00e0 <strong>Rimini<\/strong>. La deuxi\u00e8me \u00e9tape s&rsquo;\u00e9lancerait de <strong>Cesenatico<\/strong>, ville de naissance du regrett\u00e9 Marco Pantani, pour une arriv\u00e9e \u00e0 <strong>Bologne<\/strong>. La troisi\u00e8me et derni\u00e8re \u00e9tape italienne rallierait <strong>Mod\u00e8ne<\/strong> \u00e0 <strong>Plaisance<\/strong>, avant l&rsquo;entr\u00e9e en France.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Info <a href=\"https:\/\/twitter.com\/Gazzetta_it?ref_src=twsrc%5Etfw\">@Gazzetta_it<\/a> about <a href=\"https:\/\/twitter.com\/LeTour?ref_src=twsrc%5Etfw\">@LeTour<\/a> 2024 (more details on today paper edition). Florence is likely to host le grand depart &#8211; first time for Italy since 1903 &#8211; and finish could be in Nice and not in Paris to avoid nearness with Olympic Games in French capital <a href=\"https:\/\/twitter.com\/cycling_podcast?ref_src=twsrc%5Etfw\">@cycling_podcast<\/a><\/p>\n<p>\u2014 Ciro Scognamiglio (@cirogazzetta) <a href=\"https:\/\/twitter.com\/cirogazzetta\/status\/1534422688692944896?ref_src=twsrc%5Etfw\">June 8, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TOUR DE FRANCE 2024 &#8211; Selon les informations de la Gazzetta dello Sport, la 111\u00e8me \u00e9dition du Tour de France pourrait \u00eatre historique \u00e0 plus d&rsquo;un titre.<\/p>\n","protected":false},"author":4,"featured_media":230950,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2307,46995],"tags":[1262],"class_list":["post-230943","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cyclisme","category-tour-de-france","tag-tour-de-france"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tour de France 2024 : Vers une \u00e9dition historique, avec une arriv\u00e9e finale \u00e0 Nice<\/title>\n<meta name=\"description\" content=\"TOUR DE FRANCE 2024 - Selon la Gazzetta dello Sport, la 111\u00e8me \u00e9dition du Tour de France pourrait \u00eatre historique \u00e0 plus d&#039;un titre.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2024-vers-une-edition-historique-avec-une-arrivee-finale-a-nice\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tour de France 2024 : Vers une \u00e9dition historique, avec une arriv\u00e9e finale \u00e0 Nice\" \/>\n<meta property=\"og:description\" content=\"TOUR DE FRANCE 2024 - Selon la Gazzetta dello Sport, la 111\u00e8me \u00e9dition du Tour de France pourrait \u00eatre historique \u00e0 plus d&#039;un titre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2024-vers-une-edition-historique-avec-une-arrivee-finale-a-nice\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-08T09:00:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-30T07:39:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Tour-de-France-2024-Vers-une-edition-historique-avec-une-arrivee-finale-a-Nice.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Tour de France 2024 : Vers une \u00e9dition historique, avec une arriv\u00e9e finale \u00e0 Nice\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2024-vers-une-edition-historique-avec-une-arrivee-finale-a-nice\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2024-vers-une-edition-historique-avec-une-arrivee-finale-a-nice\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Tour de France 2024 : Vers une \u00e9dition historique, avec une arriv\u00e9e finale \u00e0 Nice\",\"datePublished\":\"2022-06-08T09:00:03+00:00\",\"dateModified\":\"2022-11-30T07:39:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2024-vers-une-edition-historique-avec-une-arrivee-finale-a-nice\/\"},\"wordCount\":291,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2024-vers-une-edition-historique-avec-une-arrivee-finale-a-nice\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Tour-de-France-2024-Vers-une-edition-historique-avec-une-arrivee-finale-a-Nice.png\",\"keywords\":[\"Tour de France\"],\"articleSection\":[\"Cyclisme\",\"Tour de France\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2024-vers-une-edition-historique-avec-une-arrivee-finale-a-nice\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2024-vers-une-edition-historique-avec-une-arrivee-finale-a-nice\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2024-vers-une-edition-historique-avec-une-arrivee-finale-a-nice\/\",\"name\":\"Tour de France 2024 : Vers une \u00e9dition historique, avec une arriv\u00e9e finale \u00e0 Nice\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2024-vers-une-edition-historique-avec-une-arrivee-finale-a-nice\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2024-vers-une-edition-historique-avec-une-arrivee-finale-a-nice\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Tour-de-France-2024-Vers-une-edition-historique-avec-une-arrivee-finale-a-Nice.png\",\"datePublished\":\"2022-06-08T09:00:03+00:00\",\"dateModified\":\"2022-11-30T07:39:59+00:00\",\"description\":\"TOUR DE FRANCE 2024 - Selon la Gazzetta dello Sport, la 111\u00e8me \u00e9dition du Tour de France pourrait \u00eatre historique \u00e0 plus d'un titre.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2024-vers-une-edition-historique-avec-une-arrivee-finale-a-nice\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2024-vers-une-edition-historique-avec-une-arrivee-finale-a-nice\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2024-vers-une-edition-historique-avec-une-arrivee-finale-a-nice\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Tour-de-France-2024-Vers-une-edition-historique-avec-une-arrivee-finale-a-Nice.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Tour-de-France-2024-Vers-une-edition-historique-avec-une-arrivee-finale-a-Nice.png\",\"width\":800,\"height\":445,\"caption\":\"Tour de France 2024 Vers une \u00e9dition historique, avec une arriv\u00e9e finale \u00e0 Nice\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2024-vers-une-edition-historique-avec-une-arrivee-finale-a-nice\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tour de France 2024 : Vers une \u00e9dition historique, avec une arriv\u00e9e finale \u00e0 Nice\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tour de France 2024 : Vers une \u00e9dition historique, avec une arriv\u00e9e finale \u00e0 Nice","description":"TOUR DE FRANCE 2024 - Selon la Gazzetta dello Sport, la 111\u00e8me \u00e9dition du Tour de France pourrait \u00eatre historique \u00e0 plus d'un titre.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2024-vers-une-edition-historique-avec-une-arrivee-finale-a-nice\/","og_locale":"fr_FR","og_type":"article","og_title":"Tour de France 2024 : Vers une \u00e9dition historique, avec une arriv\u00e9e finale \u00e0 Nice","og_description":"TOUR DE FRANCE 2024 - Selon la Gazzetta dello Sport, la 111\u00e8me \u00e9dition du Tour de France pourrait \u00eatre historique \u00e0 plus d'un titre.","og_url":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2024-vers-une-edition-historique-avec-une-arrivee-finale-a-nice\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2022-06-08T09:00:03+00:00","article_modified_time":"2022-11-30T07:39:59+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Tour-de-France-2024-Vers-une-edition-historique-avec-une-arrivee-finale-a-Nice.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Tour de France 2024 : Vers une \u00e9dition historique, avec une arriv\u00e9e finale \u00e0 Nice","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2024-vers-une-edition-historique-avec-une-arrivee-finale-a-nice\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2024-vers-une-edition-historique-avec-une-arrivee-finale-a-nice\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Tour de France 2024 : Vers une \u00e9dition historique, avec une arriv\u00e9e finale \u00e0 Nice","datePublished":"2022-06-08T09:00:03+00:00","dateModified":"2022-11-30T07:39:59+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2024-vers-une-edition-historique-avec-une-arrivee-finale-a-nice\/"},"wordCount":291,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2024-vers-une-edition-historique-avec-une-arrivee-finale-a-nice\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Tour-de-France-2024-Vers-une-edition-historique-avec-une-arrivee-finale-a-Nice.png","keywords":["Tour de France"],"articleSection":["Cyclisme","Tour de France"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/tour-de-france-2024-vers-une-edition-historique-avec-une-arrivee-finale-a-nice\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2024-vers-une-edition-historique-avec-une-arrivee-finale-a-nice\/","url":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2024-vers-une-edition-historique-avec-une-arrivee-finale-a-nice\/","name":"Tour de France 2024 : Vers une \u00e9dition historique, avec une arriv\u00e9e finale \u00e0 Nice","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2024-vers-une-edition-historique-avec-une-arrivee-finale-a-nice\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2024-vers-une-edition-historique-avec-une-arrivee-finale-a-nice\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Tour-de-France-2024-Vers-une-edition-historique-avec-une-arrivee-finale-a-Nice.png","datePublished":"2022-06-08T09:00:03+00:00","dateModified":"2022-11-30T07:39:59+00:00","description":"TOUR DE FRANCE 2024 - Selon la Gazzetta dello Sport, la 111\u00e8me \u00e9dition du Tour de France pourrait \u00eatre historique \u00e0 plus d'un titre.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2024-vers-une-edition-historique-avec-une-arrivee-finale-a-nice\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/tour-de-france-2024-vers-une-edition-historique-avec-une-arrivee-finale-a-nice\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2024-vers-une-edition-historique-avec-une-arrivee-finale-a-nice\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Tour-de-France-2024-Vers-une-edition-historique-avec-une-arrivee-finale-a-Nice.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Tour-de-France-2024-Vers-une-edition-historique-avec-une-arrivee-finale-a-Nice.png","width":800,"height":445,"caption":"Tour de France 2024 Vers une \u00e9dition historique, avec une arriv\u00e9e finale \u00e0 Nice"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2024-vers-une-edition-historique-avec-une-arrivee-finale-a-nice\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Tour de France 2024 : Vers une \u00e9dition historique, avec une arriv\u00e9e finale \u00e0 Nice"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/230943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=230943"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/230943\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/230950"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=230943"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=230943"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=230943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}