{"id":231330,"date":"2022-06-09T16:39:03","date_gmt":"2022-06-09T14:39:03","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=231330&#038;preview=true&#038;preview_id=231330"},"modified":"2022-06-09T18:14:06","modified_gmt":"2022-06-09T16:14:06","slug":"criterium-du-dauphine-2022-wout-van-aert-double-la-mise-sur-la-5eme-etape","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/criterium-du-dauphine-2022-wout-van-aert-double-la-mise-sur-la-5eme-etape\/","title":{"rendered":"Crit\u00e9rium du Dauphin\u00e9 2022 : Wout Van Aert double la mise sur la 5\u00e8me \u00e9tape"},"content":{"rendered":"<p style=\"text-align: justify;\"><b><i>CRITERIUM DU DAUPHINE 2022, 5\u00c8ME ETAPE &#8211; Cette \u00e9tape a vu un duel de haut vol entre les \u00e9chapp\u00e9s et le peloton. Finalement, il aura manqu\u00e9 trois cent m\u00e8tres aux fuyards. Au sprint, Wout Van Aert (Jumbo-Visma) s&rsquo;est impos\u00e9 devant Jordi Meeus (Bora-Hansgrohe) et Ethan Hayter (INEOS Grenadiers). Deuxi\u00e8me victoire de la semaine pour le Belge, qui effectue pour l&rsquo;instant une semaine quasi parfaite.\u00a0<\/i><\/b><\/p>\n<h2 style=\"text-align: justify;\">Derni\u00e8re chance de la semaine pour les sprinteurs<\/h2>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/criterium-du-dauphine-2022-filippo-ganna-remporte-chrono-4eme-etape\/\">Apr\u00e8s le duel entre <strong>Filippo Ganna<\/strong> et <strong>Wout Van Aert<\/strong> sur le contre-la-montre la veille<\/a>, une \u00e9tape de transition \u00e9tait au programme aujourd&rsquo;hui avant le gros morceau qui attend les coureurs ce week-end. \u00c0 premi\u00e8re vue, cette cinqui\u00e8me \u00e9tape entre Thizy-les-Bourgs et Chaintr\u00e9 devait faire la part belle aux sprinteurs. Mais avec 2 000 m\u00e8tres de d\u00e9nivel\u00e9 positif et quatre difficult\u00e9s r\u00e9pertori\u00e9es, tous les sc\u00e9narios \u00e9taient possibles.<\/p>\n<p style=\"text-align: justify;\">L&rsquo;\u00e9chapp\u00e9e a mis beaucoup de temps \u00e0 se dessiner puisque le d\u00e9but de course fut tr\u00e8s rythm\u00e9. <strong>R\u00e9mi Cavagna<\/strong> et <strong>Alexis<\/strong> <strong>Vuillermoz<\/strong> ont tent\u00e9 leur chance en d\u00e9but de course, mais c&rsquo;est finalement dans le col des Ecorbans que la s\u00e9lection s&rsquo;est faite. Au sortir de cette premi\u00e8re difficult\u00e9 du jour, un trio d&rsquo;attaquants form\u00e9 de <strong>Jan Balekants<\/strong> (Intermarch\u00e9-Wanty-Gobert), <strong>Fabien Doubey<\/strong> (TotalEnergies) et<strong> Sebastian Sch\u00f6nberger<\/strong> (B&amp;B &#8211; H\u00f4tels), \u00e9chapp\u00e9 avant-hier, a pris le large. Derri\u00e8re, <strong>Pierre Rolland<\/strong> \u00e9tait sorti en contre pour rejoindre son coll\u00e8gue autrichien, ainsi que <strong>Wout Van Aert<\/strong>, mais ce dernier s&rsquo;est vite ravis\u00e9. Au contraire de <strong>Benjamin Thomas<\/strong> (Cofidis), le champion de France en titre du contre-la-montre, qui a pu faire la jonction, accompagn\u00e9 de <strong>Pierre Rolland<\/strong> qui a poursuivi son effort.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"und\">&#x1f3c1; 72km<br \/>\n4&#xfe0f;&#x20e3;&#x1f6b4;&#x1f3fb;&#x200d;&#x2642;&#xfe0f; &lt; 1&rsquo;45\u00a0\u00bb &lt; &#x1f6b4;&#x1f3fb;&#x200d;&#x2642;&#xfe0f;&#x1f6b4;&#x1f3fb;&#x200d;&#x2642;&#xfe0f;&#x1f6b4;&#x1f3fb;&#x200d;&#x2642;&#xfe0f;&#x1f6b4;&#x1f3fb;&#x200d;&#x2642;&#xfe0f;&#x1f697;<\/p>\n<p>&#x1f1eb;&#x1f1f7;<a href=\"https:\/\/twitter.com\/Ben__Thomas_?ref_src=twsrc%5Etfw\">@Ben__Thomas_<\/a><br \/>\n&#x1f1eb;&#x1f1f7;<a href=\"https:\/\/twitter.com\/FabienDoubey?ref_src=twsrc%5Etfw\">@FabienDoubey<\/a><br \/>\n&#x1f1e7;&#x1f1ea;<a href=\"https:\/\/twitter.com\/Jan_Bakelants?ref_src=twsrc%5Etfw\">@Jan_Bakelants<\/a><br \/>\n&#x1f1e6;&#x1f1f9;<a href=\"https:\/\/twitter.com\/schoeni1994?ref_src=twsrc%5Etfw\">@schoeni1994<\/a><a href=\"https:\/\/twitter.com\/hashtag\/Dauphin%C3%A9?src=hash&amp;ref_src=twsrc%5Etfw\">#Dauphin\u00e9<\/a> <a href=\"https:\/\/t.co\/qgx8j4f1JH\">pic.twitter.com\/qgx8j4f1JH<\/a><\/p>\n<p>\u2014 Crit\u00e9rium du Dauphin\u00e9 (@dauphine) <a href=\"https:\/\/twitter.com\/dauphine\/status\/1534886809456590850?ref_src=twsrc%5Etfw\">June 9, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Benjamin Thomas vs INEOS Grenadiers et la Jumbo-Visma<\/h2>\n<p style=\"text-align: justify;\">Dans la c\u00f4te de Dun, <strong>Pierre Rolland<\/strong> a s\u00e9curis\u00e9 son maillot de meilleur grimpeur en empochant les cinq points au sommet. Suite \u00e0 cet effort, le grimpeur de la B&amp;B H\u00f4tels &#8211; KTM a fait son retour dans le peloton, ils n&rsquo;\u00e9taient donc plus que quatre en t\u00eate avec un \u00e9cart qui n&rsquo;a jamais d\u00e9pass\u00e9 les deux minutes avec le peloton. Moqu\u00e9s sur les r\u00e9seaux sociaux cette semaine pour leur strat\u00e9gie de course, les Bike Exchange &#8211; Jayco de <strong>Dylan Groenewegen<\/strong> \u00e9paulaient les Jumbo-Visma en t\u00eate de peloton. \u00c0 une trentaine de kilom\u00e8tres de l&rsquo;arriv\u00e9e, les quatre hommes de t\u00eate pouvaient toujours croire en leurs chance,s puisqu&rsquo;ils avaient toujours deux minutes d&rsquo;avance. Dans le peloton, les INEOS Grenadiers men\u00e9s par <strong>Filippo Ganna<\/strong> ont s\u00e9rieusement acc\u00e9l\u00e9r\u00e9 le rythme dans la c\u00f4te du Bois Clair (2.7 km \u00e0 3.7%), faisant chuter l&rsquo;\u00e9cart \u00e0 1 minute 15.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Alors que son \u00e9quipe a roul\u00e9 pour revenir sur les \u00e9chapp\u00e9s, &#x1f1f3;&#x1f1f1;<a href=\"https:\/\/twitter.com\/GroenewegenD?ref_src=twsrc%5Etfw\">@GroenewegenD<\/a> l\u00e2che prise dans la c\u00f4te de Vergisson !<\/p>\n<p>&#x1f1f3;&#x1f1f1;<a href=\"https:\/\/twitter.com\/GroenewegenD?ref_src=twsrc%5Etfw\">@GroenewegenD<\/a> is dropped in the C\u00f4te de Vergisson!<a href=\"https:\/\/twitter.com\/hashtag\/Dauphin%C3%A9?src=hash&amp;ref_src=twsrc%5Etfw\">#Dauphin\u00e9<\/a> <a href=\"https:\/\/t.co\/WlCk9JhVa9\">pic.twitter.com\/WlCk9JhVa9<\/a><\/p>\n<p>\u2014 Crit\u00e9rium du Dauphin\u00e9 (@dauphine) <a href=\"https:\/\/twitter.com\/dauphine\/status\/1534904113904898049?ref_src=twsrc%5Etfw\">June 9, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Devant, <strong>Benjamin Thomas<\/strong> faisait l&rsquo;essentiel du travail pour conserver des chances de victoire. Derri\u00e8re, dans ce final escarp\u00e9, les INEOS Grenadiers conservaient leur rythme en \u00e9tirant consid\u00e9rablement le peloton. L&rsquo;augmentation du rythme a \u00e9t\u00e9 fatale \u00e0 plusieurs coureurs comme <strong>Victor Lafay<\/strong> (Cofidis) ou <strong>Mark Padun<\/strong> (EF Easy-Post). Tout comme <strong>Dylan Groenewegen<\/strong>, qui d\u00e8s que la course s&rsquo;\u00e9l\u00e8ve a toujours autant de difficult\u00e9s \u00e0 rester dans les roues. Au sommet de la derni\u00e8re difficult\u00e9 du jour, la c\u00f4te de Vergisson, les \u00e9chapp\u00e9s n&rsquo;avaient plus qu&rsquo;une trentaine de secondes d&rsquo;avance.<\/p>\n<p style=\"text-align: justify;\">La fin de course fut haletante entre des \u00e9chapp\u00e9s h\u00e9ro\u00efques et un peloton lanc\u00e9 pleine balle. Finalement, les quatre fuyards ont \u00e9t\u00e9 repris \u00e0 300 m de l&rsquo;arriv\u00e9e, le moment o\u00f9 <strong>Christophe Laporte<\/strong> a lanc\u00e9 <strong>Wout Van Aert<\/strong>. Autoritaire, le Belge s&rsquo;est de nouveau impos\u00e9 sur cette arriv\u00e9e au sprint, pour signer sa deuxi\u00e8me victoire de la semaine. <strong>Jordi Meeus<\/strong>, le jeune sprinteur allemand, termine deuxi\u00e8me devant <strong>Ethan Hayter<\/strong>.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Cette fois, il ne s&rsquo;est pas laiss\u00e9 surprendre&#8230; Wout van Aert impose sa loi au sprint et s&rsquo;adjuge la 5e \u00e9tape du <a href=\"https:\/\/twitter.com\/hashtag\/Dauphin%C3%A9?src=hash&amp;ref_src=twsrc%5Etfw\">#Dauphin\u00e9<\/a> ! <a href=\"https:\/\/twitter.com\/hashtag\/LesRP?src=hash&amp;ref_src=twsrc%5Etfw\">#LesRP<\/a> <a href=\"https:\/\/t.co\/0kjRCuCuoo\">pic.twitter.com\/0kjRCuCuoo<\/a><\/p>\n<p>\u2014 Eurosport France (@Eurosport_FR) <a href=\"https:\/\/twitter.com\/Eurosport_FR\/status\/1534908527013158912?ref_src=twsrc%5Etfw\">June 9, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\"><strong>\u00c0 lire aussi<\/strong><\/h2>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/criterium-du-dauphine-2022-classement-5eme-etape\/\"><strong>Classement de la 5\u00e8me \u00e9tape\u00a0<\/strong><\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/criterium-du-dauphine-2022-classement-general\/\"><strong>Classement g\u00e9n\u00e9ral du Crit\u00e9rium du Dauphin\u00e9<\/strong><\/a><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>CRITERIUM DU DAUPHINE 2022, 5\u00c8ME ETAPE &#8211; Cette \u00e9tape a vu un duel de haut vol entre les \u00e9chapp\u00e9s et le peloton. Finalement, il aura manqu\u00e9 trois cent m\u00e8tres aux fuyards. Au sprint, Wout Van Aert (Jumbo-Visma) s&rsquo;est impos\u00e9 devant Jordi Meeus (Bora-Hansgrohe) et Ethan Hayter (INEOS Grenadiers). Deuxi\u00e8me victoire de la semaine pour le Belge, qui effectue pour l&rsquo;instant une semaine quasi parfaite.\u00a0<\/p>\n","protected":false},"author":42,"featured_media":231409,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[46994],"tags":[24],"class_list":["post-231330","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cyclisme-sur-route","tag-sport"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Crit\u00e9rium du Dauphin\u00e9 2022 : Wout Van Aert double la mise sur la 5\u00e8me \u00e9tape<\/title>\n<meta name=\"description\" content=\"CRITERIUM DU DAUPHIN\u00c9 2022 - Wout Van Aert s&#039;est impos\u00e9 au sprint sur la 5\u00e8me \u00e9tape, devant Jordi Meeus et Ethan Hayter.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/criterium-du-dauphine-2022-wout-van-aert-double-la-mise-sur-la-5eme-etape\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crit\u00e9rium du Dauphin\u00e9 2022 : Wout Van Aert double la mise sur la 5\u00e8me \u00e9tape\" \/>\n<meta property=\"og:description\" content=\"CRITERIUM DU DAUPHIN\u00c9 2022 - Wout Van Aert s&#039;est impos\u00e9 au sprint sur la 5\u00e8me \u00e9tape, devant Jordi Meeus et Ethan Hayter.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/criterium-du-dauphine-2022-wout-van-aert-double-la-mise-sur-la-5eme-etape\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-09T14:39:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-09T16:14:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Criterium-du-Dauphine-2022-Wout-Van-Aert-double-la-mise-sur-la-5eme-etape-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Mezine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Crit\u00e9rium du Dauphin\u00e9 2022 : Wout Van Aert double la mise sur la 5\u00e8me \u00e9tape\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Lbiji13\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/criterium-du-dauphine-2022-wout-van-aert-double-la-mise-sur-la-5eme-etape\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/criterium-du-dauphine-2022-wout-van-aert-double-la-mise-sur-la-5eme-etape\/\"},\"author\":{\"name\":\"Nicolas Mezine\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/99fcf31b3ee0d51fed53ade78139bbbf\"},\"headline\":\"Crit\u00e9rium du Dauphin\u00e9 2022 : Wout Van Aert double la mise sur la 5\u00e8me \u00e9tape\",\"datePublished\":\"2022-06-09T14:39:03+00:00\",\"dateModified\":\"2022-06-09T16:14:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/criterium-du-dauphine-2022-wout-van-aert-double-la-mise-sur-la-5eme-etape\/\"},\"wordCount\":872,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/criterium-du-dauphine-2022-wout-van-aert-double-la-mise-sur-la-5eme-etape\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Criterium-du-Dauphine-2022-Wout-Van-Aert-double-la-mise-sur-la-5eme-etape-1.png\",\"keywords\":[\"sport\"],\"articleSection\":[\"Cyclisme sur route\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/criterium-du-dauphine-2022-wout-van-aert-double-la-mise-sur-la-5eme-etape\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/criterium-du-dauphine-2022-wout-van-aert-double-la-mise-sur-la-5eme-etape\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/criterium-du-dauphine-2022-wout-van-aert-double-la-mise-sur-la-5eme-etape\/\",\"name\":\"Crit\u00e9rium du Dauphin\u00e9 2022 : Wout Van Aert double la mise sur la 5\u00e8me \u00e9tape\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/criterium-du-dauphine-2022-wout-van-aert-double-la-mise-sur-la-5eme-etape\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/criterium-du-dauphine-2022-wout-van-aert-double-la-mise-sur-la-5eme-etape\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Criterium-du-Dauphine-2022-Wout-Van-Aert-double-la-mise-sur-la-5eme-etape-1.png\",\"datePublished\":\"2022-06-09T14:39:03+00:00\",\"dateModified\":\"2022-06-09T16:14:06+00:00\",\"description\":\"CRITERIUM DU DAUPHIN\u00c9 2022 - Wout Van Aert s'est impos\u00e9 au sprint sur la 5\u00e8me \u00e9tape, devant Jordi Meeus et Ethan Hayter.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/criterium-du-dauphine-2022-wout-van-aert-double-la-mise-sur-la-5eme-etape\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/criterium-du-dauphine-2022-wout-van-aert-double-la-mise-sur-la-5eme-etape\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/criterium-du-dauphine-2022-wout-van-aert-double-la-mise-sur-la-5eme-etape\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Criterium-du-Dauphine-2022-Wout-Van-Aert-double-la-mise-sur-la-5eme-etape-1.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Criterium-du-Dauphine-2022-Wout-Van-Aert-double-la-mise-sur-la-5eme-etape-1.png\",\"width\":800,\"height\":445,\"caption\":\"Crit\u00e9rium du Dauphin\u00e9 2022 Wout Van Aert double la mise sur la 5\u00e8me \u00e9tape (1)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/criterium-du-dauphine-2022-wout-van-aert-double-la-mise-sur-la-5eme-etape\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Crit\u00e9rium du Dauphin\u00e9 2022 : Wout Van Aert double la mise sur la 5\u00e8me \u00e9tape\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/99fcf31b3ee0d51fed53ade78139bbbf\",\"name\":\"Nicolas Mezine\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/IMG_4655-e1631787111223-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/IMG_4655-e1631787111223-150x150.jpg\",\"caption\":\"Nicolas Mezine\"},\"description\":\"Passionn\u00e9 de sport, notamment de rugby dans toutes ses variantes (XV, XIII et VII). Fan du RC Toulon et de l'Olympique de Marseille.\",\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/nicolas-mezine-521380160\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/Lbiji13\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/nicolas-m\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Crit\u00e9rium du Dauphin\u00e9 2022 : Wout Van Aert double la mise sur la 5\u00e8me \u00e9tape","description":"CRITERIUM DU DAUPHIN\u00c9 2022 - Wout Van Aert s'est impos\u00e9 au sprint sur la 5\u00e8me \u00e9tape, devant Jordi Meeus et Ethan Hayter.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/criterium-du-dauphine-2022-wout-van-aert-double-la-mise-sur-la-5eme-etape\/","og_locale":"fr_FR","og_type":"article","og_title":"Crit\u00e9rium du Dauphin\u00e9 2022 : Wout Van Aert double la mise sur la 5\u00e8me \u00e9tape","og_description":"CRITERIUM DU DAUPHIN\u00c9 2022 - Wout Van Aert s'est impos\u00e9 au sprint sur la 5\u00e8me \u00e9tape, devant Jordi Meeus et Ethan Hayter.","og_url":"https:\/\/dicodusport.fr\/blog\/criterium-du-dauphine-2022-wout-van-aert-double-la-mise-sur-la-5eme-etape\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2022-06-09T14:39:03+00:00","article_modified_time":"2022-06-09T16:14:06+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Criterium-du-Dauphine-2022-Wout-Van-Aert-double-la-mise-sur-la-5eme-etape-1.png","type":"image\/png"}],"author":"Nicolas Mezine","twitter_card":"summary_large_image","twitter_title":"Crit\u00e9rium du Dauphin\u00e9 2022 : Wout Van Aert double la mise sur la 5\u00e8me \u00e9tape","twitter_creator":"@https:\/\/twitter.com\/Lbiji13","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/criterium-du-dauphine-2022-wout-van-aert-double-la-mise-sur-la-5eme-etape\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/criterium-du-dauphine-2022-wout-van-aert-double-la-mise-sur-la-5eme-etape\/"},"author":{"name":"Nicolas Mezine","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/99fcf31b3ee0d51fed53ade78139bbbf"},"headline":"Crit\u00e9rium du Dauphin\u00e9 2022 : Wout Van Aert double la mise sur la 5\u00e8me \u00e9tape","datePublished":"2022-06-09T14:39:03+00:00","dateModified":"2022-06-09T16:14:06+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/criterium-du-dauphine-2022-wout-van-aert-double-la-mise-sur-la-5eme-etape\/"},"wordCount":872,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/criterium-du-dauphine-2022-wout-van-aert-double-la-mise-sur-la-5eme-etape\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Criterium-du-Dauphine-2022-Wout-Van-Aert-double-la-mise-sur-la-5eme-etape-1.png","keywords":["sport"],"articleSection":["Cyclisme sur route"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/criterium-du-dauphine-2022-wout-van-aert-double-la-mise-sur-la-5eme-etape\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/criterium-du-dauphine-2022-wout-van-aert-double-la-mise-sur-la-5eme-etape\/","url":"https:\/\/dicodusport.fr\/blog\/criterium-du-dauphine-2022-wout-van-aert-double-la-mise-sur-la-5eme-etape\/","name":"Crit\u00e9rium du Dauphin\u00e9 2022 : Wout Van Aert double la mise sur la 5\u00e8me \u00e9tape","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/criterium-du-dauphine-2022-wout-van-aert-double-la-mise-sur-la-5eme-etape\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/criterium-du-dauphine-2022-wout-van-aert-double-la-mise-sur-la-5eme-etape\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Criterium-du-Dauphine-2022-Wout-Van-Aert-double-la-mise-sur-la-5eme-etape-1.png","datePublished":"2022-06-09T14:39:03+00:00","dateModified":"2022-06-09T16:14:06+00:00","description":"CRITERIUM DU DAUPHIN\u00c9 2022 - Wout Van Aert s'est impos\u00e9 au sprint sur la 5\u00e8me \u00e9tape, devant Jordi Meeus et Ethan Hayter.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/criterium-du-dauphine-2022-wout-van-aert-double-la-mise-sur-la-5eme-etape\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/criterium-du-dauphine-2022-wout-van-aert-double-la-mise-sur-la-5eme-etape\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/criterium-du-dauphine-2022-wout-van-aert-double-la-mise-sur-la-5eme-etape\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Criterium-du-Dauphine-2022-Wout-Van-Aert-double-la-mise-sur-la-5eme-etape-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Criterium-du-Dauphine-2022-Wout-Van-Aert-double-la-mise-sur-la-5eme-etape-1.png","width":800,"height":445,"caption":"Crit\u00e9rium du Dauphin\u00e9 2022 Wout Van Aert double la mise sur la 5\u00e8me \u00e9tape (1)"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/criterium-du-dauphine-2022-wout-van-aert-double-la-mise-sur-la-5eme-etape\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Crit\u00e9rium du Dauphin\u00e9 2022 : Wout Van Aert double la mise sur la 5\u00e8me \u00e9tape"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/99fcf31b3ee0d51fed53ade78139bbbf","name":"Nicolas Mezine","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/IMG_4655-e1631787111223-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/IMG_4655-e1631787111223-150x150.jpg","caption":"Nicolas Mezine"},"description":"Passionn\u00e9 de sport, notamment de rugby dans toutes ses variantes (XV, XIII et VII). Fan du RC Toulon et de l'Olympique de Marseille.","sameAs":["https:\/\/www.linkedin.com\/in\/nicolas-mezine-521380160\/","https:\/\/x.com\/https:\/\/twitter.com\/Lbiji13"],"url":"https:\/\/dicodusport.fr\/blog\/author\/nicolas-m\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/231330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=231330"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/231330\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/231409"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=231330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=231330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=231330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}