{"id":232314,"date":"2022-06-12T10:05:59","date_gmt":"2022-06-12T08:05:59","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=232314&#038;preview=true&#038;preview_id=232314"},"modified":"2022-06-12T10:05:59","modified_gmt":"2022-06-12T08:05:59","slug":"volley-golden-european-league-les-bleues-en-demi-finales","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/volley-golden-european-league-les-bleues-en-demi-finales\/","title":{"rendered":"Volley Golden European League : Les Bleues en demi-finales"},"content":{"rendered":"<p style=\"text-align: justify;\"><b><i>GOLDEN EUROPEAN LEAGUE DE VOLLEY &#8211; Les Tricolores n&rsquo;ont pas pris \u00e0 la l\u00e9g\u00e8re cette comp\u00e9tition et ont remport\u00e9 tous leurs matchs de poule. Ainsi, elles se qualifient pour les demi-finales pr\u00e9vues jeudi.<\/i><\/b><\/p>\n<p style=\"text-align: justify;\">La Golden European League est une comp\u00e9tition que l&rsquo;on peut qualifier de secondaire. Organis\u00e9e en m\u00eame temps que la Ligue des Nations (<a href=\"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-nations-trois-sur-trois-pour-les-francais\/\">dans laquelle les hommes brillent actuellement<\/a>), les meilleures \u00e9quipes n&rsquo;y sont en cons\u00e9quence pas engag\u00e9es. Les Fran\u00e7aises, en progr\u00e8s constants, disputent cette comp\u00e9tition, et ne l&rsquo;ont pas galvaud\u00e9e. Elles ont d\u00e9croch\u00e9 quatre victoires en autant de matchs de poule, dont la derni\u00e8re hier soir en Espagne. Les Bleues se sont impos\u00e9es <strong>3-0<\/strong> (<strong>25-17, 25-18, 25-20<\/strong>), et n&rsquo;auront perdu que deux sets en quatre rencontres.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">L&rsquo;\u00c9quipe de France f\u00e9minine de <a href=\"https:\/\/twitter.com\/hashtag\/volley?src=hash&amp;ref_src=twsrc%5Etfw\">#volley<\/a> s&rsquo;impose face \u00e0 l&rsquo;Espagne (3-0), et remporte ainsi sa 4\u00e8me victoire en autant de matchs d&rsquo;European League.<\/p>\n<p>Les bleues sont qualifi\u00e9es pour les demi-finales, qu&rsquo;elles joueront \u00e0 domicile jeudi, au Palais des sports d&rsquo;Orl\u00e9ans. <a href=\"https:\/\/twitter.com\/FFvolley?ref_src=twsrc%5Etfw\">@FFvolley<\/a> <a href=\"https:\/\/t.co\/4lIVv4XkRI\">pic.twitter.com\/4lIVv4XkRI<\/a><\/p>\n<p>\u2014 Objectif Paris 2024 &#x1f1eb;&#x1f1f7; &#x1f947; (@Objectif_2024) <a href=\"https:\/\/twitter.com\/Objectif_2024\/status\/1535697986130436097?ref_src=twsrc%5Etfw\">June 11, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Voil\u00e0 les filles d&rsquo;<strong>\u00c9mile Rousseaux<\/strong> qualifi\u00e9es en demi-finales, avec une solide chance d&rsquo;aller au bout. En effet, les Fran\u00e7aises sont les seules encore en lice \u00e0 avoir atteint les quarts de finale des derniers Championnats d&rsquo;Europe (en 2021). Jeudi soir (20h00), elles recevront la Croatie \u00e0 Orl\u00e9ans. Avec comme objectif la finale contre la R\u00e9publique Tch\u00e8que ou la Roumanie. Ces matchs ont de l&rsquo;importance, en plus d&rsquo;ajouter une ligne \u00e0 leur palmar\u00e8s. En effet, le vainqueur d\u00e9crochera une place dans la <em>Challenger Cup<\/em>. Cette comp\u00e9tition pourrait leur offrir une place dans la prestigieuse Ligue des Nations. Le moyen donc pour les Fran\u00e7aises de c\u00f4toyer l&rsquo;\u00e9lite du volleyball mondial.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>GOLDEN EUROPEAN LEAGUE DE VOLLEY &#8211; Les Tricolores n&rsquo;ont pas pris \u00e0 la l\u00e9g\u00e8re cette comp\u00e9tition et ont remport\u00e9 tous leurs matchs de poule. Ainsi, elles se qualifient pour les demi-finales pr\u00e9vues jeudi. La Golden European League est une comp\u00e9tition que l&rsquo;on peut qualifier de secondaire. Organis\u00e9e en m\u00eame temps que la Ligue des Nations [&hellip;]<\/p>\n","protected":false},"author":59,"featured_media":232318,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8369],"tags":[24162],"class_list":["post-232314","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-volley-ball","tag-golden-european-league-de-volleyball"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Volley Golden European League : Les Bleues en demi-finales<\/title>\n<meta name=\"description\" content=\"GOLDEN EUROPEAN LEAGUE DE VOLLEY - Les Tricolores n&#039;ont pas pris \u00e0 la l\u00e9g\u00e8re cette comp\u00e9tition et se qualifient pour les demi-finales.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/volley-golden-european-league-les-bleues-en-demi-finales\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Volley Golden European League : Les Bleues en demi-finales\" \/>\n<meta property=\"og:description\" content=\"GOLDEN EUROPEAN LEAGUE DE VOLLEY - Les Tricolores n&#039;ont pas pris \u00e0 la l\u00e9g\u00e8re cette comp\u00e9tition et se qualifient pour les demi-finales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/volley-golden-european-league-les-bleues-en-demi-finales\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-12T08:05:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Volley-Golden-European-League-Les-Bleues-en-demi-finales.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Volley Golden European League : Les Bleues en demi-finales\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-golden-european-league-les-bleues-en-demi-finales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-golden-european-league-les-bleues-en-demi-finales\\\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Volley Golden European League : Les Bleues en demi-finales\",\"datePublished\":\"2022-06-12T08:05:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-golden-european-league-les-bleues-en-demi-finales\\\/\"},\"wordCount\":332,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-golden-european-league-les-bleues-en-demi-finales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Volley-Golden-European-League-Les-Bleues-en-demi-finales.png\",\"keywords\":[\"Golden European League de Volleyball\"],\"articleSection\":[\"Volley-Ball\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-golden-european-league-les-bleues-en-demi-finales\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-golden-european-league-les-bleues-en-demi-finales\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-golden-european-league-les-bleues-en-demi-finales\\\/\",\"name\":\"Volley Golden European League : Les Bleues en demi-finales\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-golden-european-league-les-bleues-en-demi-finales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-golden-european-league-les-bleues-en-demi-finales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Volley-Golden-European-League-Les-Bleues-en-demi-finales.png\",\"datePublished\":\"2022-06-12T08:05:59+00:00\",\"description\":\"GOLDEN EUROPEAN LEAGUE DE VOLLEY - Les Tricolores n'ont pas pris \u00e0 la l\u00e9g\u00e8re cette comp\u00e9tition et se qualifient pour les demi-finales.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-golden-european-league-les-bleues-en-demi-finales\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-golden-european-league-les-bleues-en-demi-finales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-golden-european-league-les-bleues-en-demi-finales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Volley-Golden-European-League-Les-Bleues-en-demi-finales.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Volley-Golden-European-League-Les-Bleues-en-demi-finales.png\",\"width\":800,\"height\":445,\"caption\":\"Volley Golden European League Les Bleues en demi-finales\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-golden-european-league-les-bleues-en-demi-finales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Volley Golden European League : Les Bleues en demi-finales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sebastien.gente\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sebgente\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/sbastien-gente-a29583169\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sebastiengente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Volley Golden European League : Les Bleues en demi-finales","description":"GOLDEN EUROPEAN LEAGUE DE VOLLEY - Les Tricolores n'ont pas pris \u00e0 la l\u00e9g\u00e8re cette comp\u00e9tition et se qualifient pour les demi-finales.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/volley-golden-european-league-les-bleues-en-demi-finales\/","og_locale":"fr_FR","og_type":"article","og_title":"Volley Golden European League : Les Bleues en demi-finales","og_description":"GOLDEN EUROPEAN LEAGUE DE VOLLEY - Les Tricolores n'ont pas pris \u00e0 la l\u00e9g\u00e8re cette comp\u00e9tition et se qualifient pour les demi-finales.","og_url":"https:\/\/dicodusport.fr\/blog\/volley-golden-european-league-les-bleues-en-demi-finales\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2022-06-12T08:05:59+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Volley-Golden-European-League-Les-Bleues-en-demi-finales.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Volley Golden European League : Les Bleues en demi-finales","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/volley-golden-european-league-les-bleues-en-demi-finales\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/volley-golden-european-league-les-bleues-en-demi-finales\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Volley Golden European League : Les Bleues en demi-finales","datePublished":"2022-06-12T08:05:59+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/volley-golden-european-league-les-bleues-en-demi-finales\/"},"wordCount":332,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/volley-golden-european-league-les-bleues-en-demi-finales\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Volley-Golden-European-League-Les-Bleues-en-demi-finales.png","keywords":["Golden European League de Volleyball"],"articleSection":["Volley-Ball"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/volley-golden-european-league-les-bleues-en-demi-finales\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/volley-golden-european-league-les-bleues-en-demi-finales\/","url":"https:\/\/dicodusport.fr\/blog\/volley-golden-european-league-les-bleues-en-demi-finales\/","name":"Volley Golden European League : Les Bleues en demi-finales","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/volley-golden-european-league-les-bleues-en-demi-finales\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/volley-golden-european-league-les-bleues-en-demi-finales\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Volley-Golden-European-League-Les-Bleues-en-demi-finales.png","datePublished":"2022-06-12T08:05:59+00:00","description":"GOLDEN EUROPEAN LEAGUE DE VOLLEY - Les Tricolores n'ont pas pris \u00e0 la l\u00e9g\u00e8re cette comp\u00e9tition et se qualifient pour les demi-finales.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/volley-golden-european-league-les-bleues-en-demi-finales\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/volley-golden-european-league-les-bleues-en-demi-finales\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/volley-golden-european-league-les-bleues-en-demi-finales\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Volley-Golden-European-League-Les-Bleues-en-demi-finales.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Volley-Golden-European-League-Les-Bleues-en-demi-finales.png","width":800,"height":445,"caption":"Volley Golden European League Les Bleues en demi-finales"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/volley-golden-european-league-les-bleues-en-demi-finales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Volley Golden European League : Les Bleues en demi-finales"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/232314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=232314"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/232314\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/232318"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=232314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=232314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=232314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}