{"id":232383,"date":"2022-06-12T16:30:02","date_gmt":"2022-06-12T14:30:02","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=232383&#038;preview=true&#038;preview_id=232383"},"modified":"2022-06-12T19:18:28","modified_gmt":"2022-06-12T17:18:28","slug":"classement-du-tour-des-onze-villes-2022","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/classement-du-tour-des-onze-villes-2022\/","title":{"rendered":"Classement du Tour des Onze Villes 2022"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/cyclisme\/cyclisme-sur-route-2022\/\">CYCLISME SUR ROUTE 2022<\/a> &#8211; D\u00e9couvrez le classement du Tour des Onze Villes 2022 (Top 20), disput\u00e9 ce dimanche 12 juin 2022 autour de Bruges<span class=\"red\">\u00a0<\/span><span class=\"red fw400\">(192.3 km).<\/span><\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><div class=\"su-table su-table-alternate\">\n<table style=\"width: 800px;border-collapse: collapse\" border=\"1\">\n<tbody>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 14px\">&#x1f3c6;<br \/>\n<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>COUREURS<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>TEMPS \/ \u00c9CART<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">1.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><strong style=\"font-size: 0.9em\"><strong style=\"font-size: 14.4px\">&#x1f1f3;&#x1f1f1;<\/strong> FABIO JAKOBSEN<\/strong><br style=\"font-size: 14.4px\" \/><span style=\"font-size: 0.9em\"><span style=\"font-size: 0.8em\">QUICK-STEP ALPHA VINYL TEAM<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>4h18m46s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">2.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>&#x1f1e6;&#x1f1fa; CALEB EWAN<\/strong><br \/>\n<span style=\"font-size: 0.8em\">LOTTO SOUDAL<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">3.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><strong style=\"font-size: 0.9em\">&#x1f1e7;&#x1f1ea; TIM MERLIER<\/strong><br \/>\n<span style=\"font-size: 0.8em\">ALPECIN &#8211; FENIX<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">4.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong style=\"font-size: 14.4px\">&#x1f1e7;&#x1f1ea; SASHA WEEMAES<\/strong><br style=\"font-size: 14.4px\" \/><span style=\"font-size: 0.8em\">SPORT VLAANDEREN &#8211; BALOISE<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">5.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><strong><strong style=\"font-size: 0.9em\">&#x1f1eb;&#x1f1f7; RUDY BARBIER<\/strong><br \/>\n<\/strong><span style=\"font-size: 0.9em\"><span style=\"font-size: 0.8em\">ISRAEL &#8211; PREMIER TECH<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">6.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>&#x1f1ee;&#x1f1f9; GIACOMO NIZZOLO<br \/>\n<\/strong><span style=\"font-size: 0.8em\">ISRAEL\u00a0 &#8211; PREMIER TECH<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">7.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>&#x1f1f5;&#x1f1f1; STANISLAW ANIOLKOWSKI<\/strong><\/span><br \/>\n<span style=\"font-size: 11.52px\">BINGOAL PAUWELS SAUCES WB<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">8.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>&#x1f1ec;&#x1f1e7; MATTHEW BOSTOCK<\/strong><br \/>\n<span style=\"font-size: 0.8em\">WIV SUNGOD<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">9.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong style=\"font-size: 14.4px\">&#x1f1f3;&#x1f1f4; ERLEND BLIKRA<\/strong><br style=\"font-size: 14.4px\" \/><span style=\"font-size: 0.8em\">UNO-X PRO CYCLING TEAM<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">10.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>&#x1f1e7;&#x1f1ea; CHRISTOPHE NOPPE<br \/>\n<\/strong><span style=\"font-size: 0.8em\">TEAM ARKEA SAMSIC<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">11.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>&#x1f1e9;&#x1f1ea; MAX WALSCHEID<\/strong><br \/>\n<span style=\"font-size: 0.8em\">COFIDIS<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">12.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong style=\"font-size: 14.4px\"><strong>&#x1f1ee;&#x1f1f9; SIMONE CONSONNI<br \/>\n<\/strong><\/strong><span style=\"font-size: 0.8em\">COFIDIS<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">13.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong style=\"font-size: 14.4px\">&#x1f1e7;&#x1f1ea; ROBBE GHYS<\/strong><br style=\"font-size: 14.4px\" \/><span style=\"font-size: 0.8em\">SPORT VLAANDEREN &#8211; BALOISE<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">14.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong><strong style=\"font-size: 14.4px\">&#x1f1e7;&#x1f1ea; PIET ALLEGAERT<br \/>\n<\/strong><\/strong><span style=\"font-size: 0.8em\">COFIDIS<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">15.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>&#x1f1e9;&#x1f1ea; PASCAL ACKERMANN<\/strong><br \/>\n<span style=\"font-size: 0.8em\">UAE TEAM EMIRATES<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">16.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><strong style=\"font-size: 0.9em\">&#x1f1e7;&#x1f1ea; GIL D&rsquo;HEYGERE<\/strong><br \/>\n<span style=\"font-size: 0.8em\">MINERVA CYCLING<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">17.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>&#x1f1f3;&#x1f1f4; TORD GUDMESTAD<br \/>\n<\/strong><span style=\"font-size: 11.52px\">UNO-X PRO CYCLING TEAM<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">18.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><strong style=\"font-size: 0.9em\">&#x1f1e7;&#x1f1ea; THIBAU NYS<\/strong><br \/>\n<span style=\"font-size: 0.8em\">BALOISE &#8211; TREK LIONS<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">19.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>&#x1f1e7;&#x1f1ea; LOUIS BLOUWE<\/strong><\/span><br \/>\n<span style=\"font-size: 11.52px\">BINGOAL PAUWELS SAUCES WB<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">20.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>&#x1f1e7;&#x1f1ea; DAVIDE BOMBOI<\/strong><\/span><br \/>\n<span style=\"font-size: 11.52px\">ELEVATE P\/B HOME SOLUTION SOENENS<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<h2 style=\"text-align: justify;\"><strong>\u00c0 lire aussi<\/strong><\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/www.procyclingstats.com\/race\/circuit-des-xi-villes\/2022\/result\" target=\"_blank\" rel=\"nofollow noopener\"><strong>Le classement complet du Tour des Onze Villes 2022<\/strong><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>CYCLISME SUR ROUTE 2022 &#8211; D\u00e9couvrez le classement du Tour des Onze Villes 2022 (Top 20), disput\u00e9 ce dimanche 12 juin 2022 autour de Bruges\u00a0(192.3 km).<\/p>\n","protected":false},"author":2,"featured_media":232385,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[46994],"tags":[],"class_list":["post-232383","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cyclisme-sur-route"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Classement du Tour des Onze Villes 2022<\/title>\n<meta name=\"description\" content=\"CYCLISME SUR ROUTE 2022 - D\u00e9couvrez le classement du Tour des Onze Villes 2022 (Top 20), disput\u00e9 ce dimanche 12 juin 2022 autour de Bruges\u00a0(192.3 km).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/classement-du-tour-des-onze-villes-2022\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Classement du Tour des Onze Villes 2022\" \/>\n<meta property=\"og:description\" content=\"CYCLISME SUR ROUTE 2022 - D\u00e9couvrez le classement du Tour des Onze Villes 2022 (Top 20), disput\u00e9 ce dimanche 12 juin 2022 autour de Bruges\u00a0(192.3 km).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/classement-du-tour-des-onze-villes-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-12T14:30:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-12T17:18:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Classement-du-Tour-des-Onze-Villes-2022.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Benjamin Cots\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Classement du Tour des Onze Villes 2022\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/BenjaminCots\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/classement-du-tour-des-onze-villes-2022\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/classement-du-tour-des-onze-villes-2022\/\"},\"author\":{\"name\":\"Benjamin Cots\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0c141de963d8493840348bb7df193da4\"},\"headline\":\"Classement du Tour des Onze Villes 2022\",\"datePublished\":\"2022-06-12T14:30:02+00:00\",\"dateModified\":\"2022-06-12T17:18:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/classement-du-tour-des-onze-villes-2022\/\"},\"wordCount\":295,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/classement-du-tour-des-onze-villes-2022\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Classement-du-Tour-des-Onze-Villes-2022.png\",\"articleSection\":[\"Cyclisme sur route\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/classement-du-tour-des-onze-villes-2022\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/classement-du-tour-des-onze-villes-2022\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/classement-du-tour-des-onze-villes-2022\/\",\"name\":\"Classement du Tour des Onze Villes 2022\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/classement-du-tour-des-onze-villes-2022\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/classement-du-tour-des-onze-villes-2022\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Classement-du-Tour-des-Onze-Villes-2022.png\",\"datePublished\":\"2022-06-12T14:30:02+00:00\",\"dateModified\":\"2022-06-12T17:18:28+00:00\",\"description\":\"CYCLISME SUR ROUTE 2022 - D\u00e9couvrez le classement du Tour des Onze Villes 2022 (Top 20), disput\u00e9 ce dimanche 12 juin 2022 autour de Bruges\u00a0(192.3 km).\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/classement-du-tour-des-onze-villes-2022\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/classement-du-tour-des-onze-villes-2022\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/classement-du-tour-des-onze-villes-2022\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Classement-du-Tour-des-Onze-Villes-2022.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Classement-du-Tour-des-Onze-Villes-2022.png\",\"width\":1200,\"height\":670,\"caption\":\"Classement du Tour des Onze Villes 2022\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/classement-du-tour-des-onze-villes-2022\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Classement du Tour des Onze Villes 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0c141de963d8493840348bb7df193da4\",\"name\":\"Benjamin Cots\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Maillot-Benji-Dicodusport-150x150.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Maillot-Benji-Dicodusport-150x150.png\",\"caption\":\"Benjamin Cots\"},\"description\":\"Footballeur et fan des Girondins de Bordeaux depuis mon plus jeune \u00e2ge, le foot et le sport en g\u00e9n\u00e9ral ont rythm\u00e9 ma vie. Apr\u00e8s des \u00e9tudes en informatique, la cr\u00e9ation de Dicodusport \u00e9tait le parfait m\u00e9lange pour allier mes deux passions.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/BenjaminCots\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Classement du Tour des Onze Villes 2022","description":"CYCLISME SUR ROUTE 2022 - D\u00e9couvrez le classement du Tour des Onze Villes 2022 (Top 20), disput\u00e9 ce dimanche 12 juin 2022 autour de Bruges\u00a0(192.3 km).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/classement-du-tour-des-onze-villes-2022\/","og_locale":"fr_FR","og_type":"article","og_title":"Classement du Tour des Onze Villes 2022","og_description":"CYCLISME SUR ROUTE 2022 - D\u00e9couvrez le classement du Tour des Onze Villes 2022 (Top 20), disput\u00e9 ce dimanche 12 juin 2022 autour de Bruges\u00a0(192.3 km).","og_url":"https:\/\/dicodusport.fr\/blog\/classement-du-tour-des-onze-villes-2022\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2022-06-12T14:30:02+00:00","article_modified_time":"2022-06-12T17:18:28+00:00","og_image":[{"width":1200,"height":670,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Classement-du-Tour-des-Onze-Villes-2022.png","type":"image\/png"}],"author":"Benjamin Cots","twitter_card":"summary_large_image","twitter_title":"Classement du Tour des Onze Villes 2022","twitter_creator":"@https:\/\/twitter.com\/BenjaminCots","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/classement-du-tour-des-onze-villes-2022\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/classement-du-tour-des-onze-villes-2022\/"},"author":{"name":"Benjamin Cots","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0c141de963d8493840348bb7df193da4"},"headline":"Classement du Tour des Onze Villes 2022","datePublished":"2022-06-12T14:30:02+00:00","dateModified":"2022-06-12T17:18:28+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/classement-du-tour-des-onze-villes-2022\/"},"wordCount":295,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/classement-du-tour-des-onze-villes-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Classement-du-Tour-des-Onze-Villes-2022.png","articleSection":["Cyclisme sur route"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/classement-du-tour-des-onze-villes-2022\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/classement-du-tour-des-onze-villes-2022\/","url":"https:\/\/dicodusport.fr\/blog\/classement-du-tour-des-onze-villes-2022\/","name":"Classement du Tour des Onze Villes 2022","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/classement-du-tour-des-onze-villes-2022\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/classement-du-tour-des-onze-villes-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Classement-du-Tour-des-Onze-Villes-2022.png","datePublished":"2022-06-12T14:30:02+00:00","dateModified":"2022-06-12T17:18:28+00:00","description":"CYCLISME SUR ROUTE 2022 - D\u00e9couvrez le classement du Tour des Onze Villes 2022 (Top 20), disput\u00e9 ce dimanche 12 juin 2022 autour de Bruges\u00a0(192.3 km).","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/classement-du-tour-des-onze-villes-2022\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/classement-du-tour-des-onze-villes-2022\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/classement-du-tour-des-onze-villes-2022\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Classement-du-Tour-des-Onze-Villes-2022.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Classement-du-Tour-des-Onze-Villes-2022.png","width":1200,"height":670,"caption":"Classement du Tour des Onze Villes 2022"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/classement-du-tour-des-onze-villes-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Classement du Tour des Onze Villes 2022"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0c141de963d8493840348bb7df193da4","name":"Benjamin Cots","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Maillot-Benji-Dicodusport-150x150.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Maillot-Benji-Dicodusport-150x150.png","caption":"Benjamin Cots"},"description":"Footballeur et fan des Girondins de Bordeaux depuis mon plus jeune \u00e2ge, le foot et le sport en g\u00e9n\u00e9ral ont rythm\u00e9 ma vie. Apr\u00e8s des \u00e9tudes en informatique, la cr\u00e9ation de Dicodusport \u00e9tait le parfait m\u00e9lange pour allier mes deux passions.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/BenjaminCots"],"url":"https:\/\/dicodusport.fr\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/232383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=232383"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/232383\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/232385"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=232383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=232383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=232383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}