{"id":234403,"date":"2022-06-18T10:34:23","date_gmt":"2022-06-18T08:34:23","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=234403&#038;preview=true&#038;preview_id=234403"},"modified":"2022-06-18T12:06:26","modified_gmt":"2022-06-18T10:06:26","slug":"ugo-mola-il-ne-faut-pas-toujours-attendre-quantoine-dupont-traverse-le-terrain","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/ugo-mola-il-ne-faut-pas-toujours-attendre-quantoine-dupont-traverse-le-terrain\/","title":{"rendered":"Ugo Mola : \u00ab\u00a0Il ne faut pas toujours attendre qu&rsquo;Antoine Dupont traverse le terrain\u00a0\u00bb"},"content":{"rendered":"<p style=\"text-align: justify;\"><i><b>RUGBY \u00c0 XV\u00a0 &#8211; En conf\u00e9rence de presse, Ugo Mola est revenu sur la performance du Stade Toulousain lors de <a href=\"https:\/\/dicodusport.fr\/blog\/top-14-castres-dompte-le-stade-toulousain-et-s-offre-une-finale-au-stade-de-france\/\">la demi-finale perdue face \u00e0 Castres (24-18)<\/a>, et plus pr\u00e9cis\u00e9ment sur les performances individuelles de ses cadres.\u00a0<\/b><\/i><\/p>\n<p style=\"text-align: justify;\">Interrog\u00e9 sur la faillite de certains internationaux sur cette demi-finale, l&rsquo;entra\u00eeneur du Stade Toulousain, <strong>Ugo Mola<\/strong>, s&rsquo;est expliqu\u00e9 apr\u00e8s le match. Sans aucun d\u00e9tour.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">J&rsquo;avais surtout trouv\u00e9 le collectif bien plus fort. L\u00e0, le collectif a \u00e9t\u00e9 mis sous l&rsquo;\u00e9teignoir de la pression castraise. Mais il ne faut peut-\u00eatre pas toujours attendre qu&rsquo;Antoine Dupont traverse le terrain. Il a connu un match plut\u00f4t int\u00e9ressant \u00e0 certains moments, avec une action un peu litigieuse sur un avantage sur un en-avant qui se transforme en une possession pour Castres. \u00c0 cet instant, \u00e7a peut co\u00fbter cher. Ces matchs-l\u00e0 se jouent \u00e0 rien. Je nous ai trouv\u00e9s un peu \u00e9mouss\u00e9s dans les moments cl\u00e9s. Mais je reste convaincu que ce groupe a un bel avenir. Notre moyenne d&rsquo;\u00e2ge va se rajeunir encore la saison prochaine. J&rsquo;ai bien compris qu&rsquo;il fallait que \u00e7a change. \u00c7a y est, \u00e7a va changer. Rendez-vous l&rsquo;an prochain.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Le meilleur joueur du monde a \u00e9t\u00e9 bien musel\u00e9 par la d\u00e9fense castraise, mais a r\u00e9alis\u00e9 une belle performance en d\u00e9fense. Le <strong>Stade Toulousain<\/strong>, qui avait r\u00e9alis\u00e9 le doubl\u00e9 la saison pass\u00e9e, termine avec deux demi-finales cet exercice.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Frustr\u00e9 par l&rsquo;indiscipline de son \u00e9quipe et son manque de ma\u00eetrise dans certains moments cl\u00e9s de la demi-finale perdue contre Castres, Ugo Mola veut se servir de cette saison sans titre pour continuer \u00e0 avancer &#x1f447;<a href=\"https:\/\/t.co\/PYKphwAfHT\">https:\/\/t.co\/PYKphwAfHT<\/a><\/p>\n<p>\u2014 RUGBYRAMA (@RugbyramaFR) <a href=\"https:\/\/twitter.com\/RugbyramaFR\/status\/1538058451586269184?ref_src=twsrc%5Etfw\">June 18, 2022<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">\u00c0 lire aussi<\/h2>\n<p><span class=\"sXbp7YZcidhvXdI5oGUm9Hg2zBOMrYgz3Q3Pelts6EmS2xJyfecAWIqFC8PZvTO0iMExwFRVKhju4HNR\"><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"7XWasCfzce\"><p><a href=\"https:\/\/dicodusport.fr\/blog\/top-14-demi-finales-notes-castres-toulouse\/\">Top 14 Demi-finales : Les notes de Castres &#8211; Toulouse<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00ab\u00a0Top 14 Demi-finales : Les notes de Castres &#8211; Toulouse\u00a0\u00bb &#8212; Dicodusport\" src=\"https:\/\/dicodusport.fr\/blog\/top-14-demi-finales-notes-castres-toulouse\/embed\/#?secret=tXv0EImuy8#?secret=7XWasCfzce\" data-secret=\"7XWasCfzce\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>RUGBY \u00c0 XV\u00a0 &#8211; En conf\u00e9rence de presse, Ugo Mola est revenu sur le match de son \u00e9quipe et plus pr\u00e9cis\u00e9ment sur les performances individuelles de ses cadres.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":234406,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[47050],"tags":[2373,4008,111,4272],"class_list":["post-234403","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-top-14","tag-antoine-dupont","tag-stade-toulousain","tag-top-14","tag-ugo-mola"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ugo Mola : &quot;Il ne faut pas toujours attendre qu&#039;Antoine Dupont traverse le terrain&quot;<\/title>\n<meta name=\"description\" content=\"RUGBY \u00c0 XV\u00a0 - En conf\u00e9rence de presse, Ugo Mola est revenu sur le match de son \u00e9quipe et plus pr\u00e9cis\u00e9ment sur les performances individuelles de ses cadres.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/ugo-mola-il-ne-faut-pas-toujours-attendre-quantoine-dupont-traverse-le-terrain\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ugo Mola : &quot;Il ne faut pas toujours attendre qu&#039;Antoine Dupont traverse le terrain&quot;\" \/>\n<meta property=\"og:description\" content=\"RUGBY \u00c0 XV\u00a0 - En conf\u00e9rence de presse, Ugo Mola est revenu sur le match de son \u00e9quipe et plus pr\u00e9cis\u00e9ment sur les performances individuelles de ses cadres.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/ugo-mola-il-ne-faut-pas-toujours-attendre-quantoine-dupont-traverse-le-terrain\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-18T08:34:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-18T10:06:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Ugo-Mola-Il-ne-faut-pas-toujours-attendre-quAntoine-Dupont-traverse-le-terrain.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Ugo Mola : &quot;Il ne faut pas toujours attendre qu&#039;Antoine Dupont traverse le terrain&quot;\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ugo-mola-il-ne-faut-pas-toujours-attendre-quantoine-dupont-traverse-le-terrain\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ugo-mola-il-ne-faut-pas-toujours-attendre-quantoine-dupont-traverse-le-terrain\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Ugo Mola : \u00ab\u00a0Il ne faut pas toujours attendre qu&rsquo;Antoine Dupont traverse le terrain\u00a0\u00bb\",\"datePublished\":\"2022-06-18T08:34:23+00:00\",\"dateModified\":\"2022-06-18T10:06:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ugo-mola-il-ne-faut-pas-toujours-attendre-quantoine-dupont-traverse-le-terrain\\\/\"},\"wordCount\":314,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ugo-mola-il-ne-faut-pas-toujours-attendre-quantoine-dupont-traverse-le-terrain\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Ugo-Mola-Il-ne-faut-pas-toujours-attendre-quAntoine-Dupont-traverse-le-terrain.png\",\"keywords\":[\"Antoine Dupont\",\"Stade Toulousain\",\"Top 14\",\"Ugo Mola\"],\"articleSection\":[\"Top 14\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ugo-mola-il-ne-faut-pas-toujours-attendre-quantoine-dupont-traverse-le-terrain\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ugo-mola-il-ne-faut-pas-toujours-attendre-quantoine-dupont-traverse-le-terrain\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ugo-mola-il-ne-faut-pas-toujours-attendre-quantoine-dupont-traverse-le-terrain\\\/\",\"name\":\"Ugo Mola : \\\"Il ne faut pas toujours attendre qu'Antoine Dupont traverse le terrain\\\"\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ugo-mola-il-ne-faut-pas-toujours-attendre-quantoine-dupont-traverse-le-terrain\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ugo-mola-il-ne-faut-pas-toujours-attendre-quantoine-dupont-traverse-le-terrain\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Ugo-Mola-Il-ne-faut-pas-toujours-attendre-quAntoine-Dupont-traverse-le-terrain.png\",\"datePublished\":\"2022-06-18T08:34:23+00:00\",\"dateModified\":\"2022-06-18T10:06:26+00:00\",\"description\":\"RUGBY \u00c0 XV\u00a0 - En conf\u00e9rence de presse, Ugo Mola est revenu sur le match de son \u00e9quipe et plus pr\u00e9cis\u00e9ment sur les performances individuelles de ses cadres.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ugo-mola-il-ne-faut-pas-toujours-attendre-quantoine-dupont-traverse-le-terrain\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ugo-mola-il-ne-faut-pas-toujours-attendre-quantoine-dupont-traverse-le-terrain\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ugo-mola-il-ne-faut-pas-toujours-attendre-quantoine-dupont-traverse-le-terrain\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Ugo-Mola-Il-ne-faut-pas-toujours-attendre-quAntoine-Dupont-traverse-le-terrain.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Ugo-Mola-Il-ne-faut-pas-toujours-attendre-quAntoine-Dupont-traverse-le-terrain.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ugo-mola-il-ne-faut-pas-toujours-attendre-quantoine-dupont-traverse-le-terrain\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ugo Mola : \u00ab\u00a0Il ne faut pas toujours attendre qu&rsquo;Antoine Dupont traverse le terrain\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ugo Mola : \"Il ne faut pas toujours attendre qu'Antoine Dupont traverse le terrain\"","description":"RUGBY \u00c0 XV\u00a0 - En conf\u00e9rence de presse, Ugo Mola est revenu sur le match de son \u00e9quipe et plus pr\u00e9cis\u00e9ment sur les performances individuelles de ses cadres.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/ugo-mola-il-ne-faut-pas-toujours-attendre-quantoine-dupont-traverse-le-terrain\/","og_locale":"fr_FR","og_type":"article","og_title":"Ugo Mola : \"Il ne faut pas toujours attendre qu'Antoine Dupont traverse le terrain\"","og_description":"RUGBY \u00c0 XV\u00a0 - En conf\u00e9rence de presse, Ugo Mola est revenu sur le match de son \u00e9quipe et plus pr\u00e9cis\u00e9ment sur les performances individuelles de ses cadres.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/ugo-mola-il-ne-faut-pas-toujours-attendre-quantoine-dupont-traverse-le-terrain\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2022-06-18T08:34:23+00:00","article_modified_time":"2022-06-18T10:06:26+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Ugo-Mola-Il-ne-faut-pas-toujours-attendre-quAntoine-Dupont-traverse-le-terrain.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Ugo Mola : \"Il ne faut pas toujours attendre qu'Antoine Dupont traverse le terrain\"","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/ugo-mola-il-ne-faut-pas-toujours-attendre-quantoine-dupont-traverse-le-terrain\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/ugo-mola-il-ne-faut-pas-toujours-attendre-quantoine-dupont-traverse-le-terrain\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Ugo Mola : \u00ab\u00a0Il ne faut pas toujours attendre qu&rsquo;Antoine Dupont traverse le terrain\u00a0\u00bb","datePublished":"2022-06-18T08:34:23+00:00","dateModified":"2022-06-18T10:06:26+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ugo-mola-il-ne-faut-pas-toujours-attendre-quantoine-dupont-traverse-le-terrain\/"},"wordCount":314,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ugo-mola-il-ne-faut-pas-toujours-attendre-quantoine-dupont-traverse-le-terrain\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Ugo-Mola-Il-ne-faut-pas-toujours-attendre-quAntoine-Dupont-traverse-le-terrain.png","keywords":["Antoine Dupont","Stade Toulousain","Top 14","Ugo Mola"],"articleSection":["Top 14"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/ugo-mola-il-ne-faut-pas-toujours-attendre-quantoine-dupont-traverse-le-terrain\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/ugo-mola-il-ne-faut-pas-toujours-attendre-quantoine-dupont-traverse-le-terrain\/","url":"https:\/\/dicodusport.fr\/blog\/ugo-mola-il-ne-faut-pas-toujours-attendre-quantoine-dupont-traverse-le-terrain\/","name":"Ugo Mola : \"Il ne faut pas toujours attendre qu'Antoine Dupont traverse le terrain\"","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ugo-mola-il-ne-faut-pas-toujours-attendre-quantoine-dupont-traverse-le-terrain\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ugo-mola-il-ne-faut-pas-toujours-attendre-quantoine-dupont-traverse-le-terrain\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Ugo-Mola-Il-ne-faut-pas-toujours-attendre-quAntoine-Dupont-traverse-le-terrain.png","datePublished":"2022-06-18T08:34:23+00:00","dateModified":"2022-06-18T10:06:26+00:00","description":"RUGBY \u00c0 XV\u00a0 - En conf\u00e9rence de presse, Ugo Mola est revenu sur le match de son \u00e9quipe et plus pr\u00e9cis\u00e9ment sur les performances individuelles de ses cadres.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/ugo-mola-il-ne-faut-pas-toujours-attendre-quantoine-dupont-traverse-le-terrain\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/ugo-mola-il-ne-faut-pas-toujours-attendre-quantoine-dupont-traverse-le-terrain\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/ugo-mola-il-ne-faut-pas-toujours-attendre-quantoine-dupont-traverse-le-terrain\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Ugo-Mola-Il-ne-faut-pas-toujours-attendre-quAntoine-Dupont-traverse-le-terrain.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/06\/Ugo-Mola-Il-ne-faut-pas-toujours-attendre-quAntoine-Dupont-traverse-le-terrain.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/ugo-mola-il-ne-faut-pas-toujours-attendre-quantoine-dupont-traverse-le-terrain\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Ugo Mola : \u00ab\u00a0Il ne faut pas toujours attendre qu&rsquo;Antoine Dupont traverse le terrain\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/234403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=234403"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/234403\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/234406"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=234403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=234403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=234403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}