{"id":240580,"date":"2023-03-29T09:17:27","date_gmt":"2023-03-29T07:17:27","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=240580&#038;preview=true&#038;preview_id=240580"},"modified":"2023-03-29T09:17:48","modified_gmt":"2023-03-29T07:17:48","slug":"xv-de-france-le-programme-des-matchs-amicaux-avant-le-mondial-2023","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-programme-des-matchs-amicaux-avant-le-mondial-2023\/","title":{"rendered":"XV de France : Le programme des matchs amicaux avant la Coupe du monde"},"content":{"rendered":"<p style=\"text-align: justify;\"><i><b><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/rugby\/rugby-a-xv\/coupe-du-monde-de-rugby-2023\/\">COUPE DU MONDE DE RUGBY 2023<\/a> &#8211; Dans la nouvelle convention LNR\/FFR, le programme du <a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/rugby\/rugby-a-xv\/xv-de-france\/\">XV de France<\/a> avant la Coupe du monde a \u00e9t\u00e9 d\u00e9taill\u00e9, avec pas moins de quatre matchs amicaux.\u00a0<\/b><\/i><\/p>\n<p style=\"text-align: justify;\">S&rsquo;il y a toujours des matchs amicaux pour se pr\u00e9parer avant une Coupe du monde, quatre, ce n&rsquo;est pas vraiment commun. Car \u00e9videmment, les risques de blessures sont augment\u00e9s. <strong>Fabien Galthi\u00e9<\/strong>, qui aura \u00e0 disposition 42 joueurs avant de revenir \u00e0 33 le 21 ao\u00fbt, a pourtant d\u00e9cid\u00e9 de jouer quatre fois avant la <strong>Coupe du monde 2023<\/strong>. Les Bleus affronteront deux fois l&rsquo;<strong>\u00c9cosse<\/strong>, d&rsquo;abord le 5 ao\u00fbt \u00e0 \u00c9dimbourg puis le 12 ao\u00fbt \u00e0 Saint-\u00c9tienne. Avant de se confronter aux <strong>Fidji<\/strong> le 19 ao\u00fbt \u00e0 Nantes, puis \u00e0 l&rsquo;<strong>Australie<\/strong> le 26 ao\u00fbt, au Stade de France. Des adversaires aux profils diff\u00e9rents qui permettront au staff du XV de France de se pr\u00e9parer au mieux avant le grand rendez-vous.<\/p>\n<p style=\"text-align: justify;\">Le rassemblement des <strong>Bleus<\/strong> d\u00e9butera d\u00e8s la fin du mois de juin, avec un stage de trois jours \u00e0 <strong>Carpiagne\u00a0<\/strong>(26-28 juin). Les Tricolores encha\u00eeneront avec un autre stage \u00e0 <strong>Monaco<\/strong>, du 2 au 14 juillet. Le <strong>XV de France<\/strong> sera ensuite de retour \u00e0 Marcoussis, du 24 juillet au 3 ao\u00fbt. Avant un dernier stage \u00e0 <strong>Capbreton<\/strong>, au milieu des quatre matchs amicaux, du 7 au 25 ao\u00fbt.<\/p>\n<h2 style=\"text-align: justify;\">Le programme des matchs amicaux<\/h2>\n<p style=\"text-align: justify;\"><strong>5\/08\/2023 \u00e0 \u00c9dimbourg :<\/strong> France &#8211; \u00c9cosse<br \/>\n<strong>12\/08\/2023 \u00e0 Saint-\u00c9tienne :<\/strong> France &#8211; \u00c9cosse<br \/>\n<strong>19\/08\/2023 \u00e0 Nantes :<\/strong> France &#8211; Fidji<br \/>\n<strong>26\/08\/2023 au Stade de France :<\/strong> France &#8211; Australie<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Les joueurs de Fabien Galthi\u00e9 disputeront quatre matchs amicaux et r\u00e9aliseront deux stages en Guyane et Monaco. Tous les d\u00e9tails de la pr\u00e9paration sont ici !<a href=\"https:\/\/t.co\/F5MxWGZtwN\">https:\/\/t.co\/F5MxWGZtwN<\/a><\/p>\n<p>\u2014 RUGBYRAMA (@RugbyramaFR) <a href=\"https:\/\/twitter.com\/RugbyramaFR\/status\/1544662672033169409?ref_src=twsrc%5Etfw\">July 6, 2022<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>COUPE DU MONDE DE RUGBY 2023 &#8211; Dans la nouvelle convention LNR\/FFR, le programme du XV de France avant la Coupe du monde a \u00e9t\u00e9 d\u00e9taill\u00e9, avec pas moins de quatre matchs amicaux.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":358823,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[47049,9129,19951],"tags":[523,1638],"class_list":["post-240580","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coupe-du-monde-de-rugby","category-rugby-a-xv","category-xv-de-france","tag-bleus","tag-xv-de-france"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>XV de France : Le programme des matchs amicaux avant la Coupe du monde<\/title>\n<meta name=\"description\" content=\"COUPE DU MONDE DE RUGBY 2023 - Dans la nouvelle convention LNR\/FFR, le programme du XV de France avant la Coupe du monde a \u00e9t\u00e9 d\u00e9taill\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-programme-des-matchs-amicaux-avant-le-mondial-2023\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"XV de France : Le programme des matchs amicaux avant la Coupe du monde\" \/>\n<meta property=\"og:description\" content=\"COUPE DU MONDE DE RUGBY 2023 - Dans la nouvelle convention LNR\/FFR, le programme du XV de France avant la Coupe du monde a \u00e9t\u00e9 d\u00e9taill\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-programme-des-matchs-amicaux-avant-le-mondial-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-29T07:17:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-29T07:17:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/XV-de-France-Composition-des-Bleus-face-a-lEcosse.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"XV de France : Le programme des matchs amicaux avant la Coupe du monde\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-programme-des-matchs-amicaux-avant-le-mondial-2023\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-programme-des-matchs-amicaux-avant-le-mondial-2023\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"XV de France : Le programme des matchs amicaux avant la Coupe du monde\",\"datePublished\":\"2023-03-29T07:17:27+00:00\",\"dateModified\":\"2023-03-29T07:17:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-programme-des-matchs-amicaux-avant-le-mondial-2023\/\"},\"wordCount\":293,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-programme-des-matchs-amicaux-avant-le-mondial-2023\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/XV-de-France-Composition-des-Bleus-face-a-lEcosse.png\",\"keywords\":[\"bleus\",\"XV de France\"],\"articleSection\":[\"Coupe du monde de rugby\",\"Rugby \u00e0 XV\",\"XV de France\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-programme-des-matchs-amicaux-avant-le-mondial-2023\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-programme-des-matchs-amicaux-avant-le-mondial-2023\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-programme-des-matchs-amicaux-avant-le-mondial-2023\/\",\"name\":\"XV de France : Le programme des matchs amicaux avant la Coupe du monde\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-programme-des-matchs-amicaux-avant-le-mondial-2023\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-programme-des-matchs-amicaux-avant-le-mondial-2023\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/XV-de-France-Composition-des-Bleus-face-a-lEcosse.png\",\"datePublished\":\"2023-03-29T07:17:27+00:00\",\"dateModified\":\"2023-03-29T07:17:48+00:00\",\"description\":\"COUPE DU MONDE DE RUGBY 2023 - Dans la nouvelle convention LNR\/FFR, le programme du XV de France avant la Coupe du monde a \u00e9t\u00e9 d\u00e9taill\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-programme-des-matchs-amicaux-avant-le-mondial-2023\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-programme-des-matchs-amicaux-avant-le-mondial-2023\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-programme-des-matchs-amicaux-avant-le-mondial-2023\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/XV-de-France-Composition-des-Bleus-face-a-lEcosse.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/XV-de-France-Composition-des-Bleus-face-a-lEcosse.png\",\"width\":800,\"height\":445,\"caption\":\"XV de France Composition des Bleus face \u00e0 l'\u00c9cosse\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-programme-des-matchs-amicaux-avant-le-mondial-2023\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"XV de France : Le programme des matchs amicaux avant la Coupe du monde\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"XV de France : Le programme des matchs amicaux avant la Coupe du monde","description":"COUPE DU MONDE DE RUGBY 2023 - Dans la nouvelle convention LNR\/FFR, le programme du XV de France avant la Coupe du monde a \u00e9t\u00e9 d\u00e9taill\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-programme-des-matchs-amicaux-avant-le-mondial-2023\/","og_locale":"fr_FR","og_type":"article","og_title":"XV de France : Le programme des matchs amicaux avant la Coupe du monde","og_description":"COUPE DU MONDE DE RUGBY 2023 - Dans la nouvelle convention LNR\/FFR, le programme du XV de France avant la Coupe du monde a \u00e9t\u00e9 d\u00e9taill\u00e9.","og_url":"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-programme-des-matchs-amicaux-avant-le-mondial-2023\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-03-29T07:17:27+00:00","article_modified_time":"2023-03-29T07:17:48+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/XV-de-France-Composition-des-Bleus-face-a-lEcosse.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"XV de France : Le programme des matchs amicaux avant la Coupe du monde","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-programme-des-matchs-amicaux-avant-le-mondial-2023\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-programme-des-matchs-amicaux-avant-le-mondial-2023\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"XV de France : Le programme des matchs amicaux avant la Coupe du monde","datePublished":"2023-03-29T07:17:27+00:00","dateModified":"2023-03-29T07:17:48+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-programme-des-matchs-amicaux-avant-le-mondial-2023\/"},"wordCount":293,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-programme-des-matchs-amicaux-avant-le-mondial-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/XV-de-France-Composition-des-Bleus-face-a-lEcosse.png","keywords":["bleus","XV de France"],"articleSection":["Coupe du monde de rugby","Rugby \u00e0 XV","XV de France"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/xv-de-france-le-programme-des-matchs-amicaux-avant-le-mondial-2023\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-programme-des-matchs-amicaux-avant-le-mondial-2023\/","url":"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-programme-des-matchs-amicaux-avant-le-mondial-2023\/","name":"XV de France : Le programme des matchs amicaux avant la Coupe du monde","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-programme-des-matchs-amicaux-avant-le-mondial-2023\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-programme-des-matchs-amicaux-avant-le-mondial-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/XV-de-France-Composition-des-Bleus-face-a-lEcosse.png","datePublished":"2023-03-29T07:17:27+00:00","dateModified":"2023-03-29T07:17:48+00:00","description":"COUPE DU MONDE DE RUGBY 2023 - Dans la nouvelle convention LNR\/FFR, le programme du XV de France avant la Coupe du monde a \u00e9t\u00e9 d\u00e9taill\u00e9.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-programme-des-matchs-amicaux-avant-le-mondial-2023\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/xv-de-france-le-programme-des-matchs-amicaux-avant-le-mondial-2023\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-programme-des-matchs-amicaux-avant-le-mondial-2023\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/XV-de-France-Composition-des-Bleus-face-a-lEcosse.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/XV-de-France-Composition-des-Bleus-face-a-lEcosse.png","width":800,"height":445,"caption":"XV de France Composition des Bleus face \u00e0 l'\u00c9cosse"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-programme-des-matchs-amicaux-avant-le-mondial-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"XV de France : Le programme des matchs amicaux avant la Coupe du monde"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/240580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=240580"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/240580\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/358823"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=240580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=240580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=240580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}