{"id":241078,"date":"2022-07-07T19:28:46","date_gmt":"2022-07-07T17:28:46","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=241078&#038;preview=true&#038;preview_id=241078"},"modified":"2022-07-07T19:50:16","modified_gmt":"2022-07-07T17:50:16","slug":"andy-schleck-julian-alaphilippe-est-le-coureur-qui-a-le-plus-de-classe","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/andy-schleck-julian-alaphilippe-est-le-coureur-qui-a-le-plus-de-classe\/","title":{"rendered":"Andy Schleck : \u00ab\u00a0Julian Alaphilippe est le coureur qui a le plus de classe\u00a0\u00bb"},"content":{"rendered":"<p style=\"text-align: justify;\"><b><i><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/cyclisme\/cyclisme-sur-route-2022\/\">CYCLISME SUR ROUTE 2022<\/a> &#8211; En marge de la Grande Boucle, Andy Schleck s&rsquo;est rem\u00e9mor\u00e9 ses souvenirs face \u00e0 Alberto Contador et a \u00e9voqu\u00e9 plusieurs coureurs fran\u00e7ais, dans les colonnes de L&rsquo;\u00c9quipe.<\/i><\/b><\/p>\n<p style=\"text-align: justify;\">Le duel entre <strong>Andy Schleck<\/strong> et <strong>Alberto Contador<\/strong> a tenu en haleine les fans du <strong>Tour de France<\/strong> pendant plusieurs ann\u00e9es. Le <strong>Luxembourgeois<\/strong> se souvient de cette rivalit\u00e9 qui a marqu\u00e9 les esprits.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">Je suis content d&rsquo;avoir pu me battre contre un tel coureur. Si Alberto n&rsquo;avait pas \u00e9t\u00e9 l\u00e0, j&rsquo;aurais gagn\u00e9 deux ou trois Tours de France, mais je n&rsquo;aurais pas marqu\u00e9 l&rsquo;histoire. Les gens se rappellent de notre lutte plus que de mes deuxi\u00e8mes places. C&rsquo;est quelqu&rsquo;un que je respecte \u00e9norm\u00e9ment. On ne sera jamais bons amis car on a deux caract\u00e8res tr\u00e8s forts, mais on s&rsquo;entend bien.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\"><strong>Andy Schleck<\/strong> \u00e9voque aussi les coureurs actuels et confesse son admiration pour le double champion du monde.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">J&rsquo;admire tous les coureurs, mais Julian Alaphilippe est celui qui a le plus de classe, il arrive tellement \u00e0 se faire mal \u00e0 la gueule qu&rsquo;il peut gagner des courses sans \u00eatre \u00e0 100 %. Sinon, je suis tr\u00e8s content de revoir Thibaut Pinot en forme ici. Il dit qu&rsquo;il ne vient pas pour le g\u00e9n\u00e9ral, mais s&rsquo;il est avec les meilleurs en montagne&#8230; C&rsquo;est sans doute l&rsquo;un des coureurs actuels qui me ressemble le plus.<\/p>\n<\/blockquote>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">L\u2019un des chefs-d\u2019\u0153uvre du jour, le duel avec Alberto Contador \u00e9tait tellement grand<br \/>\nL\u2019impression qu\u2019on est pas pr\u00eats de revoir \u00e7a\u2026 <a href=\"https:\/\/t.co\/8ocEbVqJ2m\">https:\/\/t.co\/8ocEbVqJ2m<\/a><\/p>\n<p>\u2014 Adrien Cornu (@adriencornu16) <a href=\"https:\/\/twitter.com\/adriencornu16\/status\/1544445420298203136?ref_src=twsrc%5Etfw\">July 5, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TOUR DE FRANCE 2022 &#8211; En marge de la Grande Boucle, Andy Schleck s&rsquo;est rem\u00e9mor\u00e9 ses souvenirs face \u00e0 Alberto Contador et a \u00e9voqu\u00e9 plusieurs coureurs fran\u00e7ais.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":241081,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[46994],"tags":[1719,1262],"class_list":["post-241078","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cyclisme-sur-route","tag-julian-alaphilippe","tag-tour-de-france"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Andy Schleck : &quot;Julian Alaphilippe est le coureur qui a le plus de classe&quot;<\/title>\n<meta name=\"description\" content=\"TOUR DE FRANCE 2022 - En marge de la Grande Boucle, Andy Schleck s&#039;est rem\u00e9mor\u00e9 ses souvenirs face \u00e0 Alberto Contador et a \u00e9voqu\u00e9 plusieurs coureurs fran\u00e7ais.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/andy-schleck-julian-alaphilippe-est-le-coureur-qui-a-le-plus-de-classe\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Andy Schleck : &quot;Julian Alaphilippe est le coureur qui a le plus de classe&quot;\" \/>\n<meta property=\"og:description\" content=\"TOUR DE FRANCE 2022 - En marge de la Grande Boucle, Andy Schleck s&#039;est rem\u00e9mor\u00e9 ses souvenirs face \u00e0 Alberto Contador et a \u00e9voqu\u00e9 plusieurs coureurs fran\u00e7ais.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/andy-schleck-julian-alaphilippe-est-le-coureur-qui-a-le-plus-de-classe\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-07T17:28:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-07T17:50:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Andy-Schleck-22Julian-Alaphilippe-est-le-coureur-qui-a-le-plus-de-classe22.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Andy Schleck : &quot;Julian Alaphilippe est le coureur qui a le plus de classe&quot;\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/andy-schleck-julian-alaphilippe-est-le-coureur-qui-a-le-plus-de-classe\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/andy-schleck-julian-alaphilippe-est-le-coureur-qui-a-le-plus-de-classe\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Andy Schleck : \u00ab\u00a0Julian Alaphilippe est le coureur qui a le plus de classe\u00a0\u00bb\",\"datePublished\":\"2022-07-07T17:28:46+00:00\",\"dateModified\":\"2022-07-07T17:50:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/andy-schleck-julian-alaphilippe-est-le-coureur-qui-a-le-plus-de-classe\/\"},\"wordCount\":292,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/andy-schleck-julian-alaphilippe-est-le-coureur-qui-a-le-plus-de-classe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Andy-Schleck-22Julian-Alaphilippe-est-le-coureur-qui-a-le-plus-de-classe22.png\",\"keywords\":[\"Julian Alaphilippe\",\"Tour de France\"],\"articleSection\":[\"Cyclisme sur route\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/andy-schleck-julian-alaphilippe-est-le-coureur-qui-a-le-plus-de-classe\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/andy-schleck-julian-alaphilippe-est-le-coureur-qui-a-le-plus-de-classe\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/andy-schleck-julian-alaphilippe-est-le-coureur-qui-a-le-plus-de-classe\/\",\"name\":\"Andy Schleck : \\\"Julian Alaphilippe est le coureur qui a le plus de classe\\\"\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/andy-schleck-julian-alaphilippe-est-le-coureur-qui-a-le-plus-de-classe\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/andy-schleck-julian-alaphilippe-est-le-coureur-qui-a-le-plus-de-classe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Andy-Schleck-22Julian-Alaphilippe-est-le-coureur-qui-a-le-plus-de-classe22.png\",\"datePublished\":\"2022-07-07T17:28:46+00:00\",\"dateModified\":\"2022-07-07T17:50:16+00:00\",\"description\":\"TOUR DE FRANCE 2022 - En marge de la Grande Boucle, Andy Schleck s'est rem\u00e9mor\u00e9 ses souvenirs face \u00e0 Alberto Contador et a \u00e9voqu\u00e9 plusieurs coureurs fran\u00e7ais.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/andy-schleck-julian-alaphilippe-est-le-coureur-qui-a-le-plus-de-classe\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/andy-schleck-julian-alaphilippe-est-le-coureur-qui-a-le-plus-de-classe\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/andy-schleck-julian-alaphilippe-est-le-coureur-qui-a-le-plus-de-classe\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Andy-Schleck-22Julian-Alaphilippe-est-le-coureur-qui-a-le-plus-de-classe22.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Andy-Schleck-22Julian-Alaphilippe-est-le-coureur-qui-a-le-plus-de-classe22.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/andy-schleck-julian-alaphilippe-est-le-coureur-qui-a-le-plus-de-classe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Andy Schleck : \u00ab\u00a0Julian Alaphilippe est le coureur qui a le plus de classe\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Andy Schleck : \"Julian Alaphilippe est le coureur qui a le plus de classe\"","description":"TOUR DE FRANCE 2022 - En marge de la Grande Boucle, Andy Schleck s'est rem\u00e9mor\u00e9 ses souvenirs face \u00e0 Alberto Contador et a \u00e9voqu\u00e9 plusieurs coureurs fran\u00e7ais.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/andy-schleck-julian-alaphilippe-est-le-coureur-qui-a-le-plus-de-classe\/","og_locale":"fr_FR","og_type":"article","og_title":"Andy Schleck : \"Julian Alaphilippe est le coureur qui a le plus de classe\"","og_description":"TOUR DE FRANCE 2022 - En marge de la Grande Boucle, Andy Schleck s'est rem\u00e9mor\u00e9 ses souvenirs face \u00e0 Alberto Contador et a \u00e9voqu\u00e9 plusieurs coureurs fran\u00e7ais.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/andy-schleck-julian-alaphilippe-est-le-coureur-qui-a-le-plus-de-classe\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2022-07-07T17:28:46+00:00","article_modified_time":"2022-07-07T17:50:16+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Andy-Schleck-22Julian-Alaphilippe-est-le-coureur-qui-a-le-plus-de-classe22.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Andy Schleck : \"Julian Alaphilippe est le coureur qui a le plus de classe\"","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/andy-schleck-julian-alaphilippe-est-le-coureur-qui-a-le-plus-de-classe\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/andy-schleck-julian-alaphilippe-est-le-coureur-qui-a-le-plus-de-classe\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Andy Schleck : \u00ab\u00a0Julian Alaphilippe est le coureur qui a le plus de classe\u00a0\u00bb","datePublished":"2022-07-07T17:28:46+00:00","dateModified":"2022-07-07T17:50:16+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/andy-schleck-julian-alaphilippe-est-le-coureur-qui-a-le-plus-de-classe\/"},"wordCount":292,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/andy-schleck-julian-alaphilippe-est-le-coureur-qui-a-le-plus-de-classe\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Andy-Schleck-22Julian-Alaphilippe-est-le-coureur-qui-a-le-plus-de-classe22.png","keywords":["Julian Alaphilippe","Tour de France"],"articleSection":["Cyclisme sur route"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/andy-schleck-julian-alaphilippe-est-le-coureur-qui-a-le-plus-de-classe\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/andy-schleck-julian-alaphilippe-est-le-coureur-qui-a-le-plus-de-classe\/","url":"https:\/\/dicodusport.fr\/blog\/andy-schleck-julian-alaphilippe-est-le-coureur-qui-a-le-plus-de-classe\/","name":"Andy Schleck : \"Julian Alaphilippe est le coureur qui a le plus de classe\"","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/andy-schleck-julian-alaphilippe-est-le-coureur-qui-a-le-plus-de-classe\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/andy-schleck-julian-alaphilippe-est-le-coureur-qui-a-le-plus-de-classe\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Andy-Schleck-22Julian-Alaphilippe-est-le-coureur-qui-a-le-plus-de-classe22.png","datePublished":"2022-07-07T17:28:46+00:00","dateModified":"2022-07-07T17:50:16+00:00","description":"TOUR DE FRANCE 2022 - En marge de la Grande Boucle, Andy Schleck s'est rem\u00e9mor\u00e9 ses souvenirs face \u00e0 Alberto Contador et a \u00e9voqu\u00e9 plusieurs coureurs fran\u00e7ais.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/andy-schleck-julian-alaphilippe-est-le-coureur-qui-a-le-plus-de-classe\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/andy-schleck-julian-alaphilippe-est-le-coureur-qui-a-le-plus-de-classe\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/andy-schleck-julian-alaphilippe-est-le-coureur-qui-a-le-plus-de-classe\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Andy-Schleck-22Julian-Alaphilippe-est-le-coureur-qui-a-le-plus-de-classe22.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Andy-Schleck-22Julian-Alaphilippe-est-le-coureur-qui-a-le-plus-de-classe22.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/andy-schleck-julian-alaphilippe-est-le-coureur-qui-a-le-plus-de-classe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Andy Schleck : \u00ab\u00a0Julian Alaphilippe est le coureur qui a le plus de classe\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/241078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=241078"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/241078\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/241081"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=241078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=241078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=241078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}