{"id":241134,"date":"2022-07-08T08:15:27","date_gmt":"2022-07-08T06:15:27","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=241134&#038;preview=true&#038;preview_id=241134"},"modified":"2022-07-08T09:38:33","modified_gmt":"2022-07-08T07:38:33","slug":"le-castres-olympique-poursuit-son-marche-en-pro-d2","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/le-castres-olympique-poursuit-son-marche-en-pro-d2\/","title":{"rendered":"Le Castres Olympique poursuit son march\u00e9 en Pro D2"},"content":{"rendered":"<p style=\"text-align: justify;\"><i><b>TOP 14 2022-2023 &#8211; Le Castres Olympique vient d&rsquo;officialiser une quatri\u00e8me recrue en provenance de Pro D2, Gauthier Doubr\u00e8re.<br \/>\n<\/b><\/i><\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s <a href=\"https:\/\/dicodusport.fr\/blog\/le-castres-olympique-met-la-main-sur-un-jeune-2eme-ligne-francais\/\"><strong>Gauthier Maravat<\/strong><\/a>, <a href=\"https:\/\/dicodusport.fr\/blog\/le-castres-olympique-officialise-sa-premiere-recrue\/\"><strong>Aur\u00e9lien Azar<\/strong><\/a> et <a href=\"https:\/\/dicodusport.fr\/blog\/asier-usarraga-quitte-laviron-bayonnais-et-signe-avec-un-cador-de-top-14\/\"><strong>Asier Usarraga<\/strong><\/a>, le <strong>Castres Olympique<\/strong> officialise l&rsquo;arriv\u00e9e de <strong>Gauthier Doubr\u00e8re<\/strong>. Le demi de m\u00eal\u00e9e de 26 ans a d\u00e9j\u00e0 connu le Top 14 avec l&rsquo;Union Bordeaux-B\u00e8gles entre 2015 et 2018, avant de partir \u00e0 <strong>Biarritz<\/strong> en <strong>Pro D2<\/strong>. Il a disput\u00e9 trois saisons avec le club basque, avant de rejoindre <strong>Mont-de Marsan<\/strong> l&rsquo;\u00e9t\u00e9 dernier, o\u00f9 il a souvent \u00e9t\u00e9 la doublure de <strong>L\u00e9o Coly<\/strong>. <strong>Gauthier Doubr\u00e8re<\/strong> s&rsquo;est engag\u00e9 pour deux saisons avec <strong>Castres<\/strong>, soit jusqu&rsquo;en juin 2024.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">&#x26aa;&#xfe0f; ,<\/p>\n<p>Le demi de m\u00eal\u00e9e \u0300 (26 ans), \u00e9voluant au <a href=\"https:\/\/twitter.com\/SMR_Rugby?ref_src=twsrc%5Etfw\">@SMR_Rugby<\/a>, s\u2019est engag\u00e9 avec le CO jusqu\u2019en 2024 !<\/p>\n<p>!<\/p>\n<p>Sa r\u00e9action <a href=\"https:\/\/t.co\/7x4Sy5okiS\">https:\/\/t.co\/7x4Sy5okiS<\/a><br \/>\navec <a href=\"https:\/\/twitter.com\/randstad_france?ref_src=twsrc%5Etfw\">@randstad_france<\/a> <a href=\"https:\/\/t.co\/V2BCpAp9Rk\">pic.twitter.com\/V2BCpAp9Rk<\/a><\/p>\n<p>\u2014 Castres Olympique (@CastresRugby) <a href=\"https:\/\/twitter.com\/CastresRugby\/status\/1545075167746936832?ref_src=twsrc%5Etfw\">July 7, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TOP 14 2022-2023 &#8211; Le Castres Olympique vient d&rsquo;officialiser une quatri\u00e8me recrue en provenance de Pro D2, Gauthier Doubr\u00e8re.<\/p>\n","protected":false},"author":1,"featured_media":241158,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[9129,47050],"tags":[4885,1839],"class_list":["post-241134","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","category-top-14","tag-castres-olympique","tag-pro-d2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Le Castres Olympique poursuit son march\u00e9 en Pro D2<\/title>\n<meta name=\"description\" content=\"TOP 14 2022-2023 - Le Castres Olympique vient d&#039;officialiser une quatri\u00e8me recrue en provenance de Pro D2, Gauthier Doubr\u00e8re.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/le-castres-olympique-poursuit-son-marche-en-pro-d2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Castres Olympique poursuit son march\u00e9 en Pro D2\" \/>\n<meta property=\"og:description\" content=\"TOP 14 2022-2023 - Le Castres Olympique vient d&#039;officialiser une quatri\u00e8me recrue en provenance de Pro D2, Gauthier Doubr\u00e8re.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/le-castres-olympique-poursuit-son-marche-en-pro-d2\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-08T06:15:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-08T07:38:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Le-Castres-Olympique-poursuit-son-marche\u0301-en-Pro-D2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Le Castres Olympique poursuit son march\u00e9 en Pro D2\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-castres-olympique-poursuit-son-marche-en-pro-d2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-castres-olympique-poursuit-son-marche-en-pro-d2\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Le Castres Olympique poursuit son march\u00e9 en Pro D2\",\"datePublished\":\"2022-07-08T06:15:27+00:00\",\"dateModified\":\"2022-07-08T07:38:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-castres-olympique-poursuit-son-marche-en-pro-d2\\\/\"},\"wordCount\":168,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-castres-olympique-poursuit-son-marche-en-pro-d2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Le-Castres-Olympique-poursuit-son-marche\u0301-en-Pro-D2.png\",\"keywords\":[\"Castres Olympique\",\"Pro D2\"],\"articleSection\":[\"Rugby \u00e0 XV\",\"Top 14\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-castres-olympique-poursuit-son-marche-en-pro-d2\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-castres-olympique-poursuit-son-marche-en-pro-d2\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-castres-olympique-poursuit-son-marche-en-pro-d2\\\/\",\"name\":\"Le Castres Olympique poursuit son march\u00e9 en Pro D2\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-castres-olympique-poursuit-son-marche-en-pro-d2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-castres-olympique-poursuit-son-marche-en-pro-d2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Le-Castres-Olympique-poursuit-son-marche\u0301-en-Pro-D2.png\",\"datePublished\":\"2022-07-08T06:15:27+00:00\",\"dateModified\":\"2022-07-08T07:38:33+00:00\",\"description\":\"TOP 14 2022-2023 - Le Castres Olympique vient d'officialiser une quatri\u00e8me recrue en provenance de Pro D2, Gauthier Doubr\u00e8re.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-castres-olympique-poursuit-son-marche-en-pro-d2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-castres-olympique-poursuit-son-marche-en-pro-d2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-castres-olympique-poursuit-son-marche-en-pro-d2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Le-Castres-Olympique-poursuit-son-marche\u0301-en-Pro-D2.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Le-Castres-Olympique-poursuit-son-marche\u0301-en-Pro-D2.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/le-castres-olympique-poursuit-son-marche-en-pro-d2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Castres Olympique poursuit son march\u00e9 en Pro D2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le Castres Olympique poursuit son march\u00e9 en Pro D2","description":"TOP 14 2022-2023 - Le Castres Olympique vient d'officialiser une quatri\u00e8me recrue en provenance de Pro D2, Gauthier Doubr\u00e8re.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/le-castres-olympique-poursuit-son-marche-en-pro-d2\/","og_locale":"fr_FR","og_type":"article","og_title":"Le Castres Olympique poursuit son march\u00e9 en Pro D2","og_description":"TOP 14 2022-2023 - Le Castres Olympique vient d'officialiser une quatri\u00e8me recrue en provenance de Pro D2, Gauthier Doubr\u00e8re.","og_url":"https:\/\/dicodusport.fr\/blog\/le-castres-olympique-poursuit-son-marche-en-pro-d2\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2022-07-08T06:15:27+00:00","article_modified_time":"2022-07-08T07:38:33+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Le-Castres-Olympique-poursuit-son-marche\u0301-en-Pro-D2.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Le Castres Olympique poursuit son march\u00e9 en Pro D2","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/le-castres-olympique-poursuit-son-marche-en-pro-d2\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/le-castres-olympique-poursuit-son-marche-en-pro-d2\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Le Castres Olympique poursuit son march\u00e9 en Pro D2","datePublished":"2022-07-08T06:15:27+00:00","dateModified":"2022-07-08T07:38:33+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/le-castres-olympique-poursuit-son-marche-en-pro-d2\/"},"wordCount":168,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/le-castres-olympique-poursuit-son-marche-en-pro-d2\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Le-Castres-Olympique-poursuit-son-marche\u0301-en-Pro-D2.png","keywords":["Castres Olympique","Pro D2"],"articleSection":["Rugby \u00e0 XV","Top 14"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/le-castres-olympique-poursuit-son-marche-en-pro-d2\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/le-castres-olympique-poursuit-son-marche-en-pro-d2\/","url":"https:\/\/dicodusport.fr\/blog\/le-castres-olympique-poursuit-son-marche-en-pro-d2\/","name":"Le Castres Olympique poursuit son march\u00e9 en Pro D2","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/le-castres-olympique-poursuit-son-marche-en-pro-d2\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/le-castres-olympique-poursuit-son-marche-en-pro-d2\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Le-Castres-Olympique-poursuit-son-marche\u0301-en-Pro-D2.png","datePublished":"2022-07-08T06:15:27+00:00","dateModified":"2022-07-08T07:38:33+00:00","description":"TOP 14 2022-2023 - Le Castres Olympique vient d'officialiser une quatri\u00e8me recrue en provenance de Pro D2, Gauthier Doubr\u00e8re.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/le-castres-olympique-poursuit-son-marche-en-pro-d2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/le-castres-olympique-poursuit-son-marche-en-pro-d2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/le-castres-olympique-poursuit-son-marche-en-pro-d2\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Le-Castres-Olympique-poursuit-son-marche\u0301-en-Pro-D2.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Le-Castres-Olympique-poursuit-son-marche\u0301-en-Pro-D2.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/le-castres-olympique-poursuit-son-marche-en-pro-d2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Le Castres Olympique poursuit son march\u00e9 en Pro D2"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/241134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=241134"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/241134\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/241158"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=241134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=241134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=241134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}